{"id":8118,"date":"2019-06-01T01:25:01","date_gmt":"2019-06-01T01:25:01","guid":{"rendered":"http:\/\/noti-america.com\/site\/venezuela\/?p=8118"},"modified":"2019-06-01T01:25:01","modified_gmt":"2019-06-01T01:25:01","slug":"usar-lentes-oscuros-te-hace-ver-mas-atractivo","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/","title":{"rendered":"Usar lentes oscuros te hace ver m\u00e1s atr\u00e1ctivo"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8119 size-full\" src=\"http:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2019\/06\/famosas-lentes.jpg\" alt=\"\" width=\"640\" height=\"396\" srcset=\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2019\/06\/famosas-lentes.jpg 640w, https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2019\/06\/famosas-lentes-300x186.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div>\n<div><\/div>\n<div style=\"text-align: justify\"><!--block-->Es habitual colocarse unos lentes oscuros cuando salimos a la calle, primeramente son \u00fatiles para cubrirnos del sol y segundo nos protegemos la vista.<\/p>\n<p>La moda de hoy en d\u00eda es llevar los lentes en cualquier ocasi\u00f3n, seg\u00fan un estudio revelado por la revista forbes, los lentes oscuros o llamados tambi\u00e9n lentes de sol nos hacen ver m\u00e1s atractivos, esto porque nos muestran como personas cultas y formidables, adem\u00e1s\u00a0 usando anteojos oscuros nos sentimos seguros en cualquier conversaci\u00f3n.<\/p>\n<p>A su vez, llevar lentes oscuros te da ese toque diferente a tu atuendo, bien sea si tienes puesto ropa formal casual o playera.<\/p>\n<p>Foto: Cortes\u00eda <a href=\"https:\/\/www.univision.com\/temas\/helen-ochoa\">Univision<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Es habitual colocarse unos lentes oscuros cuando salimos a la calle, primeramente son \u00fatiles para cubrirnos del sol y segundo nos protegemos la vista. La moda de hoy en d\u00eda es llevar los lentes&#46;&#46;&#46;<\/p>\n","protected":false},"author":45,"featured_media":8119,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[132],"tags":[],"class_list":["post-8118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Usar lentes oscuros te hace ver m\u00e1s atr\u00e1ctivo - Venezuela | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Usar lentes oscuros te hace ver m\u00e1s atr\u00e1ctivo\" \/>\n<meta property=\"og:description\" content=\"Es habitual colocarse unos lentes oscuros cuando salimos a la calle, primeramente son \u00fatiles para cubrirnos del sol y segundo nos protegemos la vista. La moda de hoy en d\u00eda es llevar los lentes&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Venezuela | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-01T01:25:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2019\/06\/famosas-lentes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"396\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marilyn Oviedo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marilyn Oviedo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/\"},\"author\":{\"name\":\"Marilyn Oviedo\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/8017f023586435e99ed107a0945f3b86\"},\"headline\":\"Usar lentes oscuros te hace ver m\u00e1s atr\u00e1ctivo\",\"datePublished\":\"2019-06-01T01:25:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/\"},\"wordCount\":123,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2019\/06\/famosas-lentes.jpg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/\",\"name\":\"Usar lentes oscuros te hace ver m\u00e1s atr\u00e1ctivo - Venezuela | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2019\/06\/famosas-lentes.jpg\",\"datePublished\":\"2019-06-01T01:25:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2019\/06\/famosas-lentes.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2019\/06\/famosas-lentes.jpg\",\"width\":640,\"height\":396},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/venezuela\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Usar lentes oscuros te hace ver m\u00e1s atr\u00e1ctivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/\",\"name\":\"Venezuela | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/venezuela\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\",\"name\":\"Noti-America LLC | Venezuela\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Venezuela\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/8017f023586435e99ed107a0945f3b86\",\"name\":\"Marilyn Oviedo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/6ab070ce76f64b066017eef1247ecdeb7c01b8e99448b515919552ac2123cc84?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6ab070ce76f64b066017eef1247ecdeb7c01b8e99448b515919552ac2123cc84?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6ab070ce76f64b066017eef1247ecdeb7c01b8e99448b515919552ac2123cc84?s=96&d=mm&r=g\",\"caption\":\"Marilyn Oviedo\"},\"description\":\"Venezolana, Licenciada en Letras | Productora | Redactora de Contenidos | Community Manager.\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/author\/moviedo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Usar lentes oscuros te hace ver m\u00e1s atr\u00e1ctivo - Venezuela | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/","og_locale":"es_ES","og_type":"article","og_title":"Usar lentes oscuros te hace ver m\u00e1s atr\u00e1ctivo","og_description":"Es habitual colocarse unos lentes oscuros cuando salimos a la calle, primeramente son \u00fatiles para cubrirnos del sol y segundo nos protegemos la vista. La moda de hoy en d\u00eda es llevar los lentes&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/","og_site_name":"Venezuela | Noti-America.com","article_published_time":"2019-06-01T01:25:01+00:00","og_image":[{"width":640,"height":396,"url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2019\/06\/famosas-lentes.jpg","type":"image\/jpeg"}],"author":"Marilyn Oviedo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marilyn Oviedo","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/"},"author":{"name":"Marilyn Oviedo","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/8017f023586435e99ed107a0945f3b86"},"headline":"Usar lentes oscuros te hace ver m\u00e1s atr\u00e1ctivo","datePublished":"2019-06-01T01:25:01+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/"},"wordCount":123,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2019\/06\/famosas-lentes.jpg","articleSection":["Actualidad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/","url":"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/","name":"Usar lentes oscuros te hace ver m\u00e1s atr\u00e1ctivo - Venezuela | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2019\/06\/famosas-lentes.jpg","datePublished":"2019-06-01T01:25:01+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#primaryimage","url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2019\/06\/famosas-lentes.jpg","contentUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2019\/06\/famosas-lentes.jpg","width":640,"height":396},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/venezuela\/2019\/06\/01\/usar-lentes-oscuros-te-hace-ver-mas-atractivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/venezuela\/"},{"@type":"ListItem","position":2,"name":"Usar lentes oscuros te hace ver m\u00e1s atr\u00e1ctivo"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/venezuela\/#website","url":"https:\/\/noti-america.com\/site\/venezuela\/","name":"Venezuela | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization","name":"Noti-America LLC | Venezuela","url":"https:\/\/noti-america.com\/site\/venezuela\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Venezuela"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/8017f023586435e99ed107a0945f3b86","name":"Marilyn Oviedo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6ab070ce76f64b066017eef1247ecdeb7c01b8e99448b515919552ac2123cc84?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ab070ce76f64b066017eef1247ecdeb7c01b8e99448b515919552ac2123cc84?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ab070ce76f64b066017eef1247ecdeb7c01b8e99448b515919552ac2123cc84?s=96&d=mm&r=g","caption":"Marilyn Oviedo"},"description":"Venezolana, Licenciada en Letras | Productora | Redactora de Contenidos | Community Manager.","url":"https:\/\/noti-america.com\/site\/venezuela\/author\/moviedo\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts\/8118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/comments?post=8118"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts\/8118\/revisions"}],"predecessor-version":[{"id":8120,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts\/8118\/revisions\/8120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/media\/8119"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/media?parent=8118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/categories?post=8118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/tags?post=8118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}