{"id":49653,"date":"2025-12-08T15:25:20","date_gmt":"2025-12-08T15:25:20","guid":{"rendered":"https:\/\/noti-america.com\/site\/venezuela\/?p=49653"},"modified":"2025-12-08T15:25:20","modified_gmt":"2025-12-08T15:25:20","slug":"zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/","title":{"rendered":"Zo\u00e9 Salda\u00f1a destaca el apoyo de Sam Worthington y James Cameron en Avatar 3"},"content":{"rendered":"<p>NOTI-AMERICA.COM | VENEZUELA<\/p>\n<p style=\"text-align: justify\">Zo\u00e9 Salda\u00f1a, actriz estadounidense de ascendencia dominicana, habl\u00f3 en Par\u00eds de c\u00f3mo el apoyo que tuvo por parte del actor Sam Worthington y el director James Cameron la ayud\u00f3 a superar la dificultad de encarnar a su personaje Neytiri, una madre de familia refugiada.<\/p>\n<p style=\"text-align: justify\">\u00abEstoy agradecida de que nunca me sent\u00ed sola porque Sam (Worthington) y tambi\u00e9n su personaje Jake (pareja de Neytiri en la ficci\u00f3n) estaban justo a mi lado\u00bb, declar\u00f3 Salda\u00f1a, tras presentarse en Par\u00eds la tercera entrega de Avatar, que se estrena en Espa\u00f1a el pr\u00f3ximo 19 de diciembre bajo el t\u00edtulo &#8216; Avatar, Fuego y Ceniza&#8217;.<\/p>\n<p style=\"text-align: justify\">Salda\u00f1a, de 47 a\u00f1os, coment\u00f3 el desaf\u00edo que le produjo la interpretaci\u00f3n de Neytiri, una madre de familia refugiada en el clan Metkayina de los Na&#8217;vi, al mismo tiempo que ella cr\u00eda a sus hijos en la realidad.<\/p>\n<p style=\"text-align: justify\">\u00abEst\u00e1bamos encarnando a estos individuos que est\u00e1n esperando un hijo y est\u00e1n intentando con todas sus fuerzas permanecer juntos y criar a los hijos que tienen. Fue dif\u00edcil estar en el cuerpo de Neytiri\u00bb, reconoci\u00f3 Salda\u00f1a.<\/p>\n<p style=\"text-align: justify\">Junto a Salda\u00f1a, Worthington y Cameron, la presentaci\u00f3n en Par\u00eds cont\u00f3 con otros de los protagonistas, Sigourney Weaver (Kiri), Stephen Lang (Miles Quaritch) y Oona Chaplin (Varang).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA.COM | VENEZUELA Zo\u00e9 Salda\u00f1a, actriz estadounidense de ascendencia dominicana, habl\u00f3 en Par\u00eds de c\u00f3mo el apoyo que tuvo por parte del actor Sam Worthington y el director James Cameron la ayud\u00f3 a superar&#46;&#46;&#46;<\/p>\n","protected":false},"author":133,"featured_media":49654,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[508],"tags":[],"class_list":["post-49653","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-acturalidad","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Zo\u00e9 Salda\u00f1a destaca el apoyo de Sam Worthington y James Cameron en Avatar 3 - Venezuela | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zo\u00e9 Salda\u00f1a destaca el apoyo de Sam Worthington y James Cameron en Avatar 3\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA.COM | VENEZUELA Zo\u00e9 Salda\u00f1a, actriz estadounidense de ascendencia dominicana, habl\u00f3 en Par\u00eds de c\u00f3mo el apoyo que tuvo por parte del actor Sam Worthington y el director James Cameron la ayud\u00f3 a superar&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Venezuela | Noti-America.com\" \/>\n<meta property=\"article:author\" content=\"Mar\u00eda Valentina Noguera\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-08T15:25:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/12\/get-25a84e.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maria Valentina Noguera Medina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Valentina Noguera Medina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/\"},\"author\":{\"name\":\"Maria Valentina Noguera Medina\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/b0777fb8ad9a321dc446ddbbceae778f\"},\"headline\":\"Zo\u00e9 Salda\u00f1a destaca el apoyo de Sam Worthington y James Cameron en Avatar 3\",\"datePublished\":\"2025-12-08T15:25:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/\"},\"wordCount\":239,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/12\/get-25a84e.jpeg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/\",\"name\":\"Zo\u00e9 Salda\u00f1a destaca el apoyo de Sam Worthington y James Cameron en Avatar 3 - Venezuela | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/12\/get-25a84e.jpeg\",\"datePublished\":\"2025-12-08T15:25:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/12\/get-25a84e.jpeg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/12\/get-25a84e.jpeg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/venezuela\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zo\u00e9 Salda\u00f1a destaca el apoyo de Sam Worthington y James Cameron en Avatar 3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/\",\"name\":\"Venezuela | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/venezuela\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\",\"name\":\"Noti-America LLC | Venezuela\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Venezuela\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/b0777fb8ad9a321dc446ddbbceae778f\",\"name\":\"Maria Valentina Noguera Medina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g\",\"caption\":\"Maria Valentina Noguera Medina\"},\"description\":\"Periodista - noti-america - Promar Community Manager - Talento Plus Dise\u00f1adora\/ creadora de contenido...\",\"sameAs\":[\"Mar\u00eda Valentina Noguera\",\"https:\/\/www.facebook.com\/mariavalentina.noguera\",\"https:\/\/www.linkedin.com\/in\/mara-valentina-noguera-medina-373075165\/\",\"https:\/\/www.pinterest.es\/valentinanoguera95\/\",\"https:\/\/www.youtube.com\/channel\/UCdek6mbUZ-Tqqw0I63i4nmQ\"],\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/author\/mnoguera\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Zo\u00e9 Salda\u00f1a destaca el apoyo de Sam Worthington y James Cameron en Avatar 3 - Venezuela | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/","og_locale":"es_ES","og_type":"article","og_title":"Zo\u00e9 Salda\u00f1a destaca el apoyo de Sam Worthington y James Cameron en Avatar 3","og_description":"NOTI-AMERICA.COM | VENEZUELA Zo\u00e9 Salda\u00f1a, actriz estadounidense de ascendencia dominicana, habl\u00f3 en Par\u00eds de c\u00f3mo el apoyo que tuvo por parte del actor Sam Worthington y el director James Cameron la ayud\u00f3 a superar&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/","og_site_name":"Venezuela | Noti-America.com","article_author":"Mar\u00eda Valentina Noguera","article_published_time":"2025-12-08T15:25:20+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/12\/get-25a84e.jpeg","type":"image\/jpeg"}],"author":"Maria Valentina Noguera Medina","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maria Valentina Noguera Medina","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/"},"author":{"name":"Maria Valentina Noguera Medina","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/b0777fb8ad9a321dc446ddbbceae778f"},"headline":"Zo\u00e9 Salda\u00f1a destaca el apoyo de Sam Worthington y James Cameron en Avatar 3","datePublished":"2025-12-08T15:25:20+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/"},"wordCount":239,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/12\/get-25a84e.jpeg","articleSection":["Actualidad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/","url":"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/","name":"Zo\u00e9 Salda\u00f1a destaca el apoyo de Sam Worthington y James Cameron en Avatar 3 - Venezuela | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/12\/get-25a84e.jpeg","datePublished":"2025-12-08T15:25:20+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#primaryimage","url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/12\/get-25a84e.jpeg","contentUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/12\/get-25a84e.jpeg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/12\/08\/zoe-saldana-destaca-el-apoyo-de-sam-worthington-y-james-cameron-en-avatar-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/venezuela\/"},{"@type":"ListItem","position":2,"name":"Zo\u00e9 Salda\u00f1a destaca el apoyo de Sam Worthington y James Cameron en Avatar 3"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/venezuela\/#website","url":"https:\/\/noti-america.com\/site\/venezuela\/","name":"Venezuela | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization","name":"Noti-America LLC | Venezuela","url":"https:\/\/noti-america.com\/site\/venezuela\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Venezuela"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/b0777fb8ad9a321dc446ddbbceae778f","name":"Maria Valentina Noguera Medina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g","caption":"Maria Valentina Noguera Medina"},"description":"Periodista - noti-america - Promar Community Manager - Talento Plus Dise\u00f1adora\/ creadora de contenido...","sameAs":["Mar\u00eda Valentina Noguera","https:\/\/www.facebook.com\/mariavalentina.noguera","https:\/\/www.linkedin.com\/in\/mara-valentina-noguera-medina-373075165\/","https:\/\/www.pinterest.es\/valentinanoguera95\/","https:\/\/www.youtube.com\/channel\/UCdek6mbUZ-Tqqw0I63i4nmQ"],"url":"https:\/\/noti-america.com\/site\/venezuela\/author\/mnoguera\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts\/49653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/comments?post=49653"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts\/49653\/revisions"}],"predecessor-version":[{"id":49655,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts\/49653\/revisions\/49655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/media\/49654"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/media?parent=49653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/categories?post=49653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/tags?post=49653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}