{"id":46526,"date":"2025-08-03T16:40:12","date_gmt":"2025-08-03T16:40:12","guid":{"rendered":"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/"},"modified":"2025-08-03T16:40:12","modified_gmt":"2025-08-03T16:40:12","slug":"por-que-las-mujeres-viven-mas","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/","title":{"rendered":"\u00bfPor qu\u00e9 las mujeres viven m\u00e1s?"},"content":{"rendered":"<p>NOTI-AMERICA.COM | CHILE<\/p>\n<p style=\"text-align: justify\">Las mujeres viven de media unos 5,5 a\u00f1os m\u00e1s que los hombres. Detr\u00e1s de esta diferencia se esconden factores biol\u00f3gicos y ambientales relacionados con los h\u00e1bitos de vida. Eso s\u00ed, la esperanza de vida podr\u00eda igualarse entre ambos sexos en los pr\u00f3ximos a\u00f1os.<\/p>\n<p style=\"text-align: justify\">Las mujeres viven m\u00e1s que los hombres, de media unos 5,5 a\u00f1os. Esta diferencia se explica por factores gen\u00e9ticos y ambientales, relacionados con los h\u00e1bitos de vida. Sin embargo, la variaci\u00f3n en estas rutinas puede traer consigo en los pr\u00f3ximos a\u00f1os una igualaci\u00f3n en la esperanza de vida para ambos sexos. Analizamos qu\u00e9 puede aprender un sexo del otro para vivir m\u00e1s a\u00f1os y con m\u00e1s calidad de vida.<\/p>\n<p style=\"text-align: justify\">La esperanza de viva en la Uni\u00f3n Europea, seg\u00fan datos del Instituto Nacional de Estad\u00edstica, es de 84 a\u00f1os para las mujeres y de 78,5 para los hombres. Esta diferencia se explica en parte por factores biol\u00f3gicos, relacionados con la acci\u00f3n de los estr\u00f3genos, que confieren unos diez a\u00f1os de protecci\u00f3n frente a la aparici\u00f3n de eventos de tipo cardiovascular, seg\u00fan explica Miguel \u00c1ngel Acosta, m\u00e9dico en el centro de salud El Espinillo, en Madrid, y coordinador del Programa de actividades preventivas y promoci\u00f3n de la salud en el mayor y miembro del grupo de trabajo de Atenci\u00f3n al mayor de la Sociedad Espa\u00f1ola de Medicina de Familia y Comunitaria (SemFYC).<\/p>\n<h2 style=\"text-align: justify\">La protecci\u00f3n de los estr\u00f3genos<\/h2>\n<p style=\"text-align: justify\">Los estr\u00f3genos son, junto con la progesterona, las principales hormonas sexuales femeninas, con funciones como la preparaci\u00f3n de la fecundaci\u00f3n y la estimulaci\u00f3n de la l\u00edbido, pero que tambi\u00e9n influyen en el metabolismo de las grasas y el colesterol de la sangre, favoreciendo la relajaci\u00f3n de las paredes de los vasos sangu\u00edneos y disminuyendo la presi\u00f3n arterial, mediando a la vez en la distribuci\u00f3n de la grasa corporal.<\/p>\n<p style=\"text-align: justify\">Estas hormonas influyen tambi\u00e9n en la protecci\u00f3n de los huesos. Por eso, cuando la producci\u00f3n de estr\u00f3genos disminuye con la edad las mujeres experimentan una p\u00e9rdida de masa \u00f3sea que se relaciona con un mayor riesgo de fracturas.<\/p>\n<h2 style=\"text-align: justify\">H\u00e1bitos de vida<\/h2>\n<p style=\"text-align: justify\">La mayor esperanza de vida de las mujeres se explica tambi\u00e9n por h\u00e1bitos de vida que, tradicionalmente, han sido m\u00e1s saludables, con menores \u00edndices de sustancias t\u00f3xicas, como tabaco y alcohol, as\u00ed como de consumo de drogas, que los hombres, explica Miguel \u00c1ngel Acosta.<\/p>\n<p style=\"text-align: justify\">Adem\u00e1s, las mujeres tambi\u00e9n han mantenido en general un patr\u00f3n diet\u00e9tico m\u00e1s favorable, con una mayor adherencia a la dieta mediterr\u00e1nea, con m\u00e1s consumo de verduras y frutas y menor de carne y de grasas saturadas, indica este especialista.<\/p>\n<p style=\"text-align: justify\">\u201cSe da la circunstancia de que las mujeres, condicionadas en parte por la presi\u00f3n social, han prestado m\u00e1s atenci\u00f3n a su imagen y se han preocupado m\u00e1s por el mantenimiento del peso. Es un h\u00e1bito saludable, siempre sin que se convierta en una obsesi\u00f3n, del que tambi\u00e9n conviene que aprendan los hombres\u201d, se\u00f1ala Acosta.<\/p>\n<p style=\"text-align: justify\">Sin embargo, los cambios en los patrones diet\u00e9ticos y de h\u00e1bitos de vida manifestados por la poblaci\u00f3n femenina en los \u00faltimos a\u00f1os se est\u00e1n traduciendo ya en un aumento de los tumores de pulm\u00f3n, relacionado este incremento con un mayor consumo de tabaco, y en m\u00e1s incidencia de c\u00e1ncer de colon, muy correlacionado este tumor con h\u00e1bitos diet\u00e9ticos, ambientales y de estilo de vida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA.COM | CHILE Las mujeres viven de media unos 5,5 a\u00f1os m\u00e1s que los hombres. Detr\u00e1s de esta diferencia se esconden factores biol\u00f3gicos y ambientales relacionados con los h\u00e1bitos de vida. Eso s\u00ed, la&#46;&#46;&#46;<\/p>\n","protected":false},"author":133,"featured_media":46527,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[132],"tags":[],"class_list":["post-46526","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-actualidad","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfPor qu\u00e9 las mujeres viven m\u00e1s? - Venezuela | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 las mujeres viven m\u00e1s?\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA.COM | CHILE Las mujeres viven de media unos 5,5 a\u00f1os m\u00e1s que los hombres. Detr\u00e1s de esta diferencia se esconden factores biol\u00f3gicos y ambientales relacionados con los h\u00e1bitos de vida. Eso s\u00ed, la&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/\" \/>\n<meta property=\"og:site_name\" content=\"Venezuela | Noti-America.com\" \/>\n<meta property=\"article:author\" content=\"Mar\u00eda Valentina Noguera\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-03T16:40:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/08\/105486598_viejita.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"976\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maria Valentina Noguera Medina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Valentina Noguera Medina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/\"},\"author\":{\"name\":\"Maria Valentina Noguera Medina\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/8e82689d84cfd274a163cfa42d51922c\"},\"headline\":\"\u00bfPor qu\u00e9 las mujeres viven m\u00e1s?\",\"datePublished\":\"2025-08-03T16:40:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/\"},\"wordCount\":625,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/08\/105486598_viejita.jpg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/\",\"name\":\"\u00bfPor qu\u00e9 las mujeres viven m\u00e1s? - Venezuela | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/08\/105486598_viejita.jpg\",\"datePublished\":\"2025-08-03T16:40:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/08\/105486598_viejita.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/08\/105486598_viejita.jpg\",\"width\":976,\"height\":549},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/venezuela\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 las mujeres viven m\u00e1s?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/\",\"name\":\"Venezuela | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/venezuela\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\",\"name\":\"Noti-America LLC | Venezuela\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Venezuela\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/8e82689d84cfd274a163cfa42d51922c\",\"name\":\"Maria Valentina Noguera Medina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g\",\"caption\":\"Maria Valentina Noguera Medina\"},\"description\":\"Periodista - noti-america - Promar Community Manager - Talento Plus Dise\u00f1adora\/ creadora de contenido...\",\"sameAs\":[\"Mar\u00eda Valentina Noguera\",\"https:\/\/www.facebook.com\/mariavalentina.noguera\",\"https:\/\/www.linkedin.com\/in\/mara-valentina-noguera-medina-373075165\/\",\"https:\/\/www.pinterest.es\/valentinanoguera95\/\",\"https:\/\/www.youtube.com\/channel\/UCdek6mbUZ-Tqqw0I63i4nmQ\"],\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/author\/mnoguera\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 las mujeres viven m\u00e1s? - Venezuela | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 las mujeres viven m\u00e1s?","og_description":"NOTI-AMERICA.COM | CHILE Las mujeres viven de media unos 5,5 a\u00f1os m\u00e1s que los hombres. Detr\u00e1s de esta diferencia se esconden factores biol\u00f3gicos y ambientales relacionados con los h\u00e1bitos de vida. Eso s\u00ed, la&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/","og_site_name":"Venezuela | Noti-America.com","article_author":"Mar\u00eda Valentina Noguera","article_published_time":"2025-08-03T16:40:12+00:00","og_image":[{"width":976,"height":549,"url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/08\/105486598_viejita.jpg","type":"image\/jpeg"}],"author":"Maria Valentina Noguera Medina","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maria Valentina Noguera Medina","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/"},"author":{"name":"Maria Valentina Noguera Medina","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/8e82689d84cfd274a163cfa42d51922c"},"headline":"\u00bfPor qu\u00e9 las mujeres viven m\u00e1s?","datePublished":"2025-08-03T16:40:12+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/"},"wordCount":625,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/08\/105486598_viejita.jpg","articleSection":["Actualidad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/","url":"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/","name":"\u00bfPor qu\u00e9 las mujeres viven m\u00e1s? - Venezuela | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/08\/105486598_viejita.jpg","datePublished":"2025-08-03T16:40:12+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#primaryimage","url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/08\/105486598_viejita.jpg","contentUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/08\/105486598_viejita.jpg","width":976,"height":549},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/08\/03\/por-que-las-mujeres-viven-mas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/venezuela\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 las mujeres viven m\u00e1s?"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/venezuela\/#website","url":"https:\/\/noti-america.com\/site\/venezuela\/","name":"Venezuela | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization","name":"Noti-America LLC | Venezuela","url":"https:\/\/noti-america.com\/site\/venezuela\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Venezuela"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/8e82689d84cfd274a163cfa42d51922c","name":"Maria Valentina Noguera Medina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g","caption":"Maria Valentina Noguera Medina"},"description":"Periodista - noti-america - Promar Community Manager - Talento Plus Dise\u00f1adora\/ creadora de contenido...","sameAs":["Mar\u00eda Valentina Noguera","https:\/\/www.facebook.com\/mariavalentina.noguera","https:\/\/www.linkedin.com\/in\/mara-valentina-noguera-medina-373075165\/","https:\/\/www.pinterest.es\/valentinanoguera95\/","https:\/\/www.youtube.com\/channel\/UCdek6mbUZ-Tqqw0I63i4nmQ"],"url":"https:\/\/noti-america.com\/site\/venezuela\/author\/mnoguera\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts\/46526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/comments?post=46526"}],"version-history":[{"count":0,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts\/46526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/media\/46527"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/media?parent=46526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/categories?post=46526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/tags?post=46526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}