{"id":45684,"date":"2025-07-07T17:32:10","date_gmt":"2025-07-07T17:32:10","guid":{"rendered":"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/"},"modified":"2025-07-07T17:32:10","modified_gmt":"2025-07-07T17:32:10","slug":"jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/","title":{"rendered":"&#8216;Jurassic World:El renacer&#8217; arrasa en su estreno en taquilla con 318,3 millones de d\u00f3lares"},"content":{"rendered":"<p>NOTI-AMERICA.COM | M\u00c9XICO<\/p>\n<p style=\"text-align: justify\">&#8216;Jurassic World: Rebirth&#8217; (&#8216;Jurassic World: El renacer&#8217;), la nueva entrega de las aventuras de dinosaurios, arras\u00f3 este fin de semana en taquilla, con una recaudaci\u00f3n de 318,3 millones de d\u00f3lares en todo el mundo (147 millones en Estados Unidos), seg\u00fan los datos de la web especializada Box Office Mojo.<\/p>\n<p style=\"text-align: justify\">Con Scarlett Johnasson a la cabeza, la pel\u00edcula que contin\u00faa la saga iniciada en 1993 por Steven Spielberg, se qued\u00f3 cerca del r\u00e9cord que mantiene &#8216;Lilo &amp; Stitch&#8217;, que sigue siendo la mejor apertura de este a\u00f1o, con 341 millones de d\u00f3lares conseguidos en su primer fin de semana en las salas, en el mes de mayo.<\/p>\n<p style=\"text-align: justify\">Aunque en el caso de la cinta de animaci\u00f3n, cont\u00f3 con un d\u00eda extra debido a la festividad del Memorial Day en Estados Unidos, as\u00ed que su cifra corresponde a cuatro jornadas en los cines.<\/p>\n<p style=\"text-align: justify\">En segunda posici\u00f3n este fin de semana se situ\u00f3 &#8216;F1&#8217;, la historia de la F\u00f3rmula 1 protagonizada por Brad Pitt, que a\u00f1adi\u00f3 149,6 millones de d\u00f3lares a su recaudaci\u00f3n, que se eleva a 293,6 millones en su segunda semana en las salas.<\/p>\n<p style=\"text-align: justify\">Una cifra que convierte a este filme en el m\u00e1s taquillero entre los centrados en el mundo del automovilismo al batir a &#8216;Ford v Ferrari&#8217; (&#8216;Le Mans &#8217;66&#8217;), que en su carrera comercial consigui\u00f3 226,3 millones de d\u00f3lares en 2019.<\/p>\n<p style=\"text-align: justify\">&#8216;How to Train Your Dragon&#8217; (&#8216;C\u00f3mo entrenar a tu drag\u00f3n&#8217;), la exitosa saga de animaci\u00f3n, sigue sumando dinero y con los 62,9 millones de este fin de semana, alcanza los 516,9 millones, lo que afianza su quinto puesto en el listado de m\u00e1s taquilleras de 2025.<\/p>\n<p style=\"text-align: justify\">&#8216;Elio&#8217;, otra cinta de animaci\u00f3n, de Pixar, contin\u00faa por debajo de lo esperado, pero obtiene otros 24,7 millones de d\u00f3lares, para un total de 96,7.<\/p>\n<p style=\"text-align: justify\">Y cierra el quinteto m\u00e1s taquillero del fin de semana &#8217;28 Years Later&#8217; (&#8217;28 a\u00f1os despu\u00e9s&#8217;), que consigue 22,8 millones y su cifra global es ya de 125,8 millones de d\u00f3lares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA.COM | M\u00c9XICO &#8216;Jurassic World: Rebirth&#8217; (&#8216;Jurassic World: El renacer&#8217;), la nueva entrega de las aventuras de dinosaurios, arras\u00f3 este fin de semana en taquilla, con una recaudaci\u00f3n de 318,3 millones de d\u00f3lares en&#46;&#46;&#46;<\/p>\n","protected":false},"author":133,"featured_media":45685,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[132],"tags":[],"class_list":["post-45684","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-actualidad","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&#8216;Jurassic World:El renacer&#8217; arrasa en su estreno en taquilla con 318,3 millones de d\u00f3lares - Venezuela | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#8216;Jurassic World:El renacer&#8217; arrasa en su estreno en taquilla con 318,3 millones de d\u00f3lares\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA.COM | M\u00c9XICO &#8216;Jurassic World: Rebirth&#8217; (&#8216;Jurassic World: El renacer&#8217;), la nueva entrega de las aventuras de dinosaurios, arras\u00f3 este fin de semana en taquilla, con una recaudaci\u00f3n de 318,3 millones de d\u00f3lares en&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/\" \/>\n<meta property=\"og:site_name\" content=\"Venezuela | Noti-America.com\" \/>\n<meta property=\"article:author\" content=\"Mar\u00eda Valentina Noguera\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-07T17:32:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/07\/jurassic-world-rebirth-trailer.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maria Valentina Noguera Medina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Valentina Noguera Medina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/\"},\"author\":{\"name\":\"Maria Valentina Noguera Medina\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/22806efcc2cfc4b45efb0e17be210ea8\"},\"headline\":\"&#8216;Jurassic World:El renacer&#8217; arrasa en su estreno en taquilla con 318,3 millones de d\u00f3lares\",\"datePublished\":\"2025-07-07T17:32:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/\"},\"wordCount\":353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/07\/jurassic-world-rebirth-trailer.jpeg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/\",\"name\":\"&#8216;Jurassic World:El renacer&#8217; arrasa en su estreno en taquilla con 318,3 millones de d\u00f3lares - Venezuela | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/07\/jurassic-world-rebirth-trailer.jpeg\",\"datePublished\":\"2025-07-07T17:32:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/07\/jurassic-world-rebirth-trailer.jpeg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/07\/jurassic-world-rebirth-trailer.jpeg\",\"width\":1440,\"height\":810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/venezuela\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8216;Jurassic World:El renacer&#8217; arrasa en su estreno en taquilla con 318,3 millones de d\u00f3lares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/\",\"name\":\"Venezuela | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/venezuela\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\",\"name\":\"Noti-America LLC | Venezuela\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Venezuela\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/22806efcc2cfc4b45efb0e17be210ea8\",\"name\":\"Maria Valentina Noguera Medina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g\",\"caption\":\"Maria Valentina Noguera Medina\"},\"description\":\"Periodista - noti-america - Promar Community Manager - Talento Plus Dise\u00f1adora\/ creadora de contenido...\",\"sameAs\":[\"Mar\u00eda Valentina Noguera\",\"https:\/\/www.facebook.com\/mariavalentina.noguera\",\"https:\/\/www.linkedin.com\/in\/mara-valentina-noguera-medina-373075165\/\",\"https:\/\/www.pinterest.es\/valentinanoguera95\/\",\"https:\/\/www.youtube.com\/channel\/UCdek6mbUZ-Tqqw0I63i4nmQ\"],\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/author\/mnoguera\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"&#8216;Jurassic World:El renacer&#8217; arrasa en su estreno en taquilla con 318,3 millones de d\u00f3lares - Venezuela | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/","og_locale":"es_ES","og_type":"article","og_title":"&#8216;Jurassic World:El renacer&#8217; arrasa en su estreno en taquilla con 318,3 millones de d\u00f3lares","og_description":"NOTI-AMERICA.COM | M\u00c9XICO &#8216;Jurassic World: Rebirth&#8217; (&#8216;Jurassic World: El renacer&#8217;), la nueva entrega de las aventuras de dinosaurios, arras\u00f3 este fin de semana en taquilla, con una recaudaci\u00f3n de 318,3 millones de d\u00f3lares en&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/","og_site_name":"Venezuela | Noti-America.com","article_author":"Mar\u00eda Valentina Noguera","article_published_time":"2025-07-07T17:32:10+00:00","og_image":[{"width":1440,"height":810,"url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/07\/jurassic-world-rebirth-trailer.jpeg","type":"image\/jpeg"}],"author":"Maria Valentina Noguera Medina","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maria Valentina Noguera Medina","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/"},"author":{"name":"Maria Valentina Noguera Medina","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/22806efcc2cfc4b45efb0e17be210ea8"},"headline":"&#8216;Jurassic World:El renacer&#8217; arrasa en su estreno en taquilla con 318,3 millones de d\u00f3lares","datePublished":"2025-07-07T17:32:10+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/"},"wordCount":353,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/07\/jurassic-world-rebirth-trailer.jpeg","articleSection":["Actualidad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/","url":"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/","name":"&#8216;Jurassic World:El renacer&#8217; arrasa en su estreno en taquilla con 318,3 millones de d\u00f3lares - Venezuela | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/07\/jurassic-world-rebirth-trailer.jpeg","datePublished":"2025-07-07T17:32:10+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#primaryimage","url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/07\/jurassic-world-rebirth-trailer.jpeg","contentUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2025\/07\/jurassic-world-rebirth-trailer.jpeg","width":1440,"height":810},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/venezuela\/2025\/07\/07\/jurassic-worldel-renacer-arrasa-en-su-estreno-en-taquilla-con-3183-millones-de-dolares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/venezuela\/"},{"@type":"ListItem","position":2,"name":"&#8216;Jurassic World:El renacer&#8217; arrasa en su estreno en taquilla con 318,3 millones de d\u00f3lares"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/venezuela\/#website","url":"https:\/\/noti-america.com\/site\/venezuela\/","name":"Venezuela | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization","name":"Noti-America LLC | Venezuela","url":"https:\/\/noti-america.com\/site\/venezuela\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Venezuela"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/22806efcc2cfc4b45efb0e17be210ea8","name":"Maria Valentina Noguera Medina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g","caption":"Maria Valentina Noguera Medina"},"description":"Periodista - noti-america - Promar Community Manager - Talento Plus Dise\u00f1adora\/ creadora de contenido...","sameAs":["Mar\u00eda Valentina Noguera","https:\/\/www.facebook.com\/mariavalentina.noguera","https:\/\/www.linkedin.com\/in\/mara-valentina-noguera-medina-373075165\/","https:\/\/www.pinterest.es\/valentinanoguera95\/","https:\/\/www.youtube.com\/channel\/UCdek6mbUZ-Tqqw0I63i4nmQ"],"url":"https:\/\/noti-america.com\/site\/venezuela\/author\/mnoguera\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts\/45684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/comments?post=45684"}],"version-history":[{"count":0,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts\/45684\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/media\/45685"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/media?parent=45684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/categories?post=45684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/tags?post=45684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}