{"id":4399,"date":"2018-12-31T10:21:32","date_gmt":"2018-12-31T10:21:32","guid":{"rendered":"http:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/"},"modified":"2018-12-31T10:21:32","modified_gmt":"2018-12-31T10:21:32","slug":"la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/","title":{"rendered":"La hambruna se apoder\u00f3 de toda Venezuela en este a\u00f1o 2018"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/s3.us-east-2.amazonaws.com\/portal-laneta\/diosa77\/13-mm-de-nuevos-pobres-deja-gobierno-de-maduro-01-201812311052255225\" alt=\"13 MM de nuevos pobres deja gobierno de Maduro\" \/><\/p>\n<p style=\"text-align: justify\"><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Seg\u00fan escribe el portal www.descifrado.com \u00abEn los seis a\u00f1os del Gobierno del presidente Nicol\u00e1s Maduro, los venezolanos sufrieron los efectos agresivos de la hiperinflaci\u00f3n y la desaparici\u00f3n de alimentos y medicinas de primera necesidad en el mercado.<\/span><\/span><\/p>\n<p style=\"text-align: justify\">\n<span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Seg\u00fan la \u00faltima Encuesta Nacional de Condiciones de Vida (Encovi), en Venezuela hay 15.277.492 de habitantes pobres (estimado sobre la poblaci\u00f3n estimada por el INE); <\/span><span style=\"vertical-align: inherit\">Es decir, 48% de hogares venezolanos. <\/span><\/span><\/p>\n<p style=\"text-align: justify\">\n<span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">\u00abLo que contrasta con el 1.899.590 (27,3% de hogares venezolanos) que figura en el Instituto Nacional de Estad\u00edsticas (INE) en 2013, el a\u00f1o en que fue electo Maduro\u00bb.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan escribe el portal www.descifrado.com \u00abEn los seis a\u00f1os del Gobierno del presidente Nicol\u00e1s Maduro, los venezolanos sufrieron los efectos agresivos de la hiperinflaci\u00f3n y la desaparici\u00f3n de alimentos y medicinas de primera necesidad&#46;&#46;&#46;<\/p>\n","protected":false},"author":4,"featured_media":4400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La hambruna se apoder\u00f3 de toda Venezuela en este a\u00f1o 2018 - Venezuela | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La hambruna se apoder\u00f3 de toda Venezuela en este a\u00f1o 2018\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan escribe el portal www.descifrado.com \u00abEn los seis a\u00f1os del Gobierno del presidente Nicol\u00e1s Maduro, los venezolanos sufrieron los efectos agresivos de la hiperinflaci\u00f3n y la desaparici\u00f3n de alimentos y medicinas de primera necesidad&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Venezuela | Noti-America.com\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/AndresSalazarTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-31T10:21:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2018\/12\/13-mm-de-nuevos-pobres-deja-gobierno-de-maduro-01-201812311052255225.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andr\u00e9s Salazar TV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andr\u00e9s Salazar TV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/\"},\"author\":{\"name\":\"Andr\u00e9s Salazar TV\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/cc0141a67206eb21d64442147832e47f\"},\"headline\":\"La hambruna se apoder\u00f3 de toda Venezuela en este a\u00f1o 2018\",\"datePublished\":\"2018-12-31T10:21:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/\"},\"wordCount\":113,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2018\/12\/13-mm-de-nuevos-pobres-deja-gobierno-de-maduro-01-201812311052255225.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/\",\"name\":\"La hambruna se apoder\u00f3 de toda Venezuela en este a\u00f1o 2018 - Venezuela | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2018\/12\/13-mm-de-nuevos-pobres-deja-gobierno-de-maduro-01-201812311052255225.jpg\",\"datePublished\":\"2018-12-31T10:21:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2018\/12\/13-mm-de-nuevos-pobres-deja-gobierno-de-maduro-01-201812311052255225.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2018\/12\/13-mm-de-nuevos-pobres-deja-gobierno-de-maduro-01-201812311052255225.jpg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/venezuela\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La hambruna se apoder\u00f3 de toda Venezuela en este a\u00f1o 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/\",\"name\":\"Venezuela | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/venezuela\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\",\"name\":\"Noti-America LLC | Venezuela\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Venezuela\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/cc0141a67206eb21d64442147832e47f\",\"name\":\"Andr\u00e9s Salazar TV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/afe6826ba750395b641021d9bf08e5496b9d29671cfabb16346350901fb94310?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/afe6826ba750395b641021d9bf08e5496b9d29671cfabb16346350901fb94310?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/afe6826ba750395b641021d9bf08e5496b9d29671cfabb16346350901fb94310?s=96&d=mm&r=g\",\"caption\":\"Andr\u00e9s Salazar TV\"},\"description\":\"Andr\u00e9s Salazar. Corresponsal de Noti-Am\u00e9rica en Venezuela. Periodista con m\u00e1s de 14 a\u00f1os de trayectoria en la cobertura de hechos informativos. Amplia experiencia en la narrativa de eventos deportivos, musicales y sucesos de \u00faltima hora.\",\"sameAs\":[\"https:\/\/www.facebook.com\/AndresSalazarTV\/\",\"https:\/\/youtube.com\/@andressalazartv?si=fYrt2l__ee2OK_Fh\"],\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/author\/asalazar\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La hambruna se apoder\u00f3 de toda Venezuela en este a\u00f1o 2018 - Venezuela | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/","og_locale":"es_ES","og_type":"article","og_title":"La hambruna se apoder\u00f3 de toda Venezuela en este a\u00f1o 2018","og_description":"Seg\u00fan escribe el portal www.descifrado.com \u00abEn los seis a\u00f1os del Gobierno del presidente Nicol\u00e1s Maduro, los venezolanos sufrieron los efectos agresivos de la hiperinflaci\u00f3n y la desaparici\u00f3n de alimentos y medicinas de primera necesidad&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/","og_site_name":"Venezuela | Noti-America.com","article_author":"https:\/\/www.facebook.com\/AndresSalazarTV\/","article_published_time":"2018-12-31T10:21:32+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2018\/12\/13-mm-de-nuevos-pobres-deja-gobierno-de-maduro-01-201812311052255225.jpg","type":"image\/jpeg"}],"author":"Andr\u00e9s Salazar TV","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andr\u00e9s Salazar TV","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/"},"author":{"name":"Andr\u00e9s Salazar TV","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/cc0141a67206eb21d64442147832e47f"},"headline":"La hambruna se apoder\u00f3 de toda Venezuela en este a\u00f1o 2018","datePublished":"2018-12-31T10:21:32+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/"},"wordCount":113,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2018\/12\/13-mm-de-nuevos-pobres-deja-gobierno-de-maduro-01-201812311052255225.jpg","articleSection":["Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/","url":"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/","name":"La hambruna se apoder\u00f3 de toda Venezuela en este a\u00f1o 2018 - Venezuela | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2018\/12\/13-mm-de-nuevos-pobres-deja-gobierno-de-maduro-01-201812311052255225.jpg","datePublished":"2018-12-31T10:21:32+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#primaryimage","url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2018\/12\/13-mm-de-nuevos-pobres-deja-gobierno-de-maduro-01-201812311052255225.jpg","contentUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2018\/12\/13-mm-de-nuevos-pobres-deja-gobierno-de-maduro-01-201812311052255225.jpg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/venezuela\/2018\/12\/31\/la-hambruna-se-apodero-de-toda-venezuela-en-este-ano-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/venezuela\/"},{"@type":"ListItem","position":2,"name":"La hambruna se apoder\u00f3 de toda Venezuela en este a\u00f1o 2018"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/venezuela\/#website","url":"https:\/\/noti-america.com\/site\/venezuela\/","name":"Venezuela | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization","name":"Noti-America LLC | Venezuela","url":"https:\/\/noti-america.com\/site\/venezuela\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Venezuela"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/cc0141a67206eb21d64442147832e47f","name":"Andr\u00e9s Salazar TV","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/afe6826ba750395b641021d9bf08e5496b9d29671cfabb16346350901fb94310?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/afe6826ba750395b641021d9bf08e5496b9d29671cfabb16346350901fb94310?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/afe6826ba750395b641021d9bf08e5496b9d29671cfabb16346350901fb94310?s=96&d=mm&r=g","caption":"Andr\u00e9s Salazar TV"},"description":"Andr\u00e9s Salazar. Corresponsal de Noti-Am\u00e9rica en Venezuela. Periodista con m\u00e1s de 14 a\u00f1os de trayectoria en la cobertura de hechos informativos. Amplia experiencia en la narrativa de eventos deportivos, musicales y sucesos de \u00faltima hora.","sameAs":["https:\/\/www.facebook.com\/AndresSalazarTV\/","https:\/\/youtube.com\/@andressalazartv?si=fYrt2l__ee2OK_Fh"],"url":"https:\/\/noti-america.com\/site\/venezuela\/author\/asalazar\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts\/4399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/comments?post=4399"}],"version-history":[{"count":0,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts\/4399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/media\/4400"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/media?parent=4399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/categories?post=4399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/tags?post=4399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}