{"id":27423,"date":"2023-05-05T22:20:59","date_gmt":"2023-05-05T22:20:59","guid":{"rendered":"https:\/\/noti-america.com\/site\/venezuela\/?p=27423"},"modified":"2023-05-07T04:54:56","modified_gmt":"2023-05-07T04:54:56","slug":"alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/","title":{"rendered":"Alcald\u00eda de Lagunillas realiz\u00f3 jornada de salud en el sector La Pica Pica"},"content":{"rendered":"\r\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-27447 aligncenter\" src=\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0031-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0031-300x169.jpg 300w, https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0031-1024x576.jpg 1024w, https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0031-768x432.jpg 768w, https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0031-600x338.jpg 600w, https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0031.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/><strong>La atenci\u00f3n social a los sectores m\u00e1s necesitados del municipio Lagunillas, es prioridad en la gesti\u00f3n del alcalde Jos\u00e9 Mosquera, es por esto que el burgomaestre, junto a la primera dama, Margarita de Mosquera, y todo el equipo de la Alcald\u00eda de Lagunillas, realizaron este s\u00e1bado 6 de mayo, una jornada de salud en el sector La Pica Pica, kil\u00f3metro 26, parroquia Eleazar L\u00f3pez Contreras, que tambi\u00e9n cont\u00f3 con la presencia del concejal Carlosman Leal<\/strong>.<\/p>\r\n<p style=\"text-align: justify\"><br \/><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-27448 aligncenter\" src=\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0033-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0033-300x169.jpg 300w, https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0033-1024x576.jpg 1024w, https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0033-768x432.jpg 768w, https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0033-600x338.jpg 600w, https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0033.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>El punto de encuentro para que alrededor de cien personas, entre ni\u00f1os, adultos y adultos mayores, fueran atendidos con medicina general, pediatr\u00eda, despistaje de hipertensi\u00f3n arterial, peluquer\u00eda, pintacaritas y entrega de medicamentos, fue la cancha de usos m\u00faltiples del sector, donde se despleg\u00f3 el personal de Desarrollo Social y Humano, encabezado por su directora Yuleima de Vel\u00e1squez y el equipo de la Direcci\u00f3n Municipal de Salud, a cargo del doctor Williams Sandrea.<\/p>\r\n<p style=\"text-align: justify\"><br \/><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-27449 aligncenter\" src=\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0034-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0034-300x169.jpg 300w, https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0034-1024x576.jpg 1024w, https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0034-768x432.jpg 768w, https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0034-600x338.jpg 600w, https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0034.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/><em>\u00abHoy hicimos una jornada en esta zona que est\u00e1 bastante retirada de la ciudad, porque nosotros abarcamos todo el municipio y lo principal son las comunidades. Adem\u00e1s de la atenci\u00f3n en salud, entregamos implementos deportivos a los j\u00f3venes del sector para que sigan ejercit\u00e1ndose\u00bb, dijo Mosquera.<\/em><\/p>\r\n<p style=\"text-align: justify\"><em>Por su parte, la primera dama, Margarita de Mosquera, hizo entrega de una andadera y asegur\u00f3 \u00abseguiremos atendiendo las necesidades de nuestra gente. Tenemos un gran equipo dispuesto a tenderle la mano a su pueblo\u00bb.<\/em> <br \/><br \/><strong>Fuente: Nota de Prensa<\/strong><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>La atenci\u00f3n social a los sectores m\u00e1s necesitados del municipio Lagunillas, es prioridad en la gesti\u00f3n del alcalde Jos\u00e9 Mosquera, es por esto que el burgomaestre, junto a la primera dama, Margarita de Mosquera,&#46;&#46;&#46;<\/p>\n","protected":false},"author":40,"featured_media":27450,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[164,166,156],"tags":[221,917],"class_list":["post-27423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidades","category-salud","category-venezuela","tag-ciudad-ojeda","tag-universidad-del-zulia"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Alcald\u00eda de Lagunillas realiz\u00f3 jornada de salud en el sector La Pica Pica - Venezuela | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alcald\u00eda de Lagunillas realiz\u00f3 jornada de salud en el sector La Pica Pica\" \/>\n<meta property=\"og:description\" content=\"La atenci\u00f3n social a los sectores m\u00e1s necesitados del municipio Lagunillas, es prioridad en la gesti\u00f3n del alcalde Jos\u00e9 Mosquera, es por esto que el burgomaestre, junto a la primera dama, Margarita de Mosquera,&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/\" \/>\n<meta property=\"og:site_name\" content=\"Venezuela | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-05T22:20:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-07T04:54:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0030.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hendrick Garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hendrick Garcia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/\"},\"author\":{\"name\":\"Hendrick Garcia\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/2f37ed06a1cd058e8d611b3d42cce678\"},\"headline\":\"Alcald\u00eda de Lagunillas realiz\u00f3 jornada de salud en el sector La Pica Pica\",\"datePublished\":\"2023-05-05T22:20:59+00:00\",\"dateModified\":\"2023-05-07T04:54:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/\"},\"wordCount\":263,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0030.jpg\",\"keywords\":[\"ciudad ojeda\",\"Universidad del Zulia\"],\"articleSection\":[\"Comunidades\",\"Salud\",\"Venezuela\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/\",\"name\":\"Alcald\u00eda de Lagunillas realiz\u00f3 jornada de salud en el sector La Pica Pica - Venezuela | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0030.jpg\",\"datePublished\":\"2023-05-05T22:20:59+00:00\",\"dateModified\":\"2023-05-07T04:54:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0030.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0030.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/venezuela\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alcald\u00eda de Lagunillas realiz\u00f3 jornada de salud en el sector La Pica Pica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/\",\"name\":\"Venezuela | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/venezuela\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\",\"name\":\"Noti-America LLC | Venezuela\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Venezuela\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/2f37ed06a1cd058e8d611b3d42cce678\",\"name\":\"Hendrick Garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/07f13ce868ede7f0937b7abbada276f430e4ed25cfff75dbe7f98f95ac02358c?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/07f13ce868ede7f0937b7abbada276f430e4ed25cfff75dbe7f98f95ac02358c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/07f13ce868ede7f0937b7abbada276f430e4ed25cfff75dbe7f98f95ac02358c?s=96&d=mm&r=g\",\"caption\":\"Hendrick Garcia\"},\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/author\/hegarcia\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alcald\u00eda de Lagunillas realiz\u00f3 jornada de salud en el sector La Pica Pica - Venezuela | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/","og_locale":"es_ES","og_type":"article","og_title":"Alcald\u00eda de Lagunillas realiz\u00f3 jornada de salud en el sector La Pica Pica","og_description":"La atenci\u00f3n social a los sectores m\u00e1s necesitados del municipio Lagunillas, es prioridad en la gesti\u00f3n del alcalde Jos\u00e9 Mosquera, es por esto que el burgomaestre, junto a la primera dama, Margarita de Mosquera,&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/","og_site_name":"Venezuela | Noti-America.com","article_published_time":"2023-05-05T22:20:59+00:00","article_modified_time":"2023-05-07T04:54:56+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0030.jpg","type":"image\/jpeg"}],"author":"Hendrick Garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Hendrick Garcia","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/"},"author":{"name":"Hendrick Garcia","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/2f37ed06a1cd058e8d611b3d42cce678"},"headline":"Alcald\u00eda de Lagunillas realiz\u00f3 jornada de salud en el sector La Pica Pica","datePublished":"2023-05-05T22:20:59+00:00","dateModified":"2023-05-07T04:54:56+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/"},"wordCount":263,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0030.jpg","keywords":["ciudad ojeda","Universidad del Zulia"],"articleSection":["Comunidades","Salud","Venezuela"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/","url":"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/","name":"Alcald\u00eda de Lagunillas realiz\u00f3 jornada de salud en el sector La Pica Pica - Venezuela | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0030.jpg","datePublished":"2023-05-05T22:20:59+00:00","dateModified":"2023-05-07T04:54:56+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#primaryimage","url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0030.jpg","contentUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG-20230507-WA0030.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/venezuela\/2023\/05\/05\/alcaldia-de-lagunillas-realizo-jornada-de-salud-en-el-sector-la-pica-pica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/venezuela\/"},{"@type":"ListItem","position":2,"name":"Alcald\u00eda de Lagunillas realiz\u00f3 jornada de salud en el sector La Pica Pica"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/venezuela\/#website","url":"https:\/\/noti-america.com\/site\/venezuela\/","name":"Venezuela | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization","name":"Noti-America LLC | Venezuela","url":"https:\/\/noti-america.com\/site\/venezuela\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Venezuela"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/person\/2f37ed06a1cd058e8d611b3d42cce678","name":"Hendrick Garcia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/07f13ce868ede7f0937b7abbada276f430e4ed25cfff75dbe7f98f95ac02358c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/07f13ce868ede7f0937b7abbada276f430e4ed25cfff75dbe7f98f95ac02358c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/07f13ce868ede7f0937b7abbada276f430e4ed25cfff75dbe7f98f95ac02358c?s=96&d=mm&r=g","caption":"Hendrick Garcia"},"url":"https:\/\/noti-america.com\/site\/venezuela\/author\/hegarcia\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts\/27423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/comments?post=27423"}],"version-history":[{"count":2,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts\/27423\/revisions"}],"predecessor-version":[{"id":27451,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts\/27423\/revisions\/27451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/media\/27450"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/media?parent=27423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/categories?post=27423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/tags?post=27423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}