{"id":394,"count":532,"description":"","link":"https:\/\/noti-america.com\/site\/venezuela\/category\/deportes\/futbol-internacional\/","name":"Futbol Internacional","slug":"futbol-internacional","taxonomy":"category","parent":16,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Futbol Internacional archivos - Venezuela | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/venezuela\/category\/deportes\/futbol-internacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Futbol Internacional archivos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/venezuela\/category\/deportes\/futbol-internacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Venezuela | Noti-America.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/category\/deportes\/futbol-internacional\/\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/category\/deportes\/futbol-internacional\/\",\"name\":\"Futbol Internacional archivos - Venezuela | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/category\/deportes\/futbol-internacional\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/category\/deportes\/futbol-internacional\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/venezuela\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\/\/noti-america.com\/site\/venezuela\/category\/deportes\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Futbol Internacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/\",\"name\":\"Venezuela | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/venezuela\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#organization\",\"name\":\"Noti-America LLC | Venezuela\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Venezuela\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Futbol Internacional archivos - Venezuela | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/venezuela\/category\/deportes\/futbol-internacional\/","og_locale":"es_ES","og_type":"article","og_title":"Futbol Internacional archivos","og_url":"https:\/\/noti-america.com\/site\/venezuela\/category\/deportes\/futbol-internacional\/","og_site_name":"Venezuela | Noti-America.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/noti-america.com\/site\/venezuela\/category\/deportes\/futbol-internacional\/","url":"https:\/\/noti-america.com\/site\/venezuela\/category\/deportes\/futbol-internacional\/","name":"Futbol Internacional archivos - Venezuela | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#website"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/category\/deportes\/futbol-internacional\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/venezuela\/category\/deportes\/futbol-internacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/venezuela\/"},{"@type":"ListItem","position":2,"name":"Deportes","item":"https:\/\/noti-america.com\/site\/venezuela\/category\/deportes\/"},{"@type":"ListItem","position":3,"name":"Futbol Internacional"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/venezuela\/#website","url":"https:\/\/noti-america.com\/site\/venezuela\/","name":"Venezuela | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/venezuela\/#organization","name":"Noti-America LLC | Venezuela","url":"https:\/\/noti-america.com\/site\/venezuela\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/venezuela\/wp-content\/uploads\/sites\/2\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Venezuela"},"image":{"@id":"https:\/\/noti-america.com\/site\/venezuela\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/categories\/394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/categories\/16"}],"wp:post_type":[{"href":"https:\/\/noti-america.com\/site\/venezuela\/wp-json\/wp\/v2\/posts?categories=394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}