{"id":5653,"date":"2018-12-12T03:04:02","date_gmt":"2018-12-12T03:04:02","guid":{"rendered":"http:\/\/noti-america.com\/site\/us-ny\/?p=5653"},"modified":"2018-12-12T03:04:02","modified_gmt":"2018-12-12T03:04:02","slug":"llega-una-nueva-tormenta-invernal-a-eeuu-con-nieve-lluvias-y-heladas","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/us-ny\/2018\/12\/12\/llega-una-nueva-tormenta-invernal-a-eeuu-con-nieve-lluvias-y-heladas\/","title":{"rendered":"\u00a0\u00a0Llega una nueva tormenta invernal a EEUU con nieve, lluvias y heladas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5654 aligncenter\" src=\"http:\/\/noti-america.com\/site\/us-ny\/wp-content\/uploads\/sites\/12\/2018\/12\/gettyimages-940985280-300x200.jpg\" alt=\"\" width=\"650\" height=\"433\" srcset=\"https:\/\/noti-america.com\/site\/us-ny\/wp-content\/uploads\/sites\/12\/2018\/12\/gettyimages-940985280-300x200.jpg 300w, https:\/\/noti-america.com\/site\/us-ny\/wp-content\/uploads\/sites\/12\/2018\/12\/gettyimages-940985280-768x512.jpg 768w, https:\/\/noti-america.com\/site\/us-ny\/wp-content\/uploads\/sites\/12\/2018\/12\/gettyimages-940985280-272x182.jpg 272w, https:\/\/noti-america.com\/site\/us-ny\/wp-content\/uploads\/sites\/12\/2018\/12\/gettyimages-940985280.jpg 940w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Fuente:\u00a0 https:\/\/eldiariony.com<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Seis estados en el Oeste est\u00e1n bajo alertas y advertencias meteorol\u00f3gicas del Servicio Meteorol\u00f3gico Nacional (NWS) porque se\u00a0esperan lluvias m\u00e1s fuertes en el noroeste el martes, y pueden provocar inundaciones repentinas,\u00a0ya que los vientos superan las 50 mph. adem\u00e1s de fuertes nevadas.<\/p>\n<p>&nbsp;<\/p>\n<p>La lluvia y las nevadas en las monta\u00f1as, a veces pesadas, se esperan en el noroeste hasta la madrugada del mi\u00e9rcoles,\u00a0y las nevadas se extender\u00e1n a las Rocosas m\u00e1s tarde el mi\u00e9rcoles.<\/p>\n<p>Se esperan varios pies de nieve en las Cascadas de Washington, y m\u00e1s de un pie de nieve puede cubrir partes de las Monta\u00f1as Rocosas del norte.<\/p>\n<p>El sistema llegar\u00e1 en las llanuras y el medio oeste durante el jueves, antes de avanzar lentamente hacia la costa este durante el viernes y hacia el fin de semana.<\/p>\n<p>Con el aire fr\u00edo limitado al este de las Monta\u00f1as Rocosas en los pr\u00f3ximos d\u00edas, cualquier nieve o hielo de esta pr\u00f3xima tormenta debe ser menor que las nevadas de la tormenta invernal Diego, que produjo fuertes nevadas y heladas en el sur.<\/p>\n<p>A nivel local,\u00a0es probable que haya lluvias fuertes en partes del sur a fines de esta semana.\u00a0Tambi\u00e9n podr\u00eda haber tormentas el\u00e9ctricas severas en algunas partes del sur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Fuente:\u00a0 https:\/\/eldiariony.com &nbsp; Seis estados en el Oeste est\u00e1n bajo alertas y advertencias meteorol\u00f3gicas del Servicio Meteorol\u00f3gico Nacional (NWS) porque se\u00a0esperan lluvias m\u00e1s fuertes en el noroeste el martes, y pueden provocar inundaciones&#46;&#46;&#46;<\/p>\n","protected":false},"author":28,"featured_media":5654,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,31,30],"tags":[601],"class_list":["post-5653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-norteamerica","category-new-york","category-noticias","tag-llega-una-nueva-tormenta-invernal-a-eeuu"],"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/us-ny\/wp-json\/wp\/v2\/posts\/5653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/us-ny\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/us-ny\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/us-ny\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/us-ny\/wp-json\/wp\/v2\/comments?post=5653"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/us-ny\/wp-json\/wp\/v2\/posts\/5653\/revisions"}],"predecessor-version":[{"id":5655,"href":"https:\/\/noti-america.com\/site\/us-ny\/wp-json\/wp\/v2\/posts\/5653\/revisions\/5655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/us-ny\/wp-json\/wp\/v2\/media\/5654"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/us-ny\/wp-json\/wp\/v2\/media?parent=5653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/us-ny\/wp-json\/wp\/v2\/categories?post=5653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/us-ny\/wp-json\/wp\/v2\/tags?post=5653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}