{"id":1308,"date":"2018-03-12T06:11:18","date_gmt":"2018-03-12T11:11:18","guid":{"rendered":"http:\/\/noti-america.com\/site\/us-tx\/?p=1308"},"modified":"2018-03-12T06:11:18","modified_gmt":"2018-03-12T11:11:18","slug":"300-anos-de-la-llegada-de-espana-a-texas-con-canarios","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/","title":{"rendered":"300 a\u00f1os de la llegada de Espa\u00f1a a Texas con canarios"},"content":{"rendered":"<h1><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1309 alignright\" src=\"http:\/\/noti-america.com\/site\/us-tx\/wp-content\/uploads\/sites\/4\/2018\/03\/Texanos_Canarios-1023x575-300x169.jpg\" alt=\"\" width=\"511\" height=\"288\" srcset=\"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2018\/03\/Texanos_Canarios-1023x575-300x169.jpg 300w, https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2018\/03\/Texanos_Canarios-1023x575-768x432.jpg 768w, https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2018\/03\/Texanos_Canarios-1023x575.jpg 1023w\" sizes=\"auto, (max-width: 511px) 100vw, 511px\" \/><\/h1>\n<h4><\/h4>\n<h4><\/h4>\n<h4><\/h4>\n<h4><\/h4>\n<h4 class=\"subtitulo\" style=\"text-align: center\"><strong>San Antonio de Texas conmemora su fundaci\u00f3n en un emocionante homenaje a los isle\u00f1os que la crearon para defender la influencia de Espa\u00f1a en Am\u00e9rica del Norte<\/strong><\/h4>\n<p>&nbsp;<\/p>\n<aside class=\"herramientas\"><label for=\"capa_compartir\"><\/label><\/aside>\n<p>La\u00a0<a href=\"http:\/\/www.abc.es\/espana\/canarias\/abci-triste-estado-fosa-comun-canarios-texas-201707171107_noticia.html\">ciudad estadounidense de San Antonio<\/a>\u00a0ha vivido este fin de semana un emocionante acto de reconocimiento al papel que Espa\u00f1a jug\u00f3 hace 300 a\u00f1os con la presencia de\u00a0<strong>familias prodedentes<\/strong>\u00a0de Canarias y que fundadon el primer espacio urbano de\u00a0<a href=\"http:\/\/www.abc.es\/espana\/canarias\/abci-curioso-origen-canario-vacas-texas-201706200205_noticia.html\">Texas<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Fuente:\u00a0http:\/\/www.abc.es<\/strong><\/em><\/p>\n<p>El\u00a0<strong>nombre de Texas<\/strong>\u00a0se debe a que las tribus americanas originales, los Caddos, llamaba a los espa\u00f1oles \u00abtayshas\u00bb, que en su idioma significaba aliados frente a los Apaches. Los canarios pronunciaban eso como Tejas. Despu\u00e9s se adapt\u00f3 como Texas.<\/p>\n<p>En Texas han odeado banderas de Espa\u00f1a, Francia y M\u00e9xico. Tras indendizarse de M\u00e9xico se hizo rep\u00fablica y en 1845 opt\u00f3 por sumarse a Estados Unidos. En 1850 Texas ingres\u00f3 dinero en el traspaso de Colorado, Kansas, Nuevo M\u00e9xico, Oklahoma y Wyoming al gobierno\u00a0<strong>norteamericano<\/strong>.<\/p>\n<p>Texas tiene alrededor de 400 a\u00f1os de historia. Sus \u00faltimos\u00a0<strong>300 a\u00f1os escritas en espa\u00f1ol<\/strong>. El 9 de marzo de 1731, un grupo de inmigrantes de las islas Canarias fundaron San Antonio de Bexar.<\/p>\n<h3 class=\"ladillo\">Desde Canarias a Texas por Cuba<\/h3>\n<p>El Gobierno de Canarias ha desplegado por el 300 aniversairo a una comitiva que lidera el consejero de Econom\u00eda, Industria, Comercio y Conocimiento del Gobierno de Canarias,\u00a0Pedro Manuel Ortega,\u00a0junto a alcaldes de las dos capitales canarias de provincia y el presidente de Lanzarote, isla de la que era el primer espa\u00f1ol que lleg\u00f3 a San Antonio en 1718.<\/p>\n<p>En la Plaza Principal de San Antonio se ha hecho un\u00a0<strong>homenaje\u00a0<\/strong>titulado \u00abEl Nacimiento\u00bb con m\u00fasica de las islas interpretado porl Quinteto Victor Est\u00e1rico. San Antonio de Texas celebra de esta forma y por todo lo alto la presencia de los\u00a0<strong>pioneros canarios<\/strong>. Adem\u00e1s de m\u00fasica hay encuentros culturales como una exposici\u00f3n y reuniones entre empresarios.<\/p>\n<p>Los isle\u00f1os salieron de Canarias el 27 de marzo de 1730 en un viaje que les llevar\u00eda\u00a0<strong>de Santa Cruz de Tenerife a La Habana<\/strong>, Cuba, y, finalmente, A Veracruz, M\u00e9xico. Tras un largo viaje el 9 de marzo de 1731 llegaron a San Fernando. Por eso se cumplen 300 a\u00f1os.<\/p>\n<h3 class=\"ladillo\">De Lanzarote<\/h3>\n<p>Los canarios organizaron el\u00a0<strong>primer asentamiento<\/strong>\u00a0de manera que, en la d\u00e9cada de 1730, encontraron una forma de vivir juntos, respetar la memoria y las tradiciones. Uno de los primeros en llegar fue<strong>\u00a0Juan Leal Goras<\/strong>, hijo de Antonio Goras y Mar\u00eda P\u00e9rez, natural de la isla de\u00a0<strong>Lanzarote<\/strong>, con 54 a\u00f1os \u00abalto cara larga, espesa barba, tez oscura, nariz afilada, ciego del ojo izquierdo, barba y el pelo negro, ojos color caf\u00e9\u00bb, dice el acta de aquella \u00e9poca.<\/p>\n<p>Han pasado 300 a\u00f1os pero sus descendientes mantienen viva la historia. Mientras que el a\u00f1o\u00a0<strong>1718 se reconoce como la fundaci\u00f3n de San Antonio<\/strong>, no fue hasta 1731 que 16 familias de las islas Canarias llegaron y se establecieron gobierno civil de la ciudad, la primera en Texas.<\/p>\n<aside class=\"despiece\">\n<figure class=\"foto-intercalada\"><span class=\"imagen\"><img loading=\"lazy\" decoding=\"async\" class=\"lzld loaded aligncenter\" src=\"http:\/\/www.abc.es\/media\/espana\/2018\/03\/10\/DX9KnBNUQAAFKg0-kN6D--540x285@abc.jpg\" alt=\"Desciendientas de canarios este fin de semana en San Antonio\" width=\"540\" height=\"285\" \/><\/span><\/figure>\n<h5 class=\"ladillo\" style=\"text-align: center\">Desciendientas de canarios este fin de semana en San Antonio<span class=\"firma\">\u00a0&#8211; COSAIRO<\/span><\/h5>\n<h3><\/h3>\n<h3 class=\"ladillo\" style=\"text-align: left\">Tres siglos<\/h3>\n<p>300 a\u00f1os despu\u00e9s han cosechado una convivencia ejemplar en u<strong>na de las ciudades m\u00e1s importantes de Estados Unidos<\/strong>. Los primeros hombres sin familia en esa ciudad Phelipe P\u00e9rez, Jos\u00e9 Antonio P\u00e9rez, Mart\u00edn Lorenzo de Armas e Ignacio Lorenzo de Armas, todos de\u00a0<strong>Tenerife<\/strong>, desde donde sali\u00f3 el nav\u00edo que les llev\u00f3 a San Antonio.<\/p>\n<p>Adem\u00e1s de establecer el<strong>\u00a0primer gobierno civil en\u00a0<\/strong>la ciudad y en Texas, los isle\u00f1os tambi\u00e9n construyeron la catedral de San Fernando. Cada a\u00f1o, nuevos descendientes de esas 16 familias\u00a0<strong>procedentes de Canarias<\/strong>\u00a0se suman a esta respetada comunidad. Era gente de la\u00a0<strong>d\u00e9cada de 1730<\/strong>\u00a0que encontr\u00f3 una manera de vivir fuera de su tierra, pero siempre con Espa\u00f1a en el coraz\u00f3n.<\/p>\n<\/aside>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Antonio de Texas conmemora su fundaci\u00f3n en un emocionante homenaje a los isle\u00f1os que la crearon para defender la influencia de Espa\u00f1a en Am\u00e9rica del Norte &nbsp; La\u00a0ciudad estadounidense de San Antonio\u00a0ha vivido&#46;&#46;&#46;<\/p>\n","protected":false},"author":30,"featured_media":1309,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>300 a\u00f1os de la llegada de Espa\u00f1a a Texas con canarios - Texas | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"300 a\u00f1os de la llegada de Espa\u00f1a a Texas con canarios\" \/>\n<meta property=\"og:description\" content=\"San Antonio de Texas conmemora su fundaci\u00f3n en un emocionante homenaje a los isle\u00f1os que la crearon para defender la influencia de Espa\u00f1a en Am\u00e9rica del Norte &nbsp; La\u00a0ciudad estadounidense de San Antonio\u00a0ha vivido&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/\" \/>\n<meta property=\"og:site_name\" content=\"Texas | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-12T11:11:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2018\/03\/Texanos_Canarios-1023x575.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1023\" \/>\n\t<meta property=\"og:image:height\" content=\"575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n NA-TX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n NA-TX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/\"},\"author\":{\"name\":\"Redacci\u00f3n NA-TX\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#\/schema\/person\/3ff56dd7f390fce962da2b3c4a562392\"},\"headline\":\"300 a\u00f1os de la llegada de Espa\u00f1a a Texas con canarios\",\"datePublished\":\"2018-03-12T11:11:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/\"},\"wordCount\":667,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2018\/03\/Texanos_Canarios-1023x575.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/\",\"url\":\"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/\",\"name\":\"300 a\u00f1os de la llegada de Espa\u00f1a a Texas con canarios - Texas | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2018\/03\/Texanos_Canarios-1023x575.jpg\",\"datePublished\":\"2018-03-12T11:11:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2018\/03\/Texanos_Canarios-1023x575.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2018\/03\/Texanos_Canarios-1023x575.jpg\",\"width\":1023,\"height\":575},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/texas\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"300 a\u00f1os de la llegada de Espa\u00f1a a Texas con canarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/texas\/\",\"name\":\"Texas | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/texas\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#organization\",\"name\":\"Noti-America LLC | Texas-USA\",\"url\":\"https:\/\/noti-america.com\/site\/texas\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/us-tx\/wp-content\/uploads\/sites\/4\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/us-tx\/wp-content\/uploads\/sites\/4\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Texas-USA\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#\/schema\/person\/3ff56dd7f390fce962da2b3c4a562392\",\"name\":\"Redacci\u00f3n NA-TX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/1ede8345cc79df032062efa286d5b99b0e4e5bd13e51f7cb031f715a3a43b386?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ede8345cc79df032062efa286d5b99b0e4e5bd13e51f7cb031f715a3a43b386?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ede8345cc79df032062efa286d5b99b0e4e5bd13e51f7cb031f715a3a43b386?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n NA-TX\"},\"url\":\"https:\/\/noti-america.com\/site\/texas\/author\/redacciontx\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"300 a\u00f1os de la llegada de Espa\u00f1a a Texas con canarios - Texas | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/","og_locale":"es_ES","og_type":"article","og_title":"300 a\u00f1os de la llegada de Espa\u00f1a a Texas con canarios","og_description":"San Antonio de Texas conmemora su fundaci\u00f3n en un emocionante homenaje a los isle\u00f1os que la crearon para defender la influencia de Espa\u00f1a en Am\u00e9rica del Norte &nbsp; La\u00a0ciudad estadounidense de San Antonio\u00a0ha vivido&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/","og_site_name":"Texas | Noti-America.com","article_published_time":"2018-03-12T11:11:18+00:00","og_image":[{"width":1023,"height":575,"url":"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2018\/03\/Texanos_Canarios-1023x575.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n NA-TX","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redacci\u00f3n NA-TX","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/"},"author":{"name":"Redacci\u00f3n NA-TX","@id":"https:\/\/noti-america.com\/site\/texas\/#\/schema\/person\/3ff56dd7f390fce962da2b3c4a562392"},"headline":"300 a\u00f1os de la llegada de Espa\u00f1a a Texas con canarios","datePublished":"2018-03-12T11:11:18+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/"},"wordCount":667,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/texas\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2018\/03\/Texanos_Canarios-1023x575.jpg","articleSection":["Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/","url":"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/","name":"300 a\u00f1os de la llegada de Espa\u00f1a a Texas con canarios - Texas | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/texas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2018\/03\/Texanos_Canarios-1023x575.jpg","datePublished":"2018-03-12T11:11:18+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#primaryimage","url":"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2018\/03\/Texanos_Canarios-1023x575.jpg","contentUrl":"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2018\/03\/Texanos_Canarios-1023x575.jpg","width":1023,"height":575},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/texas\/2018\/03\/12\/300-anos-de-la-llegada-de-espana-a-texas-con-canarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/texas\/"},{"@type":"ListItem","position":2,"name":"300 a\u00f1os de la llegada de Espa\u00f1a a Texas con canarios"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/texas\/#website","url":"https:\/\/noti-america.com\/site\/texas\/","name":"Texas | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/texas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/texas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/texas\/#organization","name":"Noti-America LLC | Texas-USA","url":"https:\/\/noti-america.com\/site\/texas\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/texas\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/us-tx\/wp-content\/uploads\/sites\/4\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/us-tx\/wp-content\/uploads\/sites\/4\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Texas-USA"},"image":{"@id":"https:\/\/noti-america.com\/site\/texas\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/texas\/#\/schema\/person\/3ff56dd7f390fce962da2b3c4a562392","name":"Redacci\u00f3n NA-TX","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1ede8345cc79df032062efa286d5b99b0e4e5bd13e51f7cb031f715a3a43b386?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1ede8345cc79df032062efa286d5b99b0e4e5bd13e51f7cb031f715a3a43b386?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ede8345cc79df032062efa286d5b99b0e4e5bd13e51f7cb031f715a3a43b386?s=96&d=mm&r=g","caption":"Redacci\u00f3n NA-TX"},"url":"https:\/\/noti-america.com\/site\/texas\/author\/redacciontx\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/posts\/1308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/comments?post=1308"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/posts\/1308\/revisions"}],"predecessor-version":[{"id":1310,"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/posts\/1308\/revisions\/1310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/media\/1309"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/media?parent=1308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/categories?post=1308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/tags?post=1308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}