{"id":11403,"date":"2019-02-08T12:02:41","date_gmt":"2019-02-08T17:02:41","guid":{"rendered":"http:\/\/noti-america.com\/site\/us-tx\/?p=11403"},"modified":"2019-02-08T07:02:44","modified_gmt":"2019-02-08T12:02:44","slug":"la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/","title":{"rendered":"La ayuda humanitaria llega a Venezuela pero Maduro no abre las puertas"},"content":{"rendered":"<h2 style=\"text-align: center;\"><span style=\"color: #000000;\">\u00a0Los primeros cargamentos con comida y medicamentos esperan en la frontera. <\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #000000;\">El l\u00edder chavista niega que haya una crisis. <\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11404 aligncenter\" src=\"http:\/\/noti-america.com\/site\/us-tx\/wp-content\/uploads\/sites\/4\/2019\/02\/Ayuda-Humanitaria-Vzla-300x184.jpg\" alt=\"\" width=\"685\" height=\"420\" srcset=\"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2019\/02\/Ayuda-Humanitaria-Vzla-300x184.jpg 300w, https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2019\/02\/Ayuda-Humanitaria-Vzla.jpg 768w\" sizes=\"auto, (max-width: 685px) 100vw, 685px\" \/><\/p>\n<h5 style=\"text-align: center;\"><em>El gobierno colombiano inform\u00f3 esta tarde que llegaron a C\u00facuta, ciudad fronteriza con Venezuela, los primeros camiones con la asistencia humanitaria que pidi\u00f3 el presidente interino Juan Guaid\u00f3. FOTO: AFP<\/em><\/h5>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Fuente:\u00a0https:\/\/www.perfil.com<\/strong><\/em><\/p>\n<hr \/>\n<hr \/>\n<h3><\/h3>\n<h3><em><span style=\"color: #000000;\">Los primeros camiones con ayuda humanitaria para millones de venezolanos llegaron el jueves a la frontera con Colombia, a la espera de que el gobierno de Caracas les permitiera la entrada, una situaci\u00f3n que Estados Unidos no planea forzar. <\/span><\/em><\/h3>\n<p>&nbsp;<\/p>\n<h4><span style=\"color: #000000;\">Al menos siete camiones llegaron al centro de acopio de la ciudad colombiana de C\u00facuta, coordinado por autoridades colombianas y la\u00a0Agencia de los Estados Unidos para el Desarrollo Internacional (USAID), inform\u00f3 la agencia Reuters. Seg\u00fan AFP, una\u00a0decena de veh\u00edculos cargados de provisiones entraron a las en el centro de almacenamiento.\u00a0<\/span><\/h4>\n<h4><span style=\"color: #000000;\"> Un numerosos grupo de venezolanos emigrados a Colombia recibieron con alegr\u00eda la caravana que llevaba la ayuda solicitada por el opositor venezolano Juan Guaid\u00f3 &#8211;reconocido como presidente interino por unos 40 pa\u00edses&#8211; y rechazada por el mandatario Nicol\u00e1s Maduro, quien orden\u00f3 bloquear el puente fronterizo.<\/span><\/h4>\n<h4><span style=\"color: #000000;\"> \u00abLa esperanza est\u00e1 llegando, y bueno, que se abra este rumbo hacia un mejor futuro\u00bb, dijo Francisco Javier Pernea, un migrante venezolano de 44 a\u00f1os, que abandon\u00f3 su pa\u00eds hace seis meses.\u00a0 Venezuela, que est\u00e1 sumergida en la peor crisis de su historia moderna, sufre graves penurias y atraviesa una situaci\u00f3n que ha provocado un \u00e9xodo de unos 2,3 millones de personas desde 2015, seg\u00fan la ONU.<\/span><\/h4>\n<h4><span style=\"color: #000000;\"> Maduro neg\u00f3 rot\u00fandamente que en Venezuela exista una crisis humanitaria, pese al \u00e9xodo de tres millones de personas en los \u00faltimos a\u00f1os, y dice que su gobierno no aceptar\u00e1 \u201climosnas\u201d y menos de la Casa Blanca, a la que acusa de querer derrocarlo y de asfixiar la econom\u00eda con sanciones. <\/span><\/h4>\n<h4><span style=\"color: #000000;\">En tanto, el enviado especial de Washington para Venezuela, Elliott Abrams, dijo el jueves que la asistencia estadounidense seguir\u00e1 llegando a la frontera venezolana con Colombia pero que no forzar\u00e1n su ingreso. La inc\u00f3gnita de los militares En Colombia, la ayuda fue recibida por la estatal Unidad Nacional para la Gesti\u00f3n del Riesgo de Desastres (UNGRD), que indic\u00f3 en un comunicado que simplemente la custodiar\u00e1 y resguardar\u00e1, \u00abcumpliendo con el compromiso del gobierno colombiano en esta operaci\u00f3n humanitaria\u00bb. <\/span><\/h4>\n<h4><span style=\"color: #000000;\">En los \u00abpr\u00f3ximas d\u00edas\u00bb, se asegura que llegar\u00e1n m\u00e1s cargamentos a los que se sumar\u00e1n otros procedentes de Brasil y de una isla caribe\u00f1a por definir, agreg\u00f3 la entidad colombiana. En su pulso con el poder, Guaid\u00f3 insiste en la necesidad de traer alimentos no perecederos y medicamentos a Venezuela.\u00a0<\/span><\/h4>\n<h4><span style=\"color: #000000;\">El mi\u00e9rcoles, inst\u00f3 a las fuerzas armadas a no impedir la llegada de esa ayuda despu\u00e9s de que militares venezolanos bloquearan el puente Tienditas.\u00a0 La forma en la que esos cargamentos llegar\u00e1n a Venezuela y se repartir\u00e1n es un misterio, y la actitud de los militares en este caso le permitir\u00e1 medir a Guaid\u00f3 la unidad del mando de las fuerzas armadas, apoyo tradicional de Maduro, seg\u00fan analistas.\u00a0 <\/span><\/h4>\n<h4><span style=\"color: #000000;\">\u00abLas tropas [venezolanas] se est\u00e1n muriendo de hambre, al igual que su poblaci\u00f3n\u00bb, dijo este jueves el almirante Craig Faller, jefe del comando del ej\u00e9rcito estadounidense encargado de Am\u00e9rica Latina, ante una comisi\u00f3n del Senado en Washington.\u00a0 Las fuerzas armadas de Estados Unidos est\u00e1n preparadas para proteger a su personal e instalaciones diplom\u00e1ticas en Venezuela en caso de que sea necesario, dijo el jueves el almirante Craig Faller,\u00a0a cargo de las fuerzas estadounidenses en Am\u00e9rica del Sur.<\/span><\/h4>\n<h4><span style=\"color: #000000;\"> \u201cEstamos preparados para proteger al personal y las instalaciones diplom\u00e1ticas de Estados Unidos si es necesario\u201d, dijo Faller durante una audiencia en la Comisi\u00f3n de Servicios Armados del Senado. La crisis de Venezuela durante el gobierno del mandatario Nicol\u00e1s Maduro, que hundi\u00f3 al pa\u00eds en la pobreza y llev\u00f3 a unos 3 millones de venezolanos a huir, oblig\u00f3\u00a0\u00a0a naciones de todo el mundo a tomar postura, particularmente despu\u00e9s de que el l\u00edder opositor Juan Guaido se declar\u00f3 presidente interino el mes pasado.<\/span><\/h4>\n<h4><span style=\"color: #000000;\"> Las principales naciones de la Uni\u00f3n Europea se unieron a Estados Unidos, Canad\u00e1 y varios pa\u00edses latinoamericanos en reconocer a Guaid\u00f3, presidente de la Asamblea Nacional, como leg\u00edtimo gobernante interino del pa\u00eds sudamericano. Faller dijo que Venezuela tiene unos 2.000 generales y la mayor\u00eda de ellos son leales a Maduro debido a la riqueza que acumularon a partir del tr\u00e1fico de drogas, los ingresos del petr\u00f3leo y otros negocios. Sin embargo, se\u00f1al\u00f3, los soldados rasos pasan hambre \u201ctal como la poblaci\u00f3n\u201d.<\/span><\/h4>\n<h4><span style=\"color: #000000;\"> \u201cEl gobierno leg\u00edtimo del presidente Guaid\u00f3 ofreci\u00f3 una amnist\u00eda y un lugar para las fuerzas militares, la mayor\u00eda de los cuales podr\u00edamos pensar que ser\u00edan leales a la Constituci\u00f3n, no a un dictador\u201d, se\u00f1al\u00f3 Faller. D.S. (Fuente <a style=\"color: #000000;\" title=\"La ayuda humanitaria llega a Venezuela pero Maduro no abre las puertas | Perfil\" href=\"https:\/\/www.perfil.com\/noticias\/internacional\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-la-deja-entrar.phtml\" target=\"_blank\" rel=\"noopener\">www.perfil.com<\/a>). <\/span><\/h4>\n<h4><span style=\"color: #000000;\">Con inforamaci\u00f3n de:\u00a0\u00a0<a style=\"color: #000000;\" title=\"Consultar por Email\" href=\"mailto:perfilcom@perfil.com\">perfilcom@perfil.com<\/a><\/span><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Los primeros cargamentos con comida y medicamentos esperan en la frontera. El l\u00edder chavista niega que haya una crisis. El gobierno colombiano inform\u00f3 esta tarde que llegaron a C\u00facuta, ciudad fronteriza con Venezuela, los&#46;&#46;&#46;<\/p>\n","protected":false},"author":27,"featured_media":11404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1781,1774,3],"tags":[1818,308,209,76],"class_list":["post-11403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sudamerica","category-noticias","category-politica","tag-ayuda-huamanitaria","tag-colombia","tag-eeuu","tag-venezuela"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La ayuda humanitaria llega a Venezuela pero Maduro no abre las puertas - Texas | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La ayuda humanitaria llega a Venezuela pero Maduro no abre las puertas\" \/>\n<meta property=\"og:description\" content=\"\u00a0Los primeros cargamentos con comida y medicamentos esperan en la frontera. El l\u00edder chavista niega que haya una crisis. El gobierno colombiano inform\u00f3 esta tarde que llegaron a C\u00facuta, ciudad fronteriza con Venezuela, los&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/\" \/>\n<meta property=\"og:site_name\" content=\"Texas | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-08T17:02:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2019\/02\/Ayuda-Humanitaria-Vzla.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n NA-TN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n NA-TN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/\"},\"author\":{\"name\":\"Redacci\u00f3n NA-TN\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#\/schema\/person\/12b5ff6a00eca8e9628255f8c739d9d6\"},\"headline\":\"La ayuda humanitaria llega a Venezuela pero Maduro no abre las puertas\",\"datePublished\":\"2019-02-08T17:02:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/\"},\"wordCount\":864,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2019\/02\/Ayuda-Humanitaria-Vzla.jpg\",\"keywords\":[\"Ayuda Huamanitaria\",\"Colombia\",\"EEUU\",\"Venezuela\"],\"articleSection\":[\"Am\u00e9rica del Sur\",\"Noticias\",\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/\",\"url\":\"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/\",\"name\":\"La ayuda humanitaria llega a Venezuela pero Maduro no abre las puertas - Texas | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2019\/02\/Ayuda-Humanitaria-Vzla.jpg\",\"datePublished\":\"2019-02-08T17:02:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2019\/02\/Ayuda-Humanitaria-Vzla.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2019\/02\/Ayuda-Humanitaria-Vzla.jpg\",\"width\":768,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/texas\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La ayuda humanitaria llega a Venezuela pero Maduro no abre las puertas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/texas\/\",\"name\":\"Texas | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/texas\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#organization\",\"name\":\"Noti-America LLC | Texas-USA\",\"url\":\"https:\/\/noti-america.com\/site\/texas\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/us-tx\/wp-content\/uploads\/sites\/4\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/us-tx\/wp-content\/uploads\/sites\/4\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Texas-USA\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/texas\/#\/schema\/person\/12b5ff6a00eca8e9628255f8c739d9d6\",\"name\":\"Redacci\u00f3n NA-TN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/894ea7549dcb9c4eb89f2bce99ffa6e5ae58287ad75ae3f10fd38a111f9ffb9b?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/894ea7549dcb9c4eb89f2bce99ffa6e5ae58287ad75ae3f10fd38a111f9ffb9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/894ea7549dcb9c4eb89f2bce99ffa6e5ae58287ad75ae3f10fd38a111f9ffb9b?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n NA-TN\"},\"url\":\"https:\/\/noti-america.com\/site\/texas\/author\/redacciontn\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La ayuda humanitaria llega a Venezuela pero Maduro no abre las puertas - Texas | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/","og_locale":"es_ES","og_type":"article","og_title":"La ayuda humanitaria llega a Venezuela pero Maduro no abre las puertas","og_description":"\u00a0Los primeros cargamentos con comida y medicamentos esperan en la frontera. El l\u00edder chavista niega que haya una crisis. El gobierno colombiano inform\u00f3 esta tarde que llegaron a C\u00facuta, ciudad fronteriza con Venezuela, los&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/","og_site_name":"Texas | Noti-America.com","article_published_time":"2019-02-08T17:02:41+00:00","og_image":[{"width":768,"height":470,"url":"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2019\/02\/Ayuda-Humanitaria-Vzla.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n NA-TN","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redacci\u00f3n NA-TN","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/"},"author":{"name":"Redacci\u00f3n NA-TN","@id":"https:\/\/noti-america.com\/site\/texas\/#\/schema\/person\/12b5ff6a00eca8e9628255f8c739d9d6"},"headline":"La ayuda humanitaria llega a Venezuela pero Maduro no abre las puertas","datePublished":"2019-02-08T17:02:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/"},"wordCount":864,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/texas\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2019\/02\/Ayuda-Humanitaria-Vzla.jpg","keywords":["Ayuda Huamanitaria","Colombia","EEUU","Venezuela"],"articleSection":["Am\u00e9rica del Sur","Noticias","Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/","url":"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/","name":"La ayuda humanitaria llega a Venezuela pero Maduro no abre las puertas - Texas | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/texas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2019\/02\/Ayuda-Humanitaria-Vzla.jpg","datePublished":"2019-02-08T17:02:41+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#primaryimage","url":"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2019\/02\/Ayuda-Humanitaria-Vzla.jpg","contentUrl":"https:\/\/noti-america.com\/site\/texas\/wp-content\/uploads\/sites\/4\/2019\/02\/Ayuda-Humanitaria-Vzla.jpg","width":768,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/texas\/2019\/02\/08\/la-ayuda-humanitaria-llega-a-venezuela-pero-maduro-no-abre-las-puertas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/texas\/"},{"@type":"ListItem","position":2,"name":"La ayuda humanitaria llega a Venezuela pero Maduro no abre las puertas"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/texas\/#website","url":"https:\/\/noti-america.com\/site\/texas\/","name":"Texas | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/texas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/texas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/texas\/#organization","name":"Noti-America LLC | Texas-USA","url":"https:\/\/noti-america.com\/site\/texas\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/texas\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/us-tx\/wp-content\/uploads\/sites\/4\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/us-tx\/wp-content\/uploads\/sites\/4\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Texas-USA"},"image":{"@id":"https:\/\/noti-america.com\/site\/texas\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/texas\/#\/schema\/person\/12b5ff6a00eca8e9628255f8c739d9d6","name":"Redacci\u00f3n NA-TN","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/894ea7549dcb9c4eb89f2bce99ffa6e5ae58287ad75ae3f10fd38a111f9ffb9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/894ea7549dcb9c4eb89f2bce99ffa6e5ae58287ad75ae3f10fd38a111f9ffb9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/894ea7549dcb9c4eb89f2bce99ffa6e5ae58287ad75ae3f10fd38a111f9ffb9b?s=96&d=mm&r=g","caption":"Redacci\u00f3n NA-TN"},"url":"https:\/\/noti-america.com\/site\/texas\/author\/redacciontn\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/posts\/11403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/comments?post=11403"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/posts\/11403\/revisions"}],"predecessor-version":[{"id":11405,"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/posts\/11403\/revisions\/11405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/media\/11404"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/media?parent=11403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/categories?post=11403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/texas\/wp-json\/wp\/v2\/tags?post=11403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}