{"id":5811,"date":"2020-11-11T12:18:37","date_gmt":"2020-11-11T12:18:37","guid":{"rendered":"https:\/\/noti-america.com\/site\/repdom\/?p=5811"},"modified":"2020-11-11T12:18:37","modified_gmt":"2020-11-11T12:18:37","slug":"autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/","title":{"rendered":"Autoridades solicitan a la ciudadan\u00eda colaborar con cambios de v\u00eda para viabilizar el tr\u00e1nsito en el Distrito Nacional."},"content":{"rendered":"<p><em>Recuerdan parqueo s\u00f3lo podr\u00e1 ser del lado derecho del sentido de la v\u00eda a partir de este s\u00e1bado. <\/em><\/p>\n<p style=\"text-align: justify\">Santo Domingo, D.N.-El Ayuntamiento del Distrito Nacional conjuntamente con INTRANT, DIGESETT y MOPC pondr\u00e1n en vigencia a partir del pr\u00f3ximo d\u00eda 14 del corriente mes los cambios de v\u00eda en el Pol\u00edgono Central y solicitan el respaldo de la ciudadan\u00eda para viabilizar el tr\u00e1nsito.<\/p>\n<p style=\"text-align: justify\">Durante una rueda de prensa en el Palacio Consistorial con la presencia de la alcaldesa Carolina Mej\u00eda, el Ministro de Obras P\u00fablicas Deligne Ascenci\u00f3n, el Director del INTRANT Rafael Arias y el Director de la DIGESSET Ram\u00f3n Guzm\u00e1n Peralta fue puesto en conocimiento de la prensa nacional el plan de cambio de v\u00edas para el pol\u00edgono central del Distrito Nacional en su primera etapa.<\/p>\n<p style=\"text-align: justify\">Los cambios viales del pol\u00edgono central ampliado comprenden 42 calles dentro del cuadrante de la Avenida M\u00e1ximo G\u00f3mez, la John F. Kennedy, la Gregorio Luper\u00f3n y la 27 de Febrero.<\/p>\n<p style=\"text-align: justify\">Estos cambios ya est\u00e1n en vigencia en el Ensanche Naco, y se han definido dos grandes \u00e1reas para continuar el proceso al este de la Avenida Winston Churchill, con los sectores: Serrall\u00e9s, Piantini, Yolanda Morales y Ensanche Para\u00edso, que favorece la circulaci\u00f3n en las calles Jos\u00e9 Amado Soler, Filomena G\u00f3mez de Cova, Freddy Prestol Castillo, David Ben Guri\u00f3n y Central entre otras.<\/p>\n<p style=\"text-align: justify\">Mientras, que al oeste de la Churchill, impacta sectores como el Evaristo Morales, Los Prados, Los Praditos, Ensanche Quisqueya, Las Praderas y El Mill\u00f3n. En tanto, que las v\u00edas que cambian su sentido de circulaci\u00f3n est\u00e1n: Max Henr\u00edquez Ure\u00f1a, Polibio D\u00edaz, Gustavo Mej\u00eda Ricart, Dr. Defill\u00f3, Teodoro Chasseriau, Biblioteca Nacional, Presa de Bao, Paseo de Los Locutores, Eugenio Deschamps, entre otras.<\/p>\n<p style=\"text-align: justify\">Los cambios viales se producen por una labor conjunta del ADN, INTRANT, DIGESETT, y al que tambi\u00e9n se suma el MOPC, con la colaboraci\u00f3n de la Asociaci\u00f3n de Parqueos y Movilidad, AGEMOV, para reducir los entaponamientos y mejorar la calidad de vida de los ciudadanos en esta \u00e1rea, que es la de mayor uso comercial en la ciudad.<\/p>\n<p style=\"text-align: justify\">Este proceso se implementa en forma gradual de manera informativa, en una primera etapa del lado este de la Avenida Winston Churchill, para que los residentes y visitantes de la zona est\u00e9n al tanto, junto a la DIGESETT, y un personal de orientaci\u00f3n del INTRANT y la Alcald\u00eda que estar\u00e1n dando las informaciones de lugar, sobre todo de la se\u00f1alizaci\u00f3n horizontal y vertical instalada.<\/p>\n<p style=\"text-align: justify\">Luego que esta \u00e1rea est\u00e9 funcionando a cabalidad, se ejecutar\u00e1 la segunda etapa en la tercera semana de diciembre, al oeste de la Avenida Winston Churchill, la cual contar\u00e1 con la misma asistencia hasta que los usuarios de las v\u00edas est\u00e9n al tanto de los nuevos patrones de circulaci\u00f3n.<\/p>\n<p style=\"text-align: justify\">Tambi\u00e9n se estar\u00e1n modificando y adecuando nuevos planes de tiempo de los sem\u00e1foros, desde la nueva sala del Centro de Control de Tr\u00e1fico, para gestionar la movilidad en esta \u00e1rea. Se estar\u00e1n notificando las rutas en las aplicaciones de movilidad en tiempo real como waze, google maps, entre otras.<\/p>\n<p style=\"text-align: justify\">Con estas medidas, las entidades que trabaja en los cambios tratan de mejorar la eficiencia de las v\u00edas, que como parte de las acciones del plan de movilidad urbano que se est\u00e1 implementando, y que se reflejar\u00e1 en una reducci\u00f3n de m\u00e1s de un 30% de las demoras, ahorro de un 5% de combustible y m\u00e1s de 60% de emisiones de CO2eq en algunas de las v\u00edas, contribuyendo a una mejor calidad del aire, as\u00ed como la reducci\u00f3n de accidentes por la disminuci\u00f3n de conflictos en algunos cruces.<\/p>\n<p style=\"text-align: justify\"><strong>Direcci\u00f3n de Comunicaciones ADN<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recuerdan parqueo s\u00f3lo podr\u00e1 ser del lado derecho del sentido de la v\u00eda a partir de este s\u00e1bado. Santo Domingo, D.N.-El Ayuntamiento del Distrito Nacional conjuntamente con INTRANT, DIGESETT y MOPC pondr\u00e1n en vigencia&#46;&#46;&#46;<\/p>\n","protected":false},"author":99,"featured_media":5812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10],"tags":[],"class_list":["post-5811","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-actualidad","post_format-post-format-gallery"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Autoridades solicitan a la ciudadan\u00eda colaborar con cambios de v\u00eda para viabilizar el tr\u00e1nsito en el Distrito Nacional. - Rep. Dominicana | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autoridades solicitan a la ciudadan\u00eda colaborar con cambios de v\u00eda para viabilizar el tr\u00e1nsito en el Distrito Nacional.\" \/>\n<meta property=\"og:description\" content=\"Recuerdan parqueo s\u00f3lo podr\u00e1 ser del lado derecho del sentido de la v\u00eda a partir de este s\u00e1bado. Santo Domingo, D.N.-El Ayuntamiento del Distrito Nacional conjuntamente con INTRANT, DIGESETT y MOPC pondr\u00e1n en vigencia&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Rep. Dominicana | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-11T12:18:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/11\/WhatsApp-Image-2020-11-10-at-11.35.42-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ann\u00e9 Cruz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ann\u00e9 Cruz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/\"},\"author\":{\"name\":\"Ann\u00e9 Cruz\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/01b6a5fcca2b30bc220da2842f0b6060\"},\"headline\":\"Autoridades solicitan a la ciudadan\u00eda colaborar con cambios de v\u00eda para viabilizar el tr\u00e1nsito en el Distrito Nacional.\",\"datePublished\":\"2020-11-11T12:18:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/\"},\"wordCount\":669,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/11\/WhatsApp-Image-2020-11-10-at-11.35.42-PM.jpeg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/\",\"name\":\"Autoridades solicitan a la ciudadan\u00eda colaborar con cambios de v\u00eda para viabilizar el tr\u00e1nsito en el Distrito Nacional. - Rep. Dominicana | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/11\/WhatsApp-Image-2020-11-10-at-11.35.42-PM.jpeg\",\"datePublished\":\"2020-11-11T12:18:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/11\/WhatsApp-Image-2020-11-10-at-11.35.42-PM.jpeg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/11\/WhatsApp-Image-2020-11-10-at-11.35.42-PM.jpeg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/repdom\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autoridades solicitan a la ciudadan\u00eda colaborar con cambios de v\u00eda para viabilizar el tr\u00e1nsito en el Distrito Nacional.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"name\":\"Rep. Dominicana | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\",\"name\":\"Noti-America LLC | Rep\u00fablica Dominicana\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Rep\u00fablica Dominicana\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/01b6a5fcca2b30bc220da2842f0b6060\",\"name\":\"Ann\u00e9 Cruz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/f5aaeb3fd16b65f7d601dd99d7f1dcaaf7065ea361b219976bcf5d43d0980e1b?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f5aaeb3fd16b65f7d601dd99d7f1dcaaf7065ea361b219976bcf5d43d0980e1b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f5aaeb3fd16b65f7d601dd99d7f1dcaaf7065ea361b219976bcf5d43d0980e1b?s=96&d=mm&r=g\",\"caption\":\"Ann\u00e9 Cruz\"},\"description\":\"Emprendedora, publirrelacionista y periodista especializada en Comunicaci\u00f3n Pol\u00edtica e Institucional.\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/author\/adelacruz\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Autoridades solicitan a la ciudadan\u00eda colaborar con cambios de v\u00eda para viabilizar el tr\u00e1nsito en el Distrito Nacional. - Rep. Dominicana | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/","og_locale":"es_ES","og_type":"article","og_title":"Autoridades solicitan a la ciudadan\u00eda colaborar con cambios de v\u00eda para viabilizar el tr\u00e1nsito en el Distrito Nacional.","og_description":"Recuerdan parqueo s\u00f3lo podr\u00e1 ser del lado derecho del sentido de la v\u00eda a partir de este s\u00e1bado. Santo Domingo, D.N.-El Ayuntamiento del Distrito Nacional conjuntamente con INTRANT, DIGESETT y MOPC pondr\u00e1n en vigencia&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/","og_site_name":"Rep. Dominicana | Noti-America.com","article_published_time":"2020-11-11T12:18:37+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/11\/WhatsApp-Image-2020-11-10-at-11.35.42-PM.jpeg","type":"image\/jpeg"}],"author":"Ann\u00e9 Cruz","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ann\u00e9 Cruz","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/"},"author":{"name":"Ann\u00e9 Cruz","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/01b6a5fcca2b30bc220da2842f0b6060"},"headline":"Autoridades solicitan a la ciudadan\u00eda colaborar con cambios de v\u00eda para viabilizar el tr\u00e1nsito en el Distrito Nacional.","datePublished":"2020-11-11T12:18:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/"},"wordCount":669,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/11\/WhatsApp-Image-2020-11-10-at-11.35.42-PM.jpeg","articleSection":["Actualidad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/","url":"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/","name":"Autoridades solicitan a la ciudadan\u00eda colaborar con cambios de v\u00eda para viabilizar el tr\u00e1nsito en el Distrito Nacional. - Rep. Dominicana | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/11\/WhatsApp-Image-2020-11-10-at-11.35.42-PM.jpeg","datePublished":"2020-11-11T12:18:37+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#primaryimage","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/11\/WhatsApp-Image-2020-11-10-at-11.35.42-PM.jpeg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/11\/WhatsApp-Image-2020-11-10-at-11.35.42-PM.jpeg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/repdom\/2020\/11\/11\/autoridades-solicitan-a-la-ciudadania-colaborar-con-cambios-de-via-para-viabilizar-el-transito-en-el-distrito-nacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/repdom\/"},{"@type":"ListItem","position":2,"name":"Autoridades solicitan a la ciudadan\u00eda colaborar con cambios de v\u00eda para viabilizar el tr\u00e1nsito en el Distrito Nacional."}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/repdom\/#website","url":"https:\/\/noti-america.com\/site\/repdom\/","name":"Rep. Dominicana | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/repdom\/#organization","name":"Noti-America LLC | Rep\u00fablica Dominicana","url":"https:\/\/noti-america.com\/site\/repdom\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Rep\u00fablica Dominicana"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/01b6a5fcca2b30bc220da2842f0b6060","name":"Ann\u00e9 Cruz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f5aaeb3fd16b65f7d601dd99d7f1dcaaf7065ea361b219976bcf5d43d0980e1b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f5aaeb3fd16b65f7d601dd99d7f1dcaaf7065ea361b219976bcf5d43d0980e1b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5aaeb3fd16b65f7d601dd99d7f1dcaaf7065ea361b219976bcf5d43d0980e1b?s=96&d=mm&r=g","caption":"Ann\u00e9 Cruz"},"description":"Emprendedora, publirrelacionista y periodista especializada en Comunicaci\u00f3n Pol\u00edtica e Institucional.","url":"https:\/\/noti-america.com\/site\/repdom\/author\/adelacruz\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/5811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/comments?post=5811"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/5811\/revisions"}],"predecessor-version":[{"id":5813,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/5811\/revisions\/5813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media\/5812"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media?parent=5811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/categories?post=5811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/tags?post=5811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}