{"id":31115,"date":"2024-12-20T12:58:37","date_gmt":"2024-12-20T12:58:37","guid":{"rendered":"https:\/\/noti-america.com\/site\/repdom\/?p=31115"},"modified":"2024-12-20T12:58:37","modified_gmt":"2024-12-20T12:58:37","slug":"aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/","title":{"rendered":"\u00c1guilas avanzan al Round Robin al vencer a las Estrellas"},"content":{"rendered":"<p>NOTI-AMERICA.COM <em>|\u00a0<\/em>REP\u00daBLICA DOMINICANA<\/p>\n<p style=\"text-align: justify\">SAN PEDRO DE MACOR\u00cdS &#8211; Juan Lagares lleg\u00f3 a la caja de bateo con la pizarra del s\u00e9ptimo acto empatada a cuatro, y en conteo de 3-2 se visti\u00f3 de h\u00e9roe tras pegar un sencillo que trajo al plato a JC Escarra y las \u00c1guilas Cibae\u00f1as anoche se clasificaron oficialmente al round robin serie semifinal en la Liga Dominicana de B\u00e9isbol tras vencer 8-6 a las Estrellas de Oriente, en un emocionante encuentro celebrado la noche de este jueves en el Estadio Tetelo Vargas.<\/p>\n<p style=\"text-align: justify\">El constancero Lagares, que en el juego anterior hab\u00eda conectado cuadrangular con las bases llenas para ser clave en el triunfo amarillo, peg\u00f3 el hit de oro contra el relevista Rom\u00e1n M\u00e9ndez, que en la misma entrada permiti\u00f3 un jonr\u00f3n de tres carrreras a Andretty Cordero, que fue factor importante para que los aguiluchos se convirtieran en el segundo equipo con pase asegurado a la segunda fase del evento.<\/p>\n<p style=\"text-align: justify\">Con el triunfo, las \u00c1guilas lograron su clasificaci\u00f3n n\u00famero 60 a la postemporada en un total de 71 campeonatos, siendo esta la cifra m\u00e1xima para cualquier equipo de LIDOM.<\/p>\n<p style=\"text-align: justify\">El triunfo mantuvo a los aguiluchos en el segundo puesto del torneo en su tramo regular con registro de 26-20, \u00a0a un juego de distancia de la primera posici\u00f3n ocupada por el conjunto oriental (27-19), primer clasificado a la siguiente estancia.<\/p>\n<p style=\"text-align: justify\">Luego de la victoria, las \u00c1guilas dominan 5-4 la serie particular contra las Estrellas.<\/p>\n<p style=\"text-align: justify\">El dirigente aguilucho, Y Molina, clasific\u00f3 con marca personal de 24-13, luego de tomar el equipo con un 2-7.<\/p>\n<p style=\"text-align: justify\">La victoria fue para Jhan Mari\u00f1ez (5-1) con una entrada y dos tercios en blanco, mientras la derrota fue para Ger\u00f3nimo Franzu\u00e1 (2-1) que toler\u00f3 dos carreras en un tercio de entrada.<\/p>\n<p style=\"text-align: justify\">Por las \u00c1guilas abri\u00f3 Jos\u00e9 Ure\u00f1a y se fue con faena de 2.1 entradas de cuatro carreras inmerecidas, tres hits, un boleto y dos ponches. El relevo fue de: Williams Jer\u00e9z (0.2), Dinelson Lamet (1.1), Jhan Mar\u00ed\u00f1ez (1.2) y Yoan L\u00f3pez (1.0) lanzaron en blanco; Jonathan Hern\u00e1ndez (0.1) permiti\u00f3 dos carreras y Richard Rodr\u00edguez se anot\u00f3 salvamento (2) de cinco outs.<\/p>\n<p style=\"text-align: justify\">Por los orientales inici\u00f3 Jorge Mart\u00ednez y tuvo actuaci\u00f3n de tres actos y un tercio de tres carreras, dos inmerecidas, cinco hits, no dio boleto y ponch\u00f3 dos. Luego lanzaron: Jos\u00e9 Fern\u00e1ndez (0.2) y Abdiel Mendoza (2.0) tiraron en blanco; Ger\u00f3nimo Franzu\u00e1 (0.1) permiti\u00f3 dos carreras; Rom\u00e1n M\u00e9ndez no sac\u00f3 out y toler\u00f3 tres vueltas; Spencer Patton (0.2) y Raffi Vizca\u00edno (1.0), no permitieron libertades.<\/p>\n<p style=\"text-align: justify\">Las \u00c1guilas conectaron 14 hits contra nueve de las Estrellas.<\/p>\n<p style=\"text-align: justify\">Por los cibae\u00f1os, Escarra de 4-3, un doble y una impulsada; Andretty Cordero de 1-1 con un jonr\u00f3n y tres empujadas; Jonathan Villar de 5-2; Ezequiel Dur\u00e1n de 3-1, una impulsada; Juan Lagares de 4-1, una empujada; Alexander Canario de 4-2, dos dobles; Cesar Prieto y Alfredo Reyes, un sencillo cada uno.<\/p>\n<p style=\"text-align: justify\">Las Estrellas tuvieron a M Sierra de 4-3; Vidal Bruj\u00e1n de 4-1 y un remolque; Robinson Can\u00f3 de 3-1 y dos impulsadas; Carlos Mart\u00ednez de 4-2 y Rodolfo Castro de 3-1.<\/p>\n<p style=\"text-align: justify\"><span data-olk-copy-source=\"MessageBody\">Las \u00c1guilas enfrentar\u00e1n esta noche a las Estrellas de Oriente en el Estadio Cibao en partido programado para iniciar a las 7:30 PM.<\/span><\/p>\n<p style=\"text-align: justify\"><strong>Fuente: Prensa \u00c1guilas Cibae\u00f1as<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA.COM |\u00a0REP\u00daBLICA DOMINICANA SAN PEDRO DE MACOR\u00cdS &#8211; Juan Lagares lleg\u00f3 a la caja de bateo con la pizarra del s\u00e9ptimo acto empatada a cuatro, y en conteo de 3-2 se visti\u00f3 de h\u00e9roe&#46;&#46;&#46;<\/p>\n","protected":false},"author":89,"featured_media":31116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1726,16],"tags":[118,119,663,120,122,123],"class_list":["post-31115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beisbol","category-deportes","tag-aguilas-cibaenas","tag-beisbol-dominicano","tag-juan-lagares","tag-lidom","tag-liga-dominicana-de-beisbol-profesional","tag-peloteros-dominicanos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00c1guilas avanzan al Round Robin al vencer a las Estrellas - Rep. Dominicana | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c1guilas avanzan al Round Robin al vencer a las Estrellas\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA.COM |\u00a0REP\u00daBLICA DOMINICANA SAN PEDRO DE MACOR\u00cdS &#8211; Juan Lagares lleg\u00f3 a la caja de bateo con la pizarra del s\u00e9ptimo acto empatada a cuatro, y en conteo de 3-2 se visti\u00f3 de h\u00e9roe&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/\" \/>\n<meta property=\"og:site_name\" content=\"Rep. Dominicana | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-20T12:58:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/Juan-Lagares-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1283\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ad\u00e1n Soriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@adansoriano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ad\u00e1n Soriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/\"},\"author\":{\"name\":\"Ad\u00e1n Soriano\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/22f45b88b9e23bbc9d0d1d2736fd196b\"},\"headline\":\"\u00c1guilas avanzan al Round Robin al vencer a las Estrellas\",\"datePublished\":\"2024-12-20T12:58:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/\"},\"wordCount\":568,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/Juan-Lagares-1.jpg\",\"keywords\":[\"\u00c1guilas Cibae\u00f1as\",\"B\u00e9isbol Dominicano\",\"Juan Lagares\",\"LIDOM\",\"Liga Dominicana de B\u00e9isbol Profesional\",\"Peloteros Dominicanos\"],\"articleSection\":[\"Beisbol\",\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/\",\"name\":\"\u00c1guilas avanzan al Round Robin al vencer a las Estrellas - Rep. Dominicana | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/Juan-Lagares-1.jpg\",\"datePublished\":\"2024-12-20T12:58:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/Juan-Lagares-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/Juan-Lagares-1.jpg\",\"width\":1920,\"height\":1283},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/repdom\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c1guilas avanzan al Round Robin al vencer a las Estrellas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"name\":\"Rep. Dominicana | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\",\"name\":\"Noti-America LLC | Rep\u00fablica Dominicana\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Rep\u00fablica Dominicana\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/22f45b88b9e23bbc9d0d1d2736fd196b\",\"name\":\"Ad\u00e1n Soriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"caption\":\"Ad\u00e1n Soriano\"},\"description\":\"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva\",\"sameAs\":[\"https:\/\/x.com\/adansoriano\"],\"url\":\"https:\/\/noti-america.com\/site\/repdom\/author\/asoriano\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c1guilas avanzan al Round Robin al vencer a las Estrellas - Rep. Dominicana | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/","og_locale":"es_ES","og_type":"article","og_title":"\u00c1guilas avanzan al Round Robin al vencer a las Estrellas","og_description":"NOTI-AMERICA.COM |\u00a0REP\u00daBLICA DOMINICANA SAN PEDRO DE MACOR\u00cdS &#8211; Juan Lagares lleg\u00f3 a la caja de bateo con la pizarra del s\u00e9ptimo acto empatada a cuatro, y en conteo de 3-2 se visti\u00f3 de h\u00e9roe&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/","og_site_name":"Rep. Dominicana | Noti-America.com","article_published_time":"2024-12-20T12:58:37+00:00","og_image":[{"width":1920,"height":1283,"url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/Juan-Lagares-1.jpg","type":"image\/jpeg"}],"author":"Ad\u00e1n Soriano","twitter_card":"summary_large_image","twitter_creator":"@adansoriano","twitter_misc":{"Escrito por":"Ad\u00e1n Soriano","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/"},"author":{"name":"Ad\u00e1n Soriano","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/22f45b88b9e23bbc9d0d1d2736fd196b"},"headline":"\u00c1guilas avanzan al Round Robin al vencer a las Estrellas","datePublished":"2024-12-20T12:58:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/"},"wordCount":568,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/Juan-Lagares-1.jpg","keywords":["\u00c1guilas Cibae\u00f1as","B\u00e9isbol Dominicano","Juan Lagares","LIDOM","Liga Dominicana de B\u00e9isbol Profesional","Peloteros Dominicanos"],"articleSection":["Beisbol","Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/","url":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/","name":"\u00c1guilas avanzan al Round Robin al vencer a las Estrellas - Rep. Dominicana | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/Juan-Lagares-1.jpg","datePublished":"2024-12-20T12:58:37+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#primaryimage","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/Juan-Lagares-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/Juan-Lagares-1.jpg","width":1920,"height":1283},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/20\/aguilas-avanzan-al-round-robin-al-vencer-a-las-estrellas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/repdom\/"},{"@type":"ListItem","position":2,"name":"\u00c1guilas avanzan al Round Robin al vencer a las Estrellas"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/repdom\/#website","url":"https:\/\/noti-america.com\/site\/repdom\/","name":"Rep. Dominicana | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/repdom\/#organization","name":"Noti-America LLC | Rep\u00fablica Dominicana","url":"https:\/\/noti-america.com\/site\/repdom\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Rep\u00fablica Dominicana"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/22f45b88b9e23bbc9d0d1d2736fd196b","name":"Ad\u00e1n Soriano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","caption":"Ad\u00e1n Soriano"},"description":"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva","sameAs":["https:\/\/x.com\/adansoriano"],"url":"https:\/\/noti-america.com\/site\/repdom\/author\/asoriano\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/31115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/comments?post=31115"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/31115\/revisions"}],"predecessor-version":[{"id":31117,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/31115\/revisions\/31117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media\/31116"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media?parent=31115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/categories?post=31115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/tags?post=31115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}