{"id":31046,"date":"2024-12-11T14:41:21","date_gmt":"2024-12-11T14:41:21","guid":{"rendered":"https:\/\/noti-america.com\/site\/repdom\/?p=31046"},"modified":"2024-12-11T14:41:21","modified_gmt":"2024-12-11T14:41:21","slug":"alexander-sosa-lanzo-su-tema-musical-una-misma-fe","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/","title":{"rendered":"Alexander Sosa lanz\u00f3 su tema musical \u201cUna Misma Fe\u201d"},"content":{"rendered":"<p style=\"font-weight: 400;text-align: justify\">El artista Alexander Sosa regres\u00f3 a la escena musical tras una pausa de tres a\u00f1os con el lanzamiento de su inspirador tema \u201cUna Misma Fe\u201d, que est\u00e1 disponible desde el viernes 6 de diciembre en todas las plataformas digitales y YouTube.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">Con su caracter\u00edstico estilo lleno de alegr\u00eda y esperanza, Alexander present\u00f3 una canci\u00f3n que invit\u00f3 a reflexionar sobre la relaci\u00f3n con Dios y a celebrar la unidad en Cristo. <em>\u201cEl lanzamiento de\u00a0Una Misma Fe\u00a0naci\u00f3 de la barrera que las personas muchas veces crean, olvidando que todos debemos seguir al mismo Cristo. Si eliminamos esas divisiones, nos queda lo esencial: una misma fe, un mismo Cristo y una misma forma de comunicarnos con Dios\u201d<\/em>, coment\u00f3 el artista en su momento.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">El videoclip que acompa\u00f1\u00f3 esta canci\u00f3n reflej\u00f3 la uni\u00f3n cristiana, con abrazos, alegr\u00eda y un esp\u00edritu de comunidad que conect\u00f3 con el mensaje central del tema.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">Alexander regres\u00f3 con una renovada propuesta musical. <em>\u201cTen\u00eda un backup de canciones y estaba esperando el tiempo apropiado para lanzarlas. Dios me regal\u00f3 nuevas letras y fue tiempo de explorar la pr\u00e9dica desde otros ritmos que tambi\u00e9n glorifican a nuestro Dios\u201d<\/em>, asegur\u00f3.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">La m\u00fasica de Alexander Sosa ha sido reconocida por su capacidad de transmitir las buenas nuevas de salvaci\u00f3n a trav\u00e9s de sonidos contagiosos y llenos de vida. Su tema,\u00a0<em>Una Misma Fe<\/em>, mostr\u00f3 su compromiso por llevar el mensaje de Cristo de una manera aut\u00e9ntica y llena de gozo.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">Este lanzamiento celebr\u00f3 la unidad en Cristo y reafirm\u00f3 el talento de Alexander para conectar con el p\u00fablico a trav\u00e9s de su m\u00fasica.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-31047 aligncenter\" src=\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-4-300x300.jpeg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-4-300x300.jpeg 300w, https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-4-1024x1024.jpeg 1024w, https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-4-150x150.jpeg 150w, https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-4-768x768.jpeg 768w, https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-4-80x80.jpeg 80w, https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-4-320x320.jpeg 320w, https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-4.jpeg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"font-weight: 400;text-align: justify\"><strong>M\u00e1s sobre el artista<\/strong><\/p>\n<p style=\"font-weight: 400;text-align: justify\">Alexander Sosa, nacido en Cotu\u00ed, Rep\u00fablica Dominicana, es un talentoso cantante conocido por transmitir esperanza y fe a trav\u00e9s de su m\u00fasica. Hijo menor de Ramona Mariano y Severino Sosa, est\u00e1 casado con Raysa Reyes y es padre de cuatro hijos.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">Desde joven, Alexander mostr\u00f3 inter\u00e9s por la m\u00fasica, tomando clases de canto y solfeo en instituciones de Rep\u00fablica Dominicana. En 2006 fue galardonado con el primer lugar del reality show\u00a0<em>Buscando el \u00c9xito<\/em>\u00a0del famoso programa dominicano\u00a0<em>9&#215;9 Roberto<\/em>, transmitido por Color Visi\u00f3n. En 2010, tras su participaci\u00f3n en el\u00a0<em>Reality Internacional Batalla de las Am\u00e9ricas<\/em>, vivi\u00f3 un encuentro transformador con Dios que marc\u00f3 un antes y un despu\u00e9s en su vida y carrera.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">En 2013 lanz\u00f3 su primera producci\u00f3n cristiana,\u00a0<em>Ahora Soy Libre<\/em>, cuyos temas principales,\u00a0<em>Jes\u00fas<\/em>\u00a0y\u00a0<em>Libre<\/em>, tuvieron un impacto significativo en la m\u00fasica cristiana en Rep\u00fablica Dominicana. En 2014 fue reconocido como \u201cRevelaci\u00f3n Masculina del A\u00f1o\u201d por la Asociaci\u00f3n Dominicana de Comunicadores Cristianos (ADOCOC) y la Academia Cristiana de Cronistas de Arte (ACCRA).<\/p>\n<p style=\"font-weight: 400;text-align: justify\">Con \u00e9xitos como\u00a0<em>Caminar\u00e9<\/em>\u00a0en 2016, Alexander continu\u00f3 fortaleciendo su ministerio musical, participando en congresos, campa\u00f1as y eventos que glorifican a Dios. Su m\u00fasica ha reflejado su testimonio personal y su compromiso con transmitir el mensaje de Cristo a trav\u00e9s de ritmos tropicales y letras llenas de esperanza.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">Alexander Sosa es un ejemplo de renovaci\u00f3n y dedicaci\u00f3n, utilizando su talento para impactar vidas y glorificar a Dios.<\/p>\n<p style=\"font-weight: 400\">\n","protected":false},"excerpt":{"rendered":"<p>El artista Alexander Sosa regres\u00f3 a la escena musical tras una pausa de tres a\u00f1os con el lanzamiento de su inspirador tema \u201cUna Misma Fe\u201d, que est\u00e1 disponible desde el viernes 6 de diciembre&#46;&#46;&#46;<\/p>\n","protected":false},"author":150,"featured_media":31048,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[277,8],"tags":[154,406],"class_list":["post-31046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acturalidad","category-arte-y-espectaculos","tag-musica","tag-musica-cristiana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Alexander Sosa lanz\u00f3 su tema musical \u201cUna Misma Fe\u201d - Rep. Dominicana | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alexander Sosa lanz\u00f3 su tema musical \u201cUna Misma Fe\u201d\" \/>\n<meta property=\"og:description\" content=\"El artista Alexander Sosa regres\u00f3 a la escena musical tras una pausa de tres a\u00f1os con el lanzamiento de su inspirador tema \u201cUna Misma Fe\u201d, que est\u00e1 disponible desde el viernes 6 de diciembre&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/\" \/>\n<meta property=\"og:site_name\" content=\"Rep. Dominicana | Noti-America.com\" \/>\n<meta property=\"article:author\" content=\"https:\/\/web.facebook.com\/jennifer.germosenrosario\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-11T14:41:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1227\" \/>\n\t<meta property=\"og:image:height\" content=\"689\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jennifer Germosen Rosario\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GermosenJenn\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jennifer Germosen Rosario\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/\"},\"author\":{\"name\":\"Jennifer Germosen Rosario\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/070e2e8e5b3f97ed51d5361e4ca623f3\"},\"headline\":\"Alexander Sosa lanz\u00f3 su tema musical \u201cUna Misma Fe\u201d\",\"datePublished\":\"2024-12-11T14:41:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/\"},\"wordCount\":546,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-2.jpeg\",\"keywords\":[\"M\u00fasica\",\"M\u00fasica Cristiana\"],\"articleSection\":[\"Actualidad\",\"Arte y Espect\u00e1culos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/\",\"name\":\"Alexander Sosa lanz\u00f3 su tema musical \u201cUna Misma Fe\u201d - Rep. Dominicana | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-2.jpeg\",\"datePublished\":\"2024-12-11T14:41:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-2.jpeg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-2.jpeg\",\"width\":1227,\"height\":689,\"caption\":\"Alexander Sosa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/repdom\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alexander Sosa lanz\u00f3 su tema musical \u201cUna Misma Fe\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"name\":\"Rep. Dominicana | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\",\"name\":\"Noti-America LLC | Rep\u00fablica Dominicana\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Rep\u00fablica Dominicana\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/070e2e8e5b3f97ed51d5361e4ca623f3\",\"name\":\"Jennifer Germosen Rosario\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/58a5e62e2fcde1051fc0bb6f1b277d87b37abd3aa5f503656bdf690b2ab79419?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/58a5e62e2fcde1051fc0bb6f1b277d87b37abd3aa5f503656bdf690b2ab79419?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/58a5e62e2fcde1051fc0bb6f1b277d87b37abd3aa5f503656bdf690b2ab79419?s=96&d=mm&r=g\",\"caption\":\"Jennifer Germosen Rosario\"},\"description\":\"Locutora y Relacionista P\u00fablico, especializada en Comunicaci\u00f3n Estrat\u00e9gica. Me encanta hacer Networking y apoyar las buenas causas.\",\"sameAs\":[\"https:\/\/web.facebook.com\/jennifer.germosenrosario\",\"https:\/\/www.instagram.com\/jenn_germosen\/?hl=es\",\"https:\/\/www.linkedin.com\/in\/jennifer-germosen-rosario-a78131186\/\",\"https:\/\/x.com\/GermosenJenn\"],\"honorificPrefix\":\"Mrs Jennifer Germosen\",\"honorificSuffix\":\"Mtr. Jennifer Germosen\",\"gender\":\"Female\",\"knowsAbout\":[\"Relaciones P\u00fablicas\",\"Comunicaci\u00f3n Estrat\u00e9gica.\"],\"knowsLanguage\":[\"Espa\u00f1ol\",\"Ingl\u00e9s.\"],\"jobTitle\":\"Encargada de Relaciones P\u00fablicas\",\"worksFor\":\"Superintendencia de Seguros Rep\u00fablica Dominicana\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/author\/jgermosen\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alexander Sosa lanz\u00f3 su tema musical \u201cUna Misma Fe\u201d - Rep. Dominicana | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/","og_locale":"es_ES","og_type":"article","og_title":"Alexander Sosa lanz\u00f3 su tema musical \u201cUna Misma Fe\u201d","og_description":"El artista Alexander Sosa regres\u00f3 a la escena musical tras una pausa de tres a\u00f1os con el lanzamiento de su inspirador tema \u201cUna Misma Fe\u201d, que est\u00e1 disponible desde el viernes 6 de diciembre&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/","og_site_name":"Rep. Dominicana | Noti-America.com","article_author":"https:\/\/web.facebook.com\/jennifer.germosenrosario","article_published_time":"2024-12-11T14:41:21+00:00","og_image":[{"width":1227,"height":689,"url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-2.jpeg","type":"image\/jpeg"}],"author":"Jennifer Germosen Rosario","twitter_card":"summary_large_image","twitter_creator":"@GermosenJenn","twitter_misc":{"Escrito por":"Jennifer Germosen Rosario","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/"},"author":{"name":"Jennifer Germosen Rosario","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/070e2e8e5b3f97ed51d5361e4ca623f3"},"headline":"Alexander Sosa lanz\u00f3 su tema musical \u201cUna Misma Fe\u201d","datePublished":"2024-12-11T14:41:21+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/"},"wordCount":546,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-2.jpeg","keywords":["M\u00fasica","M\u00fasica Cristiana"],"articleSection":["Actualidad","Arte y Espect\u00e1culos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/","url":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/","name":"Alexander Sosa lanz\u00f3 su tema musical \u201cUna Misma Fe\u201d - Rep. Dominicana | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-2.jpeg","datePublished":"2024-12-11T14:41:21+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#primaryimage","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-2.jpeg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/12\/WhatsApp-Image-2024-12-06-at-11.38.29-AM-2.jpeg","width":1227,"height":689,"caption":"Alexander Sosa"},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/12\/11\/alexander-sosa-lanzo-su-tema-musical-una-misma-fe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/repdom\/"},{"@type":"ListItem","position":2,"name":"Alexander Sosa lanz\u00f3 su tema musical \u201cUna Misma Fe\u201d"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/repdom\/#website","url":"https:\/\/noti-america.com\/site\/repdom\/","name":"Rep. Dominicana | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/repdom\/#organization","name":"Noti-America LLC | Rep\u00fablica Dominicana","url":"https:\/\/noti-america.com\/site\/repdom\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Rep\u00fablica Dominicana"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/070e2e8e5b3f97ed51d5361e4ca623f3","name":"Jennifer Germosen Rosario","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/58a5e62e2fcde1051fc0bb6f1b277d87b37abd3aa5f503656bdf690b2ab79419?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/58a5e62e2fcde1051fc0bb6f1b277d87b37abd3aa5f503656bdf690b2ab79419?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/58a5e62e2fcde1051fc0bb6f1b277d87b37abd3aa5f503656bdf690b2ab79419?s=96&d=mm&r=g","caption":"Jennifer Germosen Rosario"},"description":"Locutora y Relacionista P\u00fablico, especializada en Comunicaci\u00f3n Estrat\u00e9gica. Me encanta hacer Networking y apoyar las buenas causas.","sameAs":["https:\/\/web.facebook.com\/jennifer.germosenrosario","https:\/\/www.instagram.com\/jenn_germosen\/?hl=es","https:\/\/www.linkedin.com\/in\/jennifer-germosen-rosario-a78131186\/","https:\/\/x.com\/GermosenJenn"],"honorificPrefix":"Mrs Jennifer Germosen","honorificSuffix":"Mtr. Jennifer Germosen","gender":"Female","knowsAbout":["Relaciones P\u00fablicas","Comunicaci\u00f3n Estrat\u00e9gica."],"knowsLanguage":["Espa\u00f1ol","Ingl\u00e9s."],"jobTitle":"Encargada de Relaciones P\u00fablicas","worksFor":"Superintendencia de Seguros Rep\u00fablica Dominicana","url":"https:\/\/noti-america.com\/site\/repdom\/author\/jgermosen\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/31046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/users\/150"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/comments?post=31046"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/31046\/revisions"}],"predecessor-version":[{"id":31051,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/31046\/revisions\/31051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media\/31048"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media?parent=31046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/categories?post=31046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/tags?post=31046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}