{"id":26197,"date":"2024-02-04T17:42:13","date_gmt":"2024-02-04T17:42:13","guid":{"rendered":"https:\/\/noti-america.com\/site\/repdom\/?p=26197"},"modified":"2024-02-04T17:42:13","modified_gmt":"2024-02-04T17:42:13","slug":"cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/","title":{"rendered":"Can\u00f3 y Valdez lideran victoria de RD sobre Puerto Rico"},"content":{"rendered":"<p>https:\/\/www.youtube.com\/watch?v=0xRyxJEdu_k<\/p>\n<p>NOTI-AMERICA.COM\u00a0<em>|\u00a0<\/em>REP\u00daBLICA DOMINICANA<\/p>\n<p style=\"text-align: justify\">MIAMI &#8211; Robinson Can\u00f3 desapareci\u00f3 la pelota del parque, C\u00e9sar Valdez lanz\u00f3 cinco buenas entradas y los Tigres del Licey de Rep\u00fablica Dominicana vencieron 5-2 a los Criollos de Caguas de Puerto Rico, en la tercera jornada de la Serie del Caribe, Miami 2024 celebrada en el LoanDepot Park de esta ciudad.<\/p>\n<p style=\"text-align: justify\">Con su triunfo, los dominicanos colocaron su marca en 2-1, la misma que presentan los boricuas. Ahora ambos pa\u00edses tienen 201 victorias de por vida en las Series del Caribe. Panam\u00e1 y Venezuela presentan foja de 2-0, Curazao 1-2, Nicaragua 0-2 y M\u00e9xico 0-3.<\/p>\n<p style=\"text-align: justify\">Los dominicanos anotaron primero en la segunda entrada cuando Kelvin Guti\u00e9rrez bate\u00f3 para doble matanza con las bases llenas por la v\u00eda 643.<\/p>\n<p style=\"text-align: justify\">El Licey sac\u00f3 del box al abridor boricua Daryl Thompson en el tercer inning cuando Emilio Bonifacio abri\u00f3 con sencillo de toque por la l\u00ednea de la primera y luego de un out, Robinson Can\u00f3 conect\u00f3 cuadrangular sobre la verja del jard\u00edn derecho. Ram\u00f3n Hern\u00e1ndez sigui\u00f3 con doblete a la pared del prado izquierdo y anot\u00f3 por sencillo al central de Dawel Lugo.<\/p>\n<p style=\"text-align: justify\">Los boricuas se pusieron en el marcador en el cuarto acto ante el iniciador dominicano C\u00e9sar Valdez. Heliot Ramos abri\u00f3 con sencillo al central y anot\u00f3 por doble hacia la misma direcci\u00f3n de Daniel Ortiz. Luego de un out, Emmanuel Rivera dio sencillo al izquierdo y Ortiz avanz\u00f3 a la antesala desde donde pis\u00f3 el plato por elevado de sacrificio al central de Johneshwy Fargas.<\/p>\n<p style=\"text-align: justify\">Los Tigres anotaron otra en la s\u00e9ptima frente al relevista Christian Torres. Yadiel Hern\u00e1ndez comenz\u00f3 con sencillo al central, pas\u00f3 a segunda por toque de sacrificio de Michael De La Cruz y, luego de un out, Gustavo N\u00fa\u00f1ez dio hit remolcador al jard\u00edn izquierdo.<\/p>\n<p style=\"text-align: justify\">Valdez labor\u00f3 durante los primeros cinco innings, permiti\u00f3 seis hits, dos carreras limpias con un boleto y dos ponchados. Fue seguido en el mont\u00edculo por Cameron Gann (6), Jean Carlos Mej\u00eda (8) y Jairo Asencio (9).<\/p>\n<p style=\"text-align: justify\">Thompson solo pudo lanzar 2.2 entradas, cedi\u00f3 ocho imparables, cuatro vueltas merecidas con dos ponches. Fue relevado por Alex Claudio (3), Angel Reyes (6), Torres (7) y Ricardo G\u00f3mez (9).<\/p>\n<p style=\"text-align: justify\">Valdez fue el lanzador ganador, Thompson carg\u00f3 con la derrota y Asencio se acredit\u00f3 el salvamento.<\/p>\n<p style=\"text-align: justify\">Por los dominicanos, Can\u00f3, de 4-2 con jonr\u00f3n, anotada y dos empujadas, Ram\u00f3n Hern\u00e1ndez, de 4-2, doble y dos anotadas, Lugo de 3-2 con una remolcada, Bonifacio, de 4-2 con una anotada y H\u00e9ctor Rodr\u00edguez, de 3-2.<\/p>\n<p style=\"text-align: justify\">Por los boricuas, Ramos, de 3-2 con anotada, Ortiz, de 3-2 con doble, anotada e impulsada.<\/p>\n<p style=\"text-align: justify\">Los Tigres regresan a la acci\u00f3n este domingo a partir de las 9:30 de la noche cuando se enfrenten a los Naranjeros de Hermosillo, representantes de M\u00e9xico.<\/p>\n<p style=\"text-align: justify\"><strong>Fuente: Prensa Licey<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/www.youtube.com\/watch?v=0xRyxJEdu_k NOTI-AMERICA.COM\u00a0|\u00a0REP\u00daBLICA DOMINICANA MIAMI &#8211; Robinson Can\u00f3 desapareci\u00f3 la pelota del parque, C\u00e9sar Valdez lanz\u00f3 cinco buenas entradas y los Tigres del Licey de Rep\u00fablica Dominicana vencieron 5-2 a los Criollos de Caguas de&#46;&#46;&#46;<\/p>\n","protected":false},"author":89,"featured_media":26198,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1726,16],"tags":[737,123,108,586,3361,296],"class_list":["post-26197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beisbol","category-deportes","tag-cesar-valdez","tag-peloteros-dominicanos","tag-republica-dominicana","tag-robinson-cano","tag-serie-del-caribe-miami-2024","tag-tigres-del-licey"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Can\u00f3 y Valdez lideran victoria de RD sobre Puerto Rico - Rep. Dominicana | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Can\u00f3 y Valdez lideran victoria de RD sobre Puerto Rico\" \/>\n<meta property=\"og:description\" content=\"https:\/\/www.youtube.com\/watch?v=0xRyxJEdu_k NOTI-AMERICA.COM\u00a0|\u00a0REP\u00daBLICA DOMINICANA MIAMI &#8211; Robinson Can\u00f3 desapareci\u00f3 la pelota del parque, C\u00e9sar Valdez lanz\u00f3 cinco buenas entradas y los Tigres del Licey de Rep\u00fablica Dominicana vencieron 5-2 a los Criollos de Caguas de&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/\" \/>\n<meta property=\"og:site_name\" content=\"Rep. Dominicana | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-04T17:42:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/02\/Cano-Valdez-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ad\u00e1n Soriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@adansoriano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ad\u00e1n Soriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/\"},\"author\":{\"name\":\"Ad\u00e1n Soriano\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/e8cde3d87079627d077589321667269f\"},\"headline\":\"Can\u00f3 y Valdez lideran victoria de RD sobre Puerto Rico\",\"datePublished\":\"2024-02-04T17:42:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/\"},\"wordCount\":493,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/02\/Cano-Valdez-scaled.jpg\",\"keywords\":[\"C\u00e9sar Valdez\",\"Peloteros Dominicanos\",\"Rep\u00fablica Dominicana\",\"Robinson Can\u00f3\",\"Serie del Caribe Miami 2024\",\"Tigres del Licey\"],\"articleSection\":[\"Beisbol\",\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/\",\"name\":\"Can\u00f3 y Valdez lideran victoria de RD sobre Puerto Rico - Rep. Dominicana | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/02\/Cano-Valdez-scaled.jpg\",\"datePublished\":\"2024-02-04T17:42:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/02\/Cano-Valdez-scaled.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/02\/Cano-Valdez-scaled.jpg\",\"width\":2560,\"height\":1512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/repdom\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Can\u00f3 y Valdez lideran victoria de RD sobre Puerto Rico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"name\":\"Rep. Dominicana | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\",\"name\":\"Noti-America LLC | Rep\u00fablica Dominicana\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Rep\u00fablica Dominicana\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/e8cde3d87079627d077589321667269f\",\"name\":\"Ad\u00e1n Soriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"caption\":\"Ad\u00e1n Soriano\"},\"description\":\"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva\",\"sameAs\":[\"https:\/\/x.com\/adansoriano\"],\"url\":\"https:\/\/noti-america.com\/site\/repdom\/author\/asoriano\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Can\u00f3 y Valdez lideran victoria de RD sobre Puerto Rico - Rep. Dominicana | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/","og_locale":"es_ES","og_type":"article","og_title":"Can\u00f3 y Valdez lideran victoria de RD sobre Puerto Rico","og_description":"https:\/\/www.youtube.com\/watch?v=0xRyxJEdu_k NOTI-AMERICA.COM\u00a0|\u00a0REP\u00daBLICA DOMINICANA MIAMI &#8211; Robinson Can\u00f3 desapareci\u00f3 la pelota del parque, C\u00e9sar Valdez lanz\u00f3 cinco buenas entradas y los Tigres del Licey de Rep\u00fablica Dominicana vencieron 5-2 a los Criollos de Caguas de&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/","og_site_name":"Rep. Dominicana | Noti-America.com","article_published_time":"2024-02-04T17:42:13+00:00","og_image":[{"width":2560,"height":1512,"url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/02\/Cano-Valdez-scaled.jpg","type":"image\/jpeg"}],"author":"Ad\u00e1n Soriano","twitter_card":"summary_large_image","twitter_creator":"@adansoriano","twitter_misc":{"Escrito por":"Ad\u00e1n Soriano","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/"},"author":{"name":"Ad\u00e1n Soriano","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/e8cde3d87079627d077589321667269f"},"headline":"Can\u00f3 y Valdez lideran victoria de RD sobre Puerto Rico","datePublished":"2024-02-04T17:42:13+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/"},"wordCount":493,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/02\/Cano-Valdez-scaled.jpg","keywords":["C\u00e9sar Valdez","Peloteros Dominicanos","Rep\u00fablica Dominicana","Robinson Can\u00f3","Serie del Caribe Miami 2024","Tigres del Licey"],"articleSection":["Beisbol","Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/","url":"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/","name":"Can\u00f3 y Valdez lideran victoria de RD sobre Puerto Rico - Rep. Dominicana | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/02\/Cano-Valdez-scaled.jpg","datePublished":"2024-02-04T17:42:13+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#primaryimage","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/02\/Cano-Valdez-scaled.jpg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2024\/02\/Cano-Valdez-scaled.jpg","width":2560,"height":1512},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/repdom\/2024\/02\/04\/cano-y-valdez-lideran-victoria-de-rd-sobre-puerto-rico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/repdom\/"},{"@type":"ListItem","position":2,"name":"Can\u00f3 y Valdez lideran victoria de RD sobre Puerto Rico"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/repdom\/#website","url":"https:\/\/noti-america.com\/site\/repdom\/","name":"Rep. Dominicana | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/repdom\/#organization","name":"Noti-America LLC | Rep\u00fablica Dominicana","url":"https:\/\/noti-america.com\/site\/repdom\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Rep\u00fablica Dominicana"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/e8cde3d87079627d077589321667269f","name":"Ad\u00e1n Soriano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","caption":"Ad\u00e1n Soriano"},"description":"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva","sameAs":["https:\/\/x.com\/adansoriano"],"url":"https:\/\/noti-america.com\/site\/repdom\/author\/asoriano\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/26197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/comments?post=26197"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/26197\/revisions"}],"predecessor-version":[{"id":26199,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/26197\/revisions\/26199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media\/26198"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media?parent=26197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/categories?post=26197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/tags?post=26197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}