{"id":25087,"date":"2023-11-09T18:05:33","date_gmt":"2023-11-09T18:05:33","guid":{"rendered":"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/"},"modified":"2023-11-09T18:05:33","modified_gmt":"2023-11-09T18:05:33","slug":"adococ-filial-sanchez-ramirez-gradua-34-locutores-3","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/","title":{"rendered":"ADOCOC filial S\u00e1nchez Ram\u00edrez grad\u00faa 34 locutores"},"content":{"rendered":"<p><strong>Noti-Am\u00e9rica Rep\u00fablica Dominicana<\/strong><br \/>\n<strong>Santo Domingo,RD<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><b><i>Es la primera promoci\u00f3n del curso de Locuci\u00f3n impartido por esta filial. El evento tambi\u00e9n sirvi\u00f3 para dejar posicionada la directiva para el 2023-2025.<\/i><\/b><\/p>\n<p>S\u00e1nchez Ram\u00edrez, Rep.Dom. La Asociaci\u00f3n Dominicana de Comunicadores Cristianos (ADOCOC) Filial S\u00e1nchez Ram\u00edrez, celebr\u00f3 la primera graduaci\u00f3n del curso de locuci\u00f3n impartido por esta filial, en la que fueron investidos treinta y cuatro nuevos profesionales del micr\u00f3fono pertenecientes a diferentes congregaciones evang\u00e9licas de esta provincia.<\/p>\n<p>De acuerdo a Clara Ruiz, presidente de la filial, el principal prop\u00f3sito de este entrenamiento es \u201ccapacitar a los pastores y l\u00edderes para compartir las buenas nuevas de salvaci\u00f3n con mayor eficacia y acorde a los tiempos e incentivarlos a empoderarse de los medios de comunicaci\u00f3n puestos a la disposici\u00f3n para que la Palabra de Dios corra y sea glorificada\u201d.<br \/>\n<i><br \/>\n\u201cHoy celebramos este logro. Hoy llegamos a la meta y entregamos a la sociedad de esta provincia treinta y cuatro l\u00edderes evang\u00e9licos y pastores para que compartan el evangelio con eficacia y excelencia. Durante cinco meses fueron entrenados por nuestro querido profesor Antonio Vel\u00e1squez, quien se esmer\u00f3 cada semana en compartir sus conocimientos con excelencia para que hoy, el pueblo de Dios cuente con profesionales que compartan Su palabra con eficacia\u201d,<\/i>\u00a0a\u00f1adi\u00f3 Ruiz.<\/p>\n<p>Las palabras de motivaci\u00f3n estuvieron a cargo de Erika Oviedo Mer\u00e1n, presidente nacional de ADOCOC, quien inst\u00f3 a los graduandos a ejercer una comunicaci\u00f3n con integridad, objetividad y bajo principios \u00e9ticos. \u00abAgradecemos a Dios permitir a la filial S\u00e1nchez Ram\u00edrez llevar a cabo esta capacitaci\u00f3n en tiempos tan demandantes y desafiantes. Como cristianos, nuestro trabajo es dar gloria a Dios y nuestro oficio es ser locutores, que todo lo que hagamos sea con excelencia, como para el Se\u00f1or\u201d, expres\u00f3 Oviedo.<\/p>\n<p>De su lado, la graduanda Julissa Mendoza habl\u00f3 a nombre de sus compa\u00f1eros hom\u00f3logos y quien, por su destacado desempe\u00f1o durante la docencia mereci\u00f3<br \/>\nel privilegio de representar a los graduandos. Intervino, adem\u00e1s, de parte de los estudiantes, el pastor Antonio Florentino quien comparti\u00f3 su experiencia durante la jornada.<\/p>\n<p>En el evento, se aprovech\u00f3 la presencia de la presidente nacional y algunos de sus directivos; as\u00ed como la del expresidente nacional Alexis Rodr\u00edguez, para dejar posicionado al pastor y comunicador Mart\u00edn Reyes como nuevo presidente de la filial en la provincia S\u00e1nchez Ram\u00edrez, quien se comprometi\u00f3, junto a su directiva, a seguir trabajando arduamente a favor de la instituci\u00f3n, en su fortalecimiento crecimiento y consolidaci\u00f3n.<\/p>\n<p>Participaron de la actividad, Edward Parra, miembro de la directiva nacional; Lilly Reynoso y Yudelkis Santos, presidente y secretaria general de ADOCOC filial Santiago respectivamente.<\/p>\n<p>La conducci\u00f3n de la ceremonia, estuvo a cargo del maestro Antonio Vel\u00e1squez y Enoelia Ortega, ambos dirigieron el programa dise\u00f1ado para celebrar la victoria concedida por Dios a los nuevos profesionales del micr\u00f3fono, junto a sus familiares, amigos y directivos de la asociaci\u00f3n que se dieron cita al sal\u00f3n de eventos Janet Atelier en Cotu\u00ed. La parte musical fue amenizada por Jos\u00edas y Eliezer Reyes ambientando a piano y saxo; mientras que Ruth Sald\u00edvar y Raquel Reyes entonaron alabanzas al Creador.<\/p>\n<p><b>Sobre ADOCOC<\/b><\/p>\n<p>La Asociaci\u00f3n Dominicana de Comunicadores Cristianos (ADOCOC) fue fundada el 15 de diciembre de 2006, tiene como objetivo agrupar y unificar a los comunicadores dominicanos que profesan la fe en Jesucristo.<\/p>\n<p>Fuente: Depto. Comunicaciones ADOCOC (<a href=\"mailto:adococnacional@gmail.com\" target=\"_blank\" rel=\"noopener\">adococnacional@gmail.com<\/a>)<span style=\"color: #888888\"><br \/><\/span><\/p>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Noti-Am\u00e9rica Rep\u00fablica Dominicana Santo Domingo,RD &nbsp; Es la primera promoci\u00f3n del curso de Locuci\u00f3n impartido por esta filial. El evento tambi\u00e9n sirvi\u00f3 para dejar posicionada la directiva para el 2023-2025. S\u00e1nchez Ram\u00edrez, Rep.Dom. La&#46;&#46;&#46;<\/p>\n","protected":false},"author":129,"featured_media":25088,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[277,338],"tags":[],"class_list":["post-25087","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-acturalidad","category-nacionales","post_format-post-format-gallery"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ADOCOC filial S\u00e1nchez Ram\u00edrez grad\u00faa 34 locutores - Rep. Dominicana | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ADOCOC filial S\u00e1nchez Ram\u00edrez grad\u00faa 34 locutores\" \/>\n<meta property=\"og:description\" content=\"Noti-Am\u00e9rica Rep\u00fablica Dominicana Santo Domingo,RD &nbsp; Es la primera promoci\u00f3n del curso de Locuci\u00f3n impartido por esta filial. El evento tambi\u00e9n sirvi\u00f3 para dejar posicionada la directiva para el 2023-2025. S\u00e1nchez Ram\u00edrez, Rep.Dom. La&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Rep. Dominicana | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-09T18:05:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2023\/11\/WhatsApp-Image-2023-11-07-at-21.04.57-2-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1869\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"smitchell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"smitchell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/\"},\"author\":{\"name\":\"smitchell\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/28be91cef78e9e55666f36815b10e700\"},\"headline\":\"ADOCOC filial S\u00e1nchez Ram\u00edrez grad\u00faa 34 locutores\",\"datePublished\":\"2023-11-09T18:05:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/\"},\"wordCount\":607,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2023\/11\/WhatsApp-Image-2023-11-07-at-21.04.57-2-scaled.jpeg\",\"articleSection\":[\"Actualidad\",\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/\",\"name\":\"ADOCOC filial S\u00e1nchez Ram\u00edrez grad\u00faa 34 locutores - Rep. Dominicana | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2023\/11\/WhatsApp-Image-2023-11-07-at-21.04.57-2-scaled.jpeg\",\"datePublished\":\"2023-11-09T18:05:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2023\/11\/WhatsApp-Image-2023-11-07-at-21.04.57-2-scaled.jpeg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2023\/11\/WhatsApp-Image-2023-11-07-at-21.04.57-2-scaled.jpeg\",\"width\":2560,\"height\":1869},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/repdom\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ADOCOC filial S\u00e1nchez Ram\u00edrez grad\u00faa 34 locutores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"name\":\"Rep. Dominicana | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\",\"name\":\"Noti-America LLC | Rep\u00fablica Dominicana\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Rep\u00fablica Dominicana\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/28be91cef78e9e55666f36815b10e700\",\"name\":\"smitchell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/c18c6f834f0060488b7c3f3067def257a0bfad0791954c77f1474dd3644bdb6f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c18c6f834f0060488b7c3f3067def257a0bfad0791954c77f1474dd3644bdb6f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c18c6f834f0060488b7c3f3067def257a0bfad0791954c77f1474dd3644bdb6f?s=96&d=mm&r=g\",\"caption\":\"smitchell\"},\"url\":\"https:\/\/noti-america.com\/site\/repdom\/author\/smitchell\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ADOCOC filial S\u00e1nchez Ram\u00edrez grad\u00faa 34 locutores - Rep. Dominicana | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/","og_locale":"es_ES","og_type":"article","og_title":"ADOCOC filial S\u00e1nchez Ram\u00edrez grad\u00faa 34 locutores","og_description":"Noti-Am\u00e9rica Rep\u00fablica Dominicana Santo Domingo,RD &nbsp; Es la primera promoci\u00f3n del curso de Locuci\u00f3n impartido por esta filial. El evento tambi\u00e9n sirvi\u00f3 para dejar posicionada la directiva para el 2023-2025. S\u00e1nchez Ram\u00edrez, Rep.Dom. La&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/","og_site_name":"Rep. Dominicana | Noti-America.com","article_published_time":"2023-11-09T18:05:33+00:00","og_image":[{"width":2560,"height":1869,"url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2023\/11\/WhatsApp-Image-2023-11-07-at-21.04.57-2-scaled.jpeg","type":"image\/jpeg"}],"author":"smitchell","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"smitchell","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/"},"author":{"name":"smitchell","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/28be91cef78e9e55666f36815b10e700"},"headline":"ADOCOC filial S\u00e1nchez Ram\u00edrez grad\u00faa 34 locutores","datePublished":"2023-11-09T18:05:33+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/"},"wordCount":607,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2023\/11\/WhatsApp-Image-2023-11-07-at-21.04.57-2-scaled.jpeg","articleSection":["Actualidad","Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/","url":"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/","name":"ADOCOC filial S\u00e1nchez Ram\u00edrez grad\u00faa 34 locutores - Rep. Dominicana | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2023\/11\/WhatsApp-Image-2023-11-07-at-21.04.57-2-scaled.jpeg","datePublished":"2023-11-09T18:05:33+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#primaryimage","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2023\/11\/WhatsApp-Image-2023-11-07-at-21.04.57-2-scaled.jpeg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2023\/11\/WhatsApp-Image-2023-11-07-at-21.04.57-2-scaled.jpeg","width":2560,"height":1869},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/repdom\/2023\/11\/09\/adococ-filial-sanchez-ramirez-gradua-34-locutores-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/repdom\/"},{"@type":"ListItem","position":2,"name":"ADOCOC filial S\u00e1nchez Ram\u00edrez grad\u00faa 34 locutores"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/repdom\/#website","url":"https:\/\/noti-america.com\/site\/repdom\/","name":"Rep. Dominicana | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/repdom\/#organization","name":"Noti-America LLC | Rep\u00fablica Dominicana","url":"https:\/\/noti-america.com\/site\/repdom\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Rep\u00fablica Dominicana"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/28be91cef78e9e55666f36815b10e700","name":"smitchell","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c18c6f834f0060488b7c3f3067def257a0bfad0791954c77f1474dd3644bdb6f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c18c6f834f0060488b7c3f3067def257a0bfad0791954c77f1474dd3644bdb6f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c18c6f834f0060488b7c3f3067def257a0bfad0791954c77f1474dd3644bdb6f?s=96&d=mm&r=g","caption":"smitchell"},"url":"https:\/\/noti-america.com\/site\/repdom\/author\/smitchell\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/25087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/comments?post=25087"}],"version-history":[{"count":0,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/25087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media\/25088"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media?parent=25087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/categories?post=25087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/tags?post=25087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}