{"id":17352,"date":"2022-04-11T04:28:30","date_gmt":"2022-04-11T04:28:30","guid":{"rendered":"https:\/\/noti-america.com\/site\/repdom\/?p=17352"},"modified":"2022-04-11T04:28:30","modified_gmt":"2022-04-11T04:28:30","slug":"brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/","title":{"rendered":"Brayan Arauza es el Jugador M\u00e1s Valioso del Cl\u00e1sico de Peque\u00f1as Ligas 2022"},"content":{"rendered":"<p style=\"text-align: justify\"><span data-contrast=\"auto\">SANTO DOMINGO &#8211; Este s\u00e1bado se entreg\u00f3 el premio de Jugador M\u00e1s Valioso (JMV) del Cl\u00e1sico de Peque\u00f1as Ligas 2022, donde el lanzador Brayan Arauza de los Halcones de Santiago, fue elegido con este galard\u00f3n, as\u00ed como se reconocieron los m\u00e1s destacados de cada posici\u00f3n y los l\u00edderes individuales durante la etapa regular.<\/span><\/p>\n<p style=\"text-align: justify\"><span data-contrast=\"auto\">Arauza super\u00f3 a Vairon Bueno de los Reyes de la Capital y a Jos\u00e9 Andrickson de los Astros del Ol\u00edmpico, nominados en este rengl\u00f3n.<\/span><\/p>\n<p style=\"text-align: justify\"><span data-contrast=\"auto\">El serpentinero tuvo marca de 4-0 en cuatro aperturas, un promedio de carreras permitidas en 1.15, tras 13.0 entradas lanzadas, otorgando ocho boletos con 28 ponches, y se enfrent\u00f3 a 55 bateadores.<\/span><\/p>\n<p style=\"text-align: justify\"><span data-contrast=\"auto\">En su trayecto en la fase regular, complet\u00f3 un partido con una blanqueada, un WHIP de 1.31, quedando l\u00edder en efectividad y victorias, y segundo en ponches.<\/span><\/p>\n<p style=\"text-align: justify\"><strong>Otros galardonados<\/strong><\/p>\n<p style=\"text-align: justify\"><span data-contrast=\"auto\">Jos\u00e9 Miguel Andrickson de los Astros, recibi\u00f3 el premio a Mejor receptor de este torneo, mientras Onalfry Cruz de los Guerreros del Este fue reconocido como el Mejor inicialista, y Michael de la Cruz, de los Marineros de Villa Mella, como el Mejor Segunda base.<\/span><\/p>\n<p style=\"text-align: justify\"><span data-contrast=\"auto\">El tercera base de este 2022 recay\u00f3 en Jhoseph Leta de los Astros del Ol\u00edmpico, mientras el mejor campocorto fue Vairon Bueno y el Mejor Lanzador fue Brayan Arauza.<\/span><\/p>\n<p style=\"text-align: justify\"><span data-contrast=\"auto\">Los jardineros del Cl\u00e1sico de Peque\u00f1as Ligas 2022, son Alveuris Brito de los Halcones, Miguel Mella de los Astros, y Argenis Fern\u00e1ndez de los Metros.<\/span><\/p>\n<p style=\"text-align: justify\"><span data-contrast=\"auto\">Tambi\u00e9n recibieron sus reconocimientos como l\u00edderes de la temporada regular, Vairon Bueno en hits y cuadrangulares, Sebasti\u00e1n D\u00e1vila en carreras anotadas, Alveuris Brito con las carreras empujadas, as\u00ed como Axel Aybar quien lider\u00f3 los ponches propinados.<\/span><\/p>\n<p style=\"text-align: justify\"><span data-contrast=\"auto\">En la actividad celebrada en el estadio n\u00famero uno de softball del Centro Ol\u00edmpico, estuvieron presentes, Ver\u00f3nica Castillo, representante de Logomarca, Alfredo P\u00e9rez de la Federaci\u00f3n Dominicana de Softball y Alberto Rodr\u00edguez, embajador de esta versi\u00f3n del Cl\u00e1sico de Peque\u00f1as Ligas 2022.<\/span><\/p>\n<p style=\"text-align: justify\"><strong>Fuente: Prensa Cl\u00e1sico Peque\u00f1as Ligas<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO &#8211; Este s\u00e1bado se entreg\u00f3 el premio de Jugador M\u00e1s Valioso (JMV) del Cl\u00e1sico de Peque\u00f1as Ligas 2022, donde el lanzador Brayan Arauza de los Halcones de Santiago, fue elegido con este&#46;&#46;&#46;<\/p>\n","protected":false},"author":89,"featured_media":17353,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1726,16],"tags":[2288,2177,2289],"class_list":["post-17352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beisbol","category-deportes","tag-brayan-arauza","tag-clasico-de-pequenas-ligas-2022","tag-halcones-de-santiago"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Brayan Arauza es el Jugador M\u00e1s Valioso del Cl\u00e1sico de Peque\u00f1as Ligas 2022 - Rep. Dominicana | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brayan Arauza es el Jugador M\u00e1s Valioso del Cl\u00e1sico de Peque\u00f1as Ligas 2022\" \/>\n<meta property=\"og:description\" content=\"SANTO DOMINGO &#8211; Este s\u00e1bado se entreg\u00f3 el premio de Jugador M\u00e1s Valioso (JMV) del Cl\u00e1sico de Peque\u00f1as Ligas 2022, donde el lanzador Brayan Arauza de los Halcones de Santiago, fue elegido con este&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Rep. Dominicana | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-11T04:28:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/04\/Alberto-Rodriguez-Brayan-Arauza-y-todos-los-ganadores-de-los-premios-individuales-en-el-Clasico-2022.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ad\u00e1n Soriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@adansoriano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ad\u00e1n Soriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/\"},\"author\":{\"name\":\"Ad\u00e1n Soriano\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/e8cde3d87079627d077589321667269f\"},\"headline\":\"Brayan Arauza es el Jugador M\u00e1s Valioso del Cl\u00e1sico de Peque\u00f1as Ligas 2022\",\"datePublished\":\"2022-04-11T04:28:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/\"},\"wordCount\":356,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/04\/Alberto-Rodriguez-Brayan-Arauza-y-todos-los-ganadores-de-los-premios-individuales-en-el-Clasico-2022.jpeg\",\"keywords\":[\"Brayan Arauza\",\"Cl\u00e1sico de Peque\u00f1as Ligas 2022\",\"Halcones de Santiago\"],\"articleSection\":[\"Beisbol\",\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/\",\"name\":\"Brayan Arauza es el Jugador M\u00e1s Valioso del Cl\u00e1sico de Peque\u00f1as Ligas 2022 - Rep. Dominicana | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/04\/Alberto-Rodriguez-Brayan-Arauza-y-todos-los-ganadores-de-los-premios-individuales-en-el-Clasico-2022.jpeg\",\"datePublished\":\"2022-04-11T04:28:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/04\/Alberto-Rodriguez-Brayan-Arauza-y-todos-los-ganadores-de-los-premios-individuales-en-el-Clasico-2022.jpeg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/04\/Alberto-Rodriguez-Brayan-Arauza-y-todos-los-ganadores-de-los-premios-individuales-en-el-Clasico-2022.jpeg\",\"width\":1024,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/repdom\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brayan Arauza es el Jugador M\u00e1s Valioso del Cl\u00e1sico de Peque\u00f1as Ligas 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"name\":\"Rep. Dominicana | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\",\"name\":\"Noti-America LLC | Rep\u00fablica Dominicana\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Rep\u00fablica Dominicana\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/e8cde3d87079627d077589321667269f\",\"name\":\"Ad\u00e1n Soriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"caption\":\"Ad\u00e1n Soriano\"},\"description\":\"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva\",\"sameAs\":[\"https:\/\/x.com\/adansoriano\"],\"url\":\"https:\/\/noti-america.com\/site\/repdom\/author\/asoriano\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Brayan Arauza es el Jugador M\u00e1s Valioso del Cl\u00e1sico de Peque\u00f1as Ligas 2022 - Rep. Dominicana | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/","og_locale":"es_ES","og_type":"article","og_title":"Brayan Arauza es el Jugador M\u00e1s Valioso del Cl\u00e1sico de Peque\u00f1as Ligas 2022","og_description":"SANTO DOMINGO &#8211; Este s\u00e1bado se entreg\u00f3 el premio de Jugador M\u00e1s Valioso (JMV) del Cl\u00e1sico de Peque\u00f1as Ligas 2022, donde el lanzador Brayan Arauza de los Halcones de Santiago, fue elegido con este&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/","og_site_name":"Rep. Dominicana | Noti-America.com","article_published_time":"2022-04-11T04:28:30+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/04\/Alberto-Rodriguez-Brayan-Arauza-y-todos-los-ganadores-de-los-premios-individuales-en-el-Clasico-2022.jpeg","type":"image\/jpeg"}],"author":"Ad\u00e1n Soriano","twitter_card":"summary_large_image","twitter_creator":"@adansoriano","twitter_misc":{"Escrito por":"Ad\u00e1n Soriano","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/"},"author":{"name":"Ad\u00e1n Soriano","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/e8cde3d87079627d077589321667269f"},"headline":"Brayan Arauza es el Jugador M\u00e1s Valioso del Cl\u00e1sico de Peque\u00f1as Ligas 2022","datePublished":"2022-04-11T04:28:30+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/"},"wordCount":356,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/04\/Alberto-Rodriguez-Brayan-Arauza-y-todos-los-ganadores-de-los-premios-individuales-en-el-Clasico-2022.jpeg","keywords":["Brayan Arauza","Cl\u00e1sico de Peque\u00f1as Ligas 2022","Halcones de Santiago"],"articleSection":["Beisbol","Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/","url":"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/","name":"Brayan Arauza es el Jugador M\u00e1s Valioso del Cl\u00e1sico de Peque\u00f1as Ligas 2022 - Rep. Dominicana | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/04\/Alberto-Rodriguez-Brayan-Arauza-y-todos-los-ganadores-de-los-premios-individuales-en-el-Clasico-2022.jpeg","datePublished":"2022-04-11T04:28:30+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#primaryimage","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/04\/Alberto-Rodriguez-Brayan-Arauza-y-todos-los-ganadores-de-los-premios-individuales-en-el-Clasico-2022.jpeg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/04\/Alberto-Rodriguez-Brayan-Arauza-y-todos-los-ganadores-de-los-premios-individuales-en-el-Clasico-2022.jpeg","width":1024,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/04\/11\/brayan-arauza-es-el-jugador-mas-valioso-del-clasico-de-pequenas-ligas-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/repdom\/"},{"@type":"ListItem","position":2,"name":"Brayan Arauza es el Jugador M\u00e1s Valioso del Cl\u00e1sico de Peque\u00f1as Ligas 2022"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/repdom\/#website","url":"https:\/\/noti-america.com\/site\/repdom\/","name":"Rep. Dominicana | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/repdom\/#organization","name":"Noti-America LLC | Rep\u00fablica Dominicana","url":"https:\/\/noti-america.com\/site\/repdom\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Rep\u00fablica Dominicana"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/e8cde3d87079627d077589321667269f","name":"Ad\u00e1n Soriano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","caption":"Ad\u00e1n Soriano"},"description":"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva","sameAs":["https:\/\/x.com\/adansoriano"],"url":"https:\/\/noti-america.com\/site\/repdom\/author\/asoriano\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/17352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/comments?post=17352"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/17352\/revisions"}],"predecessor-version":[{"id":17354,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/17352\/revisions\/17354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media\/17353"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media?parent=17352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/categories?post=17352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/tags?post=17352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}