{"id":16035,"date":"2022-02-02T20:12:19","date_gmt":"2022-02-02T20:12:19","guid":{"rendered":"https:\/\/noti-america.com\/site\/repdom\/?p=16035"},"modified":"2022-02-02T20:12:19","modified_gmt":"2022-02-02T20:12:19","slug":"inap-culmina-con-exito-la-semana-del-servidor-publico-2022","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/","title":{"rendered":"INAP culmina con \u00e9xito la \u201cSemana del Servidor P\u00fablico 2022\u201d"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-16036\" style=\"text-align: justify\" src=\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-300x180.jpg\" alt=\"\" width=\"412\" height=\"247\" srcset=\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-300x180.jpg 300w, https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-1024x615.jpg 1024w, https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-768x461.jpg 768w, https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-1536x923.jpg 1536w, https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-2048x1231.jpg 2048w\" sizes=\"auto, (max-width: 412px) 100vw, 412px\" \/><\/p>\n<p><em><strong>NOTI-AMERICA REP\u00daBLICA DOMINICANA<\/strong><\/em><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 14pt\"><strong> D. N.-<\/strong><\/span>\u00a0El Instituto Nacional de Administraci\u00f3n P\u00fablica (INAP) concluy\u00f3 con \u00e9xito la \u201c<strong>Semana del Servidor P\u00fablico<\/strong>\u201d con la participaci\u00f3n de trabajadores de instituciones del Estado y de gobiernos locales (ayuntamientos y juntas de distritos municipales), del 25 al 28 de enero.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">El evento inici\u00f3, el pasado lunes 25 de enero, con las felicitaciones de parte del director general del INAP, Cristian S\u00e1nchez Reyes, por celebrarse el D\u00eda Nacional del Servidor P\u00fablico.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">A su vez, el martes 26 de enero, se desarroll\u00f3 la primera del ciclo de conferencias virtuales con la disertaci\u00f3n de Ricardo Nieves, comunicador, m\u00e9dico, abogado y activista en la lucha contra la corrupci\u00f3n, y el tema: \u201cAsumiendo la \u00e9tica como un sistema de valores que conforman un h\u00e1bito de vida\u201d, en la que revel\u00f3 su inter\u00e9s de que exista un c\u00f3digo de \u00e9tica \u00fanico y general de la administraci\u00f3n p\u00fablica, y que se le aplique a todo servidor p\u00fablico; y no un c\u00f3digo de dispersi\u00f3n como existe.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">La segunda conferencia se efectu\u00f3 el jueves 27 de enero con\u00a0el\u00a0director ejecutivo de la Comisi\u00f3n de Reforma y Modernizaci\u00f3n de la Administraci\u00f3n P\u00fablica, Jos\u00e9 Oviedo, quien present\u00f3:\u00a0\u201cPlan de Reforma y Modernizaci\u00f3n de la Administraci\u00f3n P\u00fablica\u201d.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">Mientras que el viernes 28 de enero, el presidente del Instituto Duartiano, Wilson G\u00f3mez Ram\u00edrez, comparti\u00f3 la conferencia: \u201cInfluencia Duartiana en el servidor p\u00fablico moderno\u201d.<\/p>\n<p style=\"font-weight: 400;text-align: justify\"><strong>Exaltaciones<\/strong><\/p>\n<p style=\"font-weight: 400;text-align: justify\">En la edici\u00f3n de este a\u00f1o, el INAP reconoci\u00f3 con exaltaciones\u00a0a 16 instituciones estatales por sus resultados del alto r\u00e1nking en el subindicador 8.1 del Plan de Capacitaci\u00f3n y a cinco cabildos en el indicador 1.05 del Plan Anual de Capacitaci\u00f3n Formalizado y en Marcha del Sistema de Monitoreo de la Administraci\u00f3n P\u00fablica, SISMAP Poder Ejecutivo y SISMAP Municipal, respectivamente, y por las buenas pr\u00e1cticas para el fomento de competencias en sus servidores por medio de la oferta formativa del INAP.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">Al expresar las palabras en el cierre de la \u201cSemana del Servidor P\u00fablico\u201d, S\u00e1nchez Reyes dijo: \u201cm\u00e1s que una intervenci\u00f3n de despedida, quiero manifestar aplausos y agradecimientos a los protagonistas que dedicaron su tiempo, esfuerzo, valiosas ideas y paciencia para el \u00e9xito de esta \u00abSemana del Servidor P\u00fablico\u00bb del INAP\u201d.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">Agradeci\u00f3 a Dios por permitir que las expectativas de este did\u00e1ctico encuentro se cumplieron de manera plena, orientado a los lineamientos del presidente Luis Abinader de establecer una administraci\u00f3n p\u00fablica con \u00e9nfasis en la \u00e9tica, la transparencia, la innovaci\u00f3n y la honestidad.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">\u201cHaber terminado esta \u00abSemana del Servidor P\u00fablico\u00bb del INAP, caracterizada por la virtualidad debido a la pandemia, no significa que nos retiramos a descansar, sino a utilizar las energ\u00edas del conocimiento que hemos almacenado para los grandes retos que se aproximan; y es un momento oportuno para compartirlos por su alto nivel de importancia\u201d,\u00a0adelant\u00f3.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">Antes de avanzar con las pinceladas de la futura y amplia agenda, aprovech\u00f3 para recordar un acontecimiento de alta magnitud como la elecci\u00f3n un\u00e1nime de la\u00a0Rep\u00fablica Dominicana, en la persona del ministro de Administraci\u00f3n P\u00fablica, Dar\u00edo Castillo Lugo,\u00a0a la presidencia del Centro Latinoamericano de Administraci\u00f3n para el Desarrollo (CLAD), per\u00edodo 2021-2023, durante la 51 Reuni\u00f3n Ordinaria Anual del Consejo Directivo, celebrada en Bogot\u00e1, Colombia, en noviembre pasado.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">\u201cTodo este pre\u00e1mbulo informativo se sustenta en que uno de esos retos pendientes es la celebraci\u00f3n en el pa\u00eds, en marzo venidero, de los\u00a0Talleres con Sello CLAD sobre\u00a0Desarrollo de Competencias Estrat\u00e9gicas de los Directivos P\u00fablicos, una actividad que busca desarrollar las capacidades\u00a0laborales\u00a0como eje fundamental de profesionalizaci\u00f3n de los servidores p\u00fablicos\u201d,\u00a0agreg\u00f3.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">Refiri\u00f3 que, tambi\u00e9n, en marzo, tendremos nuestra \u00abSemana Aniversario\u00bb para festejar los 23 a\u00f1os de la fundaci\u00f3n del INAP y, adem\u00e1s, la Jornada de Capacitaci\u00f3n de la Regi\u00f3n Este, cargadas de cursos, talleres, conferencias magistrales y reconocimientos, en los que el CLAD nos acompa\u00f1ar\u00e1 con su experiencia y notorios profesionales.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">\u201cEn fin, la capacitaci\u00f3n no toma vacaciones en el INAP, y continuaremos desarrollando las capacidades de los servidores p\u00fablicos para el fortalecimiento y los cambios que est\u00e1n en marcha en la administraci\u00f3n p\u00fablica dominicana\u201d,\u00a0acot\u00f3.<\/p>\n<p style=\"font-weight: 400;text-align: justify\">La \u00abSemana del Servidor P\u00fablico\u00bb cont\u00f3 con la coordinaci\u00f3n de los subdirectores \u00c1ngel Familia, Sonia L\u00f3pez y Rosa Camila Rivera; y la encargada del Departamento de Gesti\u00f3n de la Formaci\u00f3n, Yeimy Paredes; adem\u00e1s, de la integraci\u00f3n de todo el personal acad\u00e9mico, t\u00e9cnico y administrativo del INAP.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; NOTI-AMERICA REP\u00daBLICA DOMINICANA D. N.-\u00a0El Instituto Nacional de Administraci\u00f3n P\u00fablica (INAP) concluy\u00f3 con \u00e9xito la \u201cSemana del Servidor P\u00fablico\u201d con la participaci\u00f3n de trabajadores de instituciones del Estado y de gobiernos locales (ayuntamientos&#46;&#46;&#46;<\/p>\n","protected":false},"author":92,"featured_media":16036,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10,105],"tags":[],"class_list":["post-16035","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-actualidad","category-noticias","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>INAP culmina con \u00e9xito la \u201cSemana del Servidor P\u00fablico 2022\u201d - Rep. Dominicana | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INAP culmina con \u00e9xito la \u201cSemana del Servidor P\u00fablico 2022\u201d\" \/>\n<meta property=\"og:description\" content=\"&nbsp; NOTI-AMERICA REP\u00daBLICA DOMINICANA D. N.-\u00a0El Instituto Nacional de Administraci\u00f3n P\u00fablica (INAP) concluy\u00f3 con \u00e9xito la \u201cSemana del Servidor P\u00fablico\u201d con la participaci\u00f3n de trabajadores de instituciones del Estado y de gobiernos locales (ayuntamientos&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Rep. Dominicana | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-02T20:12:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1538\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sueanny Guzm\u00e1n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sueannyguzmanrd\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sueanny Guzm\u00e1n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/\"},\"author\":{\"name\":\"Sueanny Guzm\u00e1n\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/96391fd2005f34fd641a26bd0ad3e10c\"},\"headline\":\"INAP culmina con \u00e9xito la \u201cSemana del Servidor P\u00fablico 2022\u201d\",\"datePublished\":\"2022-02-02T20:12:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/\"},\"wordCount\":797,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-scaled.jpg\",\"articleSection\":[\"Actualidad\",\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/\",\"name\":\"INAP culmina con \u00e9xito la \u201cSemana del Servidor P\u00fablico 2022\u201d - Rep. Dominicana | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-scaled.jpg\",\"datePublished\":\"2022-02-02T20:12:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-scaled.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-scaled.jpg\",\"width\":2560,\"height\":1538},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/repdom\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INAP culmina con \u00e9xito la \u201cSemana del Servidor P\u00fablico 2022\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"name\":\"Rep. Dominicana | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\",\"name\":\"Noti-America LLC | Rep\u00fablica Dominicana\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Rep\u00fablica Dominicana\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/96391fd2005f34fd641a26bd0ad3e10c\",\"name\":\"Sueanny Guzm\u00e1n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/743180685ef4657e50d4fb7ec792c2c316119f5a7db45e029570122e8cd05065?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/743180685ef4657e50d4fb7ec792c2c316119f5a7db45e029570122e8cd05065?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/743180685ef4657e50d4fb7ec792c2c316119f5a7db45e029570122e8cd05065?s=96&d=mm&r=g\",\"caption\":\"Sueanny Guzm\u00e1n\"},\"sameAs\":[\"https:\/\/x.com\/sueannyguzmanrd\"],\"url\":\"https:\/\/noti-america.com\/site\/repdom\/author\/sguzman\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"INAP culmina con \u00e9xito la \u201cSemana del Servidor P\u00fablico 2022\u201d - Rep. Dominicana | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/","og_locale":"es_ES","og_type":"article","og_title":"INAP culmina con \u00e9xito la \u201cSemana del Servidor P\u00fablico 2022\u201d","og_description":"&nbsp; NOTI-AMERICA REP\u00daBLICA DOMINICANA D. N.-\u00a0El Instituto Nacional de Administraci\u00f3n P\u00fablica (INAP) concluy\u00f3 con \u00e9xito la \u201cSemana del Servidor P\u00fablico\u201d con la participaci\u00f3n de trabajadores de instituciones del Estado y de gobiernos locales (ayuntamientos&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/","og_site_name":"Rep. Dominicana | Noti-America.com","article_published_time":"2022-02-02T20:12:19+00:00","og_image":[{"width":2560,"height":1538,"url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-scaled.jpg","type":"image\/jpeg"}],"author":"Sueanny Guzm\u00e1n","twitter_card":"summary_large_image","twitter_creator":"@sueannyguzmanrd","twitter_misc":{"Escrito por":"Sueanny Guzm\u00e1n","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/"},"author":{"name":"Sueanny Guzm\u00e1n","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/96391fd2005f34fd641a26bd0ad3e10c"},"headline":"INAP culmina con \u00e9xito la \u201cSemana del Servidor P\u00fablico 2022\u201d","datePublished":"2022-02-02T20:12:19+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/"},"wordCount":797,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-scaled.jpg","articleSection":["Actualidad","Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/","url":"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/","name":"INAP culmina con \u00e9xito la \u201cSemana del Servidor P\u00fablico 2022\u201d - Rep. Dominicana | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-scaled.jpg","datePublished":"2022-02-02T20:12:19+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#primaryimage","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-scaled.jpg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2022\/02\/Director-general-Cristian-Sanchez-Reyes-2-scaled.jpg","width":2560,"height":1538},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/repdom\/2022\/02\/02\/inap-culmina-con-exito-la-semana-del-servidor-publico-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/repdom\/"},{"@type":"ListItem","position":2,"name":"INAP culmina con \u00e9xito la \u201cSemana del Servidor P\u00fablico 2022\u201d"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/repdom\/#website","url":"https:\/\/noti-america.com\/site\/repdom\/","name":"Rep. Dominicana | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/repdom\/#organization","name":"Noti-America LLC | Rep\u00fablica Dominicana","url":"https:\/\/noti-america.com\/site\/repdom\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Rep\u00fablica Dominicana"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/96391fd2005f34fd641a26bd0ad3e10c","name":"Sueanny Guzm\u00e1n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/743180685ef4657e50d4fb7ec792c2c316119f5a7db45e029570122e8cd05065?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/743180685ef4657e50d4fb7ec792c2c316119f5a7db45e029570122e8cd05065?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/743180685ef4657e50d4fb7ec792c2c316119f5a7db45e029570122e8cd05065?s=96&d=mm&r=g","caption":"Sueanny Guzm\u00e1n"},"sameAs":["https:\/\/x.com\/sueannyguzmanrd"],"url":"https:\/\/noti-america.com\/site\/repdom\/author\/sguzman\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/16035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/users\/92"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/comments?post=16035"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/16035\/revisions"}],"predecessor-version":[{"id":16037,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/16035\/revisions\/16037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media\/16036"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media?parent=16035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/categories?post=16035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/tags?post=16035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}