{"id":14196,"date":"2021-11-04T14:19:03","date_gmt":"2021-11-04T14:19:03","guid":{"rendered":"https:\/\/noti-america.com\/site\/repdom\/?p=14196"},"modified":"2021-11-04T14:19:03","modified_gmt":"2021-11-04T14:19:03","slug":"gigantes-propinan-paliza-al-licey","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/","title":{"rendered":"Gigantes propinan paliza al Licey"},"content":{"rendered":"<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Resumen Tigres del Licey vs Gigantes del Cibao | 3 NOV 2021 | Serie Regular Lidom\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/4Wo6tak_MEs?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p style=\"text-align: justify\"><span lang=\"ES-MX\">SAN FRANCISCO DE MACOR\u00cdS &#8211; Con una explosi\u00f3n ofensiva, los Gigantes del Cibao dominaron a los Tigres del Licey 10-2 en su primer enfrentamiento de la temporada este mi\u00e9rcoles.<\/span><\/p>\n<p style=\"text-align: justify\"><span lang=\"ES-MX\">Los Gigantes contaron nuevamente con una actuaci\u00f3n de lujo de su lanzador abridor, Adalberto Mej\u00eda, quien coron\u00f3 cinco entradas de tres hits, un boleto, cuatro ponches.<\/span><\/p>\n<p style=\"text-align: justify\"><span lang=\"ES-MX\">La combinaci\u00f3n de los lanzadores Gigantes propino siete ponches, cuatro boletos, con dos vueltas inmerecidas. La victoria fue para Hu\u00e1scar Brazob<\/span>\u00e1<span lang=\"ES-MX\">n.<\/span><\/p>\n<p style=\"text-align: justify\"><strong><span lang=\"ES-MX\">Las carreras<\/span><\/strong><\/p>\n<p style=\"text-align: justify\"><span lang=\"ES-MX\">El equipo del Cibao arranc\u00f3 temprano con el poder de Wilin Rosario, quien conect\u00f3 doble en la segunda entrada empujador de la primera vuelta.<\/span><\/p>\n<p style=\"text-align: justify\"><span lang=\"ES-MX\">Hanser Alberto, con doble empujador en el tercer episodio, se convirti\u00f3 en el imparable 200 en su carrera con los Gigantes.<\/span><\/p>\n<p style=\"text-align: justify\"><span lang=\"ES-MX\">Un rally de tres vueltas lleg\u00f3 en la parte baja de la sexta rompiendo el empate 2-2 con el equipo azul. Sencillo del receptor Webster Rivas con las bases llenas empuj\u00f3 dos vueltas.<\/span><\/p>\n<p style=\"text-align: justify\"><span lang=\"ES-MX\">Juan Francisco, con sencillo, empuj\u00f3 dos carreras m\u00e1s en la s\u00e9ptima.<\/span><\/p>\n<p style=\"text-align: justify\"><span lang=\"ES-MX\">Kelvin Guti\u00e9rrez y Alfredo Marte conectaron cuadrangulares seguidos en el s\u00e9ptimo episodio, productores de dos y una carrera respectivamente. Se marcaron cinco vueltas para llegar a 10, la mayor cantidad de anotadas en la temporada por el equipo del Cibao, tambi\u00e9n fue la mayor cantidad de imparables con 11.<\/span><\/p>\n<p style=\"text-align: justify\"><span lang=\"ES-MX\">Los Tigres del Licey marcaron 2 carreras en la sexta.<\/span><\/p>\n<p style=\"text-align: justify\"><span lang=\"ES-MX\">La tercera victoria consecutiva de los Gigantes los coloca con r\u00e9cord de 3-4.<\/span><\/p>\n<p style=\"text-align: justify\"><strong><span lang=\"ES-MX\">Hanser Alberto en grupo exclusivo<\/span><\/strong><\/p>\n<p style=\"text-align: justify\"><span lang=\"ES-MX\">Hanser Alberto se convirti\u00f3 en el d\u00e9cimo jugador de los Gigantes en conectar 200 imparables o m\u00e1s. El exclusivo grupo lo completan: Mois\u00e9s Sierra (389), Alexi Casilla (279), Pedro Fel\u00edz (279), Wilson Valdez (269), Juan Sosa (265), Erick Almonte (265), Fausto Cruz (208), Julio Ram\u00edrez (202) y Bryan Pena (201).<\/span><\/p>\n<p style=\"text-align: justify\"><strong>Fuente: Prensa Gigantes del Cibao<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN FRANCISCO DE MACOR\u00cdS &#8211; Con una explosi\u00f3n ofensiva, los Gigantes del Cibao dominaron a los Tigres del Licey 10-2 en su primer enfrentamiento de la temporada este mi\u00e9rcoles. Los Gigantes contaron nuevamente con&#46;&#46;&#46;<\/p>\n","protected":false},"author":89,"featured_media":14197,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1726,16],"tags":[1796,119,173,1745,122,123],"class_list":["post-14196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beisbol","category-deportes","tag-alfredo-marte","tag-beisbol-dominicano","tag-gigantes-del-cibao","tag-kelvin-gutierrez","tag-liga-dominicana-de-beisbol-profesional","tag-peloteros-dominicanos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gigantes propinan paliza al Licey - Rep. Dominicana | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gigantes propinan paliza al Licey\" \/>\n<meta property=\"og:description\" content=\"SAN FRANCISCO DE MACOR\u00cdS &#8211; Con una explosi\u00f3n ofensiva, los Gigantes del Cibao dominaron a los Tigres del Licey 10-2 en su primer enfrentamiento de la temporada este mi\u00e9rcoles. Los Gigantes contaron nuevamente con&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/\" \/>\n<meta property=\"og:site_name\" content=\"Rep. Dominicana | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-04T14:19:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/11\/Kelvin-Gutierrrez.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1059\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ad\u00e1n Soriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@adansoriano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ad\u00e1n Soriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/\"},\"author\":{\"name\":\"Ad\u00e1n Soriano\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/e8cde3d87079627d077589321667269f\"},\"headline\":\"Gigantes propinan paliza al Licey\",\"datePublished\":\"2021-11-04T14:19:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/\"},\"wordCount\":318,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/11\/Kelvin-Gutierrrez.jpeg\",\"keywords\":[\"Alfredo Marte\",\"B\u00e9isbol Dominicano\",\"Gigantes del Cibao\",\"Kelvin Guti\u00e9rrez\",\"Liga Dominicana de B\u00e9isbol Profesional\",\"Peloteros Dominicanos\"],\"articleSection\":[\"Beisbol\",\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/\",\"name\":\"Gigantes propinan paliza al Licey - Rep. Dominicana | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/11\/Kelvin-Gutierrrez.jpeg\",\"datePublished\":\"2021-11-04T14:19:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/11\/Kelvin-Gutierrrez.jpeg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/11\/Kelvin-Gutierrrez.jpeg\",\"width\":1600,\"height\":1059},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/repdom\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gigantes propinan paliza al Licey\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"name\":\"Rep. Dominicana | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\",\"name\":\"Noti-America LLC | Rep\u00fablica Dominicana\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Rep\u00fablica Dominicana\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/e8cde3d87079627d077589321667269f\",\"name\":\"Ad\u00e1n Soriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"caption\":\"Ad\u00e1n Soriano\"},\"description\":\"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva\",\"sameAs\":[\"https:\/\/x.com\/adansoriano\"],\"url\":\"https:\/\/noti-america.com\/site\/repdom\/author\/asoriano\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gigantes propinan paliza al Licey - Rep. Dominicana | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/","og_locale":"es_ES","og_type":"article","og_title":"Gigantes propinan paliza al Licey","og_description":"SAN FRANCISCO DE MACOR\u00cdS &#8211; Con una explosi\u00f3n ofensiva, los Gigantes del Cibao dominaron a los Tigres del Licey 10-2 en su primer enfrentamiento de la temporada este mi\u00e9rcoles. Los Gigantes contaron nuevamente con&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/","og_site_name":"Rep. Dominicana | Noti-America.com","article_published_time":"2021-11-04T14:19:03+00:00","og_image":[{"width":1600,"height":1059,"url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/11\/Kelvin-Gutierrrez.jpeg","type":"image\/jpeg"}],"author":"Ad\u00e1n Soriano","twitter_card":"summary_large_image","twitter_creator":"@adansoriano","twitter_misc":{"Escrito por":"Ad\u00e1n Soriano","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/"},"author":{"name":"Ad\u00e1n Soriano","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/e8cde3d87079627d077589321667269f"},"headline":"Gigantes propinan paliza al Licey","datePublished":"2021-11-04T14:19:03+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/"},"wordCount":318,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/11\/Kelvin-Gutierrrez.jpeg","keywords":["Alfredo Marte","B\u00e9isbol Dominicano","Gigantes del Cibao","Kelvin Guti\u00e9rrez","Liga Dominicana de B\u00e9isbol Profesional","Peloteros Dominicanos"],"articleSection":["Beisbol","Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/","url":"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/","name":"Gigantes propinan paliza al Licey - Rep. Dominicana | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/11\/Kelvin-Gutierrrez.jpeg","datePublished":"2021-11-04T14:19:03+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#primaryimage","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/11\/Kelvin-Gutierrrez.jpeg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/11\/Kelvin-Gutierrrez.jpeg","width":1600,"height":1059},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/11\/04\/gigantes-propinan-paliza-al-licey\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/repdom\/"},{"@type":"ListItem","position":2,"name":"Gigantes propinan paliza al Licey"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/repdom\/#website","url":"https:\/\/noti-america.com\/site\/repdom\/","name":"Rep. Dominicana | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/repdom\/#organization","name":"Noti-America LLC | Rep\u00fablica Dominicana","url":"https:\/\/noti-america.com\/site\/repdom\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Rep\u00fablica Dominicana"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/e8cde3d87079627d077589321667269f","name":"Ad\u00e1n Soriano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","caption":"Ad\u00e1n Soriano"},"description":"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva","sameAs":["https:\/\/x.com\/adansoriano"],"url":"https:\/\/noti-america.com\/site\/repdom\/author\/asoriano\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/14196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/comments?post=14196"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/14196\/revisions"}],"predecessor-version":[{"id":14198,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/14196\/revisions\/14198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media\/14197"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media?parent=14196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/categories?post=14196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/tags?post=14196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}