{"id":11453,"date":"2021-07-07T12:24:31","date_gmt":"2021-07-07T12:24:31","guid":{"rendered":"https:\/\/noti-america.com\/site\/repdom\/?p=11453"},"modified":"2021-07-07T12:24:31","modified_gmt":"2021-07-07T12:24:31","slug":"grupo-armado-asesina-al-presidente-de-haiti","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/","title":{"rendered":"Grupo armado asesina al presidente de Hait\u00ed"},"content":{"rendered":"<div id=\"ArticleSourceDivMail\" class=\"article-body-author mrf-author\" style=\"text-align: justify\"><b>Puerto Pr\u00edncipe, Hait\u00ed.- <\/b>El presidente de Hait\u00ed, Jovenel Moise, fue asesinado este mi\u00e9rcoles por hombres armados que perpetraron un asalto a su residencia de madrugada en el barrio de Pelerin de Puerto Pr\u00edncipe, inform\u00f3 el primer ministro interino, Claude Joseph.<\/div>\n<div id=\"ArticleBody\">\n<p style=\"text-align: justify\">En el asalto result\u00f3 herida de bala la primera dama, Martine Moise, que est\u00e1 recibiendo cuidados m\u00e9dicos, seg\u00fan un comunicado le\u00eddo por Joseph en la radio.<\/p>\n<p style=\"text-align: justify\">\u00abEsta ma\u00f1ana mismo, a la una de la ma\u00f1ana, 7 de julio, un grupo de personas no identificadas, que hablaban en espa\u00f1ol e ingl\u00e9s, asesinaron al presidente de la Rep\u00fablica. El presidente ha muerto a causa de sus heridas\u00bb, dijo el primer ministro interino.<\/p>\n<p style=\"text-align: justify\">Joseph llam\u00f3 a la calma de la poblaci\u00f3n y asegur\u00f3 que la \u00absituaci\u00f3n de seguridad del pa\u00eds est\u00e1 bajo control\u00bb y conden\u00f3 el magnicidio, que calific\u00f3 como \u00abun acto de barbarie\u00bb.<\/p>\n<p style=\"text-align: justify\">El asesinato se produce dos meses antes de las elecciones presidenciales y legislativas convocadas para el pr\u00f3ximo 26 de septiembre, unos comicios en los que Moise no pod\u00eda ser candidato.<\/p>\n<p style=\"text-align: justify\">Moise hab\u00eda convocado para la misma fecha un refer\u00e9ndum para aprobar una nueva Constituci\u00f3n, un proyecto que no contaba con el apoyo de la oposici\u00f3n ni de la comunidad internacional.<\/p>\n<p style=\"text-align: justify\">Hait\u00ed atraviesa una fuerte crisis pol\u00edtica desde mediados de 2018 y vivi\u00f3 su momento m\u00e1s grave el pasado 7 de febrero, fecha en la que Moise denunci\u00f3 que la oposici\u00f3n, con el apoyo de jueces, tramaban un golpe de Estado.<\/p>\n<p style=\"text-align: justify\">De forma paralela, Hait\u00ed atraviesa una honda crisis de seguridad, que se ha agravado en especial desde comienzos de junio por luchas territoriales entre las bandas armadas que se disputan el control de los barrios m\u00e1s pobres de Puerto Pr\u00edncipe.<\/p>\n<p>Fuente: EFE\/List\u00edn Diario<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Puerto Pr\u00edncipe, Hait\u00ed.- El presidente de Hait\u00ed, Jovenel Moise, fue asesinado este mi\u00e9rcoles por hombres armados que perpetraron un asalto a su residencia de madrugada en el barrio de Pelerin de Puerto Pr\u00edncipe, inform\u00f3&#46;&#46;&#46;<\/p>\n","protected":false},"author":99,"featured_media":11454,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10,277],"tags":[],"class_list":["post-11453","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-actualidad","category-acturalidad","post_format-post-format-gallery"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Grupo armado asesina al presidente de Hait\u00ed - Rep. Dominicana | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grupo armado asesina al presidente de Hait\u00ed\" \/>\n<meta property=\"og:description\" content=\"Puerto Pr\u00edncipe, Hait\u00ed.- El presidente de Hait\u00ed, Jovenel Moise, fue asesinado este mi\u00e9rcoles por hombres armados que perpetraron un asalto a su residencia de madrugada en el barrio de Pelerin de Puerto Pr\u00edncipe, inform\u00f3&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/\" \/>\n<meta property=\"og:site_name\" content=\"Rep. Dominicana | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-07T12:24:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/07\/CNN-Haiti\u0301-presidente-e1625653854498.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"380\" \/>\n\t<meta property=\"og:image:height\" content=\"215\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ann\u00e9 Cruz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ann\u00e9 Cruz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/\"},\"author\":{\"name\":\"Ann\u00e9 Cruz\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/9fd6b0b106ee1eca017e2e7e96a39aa5\"},\"headline\":\"Grupo armado asesina al presidente de Hait\u00ed\",\"datePublished\":\"2021-07-07T12:24:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/\"},\"wordCount\":315,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/07\/CNN-Haiti\u0301-presidente-e1625653854498.jpg\",\"articleSection\":[\"Actualidad\",\"Actualidad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/\",\"name\":\"Grupo armado asesina al presidente de Hait\u00ed - Rep. Dominicana | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/07\/CNN-Haiti\u0301-presidente-e1625653854498.jpg\",\"datePublished\":\"2021-07-07T12:24:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/07\/CNN-Haiti\u0301-presidente-e1625653854498.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/07\/CNN-Haiti\u0301-presidente-e1625653854498.jpg\",\"width\":380,\"height\":215},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/repdom\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grupo armado asesina al presidente de Hait\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"name\":\"Rep. Dominicana | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#organization\",\"name\":\"Noti-America LLC | Rep\u00fablica Dominicana\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Rep\u00fablica Dominicana\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/9fd6b0b106ee1eca017e2e7e96a39aa5\",\"name\":\"Ann\u00e9 Cruz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/f5aaeb3fd16b65f7d601dd99d7f1dcaaf7065ea361b219976bcf5d43d0980e1b?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f5aaeb3fd16b65f7d601dd99d7f1dcaaf7065ea361b219976bcf5d43d0980e1b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f5aaeb3fd16b65f7d601dd99d7f1dcaaf7065ea361b219976bcf5d43d0980e1b?s=96&d=mm&r=g\",\"caption\":\"Ann\u00e9 Cruz\"},\"description\":\"Emprendedora, publirrelacionista y periodista especializada en Comunicaci\u00f3n Pol\u00edtica e Institucional.\",\"url\":\"https:\/\/noti-america.com\/site\/repdom\/author\/adelacruz\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Grupo armado asesina al presidente de Hait\u00ed - Rep. Dominicana | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/","og_locale":"es_ES","og_type":"article","og_title":"Grupo armado asesina al presidente de Hait\u00ed","og_description":"Puerto Pr\u00edncipe, Hait\u00ed.- El presidente de Hait\u00ed, Jovenel Moise, fue asesinado este mi\u00e9rcoles por hombres armados que perpetraron un asalto a su residencia de madrugada en el barrio de Pelerin de Puerto Pr\u00edncipe, inform\u00f3&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/","og_site_name":"Rep. Dominicana | Noti-America.com","article_published_time":"2021-07-07T12:24:31+00:00","og_image":[{"width":380,"height":215,"url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/07\/CNN-Haiti\u0301-presidente-e1625653854498.jpg","type":"image\/jpeg"}],"author":"Ann\u00e9 Cruz","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ann\u00e9 Cruz","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/"},"author":{"name":"Ann\u00e9 Cruz","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/9fd6b0b106ee1eca017e2e7e96a39aa5"},"headline":"Grupo armado asesina al presidente de Hait\u00ed","datePublished":"2021-07-07T12:24:31+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/"},"wordCount":315,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/07\/CNN-Haiti\u0301-presidente-e1625653854498.jpg","articleSection":["Actualidad","Actualidad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/","url":"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/","name":"Grupo armado asesina al presidente de Hait\u00ed - Rep. Dominicana | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/07\/CNN-Haiti\u0301-presidente-e1625653854498.jpg","datePublished":"2021-07-07T12:24:31+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#primaryimage","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/07\/CNN-Haiti\u0301-presidente-e1625653854498.jpg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2021\/07\/CNN-Haiti\u0301-presidente-e1625653854498.jpg","width":380,"height":215},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/repdom\/2021\/07\/07\/grupo-armado-asesina-al-presidente-de-haiti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/repdom\/"},{"@type":"ListItem","position":2,"name":"Grupo armado asesina al presidente de Hait\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/repdom\/#website","url":"https:\/\/noti-america.com\/site\/repdom\/","name":"Rep. Dominicana | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/repdom\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/repdom\/#organization","name":"Noti-America LLC | Rep\u00fablica Dominicana","url":"https:\/\/noti-america.com\/site\/repdom\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/repdom\/wp-content\/uploads\/sites\/6\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Rep\u00fablica Dominicana"},"image":{"@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/repdom\/#\/schema\/person\/9fd6b0b106ee1eca017e2e7e96a39aa5","name":"Ann\u00e9 Cruz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f5aaeb3fd16b65f7d601dd99d7f1dcaaf7065ea361b219976bcf5d43d0980e1b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f5aaeb3fd16b65f7d601dd99d7f1dcaaf7065ea361b219976bcf5d43d0980e1b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5aaeb3fd16b65f7d601dd99d7f1dcaaf7065ea361b219976bcf5d43d0980e1b?s=96&d=mm&r=g","caption":"Ann\u00e9 Cruz"},"description":"Emprendedora, publirrelacionista y periodista especializada en Comunicaci\u00f3n Pol\u00edtica e Institucional.","url":"https:\/\/noti-america.com\/site\/repdom\/author\/adelacruz\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/11453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/comments?post=11453"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/11453\/revisions"}],"predecessor-version":[{"id":11457,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/posts\/11453\/revisions\/11457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media\/11454"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/media?parent=11453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/categories?post=11453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/repdom\/wp-json\/wp\/v2\/tags?post=11453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}