{"id":84128,"date":"2026-03-09T20:49:14","date_gmt":"2026-03-10T00:49:14","guid":{"rendered":"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/"},"modified":"2026-03-09T20:49:14","modified_gmt":"2026-03-10T00:49:14","slug":"20738-2","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/","title":{"rendered":"Anne Hathaway encabezar\u00e1 el evento del D\u00eda Internacional de las Mujeres de ONU Mujeres en las Naciones Unidas"},"content":{"rendered":"<p>NOTI-AMERICA | COLOMBIA<\/p>\n<p>Hoy 9 de marzo Anne Hathaway encabezar\u00e1 el evento del D\u00eda Internacional de las Mujeres de ONU Mujeres en las Naciones Unidas<\/p>\n<p>Qu\u00e9<br \/>\nVoces l\u00edderes en la defensa de derechos y la justicia de las mujeres, junto con una actuaci\u00f3n musical especial de la artista ganadora del premio Grammy y estrella de Broadway Michelle Williams, se unir\u00e1n a ONU Mujeres para la Conmemoraci\u00f3n oficial de las Naciones Unidas del D\u00eda Internacional de las Mujeres 2026, que se celebrar\u00e1 en la Sede de las Naciones Unidas en Nueva York el 9 de marzo de 2026 a las 9:00 a. m.<\/p>\n<p>Por qu\u00e9<br \/>\nEn un momento en que los derechos de las mujeres enfrentan un amenazas de retrocesos en todo el mundo, el evento del D\u00eda Internacional de las Mujeres 2026, que nos convoca bajo el lema \u201cDerechos, justicia y acci\u00f3n por y para todas las mujeres y las ni\u00f1as\u201d, relevar\u00e1 el poder de las mujeres y las ni\u00f1as \u2013a trav\u00e9s de generaciones, movimientos y culturas, en toda su diversidad\u2013 al unirse para defender la igualdad y exigir cambios para todas las mujeres y las ni\u00f1as.<\/p>\n<p>Qui\u00e9nes<br \/>\nEl evento ser\u00e1 conducido por la Sra. Sade Baderinwa, presentadora de noticias de WABC\u2011TV, y el programa contar\u00e1 con intervenciones magistrales de:<\/p>\n<p>Anne Hathaway, Embajadora de Buena Voluntad de ONU Mujeres<br \/>\nSima Bahous , Secretaria General Adjunta de las Naciones Unidas y Directora Ejecutiva de ONU Mujeres<br \/>\nAmina J. Mohammed , Vicesecretaria General de las Naciones Unidas<br \/>\nAnnalena Baerbock , Presidenta del octog\u00e9simo per\u00edodo de sesiones de la Asamblea General de las Naciones Unidas<br \/>\nMaritza Chan Valverde, Representante Permanente de Costa Rica ante las Naciones Unidas y Presidenta del septuag\u00e9simo per\u00edodo de sesiones de la Comisi\u00f3n de la Condici\u00f3n Jur\u00eddica y Social de la Mujer<br \/>\nUna reconocida persona laureada con el Premio Nobel y defensora mundial de los derechos y la justicia de las mujeres y las ni\u00f1as<br \/>\nD\u00f3nde<br \/>\nLos medios de comunicaci\u00f3n y el p\u00fablico podr\u00e1n seguir el evento en l\u00ednea por UN Web TV aqu\u00ed, de 9:00 a 10:00 a. m. (hora del Este) el 9 de marzo de 2026<br \/>\nEl evento presencial tendr\u00e1 lugar en el Sal\u00f3n de la Asamblea General de las Naciones Unidas.<\/p>\n<p>El evento antecede a la apertura del 70.\u00ba per\u00edodo de sesiones de la Comisi\u00f3n de la Condici\u00f3n Jur\u00eddica y Social de la Mujer, el mayor encuentro anual de las Naciones Unidas dedicado a promover la igualdad de g\u00e9nero y el empoderamiento de las mujeres y las ni\u00f1as.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA | COLOMBIA Hoy 9 de marzo Anne Hathaway encabezar\u00e1 el evento del D\u00eda Internacional de las Mujeres de ONU Mujeres en las Naciones Unidas Qu\u00e9 Voces l\u00edderes en la defensa de derechos y&#46;&#46;&#46;<\/p>\n","protected":false},"author":135,"featured_media":0,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10219548024599422_1632221337088128":"","twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[3173],"tags":[],"class_list":["post-84128","post","type-post","status-publish","format-image","hentry","category-mujeres","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Anne Hathaway encabezar\u00e1 el evento del D\u00eda Internacional de las Mujeres de ONU Mujeres en las Naciones Unidas - Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anne Hathaway encabezar\u00e1 el evento del D\u00eda Internacional de las Mujeres de ONU Mujeres en las Naciones Unidas\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA | COLOMBIA Hoy 9 de marzo Anne Hathaway encabezar\u00e1 el evento del D\u00eda Internacional de las Mujeres de ONU Mujeres en las Naciones Unidas Qu\u00e9 Voces l\u00edderes en la defensa de derechos y&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-10T00:49:14+00:00\" \/>\n<meta name=\"author\" content=\"mlenis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mlenis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/\"},\"author\":{\"name\":\"mlenis\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007\"},\"headline\":\"Anne Hathaway encabezar\u00e1 el evento del D\u00eda Internacional de las Mujeres de ONU Mujeres en las Naciones Unidas\",\"datePublished\":\"2026-03-10T00:49:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/\"},\"wordCount\":451,\"articleSection\":[\"Mujeres\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/\",\"name\":\"Anne Hathaway encabezar\u00e1 el evento del D\u00eda Internacional de las Mujeres de ONU Mujeres en las Naciones Unidas - Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\"},\"datePublished\":\"2026-03-10T00:49:14+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/principal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anne Hathaway encabezar\u00e1 el evento del D\u00eda Internacional de las Mujeres de ONU Mujeres en las Naciones Unidas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/\",\"name\":\"Noti-America.com\",\"description\":\"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007\",\"name\":\"mlenis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"caption\":\"mlenis\"},\"url\":\"https:\/\/noti-america.com\/site\/principal\/author\/mlenis\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Anne Hathaway encabezar\u00e1 el evento del D\u00eda Internacional de las Mujeres de ONU Mujeres en las Naciones Unidas - Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/","og_locale":"es_ES","og_type":"article","og_title":"Anne Hathaway encabezar\u00e1 el evento del D\u00eda Internacional de las Mujeres de ONU Mujeres en las Naciones Unidas","og_description":"NOTI-AMERICA | COLOMBIA Hoy 9 de marzo Anne Hathaway encabezar\u00e1 el evento del D\u00eda Internacional de las Mujeres de ONU Mujeres en las Naciones Unidas Qu\u00e9 Voces l\u00edderes en la defensa de derechos y&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/","og_site_name":"Noti-America.com","article_published_time":"2026-03-10T00:49:14+00:00","author":"mlenis","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mlenis","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/"},"author":{"name":"mlenis","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007"},"headline":"Anne Hathaway encabezar\u00e1 el evento del D\u00eda Internacional de las Mujeres de ONU Mujeres en las Naciones Unidas","datePublished":"2026-03-10T00:49:14+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/"},"wordCount":451,"articleSection":["Mujeres"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/","url":"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/","name":"Anne Hathaway encabezar\u00e1 el evento del D\u00eda Internacional de las Mujeres de ONU Mujeres en las Naciones Unidas - Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/#website"},"datePublished":"2026-03-10T00:49:14+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/principal\/2026\/03\/09\/20738-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/principal\/"},{"@type":"ListItem","position":2,"name":"Anne Hathaway encabezar\u00e1 el evento del D\u00eda Internacional de las Mujeres de ONU Mujeres en las Naciones Unidas"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/principal\/#website","url":"https:\/\/noti-america.com\/site\/principal\/","name":"Noti-America.com","description":"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007","name":"mlenis","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","caption":"mlenis"},"url":"https:\/\/noti-america.com\/site\/principal\/author\/mlenis\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/84128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/comments?post=84128"}],"version-history":[{"count":0,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/84128\/revisions"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media?parent=84128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/categories?post=84128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/tags?post=84128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}