{"id":76174,"date":"2025-10-29T13:04:32","date_gmt":"2025-10-29T17:04:32","guid":{"rendered":"https:\/\/noti-america.com\/site\/principal\/?p=76174"},"modified":"2025-10-29T13:04:32","modified_gmt":"2025-10-29T17:04:32","slug":"escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/","title":{"rendered":"Escogido se impone a Gigantes con jonrones de Lake y Maldonado"},"content":{"rendered":"<p>NOTI-AMERICA.COM <em>|\u00a0<\/em>REP\u00daBLICA DOMINICANA<\/p>\n<p dir=\"ltr\" style=\"text-align: justify\"><span data-olk-copy-source=\"MessageBody\">SANTO DOMINGO &#8211; <\/span>Por segundo d\u00eda consecutivo, los Leones del Escogido derrotaron a los Gigantes del Cibao, esta vez 7-5 en el estadio Quisqueya Juan Marichal, con lo que extienden a tres su racha de victorias.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify\">Los locales marcaron dos veces en el segundo episodio frente a Daniel Mengden, luego de que Franchy Cordero conectara sencillo al jard\u00edn izquierdo y luego, por la misma zona, Junior Lake peg\u00f3 un cuadrangular de 365 pies de distancia, batazo que tuvo una velocidad de salida de 92.6 millas por hora.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify\">En el tercero, los melenudos sumaron una m\u00e1s con otro bambinazo, esta vez solitario, pero tambi\u00e9n por el bosque izquierdo por parte de Mart\u00edn Maldonado. El jonr\u00f3n contra Mengden recorri\u00f3 una distancia de 381 pies a 99.1 millas por hora.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify\">Sin embargo, los visitantes igualaron las acciones en el quinto ante Grant Gavin, cuando Hanser Alberto abri\u00f3 con doble al prado izquierdo, pas\u00f3 a la antesala con rodado de Carlos Jorge a la inicial y entr\u00f3 en carrera con imparable de Julio Carreras al jard\u00edn izquierdo. Un cuadrangular de Johan Rojas por ese mismo lado del terreno igual\u00f3 la pizarra.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify\">En la parte baja del quinto, C\u00e9sar Prieto tom\u00f3 boleto frente a Reid Birlingmair, se estaf\u00f3 la intermedia y volvi\u00f3 a dar la ventaja a los escarlatas tras indiscutible remolcador de Erik Gonz\u00e1lez al bosque izquierdo. Pero los francomacorisanos tomaron el comando con otras dos rayitas en el s\u00e9ptimo.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify\">En el octavo, los escogidistas atacaron a Reymin Gudu\u00e1n con infield-hit de Erik Gonz\u00e1lez por segunda, transferencia a S\u00f3crates Brito y sencillo remolcador de Cordero al prado derecho. Una base por bolas intencional a Yamaico Navarro llen\u00f3 los sacos, y elevados de sacrificio consecutivos de Lake al jard\u00edn derecho y de Alexander Canario al izquierdo sumaron otras dos para los locales.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify\">Gavin se present\u00f3 en 4.2 cap\u00edtulos de tres carreras, terminando sin decisi\u00f3n. El lanzador ganador fue Luis Guerrero (1-0) al tirar en el octavo en blanco con un ponche. El rev\u00e9s fue para Gudu\u00e1n (0-2). El salvamento se lo apunt\u00f3 Jimmy Cordero (1) al presentarse en el noveno y conseguir un ponche.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify\">Por los rojos, Lake se fue de 2-1, con cuadrangular, tres empujadas, una anotada y una transferencia; Maldonado, de 2-1, con jonr\u00f3n, una producida y una anotada; Gonz\u00e1lez, de 4-2, con una remolcada y una anotada, y Cordero, de 3-2, con una impulsada y una anotada. Por los nordestanos, Rojas bate\u00f3 de 4-2, con cuadrangular, cuatro empujadas y una anotada, y Carreras, de 3-2, con una producida y una anotada.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify\">Con el triunfo, el Escogido tiene marca de (3-4) y los Gigantes (0-5) contin\u00faan sin conocer la victoria.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify\">Los Leones volver\u00e1n este mi\u00e9rcoles a San Francisco de Macor\u00eds a visitar a los Gigantes en el estadio Juli\u00e1n Javier a las 7:00 de la noche.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA.COM |\u00a0REP\u00daBLICA DOMINICANA SANTO DOMINGO &#8211; Por segundo d\u00eda consecutivo, los Leones del Escogido derrotaron a los Gigantes del Cibao, esta vez 7-5 en el estadio Quisqueya Juan Marichal, con lo que extienden a&#46;&#46;&#46;<\/p>\n","protected":false},"author":89,"featured_media":76175,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"no","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[688,16],"tags":[685,3708,765,1476,686,4337,715,2706],"class_list":["post-76174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beisbol","category-deportes","tag-beisbol-dominicano","tag-junior-lake","tag-leones-del-escogido","tag-lidom","tag-liga-dominicana-de-beisbol-profesional","tag-martin-maldonado","tag-peloteros-dominicanos","tag-peloteros-puertorriquenos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escogido se impone a Gigantes con jonrones de Lake y Maldonado - Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escogido se impone a Gigantes con jonrones de Lake y Maldonado\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA.COM |\u00a0REP\u00daBLICA DOMINICANA SANTO DOMINGO &#8211; Por segundo d\u00eda consecutivo, los Leones del Escogido derrotaron a los Gigantes del Cibao, esta vez 7-5 en el estadio Quisqueya Juan Marichal, con lo que extienden a&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/\" \/>\n<meta property=\"og:site_name\" content=\"Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-29T17:04:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/10\/Junior-Lake-Martin-Maldonado-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1510\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ad\u00e1n Soriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@adansoriano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ad\u00e1n Soriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/\"},\"author\":{\"name\":\"Ad\u00e1n Soriano\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f\"},\"headline\":\"Escogido se impone a Gigantes con jonrones de Lake y Maldonado\",\"datePublished\":\"2025-10-29T17:04:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/\"},\"wordCount\":497,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/10\/Junior-Lake-Martin-Maldonado-scaled.jpg\",\"keywords\":[\"B\u00e9isbol Dominicano\",\"Junior Lake\",\"Leones del Escogido\",\"LIDOM\",\"Liga Dominicana de B\u00e9isbol Profesional\",\"Mart\u00edn Maldonado\",\"Peloteros Dominicanos\",\"Peloteros Puertorrique\u00f1os\"],\"articleSection\":[\"Beisbol\",\"Deportes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/\",\"name\":\"Escogido se impone a Gigantes con jonrones de Lake y Maldonado - Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/10\/Junior-Lake-Martin-Maldonado-scaled.jpg\",\"datePublished\":\"2025-10-29T17:04:32+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/10\/Junior-Lake-Martin-Maldonado-scaled.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/10\/Junior-Lake-Martin-Maldonado-scaled.jpg\",\"width\":2560,\"height\":1510},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/principal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escogido se impone a Gigantes con jonrones de Lake y Maldonado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/\",\"name\":\"Noti-America.com\",\"description\":\"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f\",\"name\":\"Ad\u00e1n Soriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"caption\":\"Ad\u00e1n Soriano\"},\"description\":\"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva\",\"sameAs\":[\"https:\/\/x.com\/adansoriano\"],\"url\":\"https:\/\/noti-america.com\/site\/principal\/author\/asoriano\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escogido se impone a Gigantes con jonrones de Lake y Maldonado - Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/","og_locale":"es_ES","og_type":"article","og_title":"Escogido se impone a Gigantes con jonrones de Lake y Maldonado","og_description":"NOTI-AMERICA.COM |\u00a0REP\u00daBLICA DOMINICANA SANTO DOMINGO &#8211; Por segundo d\u00eda consecutivo, los Leones del Escogido derrotaron a los Gigantes del Cibao, esta vez 7-5 en el estadio Quisqueya Juan Marichal, con lo que extienden a&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/","og_site_name":"Noti-America.com","article_published_time":"2025-10-29T17:04:32+00:00","og_image":[{"width":2560,"height":1510,"url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/10\/Junior-Lake-Martin-Maldonado-scaled.jpg","type":"image\/jpeg"}],"author":"Ad\u00e1n Soriano","twitter_card":"summary_large_image","twitter_creator":"@adansoriano","twitter_misc":{"Escrito por":"Ad\u00e1n Soriano","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/"},"author":{"name":"Ad\u00e1n Soriano","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f"},"headline":"Escogido se impone a Gigantes con jonrones de Lake y Maldonado","datePublished":"2025-10-29T17:04:32+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/"},"wordCount":497,"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/10\/Junior-Lake-Martin-Maldonado-scaled.jpg","keywords":["B\u00e9isbol Dominicano","Junior Lake","Leones del Escogido","LIDOM","Liga Dominicana de B\u00e9isbol Profesional","Mart\u00edn Maldonado","Peloteros Dominicanos","Peloteros Puertorrique\u00f1os"],"articleSection":["Beisbol","Deportes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/","url":"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/","name":"Escogido se impone a Gigantes con jonrones de Lake y Maldonado - Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/10\/Junior-Lake-Martin-Maldonado-scaled.jpg","datePublished":"2025-10-29T17:04:32+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/#primaryimage","url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/10\/Junior-Lake-Martin-Maldonado-scaled.jpg","contentUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/10\/Junior-Lake-Martin-Maldonado-scaled.jpg","width":2560,"height":1510},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/principal\/2025\/10\/29\/escogido-se-impone-a-gigantes-con-jonrones-de-lake-y-maldonado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/principal\/"},{"@type":"ListItem","position":2,"name":"Escogido se impone a Gigantes con jonrones de Lake y Maldonado"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/principal\/#website","url":"https:\/\/noti-america.com\/site\/principal\/","name":"Noti-America.com","description":"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f","name":"Ad\u00e1n Soriano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","caption":"Ad\u00e1n Soriano"},"description":"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva","sameAs":["https:\/\/x.com\/adansoriano"],"url":"https:\/\/noti-america.com\/site\/principal\/author\/asoriano\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/76174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/comments?post=76174"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/76174\/revisions"}],"predecessor-version":[{"id":76224,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/76174\/revisions\/76224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media\/76175"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media?parent=76174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/categories?post=76174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/tags?post=76174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}