{"id":74245,"date":"2025-09-25T20:16:26","date_gmt":"2025-09-26T00:16:26","guid":{"rendered":"https:\/\/noti-america.com\/site\/principal\/?p=74245"},"modified":"2025-09-25T20:16:26","modified_gmt":"2025-09-26T00:16:26","slug":"gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/","title":{"rendered":"Gigantes del Cibao incorporan cinco agentes libres a su equipo"},"content":{"rendered":"<p>NOTI-AMERICA.COM <em>|\u00a0<\/em>REP\u00daBLICA DOMINICANA<\/p>\n<p style=\"text-align: justify\">SAN FRANCISCO DE MACOR\u00cdS &#8211; Los Gigantes del Cibao han dado un paso firme en la preparaci\u00f3n para la pr\u00f3xima temporada invernal al anunciar la incorporaci\u00f3n de cinco nuevos jugadores como agentes libres.<\/p>\n<p style=\"text-align: justify\">La gerencia de operaciones del conjunto francomacorisano busca mantener un n\u00facleo competitivo y lleno de talento, sumando a: Jos\u00e9 Torres, Frank Rodr\u00edguez, Joseilyn Gonz\u00e1lez, Christopher Molina y Deivi Mu\u00f1oz.<\/p>\n<p style=\"text-align: justify\">\u201cEstamos muy satisfechos con la llegada de estos j\u00f3venes. Confiamos en que su talento y deseo de competir ser\u00e1n claves para fortalecer la profundidad de nuestro roster\u201d, expres\u00f3 Jaylon Pimentel, gerente de operaciones del equipo.<\/p>\n<h3 style=\"text-align: justify\"><strong>Perfiles de las nuevas adquisiciones<\/strong><\/h3>\n<p style=\"text-align: justify\">Los nuevos integrantes aportan experiencia reciente en ligas menores de Estados Unidos y otras ligas de la regi\u00f3n:<\/p>\n<div class=\"horizontal-scroll-wrapper\">\n<div class=\"table-block-component\">\n<div class=\"table-block has-export-button\">\n<div class=\"table-content not-end-of-paragraph\" style=\"text-align: justify\">\n<table>\n<thead>\n<tr>\n<td>Jugador<\/td>\n<td>Posici\u00f3n<\/td>\n<td>Origen<\/td>\n<td>Experiencia Reciente (2025)<\/td>\n<td>Estad\u00edsticas Destacadas<\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Jos\u00e9 Torres<\/td>\n<td>Campocorto (25 a\u00f1os)<\/td>\n<td>Guayub\u00edn<\/td>\n<td>Doble A y Triple A (Rockies)<\/td>\n<td>.242 de promedio, 15 HR y 55 remolcadas.<\/td>\n<\/tr>\n<tr>\n<td>Frank Rodr\u00edguez<\/td>\n<td>Receptor (23 a\u00f1os)<\/td>\n<td>Santiago<\/td>\n<td>Clase A Avanzada, Doble A y Triple A (Dodgers)<\/td>\n<td>Promedio de .218 con 3 HR y 18 remolcadas.<\/td>\n<\/tr>\n<tr>\n<td>Joseilyn Gonz\u00e1lez<\/td>\n<td>Lanzador Derecho (23 a\u00f1os)<\/td>\n<td>Santiago\/La Enea<\/td>\n<td>Clase A Avanzada (Dodgers)<\/td>\n<td>R\u00e9cord de 5-2, efectividad de 2.80 en 45 entradas.<\/td>\n<\/tr>\n<tr>\n<td>Christopher Molina<\/td>\n<td>Lanzador Derecho (28 a\u00f1os)<\/td>\n<td>Moca<\/td>\n<td>Liga Mayor de Venezuela y Liga de Verano RD<\/td>\n<td>&#8211;<\/td>\n<\/tr>\n<tr>\n<td>Deivi Mu\u00f1oz<\/td>\n<td>Infielder (25 a\u00f1os)<\/td>\n<td>San Crist\u00f3bal<\/td>\n<td>Liga Mayor de Venezuela<\/td>\n<td>Promedio de .384, 1 HR y 18 remolcadas.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA.COM |\u00a0REP\u00daBLICA DOMINICANA SAN FRANCISCO DE MACOR\u00cdS &#8211; Los Gigantes del Cibao han dado un paso firme en la preparaci\u00f3n para la pr\u00f3xima temporada invernal al anunciar la incorporaci\u00f3n de cinco nuevos jugadores como&#46;&#46;&#46;<\/p>\n","protected":false},"author":89,"featured_media":74246,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"no","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[688,16],"tags":[685,713,1476,686,715],"class_list":["post-74245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beisbol","category-deportes","tag-beisbol-dominicano","tag-gigantes-del-cibao","tag-lidom","tag-liga-dominicana-de-beisbol-profesional","tag-peloteros-dominicanos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gigantes del Cibao incorporan cinco agentes libres a su equipo - Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gigantes del Cibao incorporan cinco agentes libres a su equipo\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA.COM |\u00a0REP\u00daBLICA DOMINICANA SAN FRANCISCO DE MACOR\u00cdS &#8211; Los Gigantes del Cibao han dado un paso firme en la preparaci\u00f3n para la pr\u00f3xima temporada invernal al anunciar la incorporaci\u00f3n de cinco nuevos jugadores como&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/\" \/>\n<meta property=\"og:site_name\" content=\"Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-26T00:16:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/09\/Contrataciones-Gigantes-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2028\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ad\u00e1n Soriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@adansoriano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ad\u00e1n Soriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/\"},\"author\":{\"name\":\"Ad\u00e1n Soriano\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f\"},\"headline\":\"Gigantes del Cibao incorporan cinco agentes libres a su equipo\",\"datePublished\":\"2025-09-26T00:16:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/\"},\"wordCount\":252,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/09\/Contrataciones-Gigantes-scaled.jpg\",\"keywords\":[\"B\u00e9isbol Dominicano\",\"Gigantes del Cibao\",\"LIDOM\",\"Liga Dominicana de B\u00e9isbol Profesional\",\"Peloteros Dominicanos\"],\"articleSection\":[\"Beisbol\",\"Deportes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/\",\"name\":\"Gigantes del Cibao incorporan cinco agentes libres a su equipo - Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/09\/Contrataciones-Gigantes-scaled.jpg\",\"datePublished\":\"2025-09-26T00:16:26+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/09\/Contrataciones-Gigantes-scaled.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/09\/Contrataciones-Gigantes-scaled.jpg\",\"width\":2560,\"height\":2028},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/principal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gigantes del Cibao incorporan cinco agentes libres a su equipo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/\",\"name\":\"Noti-America.com\",\"description\":\"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f\",\"name\":\"Ad\u00e1n Soriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"caption\":\"Ad\u00e1n Soriano\"},\"description\":\"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva\",\"sameAs\":[\"https:\/\/x.com\/adansoriano\"],\"url\":\"https:\/\/noti-america.com\/site\/principal\/author\/asoriano\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gigantes del Cibao incorporan cinco agentes libres a su equipo - Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/","og_locale":"es_ES","og_type":"article","og_title":"Gigantes del Cibao incorporan cinco agentes libres a su equipo","og_description":"NOTI-AMERICA.COM |\u00a0REP\u00daBLICA DOMINICANA SAN FRANCISCO DE MACOR\u00cdS &#8211; Los Gigantes del Cibao han dado un paso firme en la preparaci\u00f3n para la pr\u00f3xima temporada invernal al anunciar la incorporaci\u00f3n de cinco nuevos jugadores como&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/","og_site_name":"Noti-America.com","article_published_time":"2025-09-26T00:16:26+00:00","og_image":[{"width":2560,"height":2028,"url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/09\/Contrataciones-Gigantes-scaled.jpg","type":"image\/jpeg"}],"author":"Ad\u00e1n Soriano","twitter_card":"summary_large_image","twitter_creator":"@adansoriano","twitter_misc":{"Escrito por":"Ad\u00e1n Soriano","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/"},"author":{"name":"Ad\u00e1n Soriano","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f"},"headline":"Gigantes del Cibao incorporan cinco agentes libres a su equipo","datePublished":"2025-09-26T00:16:26+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/"},"wordCount":252,"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/09\/Contrataciones-Gigantes-scaled.jpg","keywords":["B\u00e9isbol Dominicano","Gigantes del Cibao","LIDOM","Liga Dominicana de B\u00e9isbol Profesional","Peloteros Dominicanos"],"articleSection":["Beisbol","Deportes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/","url":"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/","name":"Gigantes del Cibao incorporan cinco agentes libres a su equipo - Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/09\/Contrataciones-Gigantes-scaled.jpg","datePublished":"2025-09-26T00:16:26+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/#primaryimage","url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/09\/Contrataciones-Gigantes-scaled.jpg","contentUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/09\/Contrataciones-Gigantes-scaled.jpg","width":2560,"height":2028},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/principal\/2025\/09\/25\/gigantes-del-cibao-incorporan-cinco-agentes-libres-a-su-equipo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/principal\/"},{"@type":"ListItem","position":2,"name":"Gigantes del Cibao incorporan cinco agentes libres a su equipo"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/principal\/#website","url":"https:\/\/noti-america.com\/site\/principal\/","name":"Noti-America.com","description":"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f","name":"Ad\u00e1n Soriano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","caption":"Ad\u00e1n Soriano"},"description":"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva","sameAs":["https:\/\/x.com\/adansoriano"],"url":"https:\/\/noti-america.com\/site\/principal\/author\/asoriano\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/74245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/comments?post=74245"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/74245\/revisions"}],"predecessor-version":[{"id":74256,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/74245\/revisions\/74256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media\/74246"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media?parent=74245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/categories?post=74245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/tags?post=74245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}