{"id":7390,"date":"2021-11-20T16:35:59","date_gmt":"2021-11-20T20:35:59","guid":{"rendered":"https:\/\/noti-america.com\/site\/principal\/?p=7390"},"modified":"2021-11-20T16:35:59","modified_gmt":"2021-11-20T20:35:59","slug":"en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/","title":{"rendered":"En Ecuador se d\u00edo el encuentro de los Pueblos M\u00e1gicos"},"content":{"rendered":"<p>REDACCI\u00d3N NOTI AM\u00c9RICA (ECUADOR)<\/p>\n<div style=\"width: 2058px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.turismo.gob.ec\/wp-content\/uploads\/2021\/11\/encuentro.jpg\" alt=\"\" width=\"2048\" height=\"1152\" \/><p class=\"wp-caption-text\">Encuentro de pueblos m\u00e1gicos<\/p><\/div>\n<p style=\"text-align: justify\">Con la presencia de autoridades cantonales y provinciales, el pasado jueves inici\u00f3 el Encuentro de Pueblos M\u00e1gicos del Ecuador, evento de dos d\u00edas que se realiz\u00f3 en Azogues, con la presencia de los actores tur\u00edsticos de nueve de las localidades que han alcanzado esta denominaci\u00f3n.<\/p>\n<p style=\"text-align: justify\">Romel Sarmiento, alcalde de Azogues, dio la bienvenida a los presentes a este encuentro que busca aportar al desarrollo tur\u00edstico de los destinos participantes, a trav\u00e9s de un programa que permita generar un intercambio de conocimientos, exponer la riqueza tur\u00edstica de los cantones declarados como Pueblos M\u00e1gicos del Ecuador y\u00a0 fomentar alianzas y negocios estrat\u00e9gicos entre prestadores de servicios tur\u00edsticos de estas localidades.<\/p>\n<p style=\"text-align: justify\">Juan Jos\u00e9 N\u00fa\u00f1ez del Arco, en representaci\u00f3n de la Direcci\u00f3n Zonal 6 del Ministerio de Turismo, felicit\u00f3 al Municipio de Azogues y a los organizadores del encuentro, ratificando el apoyo de esta cartera de Estado a esta iniciativa en favor de la reactivaci\u00f3n tur\u00edstica en el pa\u00eds. Se\u00f1al\u00f3 que el programa Pueblos M\u00e1gicos Ecuador 4 Mundos, \u00a0busca\u00a0 fomentar la competitividad y facilitar la implementaci\u00f3n de acciones de fortalecimiento en el \u00e1mbito tur\u00edstico, considerando que el cumplimiento de estas condiciones b\u00e1sicas afianzan las iniciativas de inversi\u00f3n p\u00fablica y privada.<\/p>\n<p style=\"text-align: justify\">Los cantones que participaron en el \u201cEncuentro de Pueblos M\u00e1gicos del Ecuador, Azogues 2021\u201d son Shushufindi, Alausi, Calvas, El Chaco, Saraguro, Azogues, Chordeleg, Lago Agrio y Cotacachi.\u00a0 Los representantes de cada uno de ellos exponen lo m\u00e1s destacado de su oferta cultural y tur\u00edstica en los diferentes eventos que son parte del encuentro, como la casa abierta, la rueda de negocios para prestadores de servicios tur\u00edsticos y el conversatorio a llevarse a cabo en el Sal\u00f3n de la Ciudad de Azogues, en el que tambi\u00e9n se ofreci\u00f3 la conferencia \u201cMarketing de Destinos\u201d a cargo de Mar\u00eda Ang\u00e9lica Le\u00f3n, directora ejecutiva de la Fundaci\u00f3n Municipal \u201cTurismo para Cuenca\u201d.<\/p>\n<p style=\"text-align: justify\">Paralelamente, el GAD de Azogues durante el encuentro ofreci\u00f3 , recorridos a algunos de los atractivos tur\u00edsticos m\u00e1s destacados del cant\u00f3n, como son las minas de azogue (mercurio) conocidas como los boquerones de la parroquia Luis Cordero; un taller de producci\u00f3n de chocolate artesanal y una granja agroecol\u00f3gica donde se puede realizar pesca deportiva, cosecha de productos org\u00e1nicos y apicultura.<\/p>\n<p style=\"text-align: justify\">El \u201cEncuentro de Pueblos M\u00e1gicos de Ecuador, Azogues 2021\u201d finaliz\u00f3 el viernes 19 de noviembre con un fam trip en el que los participantes visitaron la parroquia de Cojitambo, con atractivos como una zona arqueol\u00f3gica, un mirador y paredes para escalada.<\/p>\n<p><strong>Fuente: Ministerio de Turismo<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>REDACCI\u00d3N NOTI AM\u00c9RICA (ECUADOR) Con la presencia de autoridades cantonales y provinciales, el pasado jueves inici\u00f3 el Encuentro de Pueblos M\u00e1gicos del Ecuador, evento de dos d\u00edas que se realiz\u00f3 en Azogues, con la&#46;&#46;&#46;<\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10219548024599422_1632221337088128":"","twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-7390","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>En Ecuador se d\u00edo el encuentro de los Pueblos M\u00e1gicos - Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Ecuador se d\u00edo el encuentro de los Pueblos M\u00e1gicos\" \/>\n<meta property=\"og:description\" content=\"REDACCI\u00d3N NOTI AM\u00c9RICA (ECUADOR) Con la presencia de autoridades cantonales y provinciales, el pasado jueves inici\u00f3 el Encuentro de Pueblos M\u00e1gicos del Ecuador, evento de dos d\u00edas que se realiz\u00f3 en Azogues, con la&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/\" \/>\n<meta property=\"og:site_name\" content=\"Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-20T20:35:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.turismo.gob.ec\/wp-content\/uploads\/2021\/11\/encuentro.jpg\" \/>\n<meta name=\"author\" content=\"Gregory Quintana Montiel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gdgregori1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gregory Quintana Montiel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/\"},\"author\":{\"name\":\"Gregory Quintana Montiel\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e\"},\"headline\":\"En Ecuador se d\u00edo el encuentro de los Pueblos M\u00e1gicos\",\"datePublished\":\"2021-11-20T20:35:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/\"},\"wordCount\":472,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.turismo.gob.ec\/wp-content\/uploads\/2021\/11\/encuentro.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/\",\"name\":\"En Ecuador se d\u00edo el encuentro de los Pueblos M\u00e1gicos - Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.turismo.gob.ec\/wp-content\/uploads\/2021\/11\/encuentro.jpg\",\"datePublished\":\"2021-11-20T20:35:59+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#primaryimage\",\"url\":\"https:\/\/www.turismo.gob.ec\/wp-content\/uploads\/2021\/11\/encuentro.jpg\",\"contentUrl\":\"https:\/\/www.turismo.gob.ec\/wp-content\/uploads\/2021\/11\/encuentro.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/principal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Ecuador se d\u00edo el encuentro de los Pueblos M\u00e1gicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/\",\"name\":\"Noti-America.com\",\"description\":\"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e\",\"name\":\"Gregory Quintana Montiel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g\",\"caption\":\"Gregory Quintana Montiel\"},\"description\":\"Licenciatura en Ciencias de la Comunicaci\u00f3n Social, egresado en la Especializaci\u00f3n Derecho Ambiental Desarrollo Sostenible y Sustentable, Miembro de la Comunidad de profesionales y experto para Latinoam\u00e9rica y el Caribe en Gesti\u00f3n por Resultado en el Desarrollo (COPLAC - GpRD) del Banco Interamericano de Desarrollo, experiencia en medios radiales y escritos.\",\"sameAs\":[\"https:\/\/x.com\/gdgregori1\",\"gquintana\"],\"url\":\"https:\/\/noti-america.com\/site\/principal\/author\/gquintana\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"En Ecuador se d\u00edo el encuentro de los Pueblos M\u00e1gicos - Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/","og_locale":"es_ES","og_type":"article","og_title":"En Ecuador se d\u00edo el encuentro de los Pueblos M\u00e1gicos","og_description":"REDACCI\u00d3N NOTI AM\u00c9RICA (ECUADOR) Con la presencia de autoridades cantonales y provinciales, el pasado jueves inici\u00f3 el Encuentro de Pueblos M\u00e1gicos del Ecuador, evento de dos d\u00edas que se realiz\u00f3 en Azogues, con la&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/","og_site_name":"Noti-America.com","article_published_time":"2021-11-20T20:35:59+00:00","og_image":[{"url":"https:\/\/www.turismo.gob.ec\/wp-content\/uploads\/2021\/11\/encuentro.jpg","type":"","width":"","height":""}],"author":"Gregory Quintana Montiel","twitter_card":"summary_large_image","twitter_creator":"@gdgregori1","twitter_misc":{"Escrito por":"Gregory Quintana Montiel","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/"},"author":{"name":"Gregory Quintana Montiel","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e"},"headline":"En Ecuador se d\u00edo el encuentro de los Pueblos M\u00e1gicos","datePublished":"2021-11-20T20:35:59+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/"},"wordCount":472,"commentCount":0,"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.turismo.gob.ec\/wp-content\/uploads\/2021\/11\/encuentro.jpg","articleSection":["Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/","url":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/","name":"En Ecuador se d\u00edo el encuentro de los Pueblos M\u00e1gicos - Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.turismo.gob.ec\/wp-content\/uploads\/2021\/11\/encuentro.jpg","datePublished":"2021-11-20T20:35:59+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#primaryimage","url":"https:\/\/www.turismo.gob.ec\/wp-content\/uploads\/2021\/11\/encuentro.jpg","contentUrl":"https:\/\/www.turismo.gob.ec\/wp-content\/uploads\/2021\/11\/encuentro.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/20\/en-ecuador-se-dio-el-encuentro-de-los-pueblos-magicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/principal\/"},{"@type":"ListItem","position":2,"name":"En Ecuador se d\u00edo el encuentro de los Pueblos M\u00e1gicos"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/principal\/#website","url":"https:\/\/noti-america.com\/site\/principal\/","name":"Noti-America.com","description":"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e","name":"Gregory Quintana Montiel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g","caption":"Gregory Quintana Montiel"},"description":"Licenciatura en Ciencias de la Comunicaci\u00f3n Social, egresado en la Especializaci\u00f3n Derecho Ambiental Desarrollo Sostenible y Sustentable, Miembro de la Comunidad de profesionales y experto para Latinoam\u00e9rica y el Caribe en Gesti\u00f3n por Resultado en el Desarrollo (COPLAC - GpRD) del Banco Interamericano de Desarrollo, experiencia en medios radiales y escritos.","sameAs":["https:\/\/x.com\/gdgregori1","gquintana"],"url":"https:\/\/noti-america.com\/site\/principal\/author\/gquintana\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/7390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/comments?post=7390"}],"version-history":[{"count":0,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/7390\/revisions"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media?parent=7390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/categories?post=7390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/tags?post=7390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}