{"id":6933,"date":"2021-11-05T16:38:48","date_gmt":"2021-11-05T20:38:48","guid":{"rendered":"https:\/\/noti-america.com\/site\/principal\/?p=6933"},"modified":"2021-11-05T16:38:48","modified_gmt":"2021-11-05T20:38:48","slug":"las-breeders-cup-tendran-jugadas-en-rd","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/","title":{"rendered":"Las Breeders Cup tendr\u00e1n jugadas en RD"},"content":{"rendered":"<p style=\"text-align: justify\">SANTO DOMINGO &#8211; Las autoridades del Hip\u00f3dromo V Centenario anunciaron este martes que se estar\u00e1n recibiendo apuestas a las carreras del Breeders Cup, que ser\u00e1n este viernes 5 y s\u00e1bado 6 de noviembre en el Hip\u00f3dromo Del Mar, en California, Estados Unidos.<\/p>\n<p style=\"text-align: justify\">Las carreras del Breeders Cup, son una serie de eventos que tienen mayor importancia en la h\u00edpica norteamericana y mundial, que este a\u00f1o constar\u00e1 de 14 carreras cl\u00e1sicas.<\/p>\n<p style=\"text-align: justify\">Las apuestas se recibir\u00e1n a trav\u00e9s del sistema simulcasting, que tiene el V Centenario con diferentes hip\u00f3dromos de Estados Unidos y el Camarero de Puerto Rico. Las carreras ser\u00e1n transmitidas a trav\u00e9s de Digital Visi\u00f3n, canal 63.<\/p>\n<p style=\"text-align: justify\">Los precios anunciados para las jugadas ser\u00e1n los siguientes: $60 al pool de seis, win, place, show, exacta, pentafecta y dupleta. De igual forma la quiniela costar\u00e1 $120 pesos, la trifecta $30, al igual que los pooles de tres, cuatro y cinco, de su lado la superfecta tendr\u00e1 valor de $10.<\/p>\n<p style=\"text-align: justify\">En Del Mar los valores ser\u00e1n estos: $12 pesos al pool de seis, $120 al win, place, show, quiniela y dupleta. $60 costar\u00e1n la exacta y p10; la trifecta, pentafecta, pool de tres, cuatro y cinco estar\u00e1n en $30; $10 costar\u00e1 la superfecta.<\/p>\n<p style=\"text-align: justify\"><strong>Fuente: Rafael D\u00edaz<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO &#8211; Las autoridades del Hip\u00f3dromo V Centenario anunciaron este martes que se estar\u00e1n recibiendo apuestas a las carreras del Breeders Cup, que ser\u00e1n este viernes 5 y s\u00e1bado 6 de noviembre en&#46;&#46;&#46;<\/p>\n","protected":false},"author":89,"featured_media":6934,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10219548024599422_1632221337088128":"","twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[16],"tags":[844,845,711],"class_list":["post-6933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-breeders-cup","tag-hipismo","tag-hipodromo-v-centenario"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Las Breeders Cup tendr\u00e1n jugadas en RD - Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las Breeders Cup tendr\u00e1n jugadas en RD\" \/>\n<meta property=\"og:description\" content=\"SANTO DOMINGO &#8211; Las autoridades del Hip\u00f3dromo V Centenario anunciaron este martes que se estar\u00e1n recibiendo apuestas a las carreras del Breeders Cup, que ser\u00e1n este viernes 5 y s\u00e1bado 6 de noviembre en&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/\" \/>\n<meta property=\"og:site_name\" content=\"Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-05T20:38:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2021\/11\/Breeders-Cup.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"930\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ad\u00e1n Soriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@adansoriano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ad\u00e1n Soriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/\"},\"author\":{\"name\":\"Ad\u00e1n Soriano\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f\"},\"headline\":\"Las Breeders Cup tendr\u00e1n jugadas en RD\",\"datePublished\":\"2021-11-05T20:38:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/\"},\"wordCount\":218,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2021\/11\/Breeders-Cup.jpg\",\"keywords\":[\"Breeders Cup\",\"Hipismo\",\"Hip\u00f3dromo V Centenario\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/\",\"name\":\"Las Breeders Cup tendr\u00e1n jugadas en RD - Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2021\/11\/Breeders-Cup.jpg\",\"datePublished\":\"2021-11-05T20:38:48+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2021\/11\/Breeders-Cup.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2021\/11\/Breeders-Cup.jpg\",\"width\":1280,\"height\":930},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/principal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las Breeders Cup tendr\u00e1n jugadas en RD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/\",\"name\":\"Noti-America.com\",\"description\":\"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f\",\"name\":\"Ad\u00e1n Soriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"caption\":\"Ad\u00e1n Soriano\"},\"description\":\"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva\",\"sameAs\":[\"https:\/\/x.com\/adansoriano\"],\"url\":\"https:\/\/noti-america.com\/site\/principal\/author\/asoriano\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Las Breeders Cup tendr\u00e1n jugadas en RD - Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/","og_locale":"es_ES","og_type":"article","og_title":"Las Breeders Cup tendr\u00e1n jugadas en RD","og_description":"SANTO DOMINGO &#8211; Las autoridades del Hip\u00f3dromo V Centenario anunciaron este martes que se estar\u00e1n recibiendo apuestas a las carreras del Breeders Cup, que ser\u00e1n este viernes 5 y s\u00e1bado 6 de noviembre en&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/","og_site_name":"Noti-America.com","article_published_time":"2021-11-05T20:38:48+00:00","og_image":[{"width":1280,"height":930,"url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2021\/11\/Breeders-Cup.jpg","type":"image\/jpeg"}],"author":"Ad\u00e1n Soriano","twitter_card":"summary_large_image","twitter_creator":"@adansoriano","twitter_misc":{"Escrito por":"Ad\u00e1n Soriano","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/"},"author":{"name":"Ad\u00e1n Soriano","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f"},"headline":"Las Breeders Cup tendr\u00e1n jugadas en RD","datePublished":"2021-11-05T20:38:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/"},"wordCount":218,"commentCount":0,"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2021\/11\/Breeders-Cup.jpg","keywords":["Breeders Cup","Hipismo","Hip\u00f3dromo V Centenario"],"articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/","url":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/","name":"Las Breeders Cup tendr\u00e1n jugadas en RD - Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2021\/11\/Breeders-Cup.jpg","datePublished":"2021-11-05T20:38:48+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#primaryimage","url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2021\/11\/Breeders-Cup.jpg","contentUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2021\/11\/Breeders-Cup.jpg","width":1280,"height":930},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/principal\/2021\/11\/05\/las-breeders-cup-tendran-jugadas-en-rd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/principal\/"},{"@type":"ListItem","position":2,"name":"Las Breeders Cup tendr\u00e1n jugadas en RD"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/principal\/#website","url":"https:\/\/noti-america.com\/site\/principal\/","name":"Noti-America.com","description":"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/e8cde3d87079627d077589321667269f","name":"Ad\u00e1n Soriano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","caption":"Ad\u00e1n Soriano"},"description":"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva","sameAs":["https:\/\/x.com\/adansoriano"],"url":"https:\/\/noti-america.com\/site\/principal\/author\/asoriano\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/6933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/comments?post=6933"}],"version-history":[{"count":0,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/6933\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media\/6934"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media?parent=6933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/categories?post=6933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/tags?post=6933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}