{"id":64335,"date":"2025-03-21T15:03:22","date_gmt":"2025-03-21T19:03:22","guid":{"rendered":"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/"},"modified":"2025-03-21T16:03:39","modified_gmt":"2025-03-21T20:03:39","slug":"el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/","title":{"rendered":"El legado de un j\u00f3ven periodista  Edwin Sport Hevia Cadevilla"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-64336 aligncenter\" src=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742477739329-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742477739329-200x300.jpg 200w, https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742477739329.jpg 533w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/p>\n<p>El d\u00eda que conoc\u00ed a Edwin usaba pantalones de jean, franela deportiva y esparc\u00eda su sonrisa\u00a0 por todo el sal\u00f3n de clases.<\/p>\n<p>\u00a8Sport, Sport\u00a8 todos le llamaban y es que a sus 17 a\u00f1os de edad ya cursaba sus primeros semestres en las escuela de Comunicaci\u00f3n de la Universidad Fermin Toro de Barquisimeto.<\/p>\n<p>Pasaban los d\u00edas y pod\u00eda observar que as\u00ed le segu\u00edan llamando, fue por eso que pregunt\u00e9 a\u00a0 los chamos\u00a0 con los que \u00e9l estudiaba \u00bf pero por qu\u00e9 le llaman as\u00ed?\u00a0 Y yo present\u00eda a ese j\u00f3ven muchacho le gustaba y lo disfrutaba.<\/p>\n<p>Fue entonces cuando Rino, Hermman y Jean Carlos me lo contaron: \u00a8Cuando lo conocimos ya otros as\u00ed le lo podaron le encanta simula narraciones en vivo y es que; profesora, Edwin se la pasa hablando de deportes, \u00e9l quiere ser periodista del \u00e1rea de deportes.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-64338\" src=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585890643-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585890643-300x200.jpg 300w, https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585890643-272x182.jpg 272w, https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585890643.jpg 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Sabiendo de \u00e9sta historia, no pude dejar de interactuar con este popular estudiante a quien le hice muchas preguntas para conocer de sus anhelos y quien muy entusiasmado, risue\u00f1o, lleno de esperanza y con su sonrisa me cont\u00f3 sobre \u00a0sus m\u00e1s anhelados sue\u00f1os.<\/p>\n<p>Como profesora experta en el \u00e1rea del desarrollo de destrezas y motivada por mi intuici\u00f3n acerca de sus ganas de crecer profesionalmente; \u00a0le dije: \u00a8Sigue narrando tus deportes aunque sea\u00a0 desde tu casa o en los pasillos de la universidad, n\u00fatrete de los saberes del deporte y ser\u00e1s grande\u00a8 y enfatic\u00e9: pero nunca olvides, (as\u00ed como inculqu\u00e9 a muchos)de d\u00f3nde vienes, conserva tu humildad. (y es que tambi\u00e9n \u00a0desde las aulas sol\u00eda hablarles de inculcar valores como la gratitud, honestidad,fraternidad\u2026)<\/p>\n<p>Pasaron los a\u00f1os y vi crecer a muchos, pero no como a Sport. \u00a0\u00a0\u00a0En su ascendencia llena de experiencias y peripecias ha tenido d\u00edas\u00a0 buenos y malos, pero eso s\u00ed, he visto como ha crecido profesionalmente; sobre todo muy espiritualmente.<\/p>\n<p>Tras correr el tiempo he observado que sus valores est\u00e1n intactos, siendo de esta forma ejemplo para otros que desde las aulas en \u00a0Escuelas de Periodismo nos muestran en que \u00e1rea \u00a0de la comunicaci\u00f3n social destacan.<\/p>\n<p>Con todo ese c\u00famulo de vivencias en la redacci\u00f3n y narraci\u00f3n de deportes como Beisbol. F\u00fatbol y otros deportes, ha sabido agradecer todas sus experiencias vividas y a todos a quienes le han acompa\u00f1ado , porque adem\u00e1s Edwin Sport Hevia Cadevilla \u00a0ha sabido\u00a0<strong>valorar el valor de valorar<\/strong>\u00a0personas, lugares hechos y cosas.<\/p>\n<p>Siendo as\u00ed el \u00fanico periodista que conozco que celebra cada paso de su camino.<\/p>\n<p>Recuerdo el d\u00eda en que celebr\u00f3 en su cuenta de Facebook resaltando y agradeciendo la a oportunidad que le dieron para narrar una gesta deportiva del futbol. Ese medio Tv Globo \u00a0le hizo un reportaje por su intervenci\u00f3n durante una transmisi\u00f3n en vivo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-64340 aligncenter\" src=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/Screenshot_20250321_143240_Facebook-135x300.jpg\" alt=\"\" width=\"135\" height=\"300\" srcset=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/Screenshot_20250321_143240_Facebook-135x300.jpg 135w, https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/Screenshot_20250321_143240_Facebook-461x1024.jpg 461w, https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/Screenshot_20250321_143240_Facebook-691x1536.jpg 691w, https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/Screenshot_20250321_143240_Facebook.jpg 720w\" sizes=\"auto, (max-width: 135px) 100vw, 135px\" \/><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/EdwinSportsHeviaCadevilla\/videos\/gran-recuerdo-brasiiil-hace-dos-a%C3%B1os-cumpl%C3%AD-un-gran-objetivo-y-un-notorio-sue%C3%B1o-\/2009730392869686\/?rdid=MQxIAKBh48i4cgHo\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.facebook.com\/EdwinSportsHeviaCadevilla\/videos\/gran-recuerdo-brasiiil-hace-dos-a%25C3%25B1os-cumpl%25C3%25AD-un-gran-objetivo-y-un-notorio-sue%25C3%25B1o-\/2009730392869686\/?rdid%3DMQxIAKBh48i4cgHo&amp;source=gmail&amp;ust=1742671294515000&amp;usg=AOvVaw2SMWP6TEvBJgqlge-FSuTk\">https:\/\/www.facebook.com\/EdwinSportsHeviaCadevilla\/videos\/gran-recuerdo-brasiiil-hace-dos-a%C3%B1os-cumpl%C3%AD-un-gran-objetivo-y-un-notorio-sue%C3%B1o-\/2009730392869686\/?rdid=MQxIAKBh48i4cgHo<\/a><\/p>\n<p>Otro d\u00eda, public\u00f3 en ese mismo perfil, un comentario alusivo a una franela que le regalaron del Club Atl\u00e9tico Mineiro \u00a0Lo que para uno no tiene significado, \u00a0para \u00e9l tiene un valor fundamental en su vida, reconociendo el valor de\u00a0 cada paso, cada acci\u00f3n y cada compromiso.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-64342\" src=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742477803683-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742477803683-300x200.jpg 300w, https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742477803683-272x182.jpg 272w, https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742477803683.jpg 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-64344\" src=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585912073-300x282.jpg\" alt=\"\" width=\"300\" height=\"282\" srcset=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585912073-300x282.jpg 300w, https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585912073.jpg 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Edwin Sport Hevia Cadevilla\u00a0 sabe \u00a0\u00a0valorar a quienes le han ayudado en su crecimiento y en su transitar por la vida del periodismo deportivo, \u00a0\u00a0como a sus maestros, profesores de la universidad,compa\u00f1eros de trabajo, y por supuesto a las personalidades del mundo deportivo como lo son los propios atletas, otros periodistas y narradores; pero hay alguien quien en siempre\u00a0 piensa, protege y honra, esa es su madre porque valora todo lo que ha hecho para ayudarlo con sus sue\u00f1os y metas; es ella, \u00a0quien siempre est\u00e1 presente en coraz\u00f3n y \u00a0alma cuando vive \u00a0sus inolvidables momentos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-64346\" src=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585928128-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585928128-300x225.jpg 300w, https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585928128.jpg 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Es impresionante como cada vez se suman m\u00e1s seguidores en sus cuentas Instagram y Facebook donde continua publicando el valor de cada momento vivido en su desarrollo del periodismo deportivo cumpliendo as\u00ed con su labor de informar y al mismo tiempo de incentivar a otros a seguir siendo m\u00e1s humanos, m\u00e1s honestos y agradecidos de la vida misma.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda que conoc\u00ed a Edwin usaba pantalones de jean, franela deportiva y esparc\u00eda su sonrisa\u00a0 por todo el sal\u00f3n de clases. \u00a8Sport, Sport\u00a8 todos le llamaban y es que a sus 17 a\u00f1os&#46;&#46;&#46;<\/p>\n","protected":false},"author":123,"featured_media":64338,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10219548024599422_1632221337088128":"","twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[202,16,100],"tags":[],"class_list":["post-64335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suramerica","category-deportes","category-venezuela"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El legado de un j\u00f3ven periodista Edwin Sport Hevia Cadevilla - Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El legado de un j\u00f3ven periodista Edwin Sport Hevia Cadevilla\" \/>\n<meta property=\"og:description\" content=\"El d\u00eda que conoc\u00ed a Edwin usaba pantalones de jean, franela deportiva y esparc\u00eda su sonrisa\u00a0 por todo el sal\u00f3n de clases. \u00a8Sport, Sport\u00a8 todos le llamaban y es que a sus 17 a\u00f1os&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/\" \/>\n<meta property=\"og:site_name\" content=\"Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-21T19:03:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-21T20:03:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585890643.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana Barcenas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Barcenas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/\"},\"author\":{\"name\":\"Ana Barcenas\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/8b8c404aee9721f021dea30cc9019d8d\"},\"headline\":\"El legado de un j\u00f3ven periodista Edwin Sport Hevia Cadevilla\",\"datePublished\":\"2025-03-21T19:03:22+00:00\",\"dateModified\":\"2025-03-21T20:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/\"},\"wordCount\":723,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585890643.jpg\",\"articleSection\":[\"Am\u00e9rica del Sur\",\"Deportes\",\"Venezuela\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/\",\"name\":\"El legado de un j\u00f3ven periodista Edwin Sport Hevia Cadevilla - Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585890643.jpg\",\"datePublished\":\"2025-03-21T19:03:22+00:00\",\"dateModified\":\"2025-03-21T20:03:39+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/8b8c404aee9721f021dea30cc9019d8d\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585890643.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585890643.jpg\",\"width\":720,\"height\":479},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/principal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El legado de un j\u00f3ven periodista Edwin Sport Hevia Cadevilla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/\",\"name\":\"Noti-America.com\",\"description\":\"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/8b8c404aee9721f021dea30cc9019d8d\",\"name\":\"Ana Barcenas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/9dcad906d2cd708cbb2e2d43908c55de4cd28d6a82d2a3576e035c3fac0fb066?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9dcad906d2cd708cbb2e2d43908c55de4cd28d6a82d2a3576e035c3fac0fb066?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9dcad906d2cd708cbb2e2d43908c55de4cd28d6a82d2a3576e035c3fac0fb066?s=96&d=mm&r=g\",\"caption\":\"Ana Barcenas\"},\"description\":\"Ana B\u00e1rcenas DESEMPE\u00d1O EN LA COMUNICACI\u00d3N SOCIAL 2017- actualidad Directora de Prensa Noti-am\u00e9rica.com en Texas. 2016-2017 Global Communication AB 2015 Asesor\u00edas de Comunicaci\u00f3n e Investigaci\u00f3n 2011 -2015 Periodismo Impreso Revista Publiservice 2010-2012 Junta Directiva de Colegio Nacional Periodistas Lara, Secretaria de Publicaciones 2006-2004 Coordinadora del Programa Radial Somos UFT. Somos 3.5fm 2002 -2003 Jefe del Departamento de Comunicaci\u00f3n Corporativa de la Universidad Yacamb\u00fa 2001-2002 Coordinadora del Centro Regional Audiovisual de la Gobernaci\u00f3n de Lara 2000-2001 Reportera y Narradora de Promar TV 2000 Reportera de Televisi\u00f3n en NCTV 1999-2000 Asesor\u00eda Comunicacional a Gerteca.Org de Demanda Habitacional 1996-1999 Periodista Institucional en la Direcci\u00f3n de Prensa de la Alcald\u00eda de Iribarren 1997 Conducci\u00f3n Producci\u00f3n del Programa Radial de Informaci\u00f3n y opini\u00f3n Amanecer Informativo. Cyma94 1996 Reportera Radial en Cristal y Radio Barquisimeto 1995 -1996 Reportera de Televisi\u00f3n en Telecentro 1993-1994 Reportera de Televisi\u00f3n en TV Guayana 1992-1993 Reportera Gr\u00e1fica en CORPOZULIA\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/author\/abarcenas\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El legado de un j\u00f3ven periodista Edwin Sport Hevia Cadevilla - Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/","og_locale":"es_ES","og_type":"article","og_title":"El legado de un j\u00f3ven periodista Edwin Sport Hevia Cadevilla","og_description":"El d\u00eda que conoc\u00ed a Edwin usaba pantalones de jean, franela deportiva y esparc\u00eda su sonrisa\u00a0 por todo el sal\u00f3n de clases. \u00a8Sport, Sport\u00a8 todos le llamaban y es que a sus 17 a\u00f1os&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/","og_site_name":"Noti-America.com","article_published_time":"2025-03-21T19:03:22+00:00","article_modified_time":"2025-03-21T20:03:39+00:00","og_image":[{"width":720,"height":479,"url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585890643.jpg","type":"image\/jpeg"}],"author":"Ana Barcenas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ana Barcenas","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/"},"author":{"name":"Ana Barcenas","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/8b8c404aee9721f021dea30cc9019d8d"},"headline":"El legado de un j\u00f3ven periodista Edwin Sport Hevia Cadevilla","datePublished":"2025-03-21T19:03:22+00:00","dateModified":"2025-03-21T20:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/"},"wordCount":723,"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585890643.jpg","articleSection":["Am\u00e9rica del Sur","Deportes","Venezuela"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/","url":"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/","name":"El legado de un j\u00f3ven periodista Edwin Sport Hevia Cadevilla - Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585890643.jpg","datePublished":"2025-03-21T19:03:22+00:00","dateModified":"2025-03-21T20:03:39+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/8b8c404aee9721f021dea30cc9019d8d"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/#primaryimage","url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585890643.jpg","contentUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2025\/03\/FB_IMG_1742585890643.jpg","width":720,"height":479},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/principal\/2025\/03\/21\/el-legado-de-un-joven-periodista-edwin-sport-hevia-cadevilla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/principal\/"},{"@type":"ListItem","position":2,"name":"El legado de un j\u00f3ven periodista Edwin Sport Hevia Cadevilla"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/principal\/#website","url":"https:\/\/noti-america.com\/site\/principal\/","name":"Noti-America.com","description":"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/8b8c404aee9721f021dea30cc9019d8d","name":"Ana Barcenas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9dcad906d2cd708cbb2e2d43908c55de4cd28d6a82d2a3576e035c3fac0fb066?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9dcad906d2cd708cbb2e2d43908c55de4cd28d6a82d2a3576e035c3fac0fb066?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9dcad906d2cd708cbb2e2d43908c55de4cd28d6a82d2a3576e035c3fac0fb066?s=96&d=mm&r=g","caption":"Ana Barcenas"},"description":"Ana B\u00e1rcenas DESEMPE\u00d1O EN LA COMUNICACI\u00d3N SOCIAL 2017- actualidad Directora de Prensa Noti-am\u00e9rica.com en Texas. 2016-2017 Global Communication AB 2015 Asesor\u00edas de Comunicaci\u00f3n e Investigaci\u00f3n 2011 -2015 Periodismo Impreso Revista Publiservice 2010-2012 Junta Directiva de Colegio Nacional Periodistas Lara, Secretaria de Publicaciones 2006-2004 Coordinadora del Programa Radial Somos UFT. Somos 3.5fm 2002 -2003 Jefe del Departamento de Comunicaci\u00f3n Corporativa de la Universidad Yacamb\u00fa 2001-2002 Coordinadora del Centro Regional Audiovisual de la Gobernaci\u00f3n de Lara 2000-2001 Reportera y Narradora de Promar TV 2000 Reportera de Televisi\u00f3n en NCTV 1999-2000 Asesor\u00eda Comunicacional a Gerteca.Org de Demanda Habitacional 1996-1999 Periodista Institucional en la Direcci\u00f3n de Prensa de la Alcald\u00eda de Iribarren 1997 Conducci\u00f3n Producci\u00f3n del Programa Radial de Informaci\u00f3n y opini\u00f3n Amanecer Informativo. Cyma94 1996 Reportera Radial en Cristal y Radio Barquisimeto 1995 -1996 Reportera de Televisi\u00f3n en Telecentro 1993-1994 Reportera de Televisi\u00f3n en TV Guayana 1992-1993 Reportera Gr\u00e1fica en CORPOZULIA","url":"https:\/\/noti-america.com\/site\/principal\/author\/abarcenas\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/64335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/users\/123"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/comments?post=64335"}],"version-history":[{"count":5,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/64335\/revisions"}],"predecessor-version":[{"id":64347,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/64335\/revisions\/64347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media\/64338"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media?parent=64335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/categories?post=64335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/tags?post=64335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}