{"id":55364,"date":"2024-10-20T21:07:46","date_gmt":"2024-10-21T01:07:46","guid":{"rendered":"https:\/\/noti-america.com\/site\/principal\/?p=55364"},"modified":"2024-10-20T21:07:46","modified_gmt":"2024-10-21T01:07:46","slug":"se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/","title":{"rendered":"Se acerca la final del Premio Latinoamericano de Arquitectura Rogelio Salmona"},"content":{"rendered":"<p>NOTI-AMERICA | COLOMBIA<\/p>\n<p>El pr\u00f3ximo 24 de octubre, en el auditorio de la Biblioteca P\u00fablica Virgilio Barco, se conocer\u00e1n las obras ganadoras del Premio Latinoamericano de Arquitectura Rogelio Salmona, se lanzar\u00e1 el libro y abrir\u00e1 la exposici\u00f3n que re\u00fane las 26 obras m\u00e1s representativas de las 47 participantes.<\/p>\n<p><strong>Ganadores<\/strong><\/p>\n<p>La ceremonia, en la cual se conocer\u00e1n los ganadores de las categor\u00edas Colombia y Latinoam\u00e9rica, estar\u00e1 presidida por Ma. Elvira Madri\u00f1\u00e1n Saa, presidenta de la Junta Directiva de la Fundaci\u00f3n Rogelio Salmona e impulsora del legado del arquitecto Rogelio Salmona en Latinoam\u00e9rica y el mundo, y los reconocidos arquitectos que hacen parte del jurado: Sol Camacho (Brasil &#8211; M\u00e9xico); Mauricio Rocha Iturbide (M\u00e9xico); Nicol\u00e1s Campodonico (Argentina) y Carlos Campuzano (Colombia).<\/p>\n<p>\u201cLos asistentes podr\u00e1n disfrutar de la exposici\u00f3n que visibilizar\u00e1 los ejemplos de arquitectura realizada en Latinoam\u00e9rica que han contribuido a la consolidaci\u00f3n de ciudades m\u00e1s democr\u00e1ticas y, a trav\u00e9s de ellos, se destaca el legado de Rogelio Salmona, cuya obra inspir\u00f3 el Premio. En el evento, adem\u00e1s, estar\u00e1 disponible el libro que se convierte en la memoria de este cuarto ciclo, donde se podr\u00e1 tener informaci\u00f3n detallada de las obras participantes\u201d, asegura Mar\u00eda Elvira Madri\u00f1\u00e1n\u00a0Saa, presidenta de la Junta Directiva de la Fundaci\u00f3n Rogelio Salmona.<\/p>\n<p><strong>Un premio multicultural y lleno de riqueza<\/strong><\/p>\n<p>Ser un premio latinoamericano, reviste una importancia de primer nivel, si se tiene en cuenta que: permite apreciar toda la riqueza del ingenio de los arquitectos, que lleva a pensar, como lo dice Nicol\u00e1s Campodonico de Argentina, uno de los jurados del Premio, que, en las condiciones de la regi\u00f3n, \u201cno son tan importantes los recursos de los cuales se dispone, sino lo que se hace con ellos\u201d. Y all\u00ed las 26 obras seleccionadas son un ejemplo de variedad de materiales, dise\u00f1os y recursos para crear espacios abiertos a la ciudad, de una alta calidad.<\/p>\n<p>Pero tambi\u00e9n, que la ciudad es el mejor invento de la humanidad como lo afirmaba Rogelio Salmona. \u201cEs la casa grande para todos, para compartir y disfrutar, para conocerse y tambi\u00e9n, para protegerse.\u00a0As\u00ed, en los proyectos postulados al\u00a0Premio este a\u00f1o, hay muestras de ello, lo que nos hizo dif\u00edcil la escogencia por la excelente calidad de los proyectos participantes, siendo muy estimulante comprobar que la obra de Rogelio Salmona es un paradigma en la creaci\u00f3n de mejores ciudades para todos\u201d, asegura Carlos Campuzano Castell\u00f3, jurado por Colombia.<\/p>\n<p>As\u00ed, entre los 26 proyectos seleccionados se pueden ver viviendas sociales, escuelas, parques, museos, centros comunitarios, bibliotecas y edificios gubernamentales y culturales, que muestran c\u00f3mo, a trav\u00e9s de un dise\u00f1o cuidadoso y colaborativo, se pueden transformar las din\u00e1micas sociales, pero tambi\u00e9n, que no hay l\u00edmites, cuando se piensa en proyectos para construir una ciudad para todos.<\/p>\n<p>Ejemplo de ello, es el Parque Educativo Saberes Ancestrales en Vig\u00eda del Fuerte en Antioquia, Colombia, que retoma los elementos t\u00edpicos de la arquitectura del lugar, con construcciones y andenes que se elevan del nivel del suelo, para disminuir el impacto de las crecidas anuales del r\u00edo, y donde hoy la comunidad se ha apropiado de los espacios interiores y exteriores, donde se desarrollan actividades colectivas, como cine, presentaciones de danzas, teatro y m\u00fasica.<\/p>\n<p>Pero tambi\u00e9n se destaca el entorno, como ocurre con Parques del R\u00edo Medell\u00edn, una obra que teje la ciudad longitudinal y transversalmente, revitalizando el rio y transform\u00e1ndolo en jerarqu\u00eda ambiental, cultural, educativa y deportiva, creando un eje de espacio p\u00fablico de convergencia ciudadana y ambiental. \u201cEsto pone de relieve que el proceso de dise\u00f1o y la forma en que se implementan los recursos tienen un impacto directo en la calidad de vida de las personas\u201d, recalca el arquitecto Campodonico.<\/p>\n<p>Tambi\u00e9n hay proyectos que traen seguridad, como pasa en la Plaza Cultural Norte ubicada en Lima, Per\u00fa, que despu\u00e9s de ser un \u00e1rea en abandono que incentivaba la delincuencia, se convirti\u00f3 en una estructura abierta a la comunidad, donde hoy se construye paisaje social, que genera espacios de encuentro, reflexi\u00f3n, alegr\u00eda, integrados con la naturaleza. Y, adem\u00e1s, en otros ejemplos, se da lugar a comunidades relegadas, como el Museo Arqueol\u00f3gico y Centro Cultural Orellana (MACCO), que promueve un espacio de encuentro de la comunidad ind\u00edgena, muy poco atendida, y mediante su arquitectura, genera un di\u00e1logo intenso con el contexto natural y urbano, construyendo un lugar de aproximaci\u00f3n y fortalecimiento social.<\/p>\n<p>&nbsp;<\/p>\n<p>Incluso, se crean nuevos espacios para que las personas sean parte de la vida de la ciudad. As\u00ed ocurre con el proyecto Parque La Mexicana en Ciudad de M\u00e9xico, que transform\u00f3 un enorme lote bald\u00edo en un parque abierto al p\u00fablico con diversas actividades que promueven no solo la convivencia, el bienestar y la salud de los visitantes, sino que adem\u00e1s, incluyen espacios de esparcimiento como ciclov\u00edas<span style=\"text-decoration: line-through\">,<\/span> un anfiteatro, senderos, pistas para patinar y canchas deportivas, restaurantes, \u00e1reas de entretenimiento, juegos de mascotas y dem\u00e1s, con un foro al aire libre y de f\u00e1cil acceso para personas con capacidades diferentes.<\/p>\n<p>Y es que el Premio permite ver que cualquier lugar es bueno para crear proyectos inclusivos. Puede ser un museo como ocurre con el Morelense de Arte Contempor\u00e1neo Juan Soriano, en Cuernavaca, M\u00e9xico, que extiende un jard\u00edn abierto al p\u00fablico de 7,376 metros, complementado por \u00e1reas para exposiciones, talleres y salas audiovisuales, que enriquecen la vida art\u00edstica, cultural y la sana convivencia en este espacio p\u00fablico de la ciudad.<\/p>\n<p>O un espacio de transporte como el Cetram Cuatro Caminos, una estaci\u00f3n de transferencia multimodal del Metro de M\u00e9xico, que mejora la experiencia del viajero, a trav\u00e9s de \u00e1reas abiertas de conexi\u00f3n a los distintos modos de transporte, zonas de entretenimiento, de gastronom\u00eda y ocio. O las UVA- tanques de agua como parques p\u00fablicos -EPM en Medell\u00edn, donde se redise\u00f1aron 14 tanques de agua de EPM y se logr\u00f3 con ayuda de la comunidad a trav\u00e9s de talleres de imaginarios, convertirlos en estos espacios de infraestructura p\u00fablica para el encuentro ciudadano, el fomento de la recreaci\u00f3n y la cultura.<\/p>\n<p>\u201cLos arquitectos tenemos oportunidad de participar y colaborar en la construcci\u00f3n de nuestras ciudades y pueblos y es nuestro deber, observar y entender las l\u00f3gicas complejas que definen al colectivo y, lograr con nuestras intervenciones, activar y estimular espacios de encuentro.\u00a0Ayudar a que se viva mejor, como colectividad, construyendo tejidos\u201d, recalca Mauricio\u00a0Rocha Iturbide, jurado de M\u00e9xico.<\/p>\n<p>All\u00ed est\u00e1 la riqueza del premio. \u201cEl tema espec\u00edfico: <em>Espacios Abiertos \/ Espacios Colectivos<\/em>, establece los criterios para promover una arquitectura m\u00e1s humana, dirigida a impulsar la colaboraci\u00f3n entre el sector p\u00fablico y el privado, fomentar decisiones proyectuales que contribuyan al desarrollo de ciudades en confluencia con su contexto natural\u201d, concluye la arquitecta Sol Camacho, jurado por M\u00e9xico y Brasil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA | COLOMBIA El pr\u00f3ximo 24 de octubre, en el auditorio de la Biblioteca P\u00fablica Virgilio Barco, se conocer\u00e1n las obras ganadoras del Premio Latinoamericano de Arquitectura Rogelio Salmona, se lanzar\u00e1 el libro y&#46;&#46;&#46;<\/p>\n","protected":false},"author":135,"featured_media":55365,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10219548024599422_1632221337088128":"","twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[8],"tags":[],"class_list":["post-55364","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-arte-y-espectaculos","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Se acerca la final del Premio Latinoamericano de Arquitectura Rogelio Salmona - Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se acerca la final del Premio Latinoamericano de Arquitectura Rogelio Salmona\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA | COLOMBIA El pr\u00f3ximo 24 de octubre, en el auditorio de la Biblioteca P\u00fablica Virgilio Barco, se conocer\u00e1n las obras ganadoras del Premio Latinoamericano de Arquitectura Rogelio Salmona, se lanzar\u00e1 el libro y&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/\" \/>\n<meta property=\"og:site_name\" content=\"Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-21T01:07:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/10\/WhatsApp-Image-2024-10-07-at-9.42.43-AM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1244\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mlenis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mlenis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/\"},\"author\":{\"name\":\"mlenis\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f\"},\"headline\":\"Se acerca la final del Premio Latinoamericano de Arquitectura Rogelio Salmona\",\"datePublished\":\"2024-10-21T01:07:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/\"},\"wordCount\":1197,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/10\/WhatsApp-Image-2024-10-07-at-9.42.43-AM.jpeg\",\"articleSection\":[\"Arte y Espect\u00e1culos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/\",\"name\":\"Se acerca la final del Premio Latinoamericano de Arquitectura Rogelio Salmona - Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/10\/WhatsApp-Image-2024-10-07-at-9.42.43-AM.jpeg\",\"datePublished\":\"2024-10-21T01:07:46+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/10\/WhatsApp-Image-2024-10-07-at-9.42.43-AM.jpeg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/10\/WhatsApp-Image-2024-10-07-at-9.42.43-AM.jpeg\",\"width\":1600,\"height\":1244},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/principal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se acerca la final del Premio Latinoamericano de Arquitectura Rogelio Salmona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/\",\"name\":\"Noti-America.com\",\"description\":\"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f\",\"name\":\"mlenis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"caption\":\"mlenis\"},\"url\":\"https:\/\/noti-america.com\/site\/principal\/author\/mlenis\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Se acerca la final del Premio Latinoamericano de Arquitectura Rogelio Salmona - Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/","og_locale":"es_ES","og_type":"article","og_title":"Se acerca la final del Premio Latinoamericano de Arquitectura Rogelio Salmona","og_description":"NOTI-AMERICA | COLOMBIA El pr\u00f3ximo 24 de octubre, en el auditorio de la Biblioteca P\u00fablica Virgilio Barco, se conocer\u00e1n las obras ganadoras del Premio Latinoamericano de Arquitectura Rogelio Salmona, se lanzar\u00e1 el libro y&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/","og_site_name":"Noti-America.com","article_published_time":"2024-10-21T01:07:46+00:00","og_image":[{"width":1600,"height":1244,"url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/10\/WhatsApp-Image-2024-10-07-at-9.42.43-AM.jpeg","type":"image\/jpeg"}],"author":"mlenis","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mlenis","Tiempo estimado de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/"},"author":{"name":"mlenis","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f"},"headline":"Se acerca la final del Premio Latinoamericano de Arquitectura Rogelio Salmona","datePublished":"2024-10-21T01:07:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/"},"wordCount":1197,"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/10\/WhatsApp-Image-2024-10-07-at-9.42.43-AM.jpeg","articleSection":["Arte y Espect\u00e1culos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/","url":"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/","name":"Se acerca la final del Premio Latinoamericano de Arquitectura Rogelio Salmona - Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/10\/WhatsApp-Image-2024-10-07-at-9.42.43-AM.jpeg","datePublished":"2024-10-21T01:07:46+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/#primaryimage","url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/10\/WhatsApp-Image-2024-10-07-at-9.42.43-AM.jpeg","contentUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/10\/WhatsApp-Image-2024-10-07-at-9.42.43-AM.jpeg","width":1600,"height":1244},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/10\/20\/se-acerca-la-final-del-premio-latinoamericano-de-arquitectura-rogelio-salmona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/principal\/"},{"@type":"ListItem","position":2,"name":"Se acerca la final del Premio Latinoamericano de Arquitectura Rogelio Salmona"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/principal\/#website","url":"https:\/\/noti-america.com\/site\/principal\/","name":"Noti-America.com","description":"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f","name":"mlenis","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","caption":"mlenis"},"url":"https:\/\/noti-america.com\/site\/principal\/author\/mlenis\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/55364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/comments?post=55364"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/55364\/revisions"}],"predecessor-version":[{"id":55403,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/55364\/revisions\/55403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media\/55365"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media?parent=55364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/categories?post=55364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/tags?post=55364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}