{"id":52277,"date":"2024-08-28T23:46:15","date_gmt":"2024-08-29T03:46:15","guid":{"rendered":"https:\/\/noti-america.com\/site\/principal\/?p=52277"},"modified":"2024-08-28T19:46:19","modified_gmt":"2024-08-28T23:46:19","slug":"antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/","title":{"rendered":"Antonio Ledezma pide a la CPI detener la represi\u00f3n en Venezuela"},"content":{"rendered":"<div id=\"attachment_40597\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-40597\" class=\"size-large wp-image-52278\" src=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Santiago-Rocha-AL-1-1024x791.jpg\" alt=\"\" width=\"1024\" height=\"791\" srcset=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Santiago-Rocha-AL-1-1024x791.jpg 1024w, https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Santiago-Rocha-AL-1-300x232.jpg 300w, https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Santiago-Rocha-AL-1-768x593.jpg 768w, https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Santiago-Rocha-AL-1.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-40597\" class=\"wp-caption-text\">Antonio Ledezma, en Madrid, con Santiago Rocha, hijo de Perkins Rocha (Cortes\u00eda)<\/p><\/div>\n<p>El portavoz internacional de Mar\u00eda Corina Machado,<a href=\"https:\/\/noti-america.com\/site\/venezuela\/2024\/08\/22\/antonio-ledezma-sentencia-del-tsj-es-tan-chimba-como-la-servilleta-que-quisieron-pasar-por-acta\/\"> Antonio Ledezma<\/a>, pidi\u00f3 a la Corte Penal Internacional (CPI) detener la ola de represi\u00f3n postelectoral que ha desatado el gobierno en contra de la oposici\u00f3n venezolana.<\/p>\n<p>Desde la plaza Puerta del Sol, centro neur\u00e1lgico de Madrid, miles de venezolanos se concentraron nuevamente por segunda vez en dos semanas en apoyo al llamado a retomar las calles de Venezuela, convocado por Mar\u00eda Corina Machado.<\/p>\n<p>En simult\u00e1neo, los venezolanos residentes en otras 350 ciudades del mundo se reencontraron con pancartas, consignas y sus banderas gritando \u201clibertad\u201d y expresiones de repudio en contra del presidente Nicol\u00e1s Maduro.<\/p>\n<p>Durante su intervenci\u00f3n, Ledezma present\u00f3 a Santiago Rocha, hijo del abogado Perkins Rocha, quien fue detenido este martes 27 por funcionarios del gobierno venezolano.<\/p>\n<p>Rocha consultor jur\u00eddico es representante, junto con la dirigente Delsa Sol\u00f3rzano, del comando de campa\u00f1a de Mar\u00eda Corina Machado y del principal grupo opositor Plataforma Unitaria Democr\u00e1tica ante el Consejo Nacional Electoral.<\/p>\n<p><strong>Al Parlamento Europeo<\/strong><\/p>\n<p>En su intervenci\u00f3n, Ledezma inform\u00f3 a la multitud que el pr\u00f3ximo lunes se dirigir\u00e1 al Parlamento Europeo para solicitar que se retomen los debates ante la ola represiva que ha desatado el gobierno venezolano en contra de la oposici\u00f3n.<\/p>\n<p>El dirigente pol\u00edtico considera que la CPI debe dar un paso firme y dictar \u00f3rdenes de captura contra los autores de cr\u00edmenes de lesa humanidad en el pa\u00eds.<\/p>\n<p>\u201cAs\u00ed lo han dicho los funcionarios del grupo de determinaci\u00f3n de los hechos de la ONU y hoy el Consejo Permanente de la OEA que han emitido un informe sobre estos delitos\u201d, dijo.<\/p>\n<p>\u201cEn Venezuela no hay autonom\u00eda de poderes y debe ser la CPI la que detenga esta carnicer\u00eda\u201d, agreg\u00f3 Ledezma, coordinador del Consejo Pol\u00edtico Internacional de MCM.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El portavoz internacional de Mar\u00eda Corina Machado, Antonio Ledezma, pidi\u00f3 a la Corte Penal Internacional (CPI) detener la ola de represi\u00f3n postelectoral que ha desatado el gobierno en contra de la oposici\u00f3n venezolana. Desde&#46;&#46;&#46;<\/p>\n","protected":false},"author":124,"featured_media":52278,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10219548024599422_1632221337088128":"","twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[886,3,100],"tags":[1491,990,4215],"class_list":["post-52277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acturalidad","category-politica","category-venezuela","tag-antonio-ledezma","tag-maria-corina-machado","tag-perkins-rocha"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Antonio Ledezma pide a la CPI detener la represi\u00f3n en Venezuela - Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antonio Ledezma pide a la CPI detener la represi\u00f3n en Venezuela\" \/>\n<meta property=\"og:description\" content=\"El portavoz internacional de Mar\u00eda Corina Machado, Antonio Ledezma, pidi\u00f3 a la Corte Penal Internacional (CPI) detener la ola de represi\u00f3n postelectoral que ha desatado el gobierno en contra de la oposici\u00f3n venezolana. Desde&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/\" \/>\n<meta property=\"og:site_name\" content=\"Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-29T03:46:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Santiago-Rocha-AL-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"927\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dick Torres\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dickeliastorres\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dick Torres\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/\"},\"author\":{\"name\":\"Dick Torres\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/ae2fe0f34cf986adfc5775246e337497\"},\"headline\":\"Antonio Ledezma pide a la CPI detener la represi\u00f3n en Venezuela\",\"datePublished\":\"2024-08-29T03:46:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/\"},\"wordCount\":339,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Santiago-Rocha-AL-1.jpg\",\"keywords\":[\"Antonio Ledezma\",\"Mar\u00eda Corina Machado\",\"Perkins Rocha\"],\"articleSection\":[\"Actualidad\",\"Pol\u00edtica\",\"Venezuela\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/\",\"name\":\"Antonio Ledezma pide a la CPI detener la represi\u00f3n en Venezuela - Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Santiago-Rocha-AL-1.jpg\",\"datePublished\":\"2024-08-29T03:46:15+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/ae2fe0f34cf986adfc5775246e337497\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Santiago-Rocha-AL-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Santiago-Rocha-AL-1.jpg\",\"width\":1200,\"height\":927,\"caption\":\"Antonio Ledezma, en Madrid, con Santiago Rocha, hijo de Perkins Rocha (Cortes\u00eda)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/principal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antonio Ledezma pide a la CPI detener la represi\u00f3n en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/\",\"name\":\"Noti-America.com\",\"description\":\"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/ae2fe0f34cf986adfc5775246e337497\",\"name\":\"Dick Torres\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/22e2833e6c12bf848665976635702488aba7ca5765137638ba39eb1b11664a55?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/22e2833e6c12bf848665976635702488aba7ca5765137638ba39eb1b11664a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/22e2833e6c12bf848665976635702488aba7ca5765137638ba39eb1b11664a55?s=96&d=mm&r=g\",\"caption\":\"Dick Torres\"},\"description\":\"Periodista\",\"sameAs\":[\"https:\/\/x.com\/dickeliastorres\"],\"url\":\"https:\/\/noti-america.com\/site\/principal\/author\/dtorres\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Antonio Ledezma pide a la CPI detener la represi\u00f3n en Venezuela - Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/","og_locale":"es_ES","og_type":"article","og_title":"Antonio Ledezma pide a la CPI detener la represi\u00f3n en Venezuela","og_description":"El portavoz internacional de Mar\u00eda Corina Machado, Antonio Ledezma, pidi\u00f3 a la Corte Penal Internacional (CPI) detener la ola de represi\u00f3n postelectoral que ha desatado el gobierno en contra de la oposici\u00f3n venezolana. Desde&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/","og_site_name":"Noti-America.com","article_published_time":"2024-08-29T03:46:15+00:00","og_image":[{"width":1200,"height":927,"url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Santiago-Rocha-AL-1.jpg","type":"image\/jpeg"}],"author":"Dick Torres","twitter_card":"summary_large_image","twitter_creator":"@dickeliastorres","twitter_misc":{"Escrito por":"Dick Torres","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/"},"author":{"name":"Dick Torres","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/ae2fe0f34cf986adfc5775246e337497"},"headline":"Antonio Ledezma pide a la CPI detener la represi\u00f3n en Venezuela","datePublished":"2024-08-29T03:46:15+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/"},"wordCount":339,"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Santiago-Rocha-AL-1.jpg","keywords":["Antonio Ledezma","Mar\u00eda Corina Machado","Perkins Rocha"],"articleSection":["Actualidad","Pol\u00edtica","Venezuela"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/","url":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/","name":"Antonio Ledezma pide a la CPI detener la represi\u00f3n en Venezuela - Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Santiago-Rocha-AL-1.jpg","datePublished":"2024-08-29T03:46:15+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/ae2fe0f34cf986adfc5775246e337497"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/#primaryimage","url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Santiago-Rocha-AL-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Santiago-Rocha-AL-1.jpg","width":1200,"height":927,"caption":"Antonio Ledezma, en Madrid, con Santiago Rocha, hijo de Perkins Rocha (Cortes\u00eda)"},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/28\/antonio-ledezma-pide-a-la-cpi-detener-la-represion-en-venezuela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/principal\/"},{"@type":"ListItem","position":2,"name":"Antonio Ledezma pide a la CPI detener la represi\u00f3n en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/principal\/#website","url":"https:\/\/noti-america.com\/site\/principal\/","name":"Noti-America.com","description":"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/ae2fe0f34cf986adfc5775246e337497","name":"Dick Torres","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/22e2833e6c12bf848665976635702488aba7ca5765137638ba39eb1b11664a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/22e2833e6c12bf848665976635702488aba7ca5765137638ba39eb1b11664a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/22e2833e6c12bf848665976635702488aba7ca5765137638ba39eb1b11664a55?s=96&d=mm&r=g","caption":"Dick Torres"},"description":"Periodista","sameAs":["https:\/\/x.com\/dickeliastorres"],"url":"https:\/\/noti-america.com\/site\/principal\/author\/dtorres\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/52277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/users\/124"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/comments?post=52277"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/52277\/revisions"}],"predecessor-version":[{"id":52279,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/52277\/revisions\/52279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media\/52278"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media?parent=52277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/categories?post=52277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/tags?post=52277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}