{"id":50740,"date":"2024-08-08T14:37:36","date_gmt":"2024-08-08T18:37:36","guid":{"rendered":"https:\/\/noti-america.com\/site\/principal\/?p=50740"},"modified":"2024-08-08T14:37:36","modified_gmt":"2024-08-08T18:37:36","slug":"metros-vencen-a-reales-y-empatan-en-el-primer-lugar","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/","title":{"rendered":"Metros vencen a Reales y empatan en el primer lugar"},"content":{"rendered":"NOTI-AMERICA.COM <em>|\u00a0<\/em>REP\u00daBLICA DOMINICANA\r\n\r\n\r\n<p style=\"text-align: justify\">SANTIAGO &#8211; Apoyados en una gran defensa en el \u00faltimo cuarto, los Metros de Santiago dispusieron 95-84 de los Reales de La Vega en un electrizante duelo disputado en la Arena Oscar Gobaira en juego de la fase de eliminaci\u00f3n de La S\u00faper Liga de la LNB.<\/p>\r\n<p style=\"text-align: justify\"> <\/p>\r\n<p style=\"text-align: justify\">Sir\u2019Jabar Rice anot\u00f3 17 puntos, Oliver Garc\u00eda 16 con 4 robos, Eloy Vargas 14 con 14 rebotes y Emmitt Williams tambi\u00e9n 14 \u00a0tantos por los Metros, que con marca de 12-7 empatan en el primer lugar con los Reales y con los Titanes del Distrito. V\u00edctor Liz tambi\u00e9n a\u00f1adi\u00f3 11 tantos y 4 asistencias.<\/p>\r\n<p style=\"text-align: justify\"> <\/p>\r\n<p style=\"text-align: justify\">Michael Warren fue el mejor por los Reales con 26 unidades y 4 asistencias, Sterling Manley consigui\u00f3 17 puntos, 22 rebotes y 2 bloqueos, en tanto que Anphernee se fue con 13 en anotaci\u00f3n, 6 rebotes y 5 asistencias para los Reales, que al igual que los Metros tienen 3-2 en esta etapa.<\/p>\r\n<p style=\"text-align: justify\"> <\/p>\r\n<p style=\"text-align: justify\">La defensa imper\u00f3 en el \u00faltimo tiempo. Los Metros llegaron ganando por cinco (87-82) a dos minutos de finalizar el encuentro. En ese momento apenas 25 puntos ten\u00edan en el parcial los dos equipos de manera combinada.<\/p>\r\n<p style=\"text-align: justify\"> <\/p>\r\n<p style=\"text-align: justify\">Cuatro puntos seguidos de Vargas despegaron 91-82 con 55 segundos a los dirigidos por Nestor (Che) Garc\u00eda. Luego Williams hizo un donqueo monstruoso faltando 38 segundos, el cual tumb\u00f3 cualquier esperanza de los veganos regresar.<\/p>\r\n<p style=\"text-align: justify\"> <\/p>\r\n<p style=\"text-align: justify\">Un total de 49 puntos encest\u00f3 la banca de los Metros, frente a s\u00f3lo 16 de los Reales.<\/p>\r\n<p style=\"text-align: justify\"> <\/p>\r\n<p style=\"text-align: justify\">Seis puntos de Vargas ayudaron a los Metros a ganar el primer cuarto 25-20. Williams y Miguel Dicent tambi\u00e9n lograron 5 tantos cada uno para los de Santiago. En los primeros 10 minutos por los Reales se destac\u00f3 Manley con 7 unidades y 4 rebotes y Warren con 5 en anotaci\u00f3n.<\/p>\r\n<p style=\"text-align: justify\"> <\/p>\r\n<p style=\"text-align: justify\">Garc\u00eda fue la punta de lanza para los Metros en el segundo cuarto. Un triple suyo puso a los amarillos en ventaja 40-32, restando 3:57. El parcial cerr\u00f3 con un triple espectacular de Williams en el \u00faltimo segundo, cerrando la primera mitad con score de 51-38.<\/p>\r\n<p style=\"text-align: justify\"> <\/p>\r\n<p style=\"text-align: justify\">Fueron 11 los puntos de Garc\u00eda en los primeros 20 minutos de acci\u00f3n, seguido por 8 tantos y 6 rebotes de Vargas. Williams tambi\u00e9n logr\u00f3 8 unidades, pero con 5 tableros. Manley sobresali\u00f3 con 11 puntos y 12 rebotes por los Reales, que tambi\u00e9n contaron con 9 tantos de Warren.<\/p>\r\n<p style=\"text-align: justify\"> <\/p>\r\n<p style=\"text-align: justify\">En el tercer cuarto, los Reales lograron una gran reacci\u00f3n y tomaron el comando 68-67 faltando 1:41, tras una bandeja de Warren. De todos modos, los Metros pudieron prevalecer y con un donqueo de Jeff Allen terminaron arriba 74-70 tras 30 minutos de acci\u00f3n.<\/p>\r\n<p style=\"text-align: justify\"> <\/p>\r\n<p style=\"text-align: justify\">Los parciales concluyeron 25-20, 26-18, 23-32 y 21-14 para los Metros.<\/p>\r\n<p style=\"text-align: justify\"> <\/p>\r\n<p style=\"text-align: justify\"><strong>Pr\u00f3ximos partidos<\/strong><\/p>\r\n<p style=\"text-align: justify\"> <\/p>\r\n<p style=\"text-align: justify\">Este viernes los Reales visitar\u00e1n a los Marineros en el Club Fant\u00e1stico (7:30 pm), los Titanes a los Indios en el Pabell\u00f3n Mario Ortega (8:00 pm) y los Ca\u00f1eros a los Metros en la Arena Oscar Gobaira (8:30 pm).<\/p>\r\n<p style=\"text-align: justify\"> <\/p>\r\n<p style=\"text-align: justify\"><strong>Fuente: Prensa LNB<\/strong><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA.COM |\u00a0REP\u00daBLICA DOMINICANA SANTIAGO &#8211; Apoyados en una gran defensa en el \u00faltimo cuarto, los Metros de Santiago dispusieron 95-84 de los Reales de La Vega en un electrizante duelo disputado en la Arena&#46;&#46;&#46;<\/p>\n","protected":false},"author":89,"featured_media":50741,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10219548024599422_1632221337088128":"","twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[16],"tags":[679,3272,1457,1759],"class_list":["post-50740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-baloncesto-dominicano","tag-la-super-liga","tag-liga-nacional-de-baloncesto","tag-metros-de-santiago"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Metros vencen a Reales y empatan en el primer lugar - Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Metros vencen a Reales y empatan en el primer lugar\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA.COM |\u00a0REP\u00daBLICA DOMINICANA SANTIAGO &#8211; Apoyados en una gran defensa en el \u00faltimo cuarto, los Metros de Santiago dispusieron 95-84 de los Reales de La Vega en un electrizante duelo disputado en la Arena&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/\" \/>\n<meta property=\"og:site_name\" content=\"Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-08T18:37:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Sir-Jabari-Rice.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ad\u00e1n Soriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@adansoriano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ad\u00e1n Soriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/\"},\"author\":{\"name\":\"Ad\u00e1n Soriano\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/fd0092c1530d275fabaa5cffcbc2b976\"},\"headline\":\"Metros vencen a Reales y empatan en el primer lugar\",\"datePublished\":\"2024-08-08T18:37:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/\"},\"wordCount\":490,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Sir-Jabari-Rice.jpg\",\"keywords\":[\"Baloncesto Dominicano\",\"La S\u00faper Liga\",\"Liga Nacional de Baloncesto\",\"Metros de Santiago\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/\",\"name\":\"Metros vencen a Reales y empatan en el primer lugar - Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Sir-Jabari-Rice.jpg\",\"datePublished\":\"2024-08-08T18:37:36+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/fd0092c1530d275fabaa5cffcbc2b976\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Sir-Jabari-Rice.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Sir-Jabari-Rice.jpg\",\"width\":1920,\"height\":1281},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/principal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Metros vencen a Reales y empatan en el primer lugar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/\",\"name\":\"Noti-America.com\",\"description\":\"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/fd0092c1530d275fabaa5cffcbc2b976\",\"name\":\"Ad\u00e1n Soriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g\",\"caption\":\"Ad\u00e1n Soriano\"},\"description\":\"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva\",\"sameAs\":[\"https:\/\/x.com\/adansoriano\"],\"url\":\"https:\/\/noti-america.com\/site\/principal\/author\/asoriano\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Metros vencen a Reales y empatan en el primer lugar - Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/","og_locale":"es_ES","og_type":"article","og_title":"Metros vencen a Reales y empatan en el primer lugar","og_description":"NOTI-AMERICA.COM |\u00a0REP\u00daBLICA DOMINICANA SANTIAGO &#8211; Apoyados en una gran defensa en el \u00faltimo cuarto, los Metros de Santiago dispusieron 95-84 de los Reales de La Vega en un electrizante duelo disputado en la Arena&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/","og_site_name":"Noti-America.com","article_published_time":"2024-08-08T18:37:36+00:00","og_image":[{"width":1920,"height":1281,"url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Sir-Jabari-Rice.jpg","type":"image\/jpeg"}],"author":"Ad\u00e1n Soriano","twitter_card":"summary_large_image","twitter_creator":"@adansoriano","twitter_misc":{"Escrito por":"Ad\u00e1n Soriano","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/"},"author":{"name":"Ad\u00e1n Soriano","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/fd0092c1530d275fabaa5cffcbc2b976"},"headline":"Metros vencen a Reales y empatan en el primer lugar","datePublished":"2024-08-08T18:37:36+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/"},"wordCount":490,"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Sir-Jabari-Rice.jpg","keywords":["Baloncesto Dominicano","La S\u00faper Liga","Liga Nacional de Baloncesto","Metros de Santiago"],"articleSection":["Deportes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/","url":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/","name":"Metros vencen a Reales y empatan en el primer lugar - Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Sir-Jabari-Rice.jpg","datePublished":"2024-08-08T18:37:36+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/fd0092c1530d275fabaa5cffcbc2b976"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/#primaryimage","url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Sir-Jabari-Rice.jpg","contentUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/08\/Sir-Jabari-Rice.jpg","width":1920,"height":1281},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/08\/08\/metros-vencen-a-reales-y-empatan-en-el-primer-lugar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/principal\/"},{"@type":"ListItem","position":2,"name":"Metros vencen a Reales y empatan en el primer lugar"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/principal\/#website","url":"https:\/\/noti-america.com\/site\/principal\/","name":"Noti-America.com","description":"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/fd0092c1530d275fabaa5cffcbc2b976","name":"Ad\u00e1n Soriano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ecf97ff3aee7ff9efdae670d7e976f3e7e8acc1077e510d73707999a8bfd4467?s=96&d=mm&r=g","caption":"Ad\u00e1n Soriano"},"description":"Soy cronista deportivo con 10 a\u00f1os de experiencia en varios espacios, y conduzco el podcast deportivo llamado Mezcla Deportiva","sameAs":["https:\/\/x.com\/adansoriano"],"url":"https:\/\/noti-america.com\/site\/principal\/author\/asoriano\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/50740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/comments?post=50740"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/50740\/revisions"}],"predecessor-version":[{"id":50792,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/50740\/revisions\/50792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media\/50741"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media?parent=50740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/categories?post=50740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/tags?post=50740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}