{"id":37481,"date":"2024-01-23T01:34:25","date_gmt":"2024-01-23T05:34:25","guid":{"rendered":"https:\/\/noti-america.com\/site\/principal\/?p=37481"},"modified":"2024-01-23T01:34:25","modified_gmt":"2024-01-23T05:34:25","slug":"noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/","title":{"rendered":"Noboa anuncia nuevas medidas en materia de seguridad y econom\u00eda"},"content":{"rendered":"<p><span style=\"color: #000000\"><strong>REDACCI\u00d3N NOTI-AM\u00c9RICA (ECUADOR)<\/strong><\/span><\/p>\n<div style=\"width: 2570px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.comunicacion.gob.ec\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-22-at-07.47.51.jpeg\" alt=\"\" width=\"2560\" height=\"1706\" \/><p class=\"wp-caption-text\">Entrevista al presidente Noboa<\/p><\/div>\n<p style=\"text-align: justify\">Esta ma\u00f1ana, el presidente de la Rep\u00fablica, Daniel Noboa Azin, en entrevista con Teleamazonas, se refiri\u00f3 a los resultados y acciones de su Gobierno en materia de seguridad y econom\u00eda, as\u00ed como el anuncio de nuevas decisiones para garantizar el funcionamiento productivo del pa\u00eds.<\/p>\n<p style=\"text-align: justify\">Precisamente, sobre este punto el primer mandatario anunci\u00f3 que pr\u00f3ximamente se implementar\u00e1 la semaforizaci\u00f3n para la aplicaci\u00f3n del toque de queda. Esta iniciativa busca focalizar los horarios de restricci\u00f3n de movilidad de acuerdo a la situaci\u00f3n de cada cant\u00f3n, con el objetivo de proteger la econom\u00eda del sector tur\u00edstico, productivo y empresarial y fomentar su reactivaci\u00f3n.\u00a0<strong><em>\u201cNo podemos permitir que estos grupos narcoterroristas destruyan nuestra forma de vivir y nuestro d\u00eda a d\u00eda trabajando\u201d<\/em><\/strong>, se\u00f1al\u00f3.<\/p>\n<p style=\"text-align: justify\">Asimismo, el presidente se\u00f1al\u00f3 la posibilidad de extender el Estado de Excepci\u00f3n, destacando la necesidad de mantener una continuidad en las estrategias implementadas. Asegur\u00f3 que los operativos permanentes de las Fuerzas Armadas y la Polic\u00eda Nacional han arrojado resultados contundentes:\u00a0<strong><em>\u201cNo podemos parar, no podemos descansar y no podemos creer que esto se ha solucionado en dos semanas, hay que seguir luchando\u201d<\/em><\/strong>, se\u00f1al\u00f3.<\/p>\n<p style=\"text-align: justify\">Estos resultados se reflejan en cifras. El presidente inform\u00f3: \u201c<strong><em>hemos logrado frenar una avalancha de violencia y disminuir de manera dram\u00e1tica las muertes violentas y la criminalidad\u00bb<\/em><\/strong>, pasando de 28 a seis muertes diarias. Tambi\u00e9n se refiri\u00f3 a la reducci\u00f3n del riesgo pa\u00eds de Ecuador que es un indicador favorable de las acciones del Gobierno. Sin embargo, el presidente fue enf\u00e1tico al asegurar que el indicador m\u00e1s importante de su gesti\u00f3n ser\u00e1 la generaci\u00f3n de empleo, la dinamizaci\u00f3n de la econom\u00eda y la resoluci\u00f3n de los problemas de seguridad.<\/p>\n<p style=\"text-align: justify\">En relaci\u00f3n la situaci\u00f3n en las c\u00e1rceles, inform\u00f3 que se mantienen conversaciones con los gobiernos de Colombia y Per\u00fa para repatriar a ciudadanos de dichos pa\u00edses que actualmente contribuyen al hacinamiento penitenciario. Estas medidas, en conjunto con la reestructuraci\u00f3n \u00a0y la construcci\u00f3n de dos nuevos centros de privaci\u00f3n de libertad, tienen como objetivo fortalecer el sistema penitenciario del pa\u00eds.<\/p>\n<p style=\"text-align: justify\">Y, en cuanto a la cooperaci\u00f3n internacional, destac\u00f3 que las miradas se han puesto en el pa\u00eds, entendiendo que Ecuador es una pieza clave dentro de la ruta y estructura de estos grupos narcoterroristas.\u00a0<strong><em>\u201cSi logramos tener el control, la regi\u00f3n mejora\u201d.\u00a0<\/em><\/strong>En este contexto, anunci\u00f3 que las conversaciones con Estados Unidos se enfocar\u00e1n en el respaldo en tecnolog\u00eda, armamento, monitoreo, protecci\u00f3n de fronteras e incluso en la posibilidad de refinanciamiento de la deuda externa.<\/p>\n<p style=\"text-align: justify\">A decir del primer mandatario, golpear los bolsillos del crimen organizado ha sido fundamental en esta lucha pero, para continuar haci\u00e9ndolo, remarc\u00f3 la importancia de aportar econ\u00f3micamente como pa\u00eds en este conflicto armado interno. En ese sentido destac\u00f3 los proyectos de ley de extinci\u00f3n de dominio y el incremento del IVA al 15 %.<\/p>\n<p style=\"text-align: justify\">Asegur\u00f3 que las conversaciones son constantes con el Legislativo. Por un lado, inform\u00f3 que la Ley de extinci\u00f3n de dominio ya tuvo la aprobaci\u00f3n del CAL. Mientras que, sobre la propuesta del incremento del IVA, indic\u00f3 que se pueden escuchar propuestas y llegar a acuerdos, principalmente resalt\u00f3 su apertura a definir la temporalidad de la medida, tal como ya se hizo en administraciones pasadas ante hechos emergentes.\u00a0<strong><em>\u201cSe trata de pensar en c\u00f3mo financiar esta guerra, c\u00f3mo luchar contra estos grupos narco terroristas que est\u00e1n llenos de dinero\u201d<\/em><\/strong>.<\/p>\n<p style=\"text-align: justify\">Asimismo, se\u00f1al\u00f3 que se recortar\u00e1n mil millones de d\u00f3lares en gastos administrativos dentro del Estado, que tambi\u00e9n tiene que \u201c<strong><em>apretar el cintur\u00f3n y hacer un sacrificio. Tambi\u00e9n creo que deber\u00edan cobrarse las utilidades de la banca\u201d<\/em><\/strong>. Este proceso se efectuar\u00e1 de la mano de la consolidaci\u00f3n de un ambiente de generaci\u00f3n de empleo para precautelar que estas medidas no afecten a los empleados p\u00fablicos.<\/p>\n<p style=\"text-align: justify\">Respecto a otros mecanismos de obtenci\u00f3n de recursos para continuar con la lucha contra el terrorismo, Noboa indic\u00f3 que la posibilidad de una focalizaci\u00f3n de los subsidios de los combustibles deber\u00e1 ejecutarse de la mano de un proceso de mejoramiento de la eficiencia energ\u00e9tica, en generaci\u00f3n y transmisi\u00f3n el\u00e9ctrica y en refinamiento nacional; de tal manera que el costo al consumidor sea el mismo.\u00a0<strong><em>\u00abNo vamos a eliminar los subsidios al pueblo y no vamos a afectar al peque\u00f1o agricultor\u00bb<\/em><\/strong>.<\/p>\n<p style=\"text-align: justify\">Finalmente, respecto a la consulta popular el presidente Daniel Noboa Azin resalt\u00f3 que asumiendo su responsabilidad con el pa\u00eds present\u00f3 preguntas que recogen las principales preocupaciones ciudadanas,\u00a0<strong><em>\u00abla Corte Constitucional va a tener que trabajar en conjunto con el Ejecutivo, y como ciudadanos deber\u00e1n hacer lo mejor para el Ecuador\u00bb<\/em><\/strong>. Adem\u00e1s, detall\u00f3 que la pregunta relacionada a casinos fue retirada debido a que no generaba afinidad de ciertos sectores. Considerando los tiempos contemplados en la ley, el Jefe de Estado estima que el plebiscito se pueda ejecutar cerca del 10 de marzo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REDACCI\u00d3N NOTI-AM\u00c9RICA (ECUADOR) Esta ma\u00f1ana, el presidente de la Rep\u00fablica, Daniel Noboa Azin, en entrevista con Teleamazonas, se refiri\u00f3 a los resultados y acciones de su Gobierno en materia de seguridad y econom\u00eda, as\u00ed&#46;&#46;&#46;<\/p>\n","protected":false},"author":17,"featured_media":37482,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10219548024599422_1632221337088128":"","twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[3],"tags":[],"class_list":["post-37481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Noboa anuncia nuevas medidas en materia de seguridad y econom\u00eda - Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noboa anuncia nuevas medidas en materia de seguridad y econom\u00eda\" \/>\n<meta property=\"og:description\" content=\"REDACCI\u00d3N NOTI-AM\u00c9RICA (ECUADOR) Esta ma\u00f1ana, el presidente de la Rep\u00fablica, Daniel Noboa Azin, en entrevista con Teleamazonas, se refiri\u00f3 a los resultados y acciones de su Gobierno en materia de seguridad y econom\u00eda, as\u00ed&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/\" \/>\n<meta property=\"og:site_name\" content=\"Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-23T05:34:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/01\/Entrevista-al-Presidente-Noboa.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gregory Quintana Montiel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gdgregori1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gregory Quintana Montiel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/\"},\"author\":{\"name\":\"Gregory Quintana Montiel\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e\"},\"headline\":\"Noboa anuncia nuevas medidas en materia de seguridad y econom\u00eda\",\"datePublished\":\"2024-01-23T05:34:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/\"},\"wordCount\":879,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/01\/Entrevista-al-Presidente-Noboa.jpeg\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/\",\"name\":\"Noboa anuncia nuevas medidas en materia de seguridad y econom\u00eda - Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/01\/Entrevista-al-Presidente-Noboa.jpeg\",\"datePublished\":\"2024-01-23T05:34:25+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/01\/Entrevista-al-Presidente-Noboa.jpeg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/01\/Entrevista-al-Presidente-Noboa.jpeg\",\"width\":2560,\"height\":1706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/principal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noboa anuncia nuevas medidas en materia de seguridad y econom\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/\",\"name\":\"Noti-America.com\",\"description\":\"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e\",\"name\":\"Gregory Quintana Montiel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g\",\"caption\":\"Gregory Quintana Montiel\"},\"description\":\"Licenciatura en Ciencias de la Comunicaci\u00f3n Social, egresado en la Especializaci\u00f3n Derecho Ambiental Desarrollo Sostenible y Sustentable, Miembro de la Comunidad de profesionales y experto para Latinoam\u00e9rica y el Caribe en Gesti\u00f3n por Resultado en el Desarrollo (COPLAC - GpRD) del Banco Interamericano de Desarrollo, experiencia en medios radiales y escritos.\",\"sameAs\":[\"https:\/\/x.com\/gdgregori1\",\"gquintana\"],\"url\":\"https:\/\/noti-america.com\/site\/principal\/author\/gquintana\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Noboa anuncia nuevas medidas en materia de seguridad y econom\u00eda - Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/","og_locale":"es_ES","og_type":"article","og_title":"Noboa anuncia nuevas medidas en materia de seguridad y econom\u00eda","og_description":"REDACCI\u00d3N NOTI-AM\u00c9RICA (ECUADOR) Esta ma\u00f1ana, el presidente de la Rep\u00fablica, Daniel Noboa Azin, en entrevista con Teleamazonas, se refiri\u00f3 a los resultados y acciones de su Gobierno en materia de seguridad y econom\u00eda, as\u00ed&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/","og_site_name":"Noti-America.com","article_published_time":"2024-01-23T05:34:25+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/01\/Entrevista-al-Presidente-Noboa.jpeg","type":"image\/jpeg"}],"author":"Gregory Quintana Montiel","twitter_card":"summary_large_image","twitter_creator":"@gdgregori1","twitter_misc":{"Escrito por":"Gregory Quintana Montiel","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/"},"author":{"name":"Gregory Quintana Montiel","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e"},"headline":"Noboa anuncia nuevas medidas en materia de seguridad y econom\u00eda","datePublished":"2024-01-23T05:34:25+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/"},"wordCount":879,"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/01\/Entrevista-al-Presidente-Noboa.jpeg","articleSection":["Pol\u00edtica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/","url":"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/","name":"Noboa anuncia nuevas medidas en materia de seguridad y econom\u00eda - Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/01\/Entrevista-al-Presidente-Noboa.jpeg","datePublished":"2024-01-23T05:34:25+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/#primaryimage","url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/01\/Entrevista-al-Presidente-Noboa.jpeg","contentUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2024\/01\/Entrevista-al-Presidente-Noboa.jpeg","width":2560,"height":1706},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/principal\/2024\/01\/23\/noboa-anuncia-nuevas-medidas-en-materia-de-seguridad-y-economia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/principal\/"},{"@type":"ListItem","position":2,"name":"Noboa anuncia nuevas medidas en materia de seguridad y econom\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/principal\/#website","url":"https:\/\/noti-america.com\/site\/principal\/","name":"Noti-America.com","description":"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e","name":"Gregory Quintana Montiel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g","caption":"Gregory Quintana Montiel"},"description":"Licenciatura en Ciencias de la Comunicaci\u00f3n Social, egresado en la Especializaci\u00f3n Derecho Ambiental Desarrollo Sostenible y Sustentable, Miembro de la Comunidad de profesionales y experto para Latinoam\u00e9rica y el Caribe en Gesti\u00f3n por Resultado en el Desarrollo (COPLAC - GpRD) del Banco Interamericano de Desarrollo, experiencia en medios radiales y escritos.","sameAs":["https:\/\/x.com\/gdgregori1","gquintana"],"url":"https:\/\/noti-america.com\/site\/principal\/author\/gquintana\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/37481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/comments?post=37481"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/37481\/revisions"}],"predecessor-version":[{"id":37487,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/37481\/revisions\/37487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media\/37482"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media?parent=37481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/categories?post=37481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/tags?post=37481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}