{"id":1555,"date":"2018-03-22T08:22:09","date_gmt":"2018-03-22T08:22:09","guid":{"rendered":"http:\/\/noti-america.com\/site\/alemania\/?p=1555"},"modified":"2018-03-22T08:22:09","modified_gmt":"2018-03-22T08:22:09","slug":"lula-podria-ingresar-a-prision-el-proximo-lunes","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/","title":{"rendered":"Lula podr\u00eda ingresar a prisi\u00f3n el pr\u00f3ximo lunes"},"content":{"rendered":"<p><span class=\"dateline\">Sao Paulo, 21 mar\u00a0&#8211; <\/span>Un Tribunal Regional Federal de Brasil analizar\u00e1 el pr\u00f3ximo lunes 26 de marzo el recurso interpuesto por Luiz In\u00e1cio Lula da Silva a su condena por corrupci\u00f3n y lavado de dinero: si la decisi\u00f3n se mantiene, el ex presidente de Brasil puede ingresar a la c\u00e1rcel\u00a0ese mismo d\u00eda, informaron hoy medios locales.<\/p>\n<p>La reuni\u00f3n del tribunal en Porto Alegre ser\u00e1 a las 13:30 (16:30 GMT). Si la sentencia a 12 a\u00f1os y un mes de reclusi\u00f3n es ratificada por los tres jueces que la analizar\u00e1n, el juez S\u00e9rgio Moro, quien lleva a cabo el proceso, podr\u00e1 pedir el ingreso\u00a0a prisi\u00f3n de Lula ese d\u00eda o, a m\u00e1s tardar, al d\u00eda siguiente.<\/p>\n<p>En el caso de que la decisi\u00f3n se modifique, o no sea un\u00e1nime, Moro deber\u00e1 esperar la publicaci\u00f3n de los votos o el texto modificado de la sentencia, para luego tomar una decisi\u00f3n sobre la potencial reclusi\u00f3n. El plazo de publicaci\u00f3n de la medida es de diez d\u00edas como m\u00e1ximo.<\/p>\n<p>Lula, de 72 a\u00f1os y quien se encuentra de gira electoral por el sur del pa\u00eds, fue condenado el 24 de enero\u00a0en segunda instancia por el tribunal de Porto Alegre,\u00a0por haber aceptado la reforma de un apartamento que ten\u00eda previsto comprar en la costa de Sao Paulo, a cambio de favorecer a la constructora OAS en sus negocios con la petrolera estatal Petrobras.<\/p>\n<p>El 20 de febrero, sin embargo, su defensa\u00a0interpuso un recurso contra la condena, que es el que se analizar\u00e1 el pr\u00f3ximo lunes.<\/p>\n<p>En el documento presentado los abogados de Lula se\u00f1alaron 38 omisiones en la decisi\u00f3n del tribunal respecto a elementos que constan en el proceso, 16 contradicciones y cinco \u00abobscuridades\u00bb, es decir decisiones de dif\u00edcil comprensi\u00f3n.<\/p>\n<p>Una vez que el recurso sea juzgado, y m\u00e1s all\u00e1 de su potencial reclusi\u00f3n, Lula puede acudir todav\u00eda al Tribunal Superior de Justicia (STJ) o al Supremo Tribunal Federal (STF).<\/p>\n<p>El STJ es la corte responsable de uniformar la interpretaci\u00f3n de la ley federal en todo el pa\u00eds. El STF es la instancia m\u00e1xima del poder judicial brasile\u00f1o. En el caso de que Lula decida presentar recursos a\u00a0estas cortes, ambas tienen la facultad de revertir la condena del tribunal de Porto Alegre.<\/p>\n<p>El pasado lunes, Moro se manifest\u00f3 respecto a los rumores de una posible revisi\u00f3n de jurisprudencia por parte del STF, por la cual no se podr\u00eda apresar a un condenado tras la decisi\u00f3n que lo condena en segunda instancia sin antes agotar todos los recursos. Seg\u00fan el juez, si eso sucediese ser\u00eda \u00abdesastroso\u00bb.<\/p>\n<p>\u00abUna eventual alteraci\u00f3n de jurisprudencia ser\u00eda desastrosa para los avances recientes respecto al fin de la impunidad de la gran corrupci\u00f3n en Brasil\u00bb, dijo el magistrado, en lo que los medios locales entendieron como un \u00abmensaje\u00bb de cara al proceso de Lula.<\/p>\n<p>Este jueves, adem\u00e1s, el plenario del STF se pronunciar\u00e1 sobre el pedido de h\u00e1beas corpus preventivo realizado por la defensa de Lula, con el que los abogados pretenden evitar la reclusi\u00f3n del ex presidente hasta tanto se agoten todos los recursos a ser presentados.<\/p>\n<p>Un h\u00e1beas corpus preventivo es un instrumento jur\u00eddico que se usa para asegurar la libertad de una persona, incluso si esa persona no est\u00e1 presa. El recurso se constituye como\u00a0una garant\u00eda constitucional que se puede utilizar para evitar una reclusi\u00f3n considerada ilegal. En el caso de ser aceptado, el juez otorga un salvoconducto al solicitante.<\/p>\n<p>Quien ya fuera presidente de Brasil entre 2003 y 2010 lidera todas las encuestas para convertirse por tercera vez en jefe de Estado, con un 37\u00a0por ciento en los \u00faltimos sondeos.<\/p>\n<p>En el caso de que, por su condena, un tribunal electoral inhabilite al l\u00edder del izquierdista Partido de los Trabajadores (PT)\u00a0para presentarse en las elecciones presidenciales de octubre, el escenario pol\u00edtico brasile\u00f1o mudar\u00e1 dr\u00e1sticamente hacia una situaci\u00f3n que, por ahora, se presenta incierta para todos los partidos.<\/p>\n<p>CP (dpa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sao Paulo, 21 mar\u00a0&#8211; Un Tribunal Regional Federal de Brasil analizar\u00e1 el pr\u00f3ximo lunes 26 de marzo el recurso interpuesto por Luiz In\u00e1cio Lula da Silva a su condena por corrupci\u00f3n y lavado de&#46;&#46;&#46;<\/p>\n","protected":false},"author":31,"featured_media":1556,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10219548024599422_1632221337088128":"","twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[93,3],"tags":[],"class_list":["post-1555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lula podr\u00eda ingresar a prisi\u00f3n el pr\u00f3ximo lunes - Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lula podr\u00eda ingresar a prisi\u00f3n el pr\u00f3ximo lunes\" \/>\n<meta property=\"og:description\" content=\"Sao Paulo, 21 mar\u00a0&#8211; Un Tribunal Regional Federal de Brasil analizar\u00e1 el pr\u00f3ximo lunes 26 de marzo el recurso interpuesto por Luiz In\u00e1cio Lula da Silva a su condena por corrupci\u00f3n y lavado de&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/\" \/>\n<meta property=\"og:site_name\" content=\"Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-22T08:22:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2018\/03\/LulaDaSilva.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"678\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ydalith Figueroa Kad-Bay\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ydalithkad\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ydalith Figueroa Kad-Bay\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/\"},\"author\":{\"name\":\"Ydalith Figueroa Kad-Bay\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/209a32aab8da938719a2d7cdfe16df64\"},\"headline\":\"Lula podr\u00eda ingresar a prisi\u00f3n el pr\u00f3ximo lunes\",\"datePublished\":\"2018-03-22T08:22:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/\"},\"wordCount\":707,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2018\/03\/LulaDaSilva.jpg\",\"articleSection\":[\"Brasil\",\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/\",\"name\":\"Lula podr\u00eda ingresar a prisi\u00f3n el pr\u00f3ximo lunes - Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2018\/03\/LulaDaSilva.jpg\",\"datePublished\":\"2018-03-22T08:22:09+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/209a32aab8da938719a2d7cdfe16df64\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2018\/03\/LulaDaSilva.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2018\/03\/LulaDaSilva.jpg\",\"width\":678,\"height\":381},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/principal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lula podr\u00eda ingresar a prisi\u00f3n el pr\u00f3ximo lunes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/principal\/\",\"name\":\"Noti-America.com\",\"description\":\"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/209a32aab8da938719a2d7cdfe16df64\",\"name\":\"Ydalith Figueroa Kad-Bay\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/7d1e350465afd215908c3ed413e32ef600cd41c3c21b95416252432a9f6c219c?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7d1e350465afd215908c3ed413e32ef600cd41c3c21b95416252432a9f6c219c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7d1e350465afd215908c3ed413e32ef600cd41c3c21b95416252432a9f6c219c?s=96&d=mm&r=g\",\"caption\":\"Ydalith Figueroa Kad-Bay\"},\"description\":\"CEO Noti-America Alemania Embajadora de Venezuela para el Proyecto de Acci\u00f3n Clim\u00e1tica de la ONU, Embajadora para la ense\u00f1anza de los ODS de la ONU, Amplificador de la Acci\u00f3n de los ODS de la ONU, Profesor Voluntario del Proyecto KAKUMA (Educaci\u00f3n de calidad para refugiados en \u00c1frica) UNHCR \u2013 ACNUR - Agencia para los refugiados de la ONU-, Miembro de la ONG Gente Y Ciudad, Embajador de las Instituciones de Microfinanzas \u201cNo a la pobreza ODS #1 de la ONU\u201d (todos tienen derecho a acceso a un cr\u00e9dito), y Voluntario al di\u00e1logo global de UN75. Twitter @ydalithkad email ydalith@yhaoo.com Locutor Profesional 32931 Universidad Central de Venezuela @ISHannover \\\"Colegio Internacional de Hannover Regi\u00f3n, Alemania\\\" Representante de Aprendizaje Innovaci\u00f3n y Tecnolog\u00eda #LMS (Sistema de Gesti\u00f3n de Aprendizaje) #LMS Gente y Ciudad &amp; Asesores Internacionales ONG Alemania. ONG \\\"Gente y Ciudad, Venezuela\\\" Miembro y Asesor especialista An\u00e1lisis de Pol\u00edtica Internacional Asesor Pol\u00edtico Internacional de Venezuela en la defensa de los Derechos Humanos y el restablecimiento Democr\u00e1tico. Diplomacia positiva y Activa. Pasi\u00f3n por el Golf Proyecto #LMS \\\"Golf para ni\u00f1os y adultos Internacional\\\" Pasi\u00f3n por los Postres Proyecto #LMS \\\"Postres, Que Unen a las Culturas del mundo\\\"\",\"sameAs\":[\"https:\/\/x.com\/ydalithkad\"],\"url\":\"https:\/\/noti-america.com\/site\/principal\/author\/yfigueroa\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lula podr\u00eda ingresar a prisi\u00f3n el pr\u00f3ximo lunes - Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/","og_locale":"es_ES","og_type":"article","og_title":"Lula podr\u00eda ingresar a prisi\u00f3n el pr\u00f3ximo lunes","og_description":"Sao Paulo, 21 mar\u00a0&#8211; Un Tribunal Regional Federal de Brasil analizar\u00e1 el pr\u00f3ximo lunes 26 de marzo el recurso interpuesto por Luiz In\u00e1cio Lula da Silva a su condena por corrupci\u00f3n y lavado de&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/","og_site_name":"Noti-America.com","article_published_time":"2018-03-22T08:22:09+00:00","og_image":[{"width":678,"height":381,"url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2018\/03\/LulaDaSilva.jpg","type":"image\/jpeg"}],"author":"Ydalith Figueroa Kad-Bay","twitter_card":"summary_large_image","twitter_creator":"@ydalithkad","twitter_misc":{"Escrito por":"Ydalith Figueroa Kad-Bay","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/"},"author":{"name":"Ydalith Figueroa Kad-Bay","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/209a32aab8da938719a2d7cdfe16df64"},"headline":"Lula podr\u00eda ingresar a prisi\u00f3n el pr\u00f3ximo lunes","datePublished":"2018-03-22T08:22:09+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/"},"wordCount":707,"commentCount":0,"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2018\/03\/LulaDaSilva.jpg","articleSection":["Brasil","Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/","url":"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/","name":"Lula podr\u00eda ingresar a prisi\u00f3n el pr\u00f3ximo lunes - Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/principal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2018\/03\/LulaDaSilva.jpg","datePublished":"2018-03-22T08:22:09+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/209a32aab8da938719a2d7cdfe16df64"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#primaryimage","url":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2018\/03\/LulaDaSilva.jpg","contentUrl":"https:\/\/noti-america.com\/site\/principal\/wp-content\/uploads\/sites\/26\/2018\/03\/LulaDaSilva.jpg","width":678,"height":381},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/principal\/2018\/03\/22\/lula-podria-ingresar-a-prision-el-proximo-lunes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/principal\/"},{"@type":"ListItem","position":2,"name":"Lula podr\u00eda ingresar a prisi\u00f3n el pr\u00f3ximo lunes"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/principal\/#website","url":"https:\/\/noti-america.com\/site\/principal\/","name":"Noti-America.com","description":"El Noticiero Digital M\u00e1s Grande de Am\u00e9rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/principal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/principal\/#\/schema\/person\/209a32aab8da938719a2d7cdfe16df64","name":"Ydalith Figueroa Kad-Bay","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7d1e350465afd215908c3ed413e32ef600cd41c3c21b95416252432a9f6c219c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d1e350465afd215908c3ed413e32ef600cd41c3c21b95416252432a9f6c219c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d1e350465afd215908c3ed413e32ef600cd41c3c21b95416252432a9f6c219c?s=96&d=mm&r=g","caption":"Ydalith Figueroa Kad-Bay"},"description":"CEO Noti-America Alemania Embajadora de Venezuela para el Proyecto de Acci\u00f3n Clim\u00e1tica de la ONU, Embajadora para la ense\u00f1anza de los ODS de la ONU, Amplificador de la Acci\u00f3n de los ODS de la ONU, Profesor Voluntario del Proyecto KAKUMA (Educaci\u00f3n de calidad para refugiados en \u00c1frica) UNHCR \u2013 ACNUR - Agencia para los refugiados de la ONU-, Miembro de la ONG Gente Y Ciudad, Embajador de las Instituciones de Microfinanzas \u201cNo a la pobreza ODS #1 de la ONU\u201d (todos tienen derecho a acceso a un cr\u00e9dito), y Voluntario al di\u00e1logo global de UN75. Twitter @ydalithkad email ydalith@yhaoo.com Locutor Profesional 32931 Universidad Central de Venezuela @ISHannover \"Colegio Internacional de Hannover Regi\u00f3n, Alemania\" Representante de Aprendizaje Innovaci\u00f3n y Tecnolog\u00eda #LMS (Sistema de Gesti\u00f3n de Aprendizaje) #LMS Gente y Ciudad &amp; Asesores Internacionales ONG Alemania. ONG \"Gente y Ciudad, Venezuela\" Miembro y Asesor especialista An\u00e1lisis de Pol\u00edtica Internacional Asesor Pol\u00edtico Internacional de Venezuela en la defensa de los Derechos Humanos y el restablecimiento Democr\u00e1tico. Diplomacia positiva y Activa. Pasi\u00f3n por el Golf Proyecto #LMS \"Golf para ni\u00f1os y adultos Internacional\" Pasi\u00f3n por los Postres Proyecto #LMS \"Postres, Que Unen a las Culturas del mundo\"","sameAs":["https:\/\/x.com\/ydalithkad"],"url":"https:\/\/noti-america.com\/site\/principal\/author\/yfigueroa\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/1555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/comments?post=1555"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/1555\/revisions"}],"predecessor-version":[{"id":1557,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/posts\/1555\/revisions\/1557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media\/1556"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/media?parent=1555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/categories?post=1555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/principal\/wp-json\/wp\/v2\/tags?post=1555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}