{"id":4514,"date":"2018-08-03T13:40:02","date_gmt":"2018-08-03T13:40:02","guid":{"rendered":"http:\/\/noti-america.com\/site\/us-fl\/?p=4514"},"modified":"2018-08-03T13:40:02","modified_gmt":"2018-08-03T13:40:02","slug":"caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/","title":{"rendered":"Caen dr\u00e1sticamente los arrestos de choferes ebrios en el sur de la Florida. Esta es la raz\u00f3n"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-4515 aligncenter\" src=\"http:\/\/noti-america.com\/site\/us-fl\/wp-content\/uploads\/sites\/16\/2018\/08\/1-9-300x169.jpg\" alt=\"\" width=\"389\" height=\"219\" srcset=\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2018\/08\/1-9-300x169.jpg 300w, https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2018\/08\/1-9-768x432.jpg 768w, https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2018\/08\/1-9-1024x576.jpg 1024w, https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2018\/08\/1-9.jpg 1140w\" sizes=\"auto, (max-width: 389px) 100vw, 389px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h5><em><strong>Fuente:\u00a0 https:\/\/www.elnuevoherald.com<\/strong><\/em><\/h5>\n<p>&nbsp;<\/p>\n<p>En el sur de la\u00a0Florida, los clubes est\u00e1n abiertos hasta altas horas de la noche, el alcohol fluye libremente y el sistema de transporte p\u00fablico deja mucho que desear. Pero la cantidad de conductores\u00a0ebrios\u00a0en las calles parece estar disminuyendo.<\/p>\n<p>Al menos, el n\u00famero de los que han sido arrestados.<\/p>\n<p>En los \u00faltimos cuatro a\u00f1os, los\u00a0arrestos\u00a0por DUI (conducir bajo la influencia) realizados por los dos departamentos de\u00a0Polic\u00eda\u00a0m\u00e1s grandes de\u00a0Miami-Dade han ca\u00eddo en picada. En el departamento de\u00a0Polic\u00eda\u00a0de\u00a0Miami-Dade, el m\u00e1s grande del sureste Estados Unidos, las detenciones cayeron un asombroso 65 por ciento en el 2017 en comparaci\u00f3n con los cuatro a\u00f1os anteriores. La\u00a0Polic\u00eda\u00a0de\u00a0Miami-Dade arrest\u00f3 a m\u00e1s de 1,500 personas al a\u00f1o entre el 2013 y el 2015, pero solo se hicieron 594\u00a0arrestos\u00a0por el mismo cargo el a\u00f1o pasado.<\/p>\n<p>Los n\u00fameros de\u00a0Miami\u00a0no fueron tan llamativos, aunque tambi\u00e9n disminuyeron mucho. La\u00a0Polic\u00eda\u00a0de\u00a0Miami\u00a0arrest\u00f3 a 461 personas por cargos de DUI en el 2013. Para el 2015, el n\u00famero se redujo a 321 y se ha estabilizado desde entonces, una disminuci\u00f3n del 31 por ciento.<\/p>\n<p>Parte del \u00e9xito probablemente se relaciona con el aumento de compa\u00f1\u00edas como Uber y Lyft. Su creciente popularidad coincidi\u00f3 casi directamente con la ca\u00edda en los\u00a0arrestos\u00a0por DUI, pero los estudios muestran que los impactos var\u00edan de una ciudad a otra.<\/p>\n<p>Tambi\u00e9n entran en juego otros factores, dicen los que rastrean las estad\u00edsticas. Algunos atribuyen la disminuci\u00f3n a un p\u00fablico mejor educado. Otros apuntan a una actuaci\u00f3n m\u00e1s proactiva de las autoridades y que a los\u00a0<em>millennials<\/em>\u00a0no les gusta conducir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Fuente:\u00a0 https:\/\/www.elnuevoherald.com &nbsp; En el sur de la\u00a0Florida, los clubes est\u00e1n abiertos hasta altas horas de la noche, el alcohol fluye libremente y el sistema de transporte p\u00fablico deja mucho que desear. Pero&#46;&#46;&#46;<\/p>\n","protected":false},"author":28,"featured_media":4515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[448],"class_list":["post-4514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-caen-drasticamente-los-arrestos-de-choferes-ebrios"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Caen dr\u00e1sticamente los arrestos de choferes ebrios en el sur de la Florida. Esta es la raz\u00f3n - Florida | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caen dr\u00e1sticamente los arrestos de choferes ebrios en el sur de la Florida. Esta es la raz\u00f3n\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Fuente:\u00a0 https:\/\/www.elnuevoherald.com &nbsp; En el sur de la\u00a0Florida, los clubes est\u00e1n abiertos hasta altas horas de la noche, el alcohol fluye libremente y el sistema de transporte p\u00fablico deja mucho que desear. Pero&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/\" \/>\n<meta property=\"og:site_name\" content=\"Florida | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-03T13:40:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2018\/08\/1-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"641\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n NA-NY\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:site\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n NA-NY\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/\"},\"author\":{\"name\":\"Redacci\u00f3n NA-NY\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#\/schema\/person\/ad79855629ba14540b48d12bd54f8f33\"},\"headline\":\"Caen dr\u00e1sticamente los arrestos de choferes ebrios en el sur de la Florida. Esta es la raz\u00f3n\",\"datePublished\":\"2018-08-03T13:40:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/\"},\"wordCount\":317,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2018\/08\/1-9.jpg\",\"keywords\":[\"Caen dr\u00e1sticamente los arrestos de choferes ebrios\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/\",\"url\":\"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/\",\"name\":\"Caen dr\u00e1sticamente los arrestos de choferes ebrios en el sur de la Florida. Esta es la raz\u00f3n - Florida | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2018\/08\/1-9.jpg\",\"datePublished\":\"2018-08-03T13:40:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2018\/08\/1-9.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2018\/08\/1-9.jpg\",\"width\":1140,\"height\":641},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/florida\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caen dr\u00e1sticamente los arrestos de choferes ebrios en el sur de la Florida. Esta es la raz\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/florida\/\",\"name\":\"Florida | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/florida\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#organization\",\"name\":\"Noti-America LLC | Florida - USA\",\"url\":\"https:\/\/noti-america.com\/site\/florida\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/us-fl\/wp-content\/uploads\/sites\/16\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/us-fl\/wp-content\/uploads\/sites\/16\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Florida - USA\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/notiamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#\/schema\/person\/ad79855629ba14540b48d12bd54f8f33\",\"name\":\"Redacci\u00f3n NA-NY\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/2bd75bb500a8deb1390f777293a9af32d934c46613d2fbac7cceb2aaa2679ae8?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2bd75bb500a8deb1390f777293a9af32d934c46613d2fbac7cceb2aaa2679ae8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2bd75bb500a8deb1390f777293a9af32d934c46613d2fbac7cceb2aaa2679ae8?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n NA-NY\"},\"url\":\"https:\/\/noti-america.com\/site\/florida\/author\/redaccionny\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Caen dr\u00e1sticamente los arrestos de choferes ebrios en el sur de la Florida. Esta es la raz\u00f3n - Florida | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/","og_locale":"es_ES","og_type":"article","og_title":"Caen dr\u00e1sticamente los arrestos de choferes ebrios en el sur de la Florida. Esta es la raz\u00f3n","og_description":"&nbsp; Fuente:\u00a0 https:\/\/www.elnuevoherald.com &nbsp; En el sur de la\u00a0Florida, los clubes est\u00e1n abiertos hasta altas horas de la noche, el alcohol fluye libremente y el sistema de transporte p\u00fablico deja mucho que desear. Pero&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/","og_site_name":"Florida | Noti-America.com","article_published_time":"2018-08-03T13:40:02+00:00","og_image":[{"width":1140,"height":641,"url":"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2018\/08\/1-9.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n NA-NY","twitter_card":"summary_large_image","twitter_creator":"@notiamerica","twitter_site":"@notiamerica","twitter_misc":{"Escrito por":"Redacci\u00f3n NA-NY","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/"},"author":{"name":"Redacci\u00f3n NA-NY","@id":"https:\/\/noti-america.com\/site\/florida\/#\/schema\/person\/ad79855629ba14540b48d12bd54f8f33"},"headline":"Caen dr\u00e1sticamente los arrestos de choferes ebrios en el sur de la Florida. Esta es la raz\u00f3n","datePublished":"2018-08-03T13:40:02+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/"},"wordCount":317,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/florida\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2018\/08\/1-9.jpg","keywords":["Caen dr\u00e1sticamente los arrestos de choferes ebrios"],"articleSection":["Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/","url":"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/","name":"Caen dr\u00e1sticamente los arrestos de choferes ebrios en el sur de la Florida. Esta es la raz\u00f3n - Florida | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/florida\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2018\/08\/1-9.jpg","datePublished":"2018-08-03T13:40:02+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#primaryimage","url":"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2018\/08\/1-9.jpg","contentUrl":"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2018\/08\/1-9.jpg","width":1140,"height":641},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/florida\/2018\/08\/03\/caen-drasticamente-los-arrestos-de-choferes-ebrios-en-el-sur-de-la-florida-esta-es-la-razon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/florida\/"},{"@type":"ListItem","position":2,"name":"Caen dr\u00e1sticamente los arrestos de choferes ebrios en el sur de la Florida. Esta es la raz\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/florida\/#website","url":"https:\/\/noti-america.com\/site\/florida\/","name":"Florida | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/florida\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/florida\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/florida\/#organization","name":"Noti-America LLC | Florida - USA","url":"https:\/\/noti-america.com\/site\/florida\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/florida\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/us-fl\/wp-content\/uploads\/sites\/16\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/us-fl\/wp-content\/uploads\/sites\/16\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Florida - USA"},"image":{"@id":"https:\/\/noti-america.com\/site\/florida\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/notiamerica"]},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/florida\/#\/schema\/person\/ad79855629ba14540b48d12bd54f8f33","name":"Redacci\u00f3n NA-NY","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2bd75bb500a8deb1390f777293a9af32d934c46613d2fbac7cceb2aaa2679ae8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bd75bb500a8deb1390f777293a9af32d934c46613d2fbac7cceb2aaa2679ae8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bd75bb500a8deb1390f777293a9af32d934c46613d2fbac7cceb2aaa2679ae8?s=96&d=mm&r=g","caption":"Redacci\u00f3n NA-NY"},"url":"https:\/\/noti-america.com\/site\/florida\/author\/redaccionny\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/posts\/4514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/comments?post=4514"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/posts\/4514\/revisions"}],"predecessor-version":[{"id":4516,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/posts\/4514\/revisions\/4516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/media\/4515"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/media?parent=4514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/categories?post=4514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/tags?post=4514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}