{"id":13796,"date":"2023-10-14T00:17:29","date_gmt":"2023-10-14T00:17:29","guid":{"rendered":"https:\/\/noti-america.com\/site\/us-fl\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/"},"modified":"2023-10-14T00:17:29","modified_gmt":"2023-10-14T00:17:29","slug":"manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/","title":{"rendered":"Manuel Ruiz impacta con su libro \u201cLibera tu potencial creativo"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13793\" src=\"https:\/\/noti-america.com\/site\/us-fl\/wp-content\/uploads\/sites\/16\/2023\/10\/libro-ruiz-m-206x300.jpg\" alt=\"\" width=\"206\" height=\"300\" srcset=\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/libro-ruiz-m-206x300.jpg 206w, https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/libro-ruiz-m-704x1024.jpg 704w, https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/libro-ruiz-m-768x1117.jpg 768w, https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/libro-ruiz-m-1057x1536.jpg 1057w, https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/libro-ruiz-m-1409x2048.jpg 1409w, https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/libro-ruiz-m-scaled.jpg 1761w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" \/><\/p>\n<p style=\"font-weight: 400\">\n<p style=\"font-weight: 400\">\n<p style=\"font-weight: 400\">Manuel Ruiz es un talento que no conoce l\u00edmites. Creativo en la m\u00e1s alta exaltaci\u00f3n. Ruiz es un creativo experto y un inspirador. Es el autor del libro \u201cLibera tu potencial creativo\u201d, una gu\u00eda para desarrollar la creatividad y el pensamiento innovador.<\/p>\n<p style=\"font-weight: 400\">\n<p style=\"font-weight: 400\">Comprobado experto en el funcionamiento interno de la mente creativa. \u00c9l comparte sus conocimientos y experiencias para ayudar a otros a desarrollar su creatividad. Su libro ofrece una variedad de herramientas\u00a0 dispuestas para ayudarte a ser especial y exitoso.<\/p>\n<p style=\"font-weight: 400\">\n<p style=\"font-weight: 400\">Manuel Ruiz es un orador motivacional y un mentor para aquellos que buscan desarrollar su creatividad. \u00c9l comparte sus conocimientos y experiencias para ayudar a otros. Su libro, es un emocionante viaje a trav\u00e9s del reino ilimitado de la creatividad, una obra maestra literaria, que revela el funcionamiento interno de la mente creativa: \u00a0la clave para abrir las puertas de logros art\u00edsticos incomparables.\u00a0Este libro desmantela las barreras que obstaculizan tu odisea creativa.<\/p>\n<p style=\"font-weight: 400\">A trav\u00e9s de las p\u00e1ginas de \u201cLibera tu potencial creativo\u201d te ayuda a \u00a0sumergirte en las profundidades de la psique creativa, una exploraci\u00f3n fascinante que revela los secretos para catalizar la metamorfosis. M\u00e1s all\u00e1 de los simples trazos de un pincel o el baile de una pluma, este libro cristaliza la esencia del viaje creativo, un viaje que trasciende el lienzo y el pergamino, alterando la estructura misma del mundo.<\/p>\n<p style=\"font-weight: 400\">Te invitamos a disfrutar de esta fascinante herramienta literaria en el link\u00a0<a href=\"https:\/\/www.amazon.com\/dp\/B0CHTQ1YG2\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.amazon.com\/dp\/B0CHTQ1YG2&amp;source=gmail&amp;ust=1697296793704000&amp;usg=AOvVaw37AZOgL7T3PLT48yKGrJwu\">https:\/\/www.amazon.com\/dp\/B0CHTQ1YG2<\/a>\u00a0y descubre tu verdadero potencial creativo para lograr el \u00e9xito que tanto anhelas.<\/p>\n<p style=\"font-weight: 400\">Una vez te adentras desde sus primeras p\u00e1ginas lograr\u00e1s despertar ese mundo tan ilimitado que escondes en tu mente, pues ofrece una variedad de herramientas y t\u00e9cnicas para ayudarte a liberar tu potencial creati<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Manuel Ruiz es un talento que no conoce l\u00edmites. Creativo en la m\u00e1s alta exaltaci\u00f3n. Ruiz es un creativo experto y un inspirador. Es el autor del libro \u201cLibera tu potencial creativo\u201d, una&#46;&#46;&#46;<\/p>\n","protected":false},"author":120,"featured_media":13797,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Manuel Ruiz impacta con su libro \u201cLibera tu potencial creativo - Florida | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manuel Ruiz impacta con su libro \u201cLibera tu potencial creativo\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Manuel Ruiz es un talento que no conoce l\u00edmites. Creativo en la m\u00e1s alta exaltaci\u00f3n. Ruiz es un creativo experto y un inspirador. Es el autor del libro \u201cLibera tu potencial creativo\u201d, una&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Florida | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-14T00:17:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/portada-libro-ruiz-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2330\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CJROJAS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:site\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"CJROJAS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/\"},\"author\":{\"name\":\"CJROJAS\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#\/schema\/person\/825105d6c664f6550458e132afb50883\"},\"headline\":\"Manuel Ruiz impacta con su libro \u201cLibera tu potencial creativo\",\"datePublished\":\"2023-10-14T00:17:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/\"},\"wordCount\":315,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/portada-libro-ruiz-scaled.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/\",\"url\":\"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/\",\"name\":\"Manuel Ruiz impacta con su libro \u201cLibera tu potencial creativo - Florida | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/portada-libro-ruiz-scaled.jpg\",\"datePublished\":\"2023-10-14T00:17:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/portada-libro-ruiz-scaled.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/portada-libro-ruiz-scaled.jpg\",\"width\":2330,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/florida\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manuel Ruiz impacta con su libro \u201cLibera tu potencial creativo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/florida\/\",\"name\":\"Florida | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/florida\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#organization\",\"name\":\"Noti-America LLC | Florida - USA\",\"url\":\"https:\/\/noti-america.com\/site\/florida\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/us-fl\/wp-content\/uploads\/sites\/16\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/us-fl\/wp-content\/uploads\/sites\/16\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Florida - USA\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/notiamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#\/schema\/person\/825105d6c664f6550458e132afb50883\",\"name\":\"CJROJAS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/c9cd06db5b861f3be12b32d0c2d4240efeaa1acc0ebc61ee588713d1cb75fa1f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c9cd06db5b861f3be12b32d0c2d4240efeaa1acc0ebc61ee588713d1cb75fa1f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c9cd06db5b861f3be12b32d0c2d4240efeaa1acc0ebc61ee588713d1cb75fa1f?s=96&d=mm&r=g\",\"caption\":\"CJROJAS\"},\"url\":\"https:\/\/noti-america.com\/site\/florida\/author\/ccamargo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Manuel Ruiz impacta con su libro \u201cLibera tu potencial creativo - Florida | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/","og_locale":"es_ES","og_type":"article","og_title":"Manuel Ruiz impacta con su libro \u201cLibera tu potencial creativo","og_description":"&nbsp; Manuel Ruiz es un talento que no conoce l\u00edmites. Creativo en la m\u00e1s alta exaltaci\u00f3n. Ruiz es un creativo experto y un inspirador. Es el autor del libro \u201cLibera tu potencial creativo\u201d, una&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/","og_site_name":"Florida | Noti-America.com","article_published_time":"2023-10-14T00:17:29+00:00","og_image":[{"width":2330,"height":2560,"url":"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/portada-libro-ruiz-scaled.jpg","type":"image\/jpeg"}],"author":"CJROJAS","twitter_card":"summary_large_image","twitter_creator":"@notiamerica","twitter_site":"@notiamerica","twitter_misc":{"Escrito por":"CJROJAS","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/"},"author":{"name":"CJROJAS","@id":"https:\/\/noti-america.com\/site\/florida\/#\/schema\/person\/825105d6c664f6550458e132afb50883"},"headline":"Manuel Ruiz impacta con su libro \u201cLibera tu potencial creativo","datePublished":"2023-10-14T00:17:29+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/"},"wordCount":315,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/florida\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/portada-libro-ruiz-scaled.jpg","articleSection":["Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/","url":"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/","name":"Manuel Ruiz impacta con su libro \u201cLibera tu potencial creativo - Florida | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/florida\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/portada-libro-ruiz-scaled.jpg","datePublished":"2023-10-14T00:17:29+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#primaryimage","url":"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/portada-libro-ruiz-scaled.jpg","contentUrl":"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/10\/portada-libro-ruiz-scaled.jpg","width":2330,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/florida\/2023\/10\/14\/manuel-ruiz-impacta-con-su-libro-libera-tu-potencial-creativo-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/florida\/"},{"@type":"ListItem","position":2,"name":"Manuel Ruiz impacta con su libro \u201cLibera tu potencial creativo"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/florida\/#website","url":"https:\/\/noti-america.com\/site\/florida\/","name":"Florida | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/florida\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/florida\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/florida\/#organization","name":"Noti-America LLC | Florida - USA","url":"https:\/\/noti-america.com\/site\/florida\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/florida\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/us-fl\/wp-content\/uploads\/sites\/16\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/us-fl\/wp-content\/uploads\/sites\/16\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Florida - USA"},"image":{"@id":"https:\/\/noti-america.com\/site\/florida\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/notiamerica"]},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/florida\/#\/schema\/person\/825105d6c664f6550458e132afb50883","name":"CJROJAS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c9cd06db5b861f3be12b32d0c2d4240efeaa1acc0ebc61ee588713d1cb75fa1f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c9cd06db5b861f3be12b32d0c2d4240efeaa1acc0ebc61ee588713d1cb75fa1f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c9cd06db5b861f3be12b32d0c2d4240efeaa1acc0ebc61ee588713d1cb75fa1f?s=96&d=mm&r=g","caption":"CJROJAS"},"url":"https:\/\/noti-america.com\/site\/florida\/author\/ccamargo\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/posts\/13796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/users\/120"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/comments?post=13796"}],"version-history":[{"count":0,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/posts\/13796\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/media\/13797"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/media?parent=13796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/categories?post=13796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/tags?post=13796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}