{"id":12841,"date":"2023-03-11T14:18:12","date_gmt":"2023-03-11T14:18:12","guid":{"rendered":"https:\/\/noti-america.com\/site\/us-fl\/?p=12841"},"modified":"2023-03-11T14:19:58","modified_gmt":"2023-03-11T14:19:58","slug":"carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/","title":{"rendered":"Carolina Quintero celebra los 15 a\u00f1os de su espacio \u201cEl placer de la belleza\u201d por La Rom\u00e1ntica 88.9FM"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-12842\" src=\"https:\/\/noti-america.com\/site\/us-fl\/wp-content\/uploads\/sites\/16\/2023\/03\/IMG-20230310-WA0004-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/03\/IMG-20230310-WA0004-225x300.jpg 225w, https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/03\/IMG-20230310-WA0004-600x800.jpg 600w, https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/03\/IMG-20230310-WA0004.jpg 768w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u201cEl Placer de la Belleza\u201d es un programa\u00a0 pionero, l\u00edder y tem\u00e1tico que desde el 2008 se transmite a trav\u00e9s de la se\u00f1al radiof\u00f3nica de La Rom\u00e1ntica 88.9 FM Center a nivel nacional, \u00a0para ofrecer a mujeres y hombres, todos esos consejos, tips, trucos y dem\u00e1s de lo que est\u00e1 en tendencia, lo \u00faltimo en cosm\u00e9tica para cuidar la piel, el cabello y sentirse especial y sobre todo esos tratamientos para \u00a0mantenerla la piel saludable.<\/strong><\/p>\n<p><strong>Este espacio radial es conducido por la reconocida periodista y especialista en belleza Carolina Quintero. Ella es referente en cuestiones de belleza y cuidados de la piel, maquillaje, tendencia y lo innovador de la industria de la cosm\u00e9tica internacional. <\/strong><\/p>\n<p><strong>\u201cEl placer de la belleza\u201d arriba a sus 15 a\u00f1os de transmisi\u00f3n ininterrumpida por La Rom\u00e1ntica, emisora del circuito FM Center en Venezuela. Y Carolina Quintero lo celebra en grande con noticias, sorteos, entrevistas y m\u00e1s para agradecer a su audiencia su fidelidad.<\/strong><\/p>\n<p><strong>Una vez le preguntaron a Quintero sobre que significaba para ella la belleza y la acuciosa periodista expres\u00f3 \u201dEs una emoci\u00f3n, es algo que te hace sentir bien contigo misma. El maquillaje es tu aliado y si aprendes a usarlo correctamente realzas tus rasgos m\u00e1s sobresalientes, o viceversa, para estar a gusto con tu f\u00edsico, con tu aspecto. Cuando logres ese ideal te sientes hermosa y lo proyectas a todo el que te rodea. De ah\u00ed, la belleza interna se hace acompa\u00f1ar, y a d\u00fao, reflejan esa belleza que s\u00f3lo te pertenece a ti.<\/strong><\/p>\n<p><strong>Recuerden este imperdible espacio <\/strong>los d\u00edas s\u00e1bados y domingos a las 4 pm por la Rom\u00e1ntica 88.9 FM Center a nivel nacional que celebra sus 15 a\u00f1os de exitosa existencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u201cEl Placer de la Belleza\u201d es un programa\u00a0 pionero, l\u00edder y tem\u00e1tico que desde el 2008 se transmite a trav\u00e9s de la se\u00f1al radiof\u00f3nica de La Rom\u00e1ntica 88.9 FM Center a nivel nacional,&#46;&#46;&#46;<\/p>\n","protected":false},"author":120,"featured_media":12842,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-12841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-y-espectaculos"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Carolina Quintero celebra los 15 a\u00f1os de su espacio \u201cEl placer de la belleza\u201d por La Rom\u00e1ntica 88.9FM - Florida | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carolina Quintero celebra los 15 a\u00f1os de su espacio \u201cEl placer de la belleza\u201d por La Rom\u00e1ntica 88.9FM\" \/>\n<meta property=\"og:description\" content=\"&nbsp; \u201cEl Placer de la Belleza\u201d es un programa\u00a0 pionero, l\u00edder y tem\u00e1tico que desde el 2008 se transmite a trav\u00e9s de la se\u00f1al radiof\u00f3nica de La Rom\u00e1ntica 88.9 FM Center a nivel nacional,&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/\" \/>\n<meta property=\"og:site_name\" content=\"Florida | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-11T14:18:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-11T14:19:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/03\/IMG-20230310-WA0004.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CJROJAS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:site\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"CJROJAS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/\"},\"author\":{\"name\":\"CJROJAS\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#\/schema\/person\/825105d6c664f6550458e132afb50883\"},\"headline\":\"Carolina Quintero celebra los 15 a\u00f1os de su espacio \u201cEl placer de la belleza\u201d por La Rom\u00e1ntica 88.9FM\",\"datePublished\":\"2023-03-11T14:18:12+00:00\",\"dateModified\":\"2023-03-11T14:19:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/\"},\"wordCount\":318,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/03\/IMG-20230310-WA0004.jpg\",\"articleSection\":[\"Arte y Espect\u00e1culos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/\",\"url\":\"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/\",\"name\":\"Carolina Quintero celebra los 15 a\u00f1os de su espacio \u201cEl placer de la belleza\u201d por La Rom\u00e1ntica 88.9FM - Florida | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/03\/IMG-20230310-WA0004.jpg\",\"datePublished\":\"2023-03-11T14:18:12+00:00\",\"dateModified\":\"2023-03-11T14:19:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/03\/IMG-20230310-WA0004.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/03\/IMG-20230310-WA0004.jpg\",\"width\":768,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/florida\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carolina Quintero celebra los 15 a\u00f1os de su espacio \u201cEl placer de la belleza\u201d por La Rom\u00e1ntica 88.9FM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/florida\/\",\"name\":\"Florida | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/florida\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#organization\",\"name\":\"Noti-America LLC | Florida - USA\",\"url\":\"https:\/\/noti-america.com\/site\/florida\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/us-fl\/wp-content\/uploads\/sites\/16\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/us-fl\/wp-content\/uploads\/sites\/16\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Florida - USA\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/notiamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/florida\/#\/schema\/person\/825105d6c664f6550458e132afb50883\",\"name\":\"CJROJAS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/c9cd06db5b861f3be12b32d0c2d4240efeaa1acc0ebc61ee588713d1cb75fa1f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c9cd06db5b861f3be12b32d0c2d4240efeaa1acc0ebc61ee588713d1cb75fa1f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c9cd06db5b861f3be12b32d0c2d4240efeaa1acc0ebc61ee588713d1cb75fa1f?s=96&d=mm&r=g\",\"caption\":\"CJROJAS\"},\"url\":\"https:\/\/noti-america.com\/site\/florida\/author\/ccamargo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Carolina Quintero celebra los 15 a\u00f1os de su espacio \u201cEl placer de la belleza\u201d por La Rom\u00e1ntica 88.9FM - Florida | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/","og_locale":"es_ES","og_type":"article","og_title":"Carolina Quintero celebra los 15 a\u00f1os de su espacio \u201cEl placer de la belleza\u201d por La Rom\u00e1ntica 88.9FM","og_description":"&nbsp; \u201cEl Placer de la Belleza\u201d es un programa\u00a0 pionero, l\u00edder y tem\u00e1tico que desde el 2008 se transmite a trav\u00e9s de la se\u00f1al radiof\u00f3nica de La Rom\u00e1ntica 88.9 FM Center a nivel nacional,&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/","og_site_name":"Florida | Noti-America.com","article_published_time":"2023-03-11T14:18:12+00:00","article_modified_time":"2023-03-11T14:19:58+00:00","og_image":[{"width":768,"height":1024,"url":"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/03\/IMG-20230310-WA0004.jpg","type":"image\/jpeg"}],"author":"CJROJAS","twitter_card":"summary_large_image","twitter_creator":"@notiamerica","twitter_site":"@notiamerica","twitter_misc":{"Escrito por":"CJROJAS","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/"},"author":{"name":"CJROJAS","@id":"https:\/\/noti-america.com\/site\/florida\/#\/schema\/person\/825105d6c664f6550458e132afb50883"},"headline":"Carolina Quintero celebra los 15 a\u00f1os de su espacio \u201cEl placer de la belleza\u201d por La Rom\u00e1ntica 88.9FM","datePublished":"2023-03-11T14:18:12+00:00","dateModified":"2023-03-11T14:19:58+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/"},"wordCount":318,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/florida\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/03\/IMG-20230310-WA0004.jpg","articleSection":["Arte y Espect\u00e1culos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/","url":"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/","name":"Carolina Quintero celebra los 15 a\u00f1os de su espacio \u201cEl placer de la belleza\u201d por La Rom\u00e1ntica 88.9FM - Florida | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/florida\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/03\/IMG-20230310-WA0004.jpg","datePublished":"2023-03-11T14:18:12+00:00","dateModified":"2023-03-11T14:19:58+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#primaryimage","url":"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/03\/IMG-20230310-WA0004.jpg","contentUrl":"https:\/\/noti-america.com\/site\/florida\/wp-content\/uploads\/sites\/16\/2023\/03\/IMG-20230310-WA0004.jpg","width":768,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/florida\/2023\/03\/11\/carolina-quintero-celebra-los-15-anos-de-su-espacio-el-placer-de-la-belleza-por-la-romantica-88-9fm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/florida\/"},{"@type":"ListItem","position":2,"name":"Carolina Quintero celebra los 15 a\u00f1os de su espacio \u201cEl placer de la belleza\u201d por La Rom\u00e1ntica 88.9FM"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/florida\/#website","url":"https:\/\/noti-america.com\/site\/florida\/","name":"Florida | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/florida\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/florida\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/florida\/#organization","name":"Noti-America LLC | Florida - USA","url":"https:\/\/noti-america.com\/site\/florida\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/florida\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/us-fl\/wp-content\/uploads\/sites\/16\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/us-fl\/wp-content\/uploads\/sites\/16\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Florida - USA"},"image":{"@id":"https:\/\/noti-america.com\/site\/florida\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/notiamerica"]},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/florida\/#\/schema\/person\/825105d6c664f6550458e132afb50883","name":"CJROJAS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c9cd06db5b861f3be12b32d0c2d4240efeaa1acc0ebc61ee588713d1cb75fa1f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c9cd06db5b861f3be12b32d0c2d4240efeaa1acc0ebc61ee588713d1cb75fa1f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c9cd06db5b861f3be12b32d0c2d4240efeaa1acc0ebc61ee588713d1cb75fa1f?s=96&d=mm&r=g","caption":"CJROJAS"},"url":"https:\/\/noti-america.com\/site\/florida\/author\/ccamargo\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/posts\/12841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/users\/120"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/comments?post=12841"}],"version-history":[{"count":2,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/posts\/12841\/revisions"}],"predecessor-version":[{"id":12844,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/posts\/12841\/revisions\/12844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/media\/12842"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/media?parent=12841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/categories?post=12841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/florida\/wp-json\/wp\/v2\/tags?post=12841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}