{"id":8693,"date":"2023-11-27T11:07:10","date_gmt":"2023-11-27T11:07:10","guid":{"rendered":"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/"},"modified":"2023-11-27T11:07:10","modified_gmt":"2023-11-27T11:07:10","slug":"estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/","title":{"rendered":"Estos son los competidores alemanes, franceses y brit\u00e1nicos de la startup espa\u00f1ola PLD"},"content":{"rendered":"<p><strong>NOTI-AMERICA.COM | ESPA\u00d1A<\/strong><\/p>\n<p>www.atalayar.com<\/p>\n<h1 class=\"title\">Estos son los competidores alemanes, franceses y brit\u00e1nicos de la startup espa\u00f1ola PLD<\/h1>\n<p>Cinco cohetes de Alemania, Francia y el Reino Unido disputan al Miura 5 el puesto de primer lanzador comercial de Europa<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.atalayar.com\/asset\/thumbnail,1280,720,center,center\/media\/atalayar\/images\/2023\/11\/27\/2023112710062658589.jpg\" alt=\"PHOTO\/PLD Space - El director general de la ESA, Josef Aschbacher, ha dicho de PLD que es una empresa s\u00f3lida y cre\u00edble. A su lado, Ezequiel S\u00e1nchez, Ra\u00fal Verd\u00fa (PLD) y el director de la Agencia Espacial Espa\u00f1ola, Miguel Bell\u00f3\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 8pt;\">PHOTO\/PLD Space &#8211; El director general de la ESA, Josef Aschbacher, ha dicho de PLD que es una empresa s\u00f3lida y cre\u00edble. A su lado, Ezequiel S\u00e1nchez, Ra\u00fal Verd\u00fa (PLD) y el director de la Agencia Espacial Espa\u00f1ola, Miguel Bell\u00f3<\/span><\/p>\n<p><a href=\"https:\/\/www.atalayar.com\/author\/juan-pons\">Juan Pons<\/a><\/p>\n<p>M\u00e1s de cuatro millones de personas han tenido la oportunidad de contemplar y conocer en detalle en Antena 3 Televisi\u00f3n un modelo a escala natural del\u00a0<strong>lanzador suborbital Miura 1 desarrollado por la compa\u00f1\u00eda espa\u00f1ola PLD Space.<\/strong><\/p>\n<p><strong>Tambi\u00e9n pudieron ver el gran tama\u00f1o de la parte superior de su hermano mayor, el Miura 5, concebido para situar sat\u00e9lites en la \u00f3rbita terrestre<\/strong>. Fue el martes, 21 de noviembre, durante la emisi\u00f3n del programa \u201cEl Hormiguero\u201d que dirige Pablo Motos.<\/p>\n<p><strong>Otros cientos de miles de espa\u00f1oles se hab\u00edan emocionado el 7 de octubre cuando presenciaron en directo el impresionante despegue del primer cohete fabricado \u00edntegramente en Espa\u00f1a<\/strong>. Sus satisfechos protagonistas son los directivos y empleados de PLD, empresa privada asentada en Elche, Alicante, y formada por un equipo entusiasta de ingenieros y t\u00e9cnicos repletos de ilusi\u00f3n y ganas de hacer bien su trabajo.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.atalayar.com\/media\/atalayar\/images\/2023\/11\/27\/2023112710062721413.jpg\" alt=\"PHOTO\/ And\u00f8ya Spaceport - La direcci\u00f3n del puerto espacial de And\u00f8ya y la compa\u00f1\u00eda Isar han acordado la construcci\u00f3n de una plataforma de despegue para uso exclusivo del lanzador Spectrum de la empresa alemana\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 8pt;\"><strong>PHOTO\/ And\u00f8ya Spaceport\u00a0<\/strong>&#8211; La direcci\u00f3n del puerto espacial de And\u00f8ya y la compa\u00f1\u00eda Isar han acordado la construcci\u00f3n de una plataforma de despegue para uso exclusivo del lanzador Spectrum de la empresa alemana<\/span><\/p>\n<p><strong>Tras el satisfactorio vuelo del Miura 1, su presidente Ezequiel Sanchez, los fundadores de PLD, Ra\u00fal Torres y Ra\u00fal Verd\u00fa, y su plana mayor han decidido que es conveniente un segundo disparo de validaci\u00f3n<\/strong>. Todav\u00eda sin fecha programada, con ese nuevo lanzamiento pretenden demostrar la viabilidad del Miura 1, que es la base tecnol\u00f3gica para hacer realidad el Miura 5, que aspira a convertirse en el primer cohete comercial de Europa y hacer de PLD \u201cla compa\u00f1\u00eda de tecnolog\u00eda m\u00e1s influyente de Europa en el sector espacio\u201d, anhela Ezequiel S\u00e1nchez.<\/p>\n<p><strong>Pero en la Uni\u00f3n Europea hace a\u00f1os que existen compa\u00f1\u00edas que siguen de cerca los pasos de los emprendedores de Elche<\/strong>. Proyectos semejantes est\u00e1n en marcha en Alemania, Dinamarca, Francia, Italia, Noruega, Pa\u00edses Bajos, Polonia y el Reino Unido. Son startups, es decir, empresas emergentes con una filosof\u00eda de negocio y una tecnolog\u00eda innovadora, que compiten con financiaci\u00f3n privada para desarrollar peque\u00f1os lanzadores. Sus ojos est\u00e1n puestos en Bruselas y en la Agencia Espacial Europea (ESA), que deben decidir qui\u00e9n o quienes merecen alzarse con la victoria, recibir su sello y sus millones.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.atalayar.com\/media\/atalayar\/images\/2023\/11\/27\/2023112710062758764.jpg\" alt=\"PHOTO\/RFA - La coordinadora de la pol\u00edtica espacial de Alemania y parlamentaria del Bundestag, Anna Christmann, con los elegidos para embarcar sat\u00e9lites en el segundo vuelo del lanzador RFA One\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 8pt;\"><strong>PHOTO\/RFA<\/strong>\u00a0&#8211; La coordinadora de la pol\u00edtica espacial de Alemania y parlamentaria del Bundestag, Anna Christmann, con los elegidos para embarcar sat\u00e9lites en el segundo vuelo del lanzador RFA One<\/span><\/p>\n<p><big>El fabricante de autom\u00f3viles Porsche es uno de los inversionistas<\/big><\/p>\n<p><strong>Entre casi una veintena de startups, cinco han puesto en marcha proyectos muy a tener en cuenta, que gozan de una especial protecci\u00f3n de sus respectivas agencias espaciales<\/strong>. Son la brit\u00e1nica Orbital Express Launch (Orbex), la francesa Maiaspace y tres alemanas: HyImpulse Technologies Gamba, Isar Aerospace Technologies GmbH y Rocket Factory Augsburg AG, conocida en el sector por su acr\u00f3nimo RFA.<\/p>\n<p><strong>Casualmente, las tres alemanas est\u00e1n localizadas en importantes polos industriales de las cercan\u00edas de M\u00fanich, la capital de Baviera, cuentan con el apoyo del gobierno federal y los euros de un notable grupo de inversores privados<\/strong>. Es el caso de Isar, que ha recibido inyecciones de fondos por un valor cercano a los 300 millones de euros. Uno de sus 12 accionistas es la automovil\u00edstica Porsche, aunque tambi\u00e9n ha recibido subvenciones de la UE por valor 10 millones de euros.<\/p>\n<p><strong>Fundada en 2018 y con su sede central en Ottobrunn, a una quincena de kil\u00f3metros de M\u00fanich, el micro lanzador que ha desarrollado Isar se llama Spectrum<\/strong>, tiene dos etapas de propulsi\u00f3n \u2012motor Aquila de oxigeno l\u00edquido y propano\u2012 y capacidad para situar sat\u00e9lites de hasta 1 tonelada en \u00f3rbita terrestre baja. Su despegue est\u00e1 previsto para \u201cel segundo semestre del a\u00f1o en curso\u201d, seg\u00fan la compa\u00f1\u00eda, que todav\u00eda no ha informado de la fecha.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.atalayar.com\/media\/atalayar\/images\/2023\/11\/27\/2023112710062776126.jpg\" alt=\"PHOTO\/RFA - De 30 metros de altura y tres etapas de propulsi\u00f3n, el RFA One es el mayor micro lanzador privado que est\u00e1 en desarrollo en Europa. Volar\u00e1 desde la base sueca de Kiruna y tambi\u00e9n desde la Guayana\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 8pt;\"><strong>PHOTO\/RFA<\/strong>\u00a0&#8211; De 30 metros de altura y tres etapas de propulsi\u00f3n, el RFA One es el mayor micro lanzador privado que est\u00e1 en desarrollo en Europa. Volar\u00e1 desde la base sueca de Kiruna y tambi\u00e9n desde la Guayana<\/span><\/p>\n<p><strong>El primer Spectrum embarcar\u00e1 siete min\u00fasculos sat\u00e9lites, que buscan validar tecnolog\u00edas de comunicaciones y datos meteorol\u00f3gicos<\/strong>. Esas cargas las han proporcionado cinco universidades e instituciones de Alemania, como la agencia aeroespacial alemana (DLR), el Instituto de Ingenier\u00eda Aeroespacial de Berl\u00edn y el Centro de Telem\u00e1tica de W\u00fcrzburg. Tambi\u00e9n la Universidad Noruega de Ciencia y Tecnolog\u00eda de Trondheim y el Instituto de Electr\u00f3nica y Telecomunicaciones de la Universidad de Maribor, de Eslovenia.<\/p>\n<p><strong>El vuelo inaugural se producir\u00e1 desde una plataforma que Isar ha sufragado en la reci\u00e9n modernizada base espacial noruega de And\u00f8ya<\/strong>, con la que la sociedad alemana suscribi\u00f3 un acuerdo en abril de 2021 para efectuar desde all\u00ed sus lanzamientos durante \u00a020 a\u00f1os con car\u00e1cter de exclusividad. Tambi\u00e9n ha recibido el benepl\u00e1cito de la agencia espacial gala para despegar desde la Guayana francesa.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.atalayar.com\/media\/atalayar\/images\/2023\/11\/27\/2023112710062998071.png\" alt=\"PHOTO\/RFA-DLR - La presidenta de la Agencia Aeroespacial de Alemania, Anke Kaysser-Pyzalla, mantiene estrechos acuerdos con RFA, la empresa de servicios de lanzamiento patrocinada por OHB, el gran fabricante alem\u00e1n de sat\u00e9lites\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 8pt;\"><strong>PHOTO\/RFA-DLR<\/strong>\u00a0&#8211; La presidenta de la Agencia Aeroespacial de Alemania, Anke Kaysser-Pyzalla, mantiene estrechos acuerdos con RFA, la empresa de servicios de lanzamiento patrocinada por OHB, el gran fabricante alem\u00e1n de sat\u00e9lites<\/span><\/p>\n<p><big>El enano gigante de 30 metros de RFA<\/big><\/p>\n<p><strong>Una segunda startup germana que disputa la primac\u00eda a PLD es RFA, cuyo cuartel general est\u00e1 en Augsburgo, a unos 55 kil\u00f3metros al noroeste de M\u00fanich<\/strong>. Es la empresa de servicios de lanzamiento patrocinada por OHB, el gran fabricante alem\u00e1n de sat\u00e9lites, cuyo mayor accionista \u201269,72 por ciento\u2012 es la familia Fuchs que encabeza Marco Fuchs, de 61 a\u00f1os.<\/p>\n<p><strong>RFA ha desarrollado el cohete RFA One, de 30 metros de altura y tres etapas propulsivas dotadas con motores-cohete Helix<\/strong>, que han sido sometidos a pruebas en la base espacial sueca de Kiruna, reinaugurada en enero pasado por el rey Carlos Gustavo y la presidenta de la Comisi\u00f3n Europea, \u00darsula von der Leyen. El RFA One podr\u00e1 emplazar en \u00f3rbita polar a 2.000 kil\u00f3metros una carga de 850 kilos.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.atalayar.com\/media\/atalayar\/images\/2023\/11\/27\/2023112710062957116.jpg\" alt=\"PHOTO\/Maiaspace - El lanzador Maia aprovecha los trabajos llevados a cabo en el cohete Themis. Cuenta con dos etapas de propulsi\u00f3n y es parcialmente reutilizable.\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 8pt;\"><strong>PHOTO\/Maiaspace<\/strong>\u00a0&#8211; El lanzador Maia aprovecha los trabajos llevados a cabo en el cohete Themis. Cuenta con dos etapas de propulsi\u00f3n y es parcialmente reutilizable<\/span><\/p>\n<p><strong>Para su primer vuelo, cinco instituciones cient\u00edficas alemanas y dos italianas proporcionan cargas con un peso al despegue de 136 kilos<\/strong>. Y para el segundo lanzamiento del RFA One, el pasado 23 de noviembre se han seleccionado ocho sat\u00e9lites que pesan 200 kilos. Pertenecen a cinco instituciones de Alemania, una de Bulgaria, otra de Polonia y otra de Espa\u00f1a, de la Universidad Polit\u00e9cnica de Catalu\u00f1a, que aporta el nano sat\u00e9lite 3Cat-8.<\/p>\n<p><strong>La tercera empresa privada germana es HyImpulse, con sede social en la peque\u00f1a localidad de Neuenstadt am Kocher, pero con sus oficinas de dise\u00f1o en Ottobrunn<\/strong>. Creada en 2018 y filial de DLR, su proyecto es el cohete de tres etapas propulsivas hibridas SL-1, dise\u00f1ado para colocar en el espacio hasta 500 kilos. Siguiendo la metodolog\u00eda de PLD con el Miura 1 y el Miura 5, HyImpulse trabaja tambi\u00e9n en el cohete suborbital SR-75, que har\u00e1 las veces de demostrador tecnol\u00f3gico y volar\u00e1 en marzo de 2024 desde el centro de ensayos de Koonibba, en Australia.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.atalayar.com\/media\/atalayar\/images\/2023\/11\/27\/2023112710063073508.png\" alt=\"PHOTO\/HyImpulse \u2013 El cohete de HyImpulse se llama SL-1 y dispone de tres etapas propulsivas hibridas para colocar en el espacio hasta 500 kilos\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 8pt;\"><strong>PHOTO\/HyImpulse<\/strong>\u00a0\u2013 El cohete de HyImpulse se llama SL-1 y dispone de tres etapas propulsivas hibridas para colocar en el espacio hasta 500 kilos<\/span><\/p>\n<p><strong>La sociedad francesa Maiaspace parte de una posici\u00f3n privilegiada. Es una filial al 100 por cien de ArianeGroup, contratista principal del Ariane 6 formada a partes iguales por Airbus Defence and Space France y el motorista galo Safran<\/strong>. Establecida en 2021 con el impulso del presidente Macron, Maia tiene dos etapas de propulsi\u00f3n con el motor de metano Prometheus \u2012financiado por la ESA\u2012 y aprovecha los trabajos llevados a cabo en el cohete Themis parcialmente reutilizable. En su vuelo inaugural previsto para 2025 debe poner en \u00f3rbita una carga del orden de 500 kilos.<\/p>\n<p><strong>Entre las iniciativas brit\u00e1nicas, la m\u00e1s destacada es la de Orbex, una sociedad constituida en mayo de 2015 que ha recibido m\u00e1s de 100 millones de libras de financiaci\u00f3n privada, de la ESA y de la agencia espacial brit\u00e1nica<\/strong>. Participada por las filiales brit\u00e1nica y portuguesa de la espa\u00f1ola Deimos Space, su lanzador orbital reutilizable Prime tiene una altura de 19 metros, dos etapas de propulsi\u00f3n con motores de oxigeno l\u00edquido y GLP para posicionar hasta 200 kilos en \u00f3rbita baja. Su vuelo inaugural desde el Centro Espacial Sutherland, en el norte de Escocia, sufre serias demoras y no ser\u00e1 hasta finales de 2024 o incluso 2025.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA.COM | ESPA\u00d1A www.atalayar.com Estos son los competidores alemanes, franceses y brit\u00e1nicos de la startup espa\u00f1ola PLD Cinco cohetes de Alemania, Francia y el Reino Unido disputan al Miura 5 el puesto de primer&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":8694,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-8693","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-internacionales","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Estos son los competidores alemanes, franceses y brit\u00e1nicos de la startup espa\u00f1ola PLD - Espa\u00f1a | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estos son los competidores alemanes, franceses y brit\u00e1nicos de la startup espa\u00f1ola PLD\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA.COM | ESPA\u00d1A www.atalayar.com Estos son los competidores alemanes, franceses y brit\u00e1nicos de la startup espa\u00f1ola PLD Cinco cohetes de Alemania, Francia y el Reino Unido disputan al Miura 5 el puesto de primer&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/\" \/>\n<meta property=\"og:site_name\" content=\"Espa\u00f1a | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-27T11:07:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2023\/11\/ESPANA-agencia-epacial-espanola.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rloaiza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:site\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rloaiza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/\"},\"author\":{\"name\":\"rloaiza\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#\/schema\/person\/d3312646ba171d7ab824643fed33ea1f\"},\"headline\":\"Estos son los competidores alemanes, franceses y brit\u00e1nicos de la startup espa\u00f1ola PLD\",\"datePublished\":\"2023-11-27T11:07:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/\"},\"wordCount\":1550,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2023\/11\/ESPANA-agencia-epacial-espanola.jpg\",\"articleSection\":[\"Internacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/\",\"url\":\"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/\",\"name\":\"Estos son los competidores alemanes, franceses y brit\u00e1nicos de la startup espa\u00f1ola PLD - Espa\u00f1a | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2023\/11\/ESPANA-agencia-epacial-espanola.jpg\",\"datePublished\":\"2023-11-27T11:07:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2023\/11\/ESPANA-agencia-epacial-espanola.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2023\/11\/ESPANA-agencia-epacial-espanola.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/espana\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estos son los competidores alemanes, franceses y brit\u00e1nicos de la startup espa\u00f1ola PLD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/espana\/\",\"name\":\"Espa\u00f1a | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/espana\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#organization\",\"name\":\"Noti-America LLC | Espa\u00f1a\",\"url\":\"https:\/\/noti-america.com\/site\/espana\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Espa\u00f1a\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/notiamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#\/schema\/person\/d3312646ba171d7ab824643fed33ea1f\",\"name\":\"rloaiza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/190058e5d4427934610b99c45aa7a6558806850adedd53ddeddd194b04773e22?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/190058e5d4427934610b99c45aa7a6558806850adedd53ddeddd194b04773e22?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/190058e5d4427934610b99c45aa7a6558806850adedd53ddeddd194b04773e22?s=96&d=mm&r=g\",\"caption\":\"rloaiza\"},\"url\":\"https:\/\/noti-america.com\/site\/espana\/author\/rloaiza\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Estos son los competidores alemanes, franceses y brit\u00e1nicos de la startup espa\u00f1ola PLD - Espa\u00f1a | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/","og_locale":"es_ES","og_type":"article","og_title":"Estos son los competidores alemanes, franceses y brit\u00e1nicos de la startup espa\u00f1ola PLD","og_description":"NOTI-AMERICA.COM | ESPA\u00d1A www.atalayar.com Estos son los competidores alemanes, franceses y brit\u00e1nicos de la startup espa\u00f1ola PLD Cinco cohetes de Alemania, Francia y el Reino Unido disputan al Miura 5 el puesto de primer&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/","og_site_name":"Espa\u00f1a | Noti-America.com","article_published_time":"2023-11-27T11:07:10+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2023\/11\/ESPANA-agencia-epacial-espanola.jpg","type":"image\/jpeg"}],"author":"rloaiza","twitter_card":"summary_large_image","twitter_creator":"@notiamerica","twitter_site":"@notiamerica","twitter_misc":{"Escrito por":"rloaiza","Tiempo estimado de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/"},"author":{"name":"rloaiza","@id":"https:\/\/noti-america.com\/site\/espana\/#\/schema\/person\/d3312646ba171d7ab824643fed33ea1f"},"headline":"Estos son los competidores alemanes, franceses y brit\u00e1nicos de la startup espa\u00f1ola PLD","datePublished":"2023-11-27T11:07:10+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/"},"wordCount":1550,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/espana\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2023\/11\/ESPANA-agencia-epacial-espanola.jpg","articleSection":["Internacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/","url":"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/","name":"Estos son los competidores alemanes, franceses y brit\u00e1nicos de la startup espa\u00f1ola PLD - Espa\u00f1a | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/espana\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2023\/11\/ESPANA-agencia-epacial-espanola.jpg","datePublished":"2023-11-27T11:07:10+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#primaryimage","url":"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2023\/11\/ESPANA-agencia-epacial-espanola.jpg","contentUrl":"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2023\/11\/ESPANA-agencia-epacial-espanola.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/espana\/2023\/11\/27\/estos-son-los-competidores-alemanes-franceses-y-britanicos-de-la-startup-espanola-pld\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/espana\/"},{"@type":"ListItem","position":2,"name":"Estos son los competidores alemanes, franceses y brit\u00e1nicos de la startup espa\u00f1ola PLD"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/espana\/#website","url":"https:\/\/noti-america.com\/site\/espana\/","name":"Espa\u00f1a | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/espana\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/espana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/espana\/#organization","name":"Noti-America LLC | Espa\u00f1a","url":"https:\/\/noti-america.com\/site\/espana\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/espana\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Espa\u00f1a"},"image":{"@id":"https:\/\/noti-america.com\/site\/espana\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/notiamerica"]},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/espana\/#\/schema\/person\/d3312646ba171d7ab824643fed33ea1f","name":"rloaiza","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/190058e5d4427934610b99c45aa7a6558806850adedd53ddeddd194b04773e22?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/190058e5d4427934610b99c45aa7a6558806850adedd53ddeddd194b04773e22?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/190058e5d4427934610b99c45aa7a6558806850adedd53ddeddd194b04773e22?s=96&d=mm&r=g","caption":"rloaiza"},"url":"https:\/\/noti-america.com\/site\/espana\/author\/rloaiza\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/posts\/8693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/comments?post=8693"}],"version-history":[{"count":0,"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/posts\/8693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/media\/8694"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/media?parent=8693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/categories?post=8693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/tags?post=8693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}