{"id":7281,"date":"2022-07-14T21:46:03","date_gmt":"2022-07-14T21:46:03","guid":{"rendered":"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/"},"modified":"2022-07-14T21:46:03","modified_gmt":"2022-07-14T21:46:03","slug":"normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/","title":{"rendered":"NORMAS M\u00c1S ESTRICTAS PARA AUMENTAR LA SEGURIDAD Y LA CALIDAD DE LA SANGRE, LOS TEJIDOS Y LAS C\u00c9LULAS por Redacci\u00f3n"},"content":{"rendered":"<p>NOTI-AMERICA.COM | ESPA\u00d1A<\/p>\n<p>www.aquieuropa.com<\/p>\n<h2>NORMAS M\u00c1S ESTRICTAS PARA AUMENTAR LA SEGURIDAD Y LA CALIDAD DE LA SANGRE, LOS TEJIDOS Y LAS C\u00c9LULAS<\/h2>\n<h4>por Redacci\u00f3n<\/h4>\n<blockquote><p>La Comisi\u00f3n ha aprobado una propuesta de normas para que, a la hora de donar o recibir sustancias de origen humano vitales, desde la sangre hasta los tejidos y c\u00e9lulas, incluyendo tambi\u00e9n la leche materna o la microbiota, los ciudadanos dispongan de mayor seguridad.<\/p><\/blockquote>\n<p>Mediante la propuesta de nuevas normas para aumentar a\u00fan m\u00e1s la seguridad y la calidad de las sustancias de origen humano, la Comisi\u00f3n est\u00e1 dando un paso m\u00e1s hacia la construcci\u00f3n de una s\u00f3lida Uni\u00f3n Europea de la Salud.<\/p>\n<p>El nuevo Reglamento tendr\u00e1 por objeto facilitar la circulaci\u00f3n transfronteriza de productos sanitarios cr\u00edticos y reforzar\u00e1 la solidaridad entre las autoridades de salud p\u00fablica, garantizando al mismo tiempo que el sector pueda gestionar el suministro de sustancias cr\u00edticas y promoviendo la innovaci\u00f3n con unos niveles elevados de calidad y seguridad similares para todos los ciudadanos que donen o reciban tratamiento con estas sustancias.<\/p>\n<p>Las cifras hablan por s\u00ed solas, ya que los tratamientos basados en sustancias de origen humano son de gran valor y proporcionan cada a\u00f1o un gran n\u00famero de terapias que salvan vidas y las mejoran.<\/p>\n<p>Concretamente, los pacientes de la UE reciben tratamiento con 25 millones de transfusiones de sangre para cirug\u00eda o tratamiento de traumatismos; se llevan a cabo m\u00e1s de 36 000 trasplantes de citoblastos para leucemias; las terapias generadoras de vida contribuyen al nacimiento de 165.000 beb\u00e9s procedentes de la reproducci\u00f3n asistida; y las terapias para mejorar las condiciones de vida incluyen 14.500 trasplantes de c\u00f3rnea para restablecer la vista o 2.000 trasplantes de piel para quemaduras y otras lesiones.<\/p>\n<p>Por ese motivo, la propuesta incluye un conjunto de nuevas medidas que colman determinadas lagunas y que se desarrollaron para apoyar el funcionamiento de este importante sector.<\/p>\n<p>Adem\u00e1s, la propuesta tiene por objeto abordar la preocupaci\u00f3n de contar con un suministro suficiente, que se hizo patente por la pandemia de COVID-19.<\/p>\n<p>Entre las principales novedades de la propuesta se busca mejorar la protecci\u00f3n de los pacientes, los donantes y la descendencia, mediante una cobertura de todas las sustancias de origen humano, excepto los \u00f3rganos s\u00f3lidos; mejorar la protecci\u00f3n de los receptores de terapias de SoHO, as\u00ed como de los donantes de dichas sustancias y de la descendencia procedente de la reproducci\u00f3n asistida; el aprovechamiento de los conocimientos especializados de los organismos t\u00e9cnicos existentes en Europa, para mantener actualizadas las directrices t\u00e9cnicas; y la introducci\u00f3n de medidas proporcionadas y basadas en el riesgo para reforzar la supervisi\u00f3n nacional, as\u00ed como medidas de apoyo para las autoridades nacionales por parte de la UE.<\/p>\n<p>Stella Kyriakides, comisaria de Salud y Seguridad Alimentaria, ha declarado que, \u201ccada a\u00f1o, millones de ciudadanos de la UE necesitan una transfusi\u00f3n de sangre durante una operaci\u00f3n o despu\u00e9s de un accidente, trasplantes de m\u00e9dula \u00f3sea para tratar la leucemia, o ciclos de FIV para ser padres. Estos son solo algunos ejemplos de la importancia de estos tratamientos, que constituyen una parte cr\u00edtica de los sistemas sanitarios de toda la UE. Las normas m\u00e1s estrictas que proponemos hoy garantizar\u00e1n que nuestros ciudadanos puedan beneficiarse de los niveles m\u00e1s elevados de calidad y seguridad de estos productos vitales, ya se trate de atenci\u00f3n del c\u00e1ncer o de una operaci\u00f3n de emergencia. La COVID-19 nos ha demostrado muy claramente la importancia de contar con sistemas sanitarios resilientes, y hoy estamos a\u00f1adiendo otro elemento importante a nuestra Uni\u00f3n Europea de la Salud\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA.COM | ESPA\u00d1A www.aquieuropa.com NORMAS M\u00c1S ESTRICTAS PARA AUMENTAR LA SEGURIDAD Y LA CALIDAD DE LA SANGRE, LOS TEJIDOS Y LAS C\u00c9LULAS por Redacci\u00f3n La Comisi\u00f3n ha aprobado una propuesta de normas para que,&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":7282,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-7281","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-vida-y-salud","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NORMAS M\u00c1S ESTRICTAS PARA AUMENTAR LA SEGURIDAD Y LA CALIDAD DE LA SANGRE, LOS TEJIDOS Y LAS C\u00c9LULAS por Redacci\u00f3n - Espa\u00f1a | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NORMAS M\u00c1S ESTRICTAS PARA AUMENTAR LA SEGURIDAD Y LA CALIDAD DE LA SANGRE, LOS TEJIDOS Y LAS C\u00c9LULAS por Redacci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA.COM | ESPA\u00d1A www.aquieuropa.com NORMAS M\u00c1S ESTRICTAS PARA AUMENTAR LA SEGURIDAD Y LA CALIDAD DE LA SANGRE, LOS TEJIDOS Y LAS C\u00c9LULAS por Redacci\u00f3n La Comisi\u00f3n ha aprobado una propuesta de normas para que,&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/\" \/>\n<meta property=\"og:site_name\" content=\"Espa\u00f1a | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-14T21:46:03+00:00\" \/>\n<meta name=\"author\" content=\"rloaiza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:site\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rloaiza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/\"},\"author\":{\"name\":\"rloaiza\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#\/schema\/person\/d3312646ba171d7ab824643fed33ea1f\"},\"headline\":\"NORMAS M\u00c1S ESTRICTAS PARA AUMENTAR LA SEGURIDAD Y LA CALIDAD DE LA SANGRE, LOS TEJIDOS Y LAS C\u00c9LULAS por Redacci\u00f3n\",\"datePublished\":\"2022-07-14T21:46:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/\"},\"wordCount\":652,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2022\/07\/donacion-sangre-madrid-img.jpg\",\"articleSection\":[\"Vida y Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/\",\"url\":\"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/\",\"name\":\"NORMAS M\u00c1S ESTRICTAS PARA AUMENTAR LA SEGURIDAD Y LA CALIDAD DE LA SANGRE, LOS TEJIDOS Y LAS C\u00c9LULAS por Redacci\u00f3n - Espa\u00f1a | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2022\/07\/donacion-sangre-madrid-img.jpg\",\"datePublished\":\"2022-07-14T21:46:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2022\/07\/donacion-sangre-madrid-img.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2022\/07\/donacion-sangre-madrid-img.jpg\",\"width\":1349,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/espana\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NORMAS M\u00c1S ESTRICTAS PARA AUMENTAR LA SEGURIDAD Y LA CALIDAD DE LA SANGRE, LOS TEJIDOS Y LAS C\u00c9LULAS por Redacci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/espana\/\",\"name\":\"Espa\u00f1a | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/espana\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#organization\",\"name\":\"Noti-America LLC | Espa\u00f1a\",\"url\":\"https:\/\/noti-america.com\/site\/espana\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Espa\u00f1a\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/notiamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/espana\/#\/schema\/person\/d3312646ba171d7ab824643fed33ea1f\",\"name\":\"rloaiza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/190058e5d4427934610b99c45aa7a6558806850adedd53ddeddd194b04773e22?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/190058e5d4427934610b99c45aa7a6558806850adedd53ddeddd194b04773e22?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/190058e5d4427934610b99c45aa7a6558806850adedd53ddeddd194b04773e22?s=96&d=mm&r=g\",\"caption\":\"rloaiza\"},\"url\":\"https:\/\/noti-america.com\/site\/espana\/author\/rloaiza\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NORMAS M\u00c1S ESTRICTAS PARA AUMENTAR LA SEGURIDAD Y LA CALIDAD DE LA SANGRE, LOS TEJIDOS Y LAS C\u00c9LULAS por Redacci\u00f3n - Espa\u00f1a | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/","og_locale":"es_ES","og_type":"article","og_title":"NORMAS M\u00c1S ESTRICTAS PARA AUMENTAR LA SEGURIDAD Y LA CALIDAD DE LA SANGRE, LOS TEJIDOS Y LAS C\u00c9LULAS por Redacci\u00f3n","og_description":"NOTI-AMERICA.COM | ESPA\u00d1A www.aquieuropa.com NORMAS M\u00c1S ESTRICTAS PARA AUMENTAR LA SEGURIDAD Y LA CALIDAD DE LA SANGRE, LOS TEJIDOS Y LAS C\u00c9LULAS por Redacci\u00f3n La Comisi\u00f3n ha aprobado una propuesta de normas para que,&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/","og_site_name":"Espa\u00f1a | Noti-America.com","article_published_time":"2022-07-14T21:46:03+00:00","author":"rloaiza","twitter_card":"summary_large_image","twitter_creator":"@notiamerica","twitter_site":"@notiamerica","twitter_misc":{"Escrito por":"rloaiza","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/"},"author":{"name":"rloaiza","@id":"https:\/\/noti-america.com\/site\/espana\/#\/schema\/person\/d3312646ba171d7ab824643fed33ea1f"},"headline":"NORMAS M\u00c1S ESTRICTAS PARA AUMENTAR LA SEGURIDAD Y LA CALIDAD DE LA SANGRE, LOS TEJIDOS Y LAS C\u00c9LULAS por Redacci\u00f3n","datePublished":"2022-07-14T21:46:03+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/"},"wordCount":652,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/espana\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2022\/07\/donacion-sangre-madrid-img.jpg","articleSection":["Vida y Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/","url":"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/","name":"NORMAS M\u00c1S ESTRICTAS PARA AUMENTAR LA SEGURIDAD Y LA CALIDAD DE LA SANGRE, LOS TEJIDOS Y LAS C\u00c9LULAS por Redacci\u00f3n - Espa\u00f1a | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/espana\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2022\/07\/donacion-sangre-madrid-img.jpg","datePublished":"2022-07-14T21:46:03+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#primaryimage","url":"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2022\/07\/donacion-sangre-madrid-img.jpg","contentUrl":"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2022\/07\/donacion-sangre-madrid-img.jpg","width":1349,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/espana\/2022\/07\/14\/normas-mas-estrictas-para-aumentar-la-seguridad-y-la-calidad-de-la-sangre-los-tejidos-y-las-celulas-por-redaccion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/espana\/"},{"@type":"ListItem","position":2,"name":"NORMAS M\u00c1S ESTRICTAS PARA AUMENTAR LA SEGURIDAD Y LA CALIDAD DE LA SANGRE, LOS TEJIDOS Y LAS C\u00c9LULAS por Redacci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/espana\/#website","url":"https:\/\/noti-america.com\/site\/espana\/","name":"Espa\u00f1a | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/espana\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/espana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/espana\/#organization","name":"Noti-America LLC | Espa\u00f1a","url":"https:\/\/noti-america.com\/site\/espana\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/espana\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/espana\/wp-content\/uploads\/sites\/25\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Espa\u00f1a"},"image":{"@id":"https:\/\/noti-america.com\/site\/espana\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/notiamerica"]},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/espana\/#\/schema\/person\/d3312646ba171d7ab824643fed33ea1f","name":"rloaiza","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/190058e5d4427934610b99c45aa7a6558806850adedd53ddeddd194b04773e22?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/190058e5d4427934610b99c45aa7a6558806850adedd53ddeddd194b04773e22?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/190058e5d4427934610b99c45aa7a6558806850adedd53ddeddd194b04773e22?s=96&d=mm&r=g","caption":"rloaiza"},"url":"https:\/\/noti-america.com\/site\/espana\/author\/rloaiza\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/posts\/7281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/comments?post=7281"}],"version-history":[{"count":0,"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/posts\/7281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/media\/7282"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/media?parent=7281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/categories?post=7281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/espana\/wp-json\/wp\/v2\/tags?post=7281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}