{"id":5802,"date":"2019-09-30T01:06:16","date_gmt":"2019-09-30T01:06:16","guid":{"rendered":"http:\/\/noti-america.com\/site\/ecuador\/?p=5802"},"modified":"2019-09-30T01:06:16","modified_gmt":"2019-09-30T01:06:16","slug":"un-sistema-de-transporte-masivo-que-mejora-la-productividad","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/","title":{"rendered":"Un sistema de transporte masivo que mejora la productividad"},"content":{"rendered":"<p>REDACCI\u00d3N NOTI-AM\u00c9RICA (ECUADOR) <b>Por Steven Ambrus .<\/b><\/p>\n<p style=\"text-align: justify\">Enfrentadas a una r\u00e1pida expansi\u00f3n urbana y un tr\u00e1fico paralizante, varias ciudades de Am\u00e9rica Latina y el Caribe han optado por construir sistemas de tr\u00e1nsito r\u00e1pido, incluyendo metro y buses con carril exclusivo (BRT, por sus siglas en ingl\u00e9s). Los funcionarios p\u00fablicos esperan que dichos sistemas desalienten el uso de autom\u00f3viles privados, mejoren el medio ambiente, y estimulen el bienestar y la productividad.<\/p>\n<p style=\"text-align: justify\">Pero evaluar la efectividad de estos sistemas puede resultar dif\u00edcil. El gran n\u00famero de actores y las relaciones extremadamente complejas que existen entre ellos superan la capacidad de las herramientas de medici\u00f3n existentes, y hacen que el dise\u00f1o y la planificaci\u00f3n efectivos de un metro o de un sistema de BRT resulten sumamente complicados.<\/p>\n<p style=\"text-align: justify\">Por ello, la propuesta de una nueva y original forma de medir c\u00f3mo el transporte masivo afecta las ciudades, presentada en un reciente\u00a0articulo\u00a0del economista Nick Tsivanidis, no pod\u00eda haber llegado en mejor momento.\u00a0Los planificadores suelen evaluar los nuevos sistemas de transporte en t\u00e9rminos de cu\u00e1nto reducen el tiempo de desplazamiento. Pero Tsivanidis introduce un concepto que denomina acceso a mercados de los viajeros (commuter market access en ingl\u00e9s) a fin de estimar c\u00f3mo mejoras en el transporte cambian el acceso de los trabajadores a lugares con buenos empleos, considerando as\u00ed varios beneficios econ\u00f3micos. Tsivanidis utiliza un m\u00e9todo similar para determinar de qu\u00e9 manera mejoras en el transporte afectan a las empresas e influyen en su capacidad de acceder a trabajadores.<\/p>\n<p style=\"text-align: justify\">El enfoque de Tsivanidis consiste en crear un modelo coherente para evaluar simult\u00e1neamente c\u00f3mo un sistema de transporte modifica m\u00faltiples dimensiones de la econom\u00eda de una ciudad: los movimientos de su poblaci\u00f3n, el empleo y los precios de la vivienda, as\u00ed como la forma en que afecta el comportamiento de distintos grupos, incluyendo trabajadores con m\u00e1s o menos nivel de educaci\u00f3n, propietarios de viviendas, y empresas. Y lo que es m\u00e1s importante, a partir de diversas fuentes de datos, muestra c\u00f3mo un sistema de transporte masivo puede permitir una mayor movilidad de los trabajadores y, en el proceso, generar una mejor correspondencia entre los requerimientos de las empresas y las competencias de sus empleados, mejorando la productividad.<\/p>\n<h2 style=\"text-align: justify\"><strong>Un sistema de transporte masivo en Colombia<\/strong><\/h2>\n<p style=\"text-align: justify\">El innovador\u00a0art\u00edculo\u00a0de Tsivanidis fue presentado el pasado 9 de septiembre en la\u00a0Conferencia de Investigaci\u00f3n en Urbanizaci\u00f3n y Reducci\u00f3n de la Pobreza, organizada conjuntamente por el BID, el Banco Mundial, la Universidad George Washington y el Centro Internacional de Crecimiento. En \u00e9l se examina espec\u00edficamente Transmilenio, el sistema de BTR m\u00e1s grande del mundo, que fue inaugurado en Bogot\u00e1 en el a\u00f1o 2000, y que actualmente representa 2,2 millones de viajes al d\u00eda a lo largo y ancho de la ciudad a velocidades comparables con las del metro de la ciudad de Nueva York.<\/p>\n<p style=\"text-align: justify\">El estudio trae algunas buenas noticias para aquellas urbes que est\u00e1n considerando construir sistemas de BTR similares a Transmilenio, con estaciones y carriles de uso exclusivo para sus buses. Los sistemas de BTR no solo son mucho m\u00e1s baratos y r\u00e1pidos de construir que los metros, y proporcionan reducciones similares en los tiempos de desplazamiento. Adem\u00e1s, pueden redundar en una mayor productividad y un aumento significativo del bienestar de la poblaci\u00f3n en general, tanto para los trabajadores con mayores niveles de educaci\u00f3n, como para aquellos con menos a\u00f1os de estudios.<\/p>\n<p style=\"text-align: justify\">Transmilenio est\u00e1 dise\u00f1ado de tal forma que sus l\u00edneas de tr\u00e1nsito, dise\u00f1adas como radios de una rueda, convergen en las zonas del centro y centro norte de la ciudad, donde est\u00e1n ubicadas las empresas m\u00e1s grandes y productivas. Un aspecto fundamental de ese dise\u00f1o fue el establecimiento de buses alimentadores, que transportan a los pasajeros, sin cargo adicional, a lugares m\u00e1s all\u00e1 de las terminales, resolviendo as\u00ed lo que los economistas y los planificadores denominan \u201cel problema del \u00faltimo kil\u00f3metro\u201d. Tsivanidis muestra, de hecho, que el mayor impacto de Transmilenio provino de los buses alimentadores.<\/p>\n<p style=\"text-align: justify\">Este dise\u00f1o abri\u00f3 nuevos horizontes para los trabajadores con menos educaci\u00f3n formal, que habitan en el sur, donde se encuentran las zonas m\u00e1s pobres de la ciudad. As\u00ed, les permiti\u00f3 viajar al centro de la ciudad y encontrar all\u00ed empleos que se adaptaran mejor a sus capacidades, y que redituaran salarios m\u00e1s altos en las empresas m\u00e1s productivas de la ciudad.<\/p>\n<h2 style=\"text-align: justify\"><strong>Las ganancias no fueron \u00fanicamente para los pobres.<\/strong><\/h2>\n<p style=\"text-align: justify\">El sistema tambi\u00e9n benefici\u00f3 a los trabajadores m\u00e1s calificados y de mayor poder adquisitivo, es decir, a aquellos con estudios secundarios o superiores, y les trajo mejoras en bienestar m\u00e1s o menos equivalentes a las obtenidas por los trabajadores menos educados. Esto es sorprendente, dado que los pobres tienden a usar el transporte p\u00fablico mucho m\u00e1s que los ricos. Pero los trabajadores altamente calificados, como ingenieros inform\u00e1ticos o abogados corporativos, no tienen muchas opciones. Sus opciones de empleo est\u00e1n limitadas a las empresas m\u00e1s productivas, ubicadas en el centro de Bogot\u00e1. Y gracias a las mejoras en la velocidad de sus desplazamientos, Transmilenio les permiti\u00f3 ganar tiempo para el trabajo y el ocio.<\/p>\n<p style=\"text-align: justify\">Las empresas tambi\u00e9n tuvieron beneficios significativos, ya que lograron emplear a personas de los barrios m\u00e1s alejados en la ciudad, para quienes antes resultaba dif\u00edcil acceder al centro de Bogot\u00e1. Y debido a la mayor disponibilidad de trabajadores de los que elegir, las firmas pudieron encontrar empleados con competencias m\u00e1s cercanas a sus requerimientos, y mejorar as\u00ed su productividad.<\/p>\n<p style=\"text-align: justify\">Un hallazgo importante es que Transmilenio gener\u00f3 cambios m\u00e1s all\u00e1 de la simple disminuci\u00f3n de los tiempos de viaje y el acceso al empleo.\u00a0 La mayor productividad y crecimiento de las empresas ubicadas en centro de la ciudad gener\u00f3 un incremento de los alquileres comerciales, beneficiando a los propietarios de inmuebles, y mitigando algunas de las ganancias de empresas privadas. El mejor acceso a buenos empleos en las zonas pobres, al sur de la ciudad, anim\u00f3 a m\u00e1s personas a mudarse cerca de las l\u00edneas del BTR, con lo cual se elev\u00f3 la competencia en el mercado de venta y alquiler de propriedades, beneficiando a los propietarios a costa de las familias residentes.<\/p>\n<p style=\"text-align: justify\">Algunos de estos efectos podr\u00edan haber sido mitigados. Por ejemplo, mediante la supresi\u00f3n de las restricciones de construcci\u00f3n, Tsivanidis calcula que Bogot\u00e1 habr\u00eda podido aliviar la presi\u00f3n sobre los alquileres y aumentar las ganancias de bienestar en un 25%.<\/p>\n<h2 style=\"text-align: justify\"><strong>Transporte masivo que estimula el PIB.<\/strong><\/h2>\n<p style=\"text-align: justify\">Aun considerando todo lo anterior, el nuevo sistema aument\u00f3 los ingresos reales en cerca de un 1,6% tanto entre los trabajadores poco calificados y como entre\u00a0los m\u00e1s calificados. Tambi\u00e9n elev\u00f3 el PIB de la ciudad en un 1,4%, incluso tras deducir el costo de construcci\u00f3n y operaci\u00f3n del nuevo sistema, con un 60% a 80% de esas ganancias provenientes del tiempo adicional disponible para trabajo y ocio, y un 20% a 40% de una mejor asignaci\u00f3n laboral.<\/p>\n<p style=\"text-align: justify\">Hoy en d\u00eda, m\u00e1s de 200 ciudades cuentan con sistemas de BTR, la mayor\u00eda construidos en las dos \u00faltimas d\u00e9cadas en Am\u00e9rica Latina y Asia.\u00a0No todos estos han tenido \u00e9xito, c\u00f3mo lo muestra un reciente\u00a0estudio\u00a0de Yakarta, que tambi\u00e9n fue presentado en la conferencia. Pero la investigaci\u00f3n de Tsivanidis muestra que estos sistemas pueden traer grandes beneficios en t\u00e9rminos de producci\u00f3n y bienestar, permitiendo que los trabajadores tengan mejor acceso a empleos bien remunerados, y que las empresas tengan un mejor acceso a los trabajadores. Adem\u00e1s, dichos beneficios pueden maximizarse invirtiendo en buses alimentadores que transporten a los trabajadores m\u00e1s all\u00e1 de las terminales, hasta sus destinos finales, y si se eliminan restricciones que limitan la ampliaci\u00f3n de la oferta de la vivienda y producen aumentos de los alquileres.<\/p>\n<p style=\"text-align: justify\">Fuente: BID.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REDACCI\u00d3N NOTI-AM\u00c9RICA (ECUADOR) Por Steven Ambrus . Enfrentadas a una r\u00e1pida expansi\u00f3n urbana y un tr\u00e1fico paralizante, varias ciudades de Am\u00e9rica Latina y el Caribe han optado por construir sistemas de tr\u00e1nsito r\u00e1pido, incluyendo&#46;&#46;&#46;<\/p>\n","protected":false},"author":17,"featured_media":5803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":["post-5802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilidad-y-cambio-climatico"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un sistema de transporte masivo que mejora la productividad - Ecuador | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un sistema de transporte masivo que mejora la productividad\" \/>\n<meta property=\"og:description\" content=\"REDACCI\u00d3N NOTI-AM\u00c9RICA (ECUADOR) Por Steven Ambrus . Enfrentadas a una r\u00e1pida expansi\u00f3n urbana y un tr\u00e1fico paralizante, varias ciudades de Am\u00e9rica Latina y el Caribe han optado por construir sistemas de tr\u00e1nsito r\u00e1pido, incluyendo&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecuador | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-30T01:06:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2019\/09\/sistema-transporte-masivo-mejora-productividad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gregory Quintana Montiel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gdgregori1\" \/>\n<meta name=\"twitter:site\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gregory Quintana Montiel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/\"},\"author\":{\"name\":\"Gregory Quintana Montiel\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e\"},\"headline\":\"Un sistema de transporte masivo que mejora la productividad\",\"datePublished\":\"2019-09-30T01:06:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/\"},\"wordCount\":1360,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2019\/09\/sistema-transporte-masivo-mejora-productividad.jpg\",\"articleSection\":[\"Sostenibilidad y Cambio Clim\u00e1tico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/\",\"url\":\"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/\",\"name\":\"Un sistema de transporte masivo que mejora la productividad - Ecuador | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2019\/09\/sistema-transporte-masivo-mejora-productividad.jpg\",\"datePublished\":\"2019-09-30T01:06:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2019\/09\/sistema-transporte-masivo-mejora-productividad.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2019\/09\/sistema-transporte-masivo-mejora-productividad.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/ecuador\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un sistema de transporte masivo que mejora la productividad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/ecuador\/\",\"name\":\"Ecuador | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/ecuador\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#organization\",\"name\":\"Noti-America LLC | Ecuador\",\"url\":\"https:\/\/noti-america.com\/site\/ecuador\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Ecuador\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/notiamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e\",\"name\":\"Gregory Quintana Montiel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g\",\"caption\":\"Gregory Quintana Montiel\"},\"description\":\"Licenciatura en Ciencias de la Comunicaci\u00f3n Social, egresado en la Especializaci\u00f3n Derecho Ambiental Desarrollo Sostenible y Sustentable, Miembro de la Comunidad de profesionales y experto para Latinoam\u00e9rica y el Caribe en Gesti\u00f3n por Resultado en el Desarrollo (COPLAC - GpRD) del Banco Interamericano de Desarrollo, experiencia en medios radiales y escritos.\",\"sameAs\":[\"https:\/\/x.com\/gdgregori1\",\"gquintana\"],\"url\":\"https:\/\/noti-america.com\/site\/ecuador\/author\/gquintana\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un sistema de transporte masivo que mejora la productividad - Ecuador | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/","og_locale":"es_ES","og_type":"article","og_title":"Un sistema de transporte masivo que mejora la productividad","og_description":"REDACCI\u00d3N NOTI-AM\u00c9RICA (ECUADOR) Por Steven Ambrus . Enfrentadas a una r\u00e1pida expansi\u00f3n urbana y un tr\u00e1fico paralizante, varias ciudades de Am\u00e9rica Latina y el Caribe han optado por construir sistemas de tr\u00e1nsito r\u00e1pido, incluyendo&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/","og_site_name":"Ecuador | Noti-America.com","article_published_time":"2019-09-30T01:06:16+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2019\/09\/sistema-transporte-masivo-mejora-productividad.jpg","type":"image\/jpeg"}],"author":"Gregory Quintana Montiel","twitter_card":"summary_large_image","twitter_creator":"@gdgregori1","twitter_site":"@notiamerica","twitter_misc":{"Escrito por":"Gregory Quintana Montiel","Tiempo estimado de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/"},"author":{"name":"Gregory Quintana Montiel","@id":"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e"},"headline":"Un sistema de transporte masivo que mejora la productividad","datePublished":"2019-09-30T01:06:16+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/"},"wordCount":1360,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2019\/09\/sistema-transporte-masivo-mejora-productividad.jpg","articleSection":["Sostenibilidad y Cambio Clim\u00e1tico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/","url":"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/","name":"Un sistema de transporte masivo que mejora la productividad - Ecuador | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2019\/09\/sistema-transporte-masivo-mejora-productividad.jpg","datePublished":"2019-09-30T01:06:16+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#primaryimage","url":"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2019\/09\/sistema-transporte-masivo-mejora-productividad.jpg","contentUrl":"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2019\/09\/sistema-transporte-masivo-mejora-productividad.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/ecuador\/2019\/09\/30\/un-sistema-de-transporte-masivo-que-mejora-la-productividad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/ecuador\/"},{"@type":"ListItem","position":2,"name":"Un sistema de transporte masivo que mejora la productividad"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/ecuador\/#website","url":"https:\/\/noti-america.com\/site\/ecuador\/","name":"Ecuador | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/ecuador\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/ecuador\/#organization","name":"Noti-America LLC | Ecuador","url":"https:\/\/noti-america.com\/site\/ecuador\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Ecuador"},"image":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/notiamerica"]},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e","name":"Gregory Quintana Montiel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g","caption":"Gregory Quintana Montiel"},"description":"Licenciatura en Ciencias de la Comunicaci\u00f3n Social, egresado en la Especializaci\u00f3n Derecho Ambiental Desarrollo Sostenible y Sustentable, Miembro de la Comunidad de profesionales y experto para Latinoam\u00e9rica y el Caribe en Gesti\u00f3n por Resultado en el Desarrollo (COPLAC - GpRD) del Banco Interamericano de Desarrollo, experiencia en medios radiales y escritos.","sameAs":["https:\/\/x.com\/gdgregori1","gquintana"],"url":"https:\/\/noti-america.com\/site\/ecuador\/author\/gquintana\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/posts\/5802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/comments?post=5802"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/posts\/5802\/revisions"}],"predecessor-version":[{"id":5804,"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/posts\/5802\/revisions\/5804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/media\/5803"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/media?parent=5802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/categories?post=5802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/tags?post=5802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}