{"id":13441,"date":"2021-03-17T04:00:53","date_gmt":"2021-03-17T04:00:53","guid":{"rendered":"https:\/\/noti-america.com\/site\/ecuador\/?p=13441"},"modified":"2021-03-17T04:00:53","modified_gmt":"2021-03-17T04:00:53","slug":"china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/","title":{"rendered":"China busca reducir las emisiones de carbono en un 18% para 2025"},"content":{"rendered":"<p>REDACCI\u00d3N NOTI AM\u00c9RICA (ECUADOR)<\/p>\n<p style=\"text-align: justify\"><strong>Se impuls\u00f3 un s\u00faper ambicioso plan de desarrollo sostenible en China para abordar la sustentabilidad y el cambio clim\u00e1tico. \u00bfFuncionar\u00e1?<\/strong><\/p>\n<div style=\"width: 820px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-china-1-810x540.jpg\" alt=\"\" width=\"810\" height=\"540\" \/><p class=\"wp-caption-text\">Desarrollo sostenible en China: as\u00ed es como piensan avanzar a 2025<\/p><\/div>\n<p style=\"text-align: justify\">El plan de desarrollo sostenible en China busca alcanzar la\u00a0<a href=\"https:\/\/www.sostenibilidad.com\/cambio-climatico\/que-es-la-neutralidad-en-carbono\/\">neutralidad cero<\/a>, y con ello, contribuir a luchar contra el cambio clim\u00e1tico que para expertos como\u00a0<a href=\"https:\/\/www.expoknews.com\/mesa-de-analisis-carta-anual-2021-larry-fink-e-informe-de-oxfam\/\">Larry Fink<\/a>, es el problema n\u00famero uno a nivel mundial.<\/p>\n<p style=\"text-align: justify\">La estrategia busca reducir las\u00a0<a href=\"https:\/\/www.expoknews.com\/?s=emisiones+de+carbono\">emisiones de carbono<\/a>\u00a0en un 18% para 2025 y el uso de energ\u00eda e un 13,5%. Tambi\u00e9n planea impulsar los combustibles no f\u00f3siles al 20% de toda su energ\u00eda para ese a\u00f1o y crear\u00e1 un plan de acci\u00f3n durante 2021 para detallar c\u00f3mo pretende alcanzar una reducci\u00f3n m\u00e1xima de emisiones para 2030.<\/p>\n<figure class=\"wp-block-image size-large\" style=\"text-align: justify\">\n<p><div id=\"attachment_307286\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-307286\" class=\"lazyloaded wp-image-307286\" src=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/01\/Sustanability1-1024x683.jpg\" alt=\"desarrollo sostenible en china\" width=\"1024\" height=\"683\" data-srcset=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/01\/Sustanability1-1024x683.jpg 1024w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/01\/Sustanability1-300x200.jpg 300w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/01\/Sustanability1-768x512.jpg 768w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/01\/Sustanability1-810x540.jpg 810w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/01\/Sustanability1-1140x760.jpg 1140w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/01\/Sustanability1-scaled.jpg 1200w\" data-src=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/01\/Sustanability1-1024x683.jpg\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-307286\" class=\"wp-caption-text\">Wind turbines against blue sky.Green energy concept.Zhoushan,Zhejiang province,China.<\/p><\/div><\/figure>\n<p style=\"text-align: justify\">Sin embargo y aunque parezca contradictorio, la iniciativa de desarrollo sostenible de China tiene como objetivo tambi\u00e9n aumentar la producci\u00f3n nacional de combustibles f\u00f3siles como el carb\u00f3n y el petr\u00f3leo para mejorar la seguridad energ\u00e9tica y con ella liderar la importaci\u00f3n de materias primas a nivel mundial.<\/p>\n<h3 style=\"text-align: justify\">Un vistazo hacia el desarrollo sostenible en China<\/h3>\n<p style=\"text-align: justify\">El primer ministro\u00a0<a href=\"https:\/\/es.wikipedia.org\/wiki\/Li_Keqiang\">Li Keqiang<\/a>\u00a0en la inauguraci\u00f3n de la\u00a0<a href=\"https:\/\/es.wikipedia.org\/wiki\/Asamblea_Popular_Nacional_de_China\">Asamblea Popular Nacional<\/a>, se\u00f1ala que el decimocuarto plan quinquenal del pa\u00eds abarca de 2021 a 2021 y representa el primer plan estrat\u00e9gico de Beijing desde septiembre cuando Xi Jinping estableci\u00f3 un objetivo de cero emisiones netas para 2060.<\/p>\n<p style=\"text-align: justify\">Para lograrlo, el primer ministro Li Keqiang desglos\u00f3 c\u00f3mo impactar\u00e1 este plan de desarrollo sostenible en diversas \u00e1reas:<\/p>\n<h4 style=\"text-align: justify\">Eficiencia energ\u00e9tica<\/h4>\n<p style=\"text-align: justify\">Despu\u00e9s de casi un siglo, China comenz\u00f3 a industrializar su econom\u00eda despu\u00e9s de pa\u00edses como Estados Unidos y Reino Unido, por lo que su consumo de energ\u00eda sigue creciendo con fuerza a medida que otros han alcanzado su punto m\u00e1ximo o se han estancado.<\/p>\n<figure class=\"wp-block-image size-large\" style=\"text-align: justify\">\n<p><div id=\"attachment_310540\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-310540\" class=\"lazyloaded wp-image-310540\" src=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-1024x682.jpg\" alt=\"desarrollo sostenible en china\" width=\"1024\" height=\"682\" data-srcset=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-1024x682.jpg 1024w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-300x200.jpg 300w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-768x512.jpg 768w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-810x540.jpg 810w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-1140x760.jpg 1140w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-scaled.jpg 1200w\" data-src=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-1024x682.jpg\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-310540\" class=\"wp-caption-text\">desarrollo sostenible en china<\/p><\/div><\/figure>\n<p style=\"text-align: justify\">Y a pesar de que Beijing no ha querido frenar el crecimiento delimitando el uso de energ\u00eda, se tom\u00f3 la decisi\u00f3n de gestionarlo de manera m\u00e1s eficiente, sobre todo porque China represent\u00f3 m\u00e1s del 30% de las emisiones globales de carbono el a\u00f1o pasado<\/p>\n<h4 style=\"text-align: justify\">Gases de efecto invernadero<\/h4>\n<p style=\"text-align: justify\">La nueva meta de reducir el uso de energ\u00eda en un 13,5% es ligeramente inferior a la meta del 15% que el pa\u00eds estableci\u00f3 en su \u00faltimo plan quinquenal. De hecho, China super\u00f3 ese objetivo, reduciendo la intensidad energ\u00e9tica en aproximadamente un 18% en el per\u00edodo 2016-2020.<\/p>\n<figure class=\"wp-block-image size-large\" style=\"text-align: justify\">\n<p><div id=\"attachment_286427\" style=\"width: 650px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-286427\" class=\"lazyloaded wp-image-286427\" src=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2020\/04\/industry-611668_640.jpg\" alt=\"desarrollo sostenible en china\" width=\"640\" height=\"326\" data-srcset=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2020\/04\/industry-611668_640.jpg 640w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2020\/04\/industry-611668_640-300x153.jpg 300w\" data-src=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2020\/04\/industry-611668_640.jpg\" data-sizes=\"(max-width: 640px) 100vw, 640px\" \/><p id=\"caption-attachment-286427\" class=\"wp-caption-text\">desarrollo sostenible en china<\/p><\/div><\/figure>\n<p style=\"text-align: justify\">Por su parte, State Grid Corp. de China, el gigante de los servicios p\u00fablicos de la naci\u00f3n,\u00a0<a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2021-03-02\/china-s-power-giant-wants-to-get-ahead-on-xi-s-emissions-goals\" target=\"_blank\" rel=\"noreferrer noopener\">recientemente se\u00f1al\u00f3<\/a>\u00a0un mayor enfoque en la eficiencia energ\u00e9tica y las reformas durante los pr\u00f3ximos cinco a\u00f1os para apoyar todo el plan de desarrollo sustentable de China.<\/p>\n<h4 style=\"text-align: justify\">Emisiones de carb\u00f3n<\/h4>\n<p style=\"text-align: justify\">Al igual que el uso de energ\u00eda, el enfoque de China hacia las emisiones es reducir la intensidad en lugar de establecer un objetivo general.<\/p>\n<figure class=\"wp-block-image size-large\" style=\"text-align: justify\">\n<p><div id=\"attachment_310541\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-310541\" class=\"lazyloaded wp-image-310541\" src=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/china-1024x768.jpg\" alt=\"desarrollo sostenible en china\" width=\"1024\" height=\"768\" data-srcset=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/china-1024x768.jpg 1024w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/china-300x225.jpg 300w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/china-768x576.jpg 768w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/china-810x608.jpg 810w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/china-1140x855.jpg 1140w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/china-scaled.jpg 1067w\" data-src=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/china-1024x768.jpg\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-310541\" class=\"wp-caption-text\">desarrollo sostenible en china<\/p><\/div><\/figure>\n<p style=\"text-align: justify\">La meta de reducci\u00f3n del 18% durante los pr\u00f3ximos cinco a\u00f1os es el mismo nivel que se propuso y alcanz\u00f3 con \u00e9xito en el \u00faltimo plan.<\/p>\n<h3 style=\"text-align: justify\">\u00bfMenos intensidad?<\/h3>\n<p style=\"text-align: justify\">Si bien China est\u00e1 tomando en cuenta c\u00f3mo su estrategia de desarrollo sostenible impactar\u00e1 en \u00e1reas como en la eficiencia energ\u00e9tica, el pa\u00eds quiere seguir emitiendo menos carbono por unidad.<\/p>\n<p style=\"text-align: justify\">A\u00fan as\u00ed, a medida que el producto interno bruto (PIB), contin\u00faa creciendo, las emisiones tambi\u00e9n han aumentado y China arroj\u00f3 9.800 millones de toneladas de carbono en 2019, casi el 29% del total mundial.<\/p>\n<figure class=\"wp-block-image size-large\" style=\"text-align: justify\">\n<p><div id=\"attachment_248979\" style=\"width: 910px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-248979\" class=\"lazyloaded wp-image-248979\" src=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2018\/11\/Cuanto-deben-bajar-las-emisiones-para-alcanzar-los-objetivos-2030.jpeg\" alt=\"\" width=\"900\" height=\"600\" data-srcset=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2018\/11\/Cuanto-deben-bajar-las-emisiones-para-alcanzar-los-objetivos-2030.jpeg 900w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2018\/11\/Cuanto-deben-bajar-las-emisiones-para-alcanzar-los-objetivos-2030-300x200.jpeg 300w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2018\/11\/Cuanto-deben-bajar-las-emisiones-para-alcanzar-los-objetivos-2030-768x512.jpeg 768w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2018\/11\/Cuanto-deben-bajar-las-emisiones-para-alcanzar-los-objetivos-2030-810x540.jpeg 810w\" data-src=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2018\/11\/Cuanto-deben-bajar-las-emisiones-para-alcanzar-los-objetivos-2030.jpeg\" data-sizes=\"(max-width: 900px) 100vw, 900px\" \/><p id=\"caption-attachment-248979\" class=\"wp-caption-text\">desarrollo sostenible en china<\/p><\/div><\/figure>\n<blockquote class=\"wp-block-quote\"><p><strong>Los expertos en el clima dicen que China necesita establecer un l\u00edmite absoluto, y el\u00a0<a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2021-03-05\/this-is-how-top-polluter-china-plans-to-be-greener-by-2025\">Centro de Investigaci\u00f3n sobre Energ\u00eda y Aire Limpio<\/a>\u00a0afirma que debe ser de 8.750 millones de toneladas para 2025 para cumplir con el camino lineal hacia el objetivo de neutralidad de carbono de 2060.<\/strong><\/p><\/blockquote>\n<p style=\"text-align: justify\">De hecho, se\u00f1alaron que el carb\u00f3n es el combustible f\u00f3sil m\u00e1s contaminante y China extrae y quema la mitad del suministro mundial.\u00a0Sin embargo, en los \u00faltimos a\u00f1os, Beijing ha logrado disminuir la participaci\u00f3n del carb\u00f3n en su combinaci\u00f3n energ\u00e9tica, pero eso ocurri\u00f3 a medida que aument\u00f3 el consumo total de energ\u00eda, lo que significa que la cantidad de carb\u00f3n que se quema no ha cambiado mucho desde principios de la d\u00e9cada de 2010.<\/p>\n<h3 id=\"reducing-coal-dependency\" style=\"text-align: justify\">Menos dependencia del carb\u00f3n, m\u00e1s desarrollo sostenible en China<\/h3>\n<p style=\"text-align: justify\">Li Keqiang, el primer ministro, mencion\u00f3 que es probable que China contin\u00fae promoviendo el uso limpio y eficiente del combustible mientras hace un gran esfuerzo para desarrollar nuevas fuentes de energ\u00eda.<\/p>\n<figure class=\"wp-block-image size-large\" style=\"text-align: justify\">\n<p><div id=\"attachment_310544\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-310544\" class=\"lazyloaded wp-image-310544\" src=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-china-2-1024x682.jpg\" alt=\"desarrollo sostenible en china\" width=\"1024\" height=\"682\" data-srcset=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-china-2-1024x682.jpg 1024w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-china-2-300x200.jpg 300w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-china-2-768x512.jpg 768w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-china-2-810x540.jpg 810w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-china-2-1140x760.jpg 1140w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-china-2-scaled.jpg 1200w\" data-src=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2021\/03\/energia-china-2-1024x682.jpg\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-310544\" class=\"wp-caption-text\">desarrollo sostenible en china<\/p><\/div><\/figure>\n<p style=\"text-align: justify\">El pa\u00eds seguir\u00e1 construyendo sistemas de producci\u00f3n de carb\u00f3n, petr\u00f3leo y gas. De hecho, el grupo de la industria del carb\u00f3n de China dijo a principios de esta semana que planea aumentar la producci\u00f3n para 2025 y que el consumo total ser\u00e1 ligeramente\u00a0<a href=\"https:\/\/www.bloomberg.com\/news\/terminal\/QPE15GT0AFBA\" target=\"_blank\" rel=\"noreferrer noopener\">m\u00e1s alto<\/a>\u00a0al final del per\u00edodo que en 2020.<\/p>\n<blockquote class=\"wp-block-quote\"><p><strong>El objetivo de China de alcanzar el 20% de sus necesidades energ\u00e9ticas con fuentes de combustibles sostenibles para 2025 es m\u00e1s r\u00e1pido que el objetivo anterior de alcanzar esa marca para 2030, e ilustra el enorme \u00e9xito que ha tenido el pa\u00eds al impulsar las\u00a0<a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2021-02-04\/china-solar-industry-sets-sights-on-record-2021-after-green-push\" target=\"_blank\" rel=\"noreferrer noopener\">instalaciones<\/a>\u00a0de capacidad solar y e\u00f3lica en a\u00f1os anteriores.<\/strong><\/p><\/blockquote>\n<h3 style=\"text-align: justify\">Energ\u00edas renovables para el desarrollo sostenible en China<\/h3>\n<p style=\"text-align: justify\">Se espera que la capacidad solar y e\u00f3lica del pa\u00eds aumente en los pr\u00f3ximos a\u00f1os y con ello se pueda fortalecer el desarrollo sostenible en China.<\/p>\n<p style=\"text-align: justify\">El primer ministro Li Keqiang reiter\u00f3 el apoyo de China a la energ\u00eda nuclear, despu\u00e9s de que no alcanzara el objetivo del \u00faltimo plan de 5 a\u00f1os de tener 58 gigavatios de plantas para 2020, terminando con un poco menos de 50 en su lugar.<\/p>\n<figure class=\"wp-block-image size-large\" style=\"text-align: justify\">\n<p><div id=\"attachment_291884\" style=\"width: 650px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-291884\" class=\"lazyloaded wp-image-291884\" src=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2020\/06\/energia-renovable-2.jpg\" alt=\"\" width=\"640\" height=\"480\" data-srcset=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2020\/06\/energia-renovable-2.jpg 640w, https:\/\/www.expoknews.com\/wp-content\/uploads\/2020\/06\/energia-renovable-2-300x225.jpg 300w\" data-src=\"https:\/\/www.expoknews.com\/wp-content\/uploads\/2020\/06\/energia-renovable-2.jpg\" data-sizes=\"(max-width: 640px) 100vw, 640px\" \/><p id=\"caption-attachment-291884\" class=\"wp-caption-text\">bombillo<\/p><\/div><\/figure>\n<blockquote class=\"wp-block-quote\"><p><strong>Durante los pr\u00f3ximos cinco a\u00f1os, el pa\u00eds planea aumentar la capacidad de la energ\u00eda de divisi\u00f3n de \u00e1tomos en un 40% a 70 gigavatios.<\/strong><\/p><\/blockquote>\n<p style=\"text-align: justify\">El aumento de las fuentes de electricidad ser\u00e1 un objetivo durante los pr\u00f3ximos cinco a\u00f1os. La electricidad represent\u00f3 alrededor del 25% del uso total de energ\u00eda en 2018, seg\u00fan la Agencia Internacional de Energ\u00eda, m\u00e1s del doble de la participaci\u00f3n en 2000.<\/p>\n<p style=\"text-align: justify\">La principal empresa de servicios p\u00fablicos del pa\u00eds dice que el porcentaje aumentar\u00e1 al 30% para 2025 y al 35% para 2030 a medida que la naci\u00f3n refuerce su compromiso para alcanzar la neutralidad cero. \u00bfLo lograr\u00e1n?<\/p>\n<p>Fuente: EXPOK<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REDACCI\u00d3N NOTI AM\u00c9RICA (ECUADOR) Se impuls\u00f3 un s\u00faper ambicioso plan de desarrollo sostenible en China para abordar la sustentabilidad y el cambio clim\u00e1tico. \u00bfFuncionar\u00e1? El plan de desarrollo sostenible en China busca alcanzar la\u00a0neutralidad&#46;&#46;&#46;<\/p>\n","protected":false},"author":17,"featured_media":13442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":["post-13441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilidad-y-cambio-climatico"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>China busca reducir las emisiones de carbono en un 18% para 2025 - Ecuador | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"China busca reducir las emisiones de carbono en un 18% para 2025\" \/>\n<meta property=\"og:description\" content=\"REDACCI\u00d3N NOTI AM\u00c9RICA (ECUADOR) Se impuls\u00f3 un s\u00faper ambicioso plan de desarrollo sostenible en China para abordar la sustentabilidad y el cambio clim\u00e1tico. \u00bfFuncionar\u00e1? El plan de desarrollo sostenible en China busca alcanzar la\u00a0neutralidad&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecuador | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-17T04:00:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2021\/03\/energia-china-1-810x540-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gregory Quintana Montiel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gdgregori1\" \/>\n<meta name=\"twitter:site\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gregory Quintana Montiel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/\"},\"author\":{\"name\":\"Gregory Quintana Montiel\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e\"},\"headline\":\"China busca reducir las emisiones de carbono en un 18% para 2025\",\"datePublished\":\"2021-03-17T04:00:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/\"},\"wordCount\":1182,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2021\/03\/energia-china-1-810x540-1.jpg\",\"articleSection\":[\"Sostenibilidad y Cambio Clim\u00e1tico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/\",\"url\":\"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/\",\"name\":\"China busca reducir las emisiones de carbono en un 18% para 2025 - Ecuador | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2021\/03\/energia-china-1-810x540-1.jpg\",\"datePublished\":\"2021-03-17T04:00:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2021\/03\/energia-china-1-810x540-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2021\/03\/energia-china-1-810x540-1.jpg\",\"width\":810,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/ecuador\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"China busca reducir las emisiones de carbono en un 18% para 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/ecuador\/\",\"name\":\"Ecuador | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/ecuador\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#organization\",\"name\":\"Noti-America LLC | Ecuador\",\"url\":\"https:\/\/noti-america.com\/site\/ecuador\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Ecuador\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/notiamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e\",\"name\":\"Gregory Quintana Montiel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g\",\"caption\":\"Gregory Quintana Montiel\"},\"description\":\"Licenciatura en Ciencias de la Comunicaci\u00f3n Social, egresado en la Especializaci\u00f3n Derecho Ambiental Desarrollo Sostenible y Sustentable, Miembro de la Comunidad de profesionales y experto para Latinoam\u00e9rica y el Caribe en Gesti\u00f3n por Resultado en el Desarrollo (COPLAC - GpRD) del Banco Interamericano de Desarrollo, experiencia en medios radiales y escritos.\",\"sameAs\":[\"https:\/\/x.com\/gdgregori1\",\"gquintana\"],\"url\":\"https:\/\/noti-america.com\/site\/ecuador\/author\/gquintana\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"China busca reducir las emisiones de carbono en un 18% para 2025 - Ecuador | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/","og_locale":"es_ES","og_type":"article","og_title":"China busca reducir las emisiones de carbono en un 18% para 2025","og_description":"REDACCI\u00d3N NOTI AM\u00c9RICA (ECUADOR) Se impuls\u00f3 un s\u00faper ambicioso plan de desarrollo sostenible en China para abordar la sustentabilidad y el cambio clim\u00e1tico. \u00bfFuncionar\u00e1? El plan de desarrollo sostenible en China busca alcanzar la\u00a0neutralidad&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/","og_site_name":"Ecuador | Noti-America.com","article_published_time":"2021-03-17T04:00:53+00:00","og_image":[{"width":810,"height":540,"url":"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2021\/03\/energia-china-1-810x540-1.jpg","type":"image\/jpeg"}],"author":"Gregory Quintana Montiel","twitter_card":"summary_large_image","twitter_creator":"@gdgregori1","twitter_site":"@notiamerica","twitter_misc":{"Escrito por":"Gregory Quintana Montiel","Tiempo estimado de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/"},"author":{"name":"Gregory Quintana Montiel","@id":"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e"},"headline":"China busca reducir las emisiones de carbono en un 18% para 2025","datePublished":"2021-03-17T04:00:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/"},"wordCount":1182,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2021\/03\/energia-china-1-810x540-1.jpg","articleSection":["Sostenibilidad y Cambio Clim\u00e1tico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/","url":"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/","name":"China busca reducir las emisiones de carbono en un 18% para 2025 - Ecuador | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2021\/03\/energia-china-1-810x540-1.jpg","datePublished":"2021-03-17T04:00:53+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#primaryimage","url":"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2021\/03\/energia-china-1-810x540-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2021\/03\/energia-china-1-810x540-1.jpg","width":810,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/ecuador\/2021\/03\/17\/china-busca-reducir-las-emisiones-de-carbono-en-un-18-para-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/ecuador\/"},{"@type":"ListItem","position":2,"name":"China busca reducir las emisiones de carbono en un 18% para 2025"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/ecuador\/#website","url":"https:\/\/noti-america.com\/site\/ecuador\/","name":"Ecuador | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/ecuador\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/ecuador\/#organization","name":"Noti-America LLC | Ecuador","url":"https:\/\/noti-america.com\/site\/ecuador\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/ecuador\/wp-content\/uploads\/sites\/18\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Ecuador"},"image":{"@id":"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/notiamerica"]},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/ecuador\/#\/schema\/person\/92f50451ab6e6e924f374e231c78e86e","name":"Gregory Quintana Montiel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d6b802f7720c2ec7744dcbe608cc2f3417aeb964d58b443c6d612b77531de1d?s=96&d=mm&r=g","caption":"Gregory Quintana Montiel"},"description":"Licenciatura en Ciencias de la Comunicaci\u00f3n Social, egresado en la Especializaci\u00f3n Derecho Ambiental Desarrollo Sostenible y Sustentable, Miembro de la Comunidad de profesionales y experto para Latinoam\u00e9rica y el Caribe en Gesti\u00f3n por Resultado en el Desarrollo (COPLAC - GpRD) del Banco Interamericano de Desarrollo, experiencia en medios radiales y escritos.","sameAs":["https:\/\/x.com\/gdgregori1","gquintana"],"url":"https:\/\/noti-america.com\/site\/ecuador\/author\/gquintana\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/posts\/13441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/comments?post=13441"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/posts\/13441\/revisions"}],"predecessor-version":[{"id":13443,"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/posts\/13441\/revisions\/13443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/media\/13442"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/media?parent=13441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/categories?post=13441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/ecuador\/wp-json\/wp\/v2\/tags?post=13441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}