{"id":5390,"date":"2020-08-21T14:03:33","date_gmt":"2020-08-21T14:03:33","guid":{"rendered":"https:\/\/noti-america.com\/site\/colombia\/?p=5390"},"modified":"2020-08-21T14:03:33","modified_gmt":"2020-08-21T14:03:33","slug":"venezuela-cierra-la-principal-frontera-con-colombia","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/","title":{"rendered":"Venezuela cierra la principal frontera con Colombia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5391 aligncenter\" src=\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2020\/08\/inmigracion-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2020\/08\/inmigracion-300x192.jpg 300w, https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2020\/08\/inmigracion.jpg 515w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify\"><em>El ingreso de venezolanos a trav\u00e9s del Puente Sim\u00f3n Bol\u00edvar qued\u00f3 suspendido a partir de hoy.<\/em><\/p>\n<p style=\"text-align: justify\">El retorno de los venezolanos a su pa\u00eds est\u00e1 en vilo, Migraci\u00f3n Colombia, mediante un comunicado, anunci\u00f3 que de acuerdo con la informaci\u00f3n entregada por las autoridades migratorias venezolanas en las \u00faltimas horas, el ingreso a Venezuela a trav\u00e9s del Puente Internacional Sim\u00f3n Bol\u00edvar queda suspendido. El cierre del paso fronterizo obedecer\u00eda al represamiento de venezolanos retornados que permanecen en el Estado T\u00e1chira.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/AEstaHora?src=hash&amp;ref_src=twsrc%5Etfw\">#AEstaHora<\/a> &#8211; Acabamos de ser notificados de la decisi\u00f3n de Venezuela de restringir el ingreso de sus nacionales a ese pa\u00eds, partir del d\u00eda de ma\u00f1ana por el Puente Internacional Sim\u00f3n Bol\u00edvar, en Norte de Santander. <a href=\"https:\/\/t.co\/NNEcDDJP5J\">pic.twitter.com\/NNEcDDJP5J<\/a><\/p>\n<p>&mdash; Migraci\u00f3n Colombia (@MigracionCol) <a href=\"https:\/\/twitter.com\/MigracionCol\/status\/1296625058715230209?ref_src=twsrc%5Etfw\">August 21, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify\">De acuerdo a esto, el traslado de ciudadanos venezolanos desde el interior de Colombia hacia Norte de Santander, tambi\u00e9n queda suspendido para evitar embotellamientos y emergencias sanitarias del lado colombiano. \u00abNos preocupa la integridad y la salud de todas las personas que se encuentran en zona de frontera y por eso hemos tomado la decisi\u00f3n de suspender el tr\u00e1nsito de ciudadanos venezolanos hacia el departamento de Norte de Santander. En los pr\u00f3ximos minutos empezaremos a organizar, junto con las alcald\u00edas y Gobernaciones, un nuevo cronograma de traslados atendiendo esta situaci\u00f3n que se presenta el vecino pa\u00eds. Hacemos un llamado a la poblaci\u00f3n venezolana para que evite desplazarse en este momento. Este no es un momento para movilizarse, es un momento para cuidarnos unos a otros\u00bb, afirm\u00f3 el director general de Migraci\u00f3n Colombia, Juan Francisco Espinosa.<\/p>\n<p style=\"text-align: justify\">Desde que inici\u00f3 la pandemia, hace cinco meses, cerca de cien mil ciudadanos venezolanos han retornado de manera voluntaria a su pa\u00eds y 40 mil m\u00e1s est\u00e1n a la espera de poderlo hacer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ingreso de venezolanos a trav\u00e9s del Puente Sim\u00f3n Bol\u00edvar qued\u00f3 suspendido a partir de hoy. El retorno de los venezolanos a su pa\u00eds est\u00e1 en vilo, Migraci\u00f3n Colombia, mediante un comunicado, anunci\u00f3 que&#46;&#46;&#46;<\/p>\n","protected":false},"author":85,"featured_media":5391,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[121,4,154],"tags":[],"class_list":["post-5390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-internacionales","category-migracion"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Venezuela cierra la principal frontera con Colombia - Colombia | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venezuela cierra la principal frontera con Colombia\" \/>\n<meta property=\"og:description\" content=\"El ingreso de venezolanos a trav\u00e9s del Puente Sim\u00f3n Bol\u00edvar qued\u00f3 suspendido a partir de hoy. El retorno de los venezolanos a su pa\u00eds est\u00e1 en vilo, Migraci\u00f3n Colombia, mediante un comunicado, anunci\u00f3 que&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/\" \/>\n<meta property=\"og:site_name\" content=\"Colombia | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-21T14:03:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2020\/08\/inmigracion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"515\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Silvia S\u00e1nchez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:site\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Silvia S\u00e1nchez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/\"},\"author\":{\"name\":\"Silvia S\u00e1nchez\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/54a1f5656d2b8acb0c1530cda7fabda4\"},\"headline\":\"Venezuela cierra la principal frontera con Colombia\",\"datePublished\":\"2020-08-21T14:03:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/\"},\"wordCount\":282,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2020\/08\/inmigracion.jpg\",\"articleSection\":[\"Actualidad\",\"Internacionales\",\"Migraci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/\",\"name\":\"Venezuela cierra la principal frontera con Colombia - Colombia | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2020\/08\/inmigracion.jpg\",\"datePublished\":\"2020-08-21T14:03:33+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/54a1f5656d2b8acb0c1530cda7fabda4\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2020\/08\/inmigracion.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2020\/08\/inmigracion.jpg\",\"width\":515,\"height\":330},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venezuela cierra la principal frontera con Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/\",\"name\":\"Colombia | Noti-America.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/54a1f5656d2b8acb0c1530cda7fabda4\",\"name\":\"Silvia S\u00e1nchez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/2287cfc8de78326c0baee5bffce79d09df06b397cb6bd0bce79b2faf6d45aa43?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2287cfc8de78326c0baee5bffce79d09df06b397cb6bd0bce79b2faf6d45aa43?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2287cfc8de78326c0baee5bffce79d09df06b397cb6bd0bce79b2faf6d45aa43?s=96&d=mm&r=g\",\"caption\":\"Silvia S\u00e1nchez\"},\"url\":\"https:\/\/noti-america.com\/site\/colombia\/author\/ssanchez\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Venezuela cierra la principal frontera con Colombia - Colombia | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/","og_locale":"es_ES","og_type":"article","og_title":"Venezuela cierra la principal frontera con Colombia","og_description":"El ingreso de venezolanos a trav\u00e9s del Puente Sim\u00f3n Bol\u00edvar qued\u00f3 suspendido a partir de hoy. El retorno de los venezolanos a su pa\u00eds est\u00e1 en vilo, Migraci\u00f3n Colombia, mediante un comunicado, anunci\u00f3 que&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/","og_site_name":"Colombia | Noti-America.com","article_published_time":"2020-08-21T14:03:33+00:00","og_image":[{"width":515,"height":330,"url":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2020\/08\/inmigracion.jpg","type":"image\/jpeg"}],"author":"Silvia S\u00e1nchez","twitter_card":"summary_large_image","twitter_creator":"@notiamerica","twitter_site":"@notiamerica","twitter_misc":{"Escrito por":"Silvia S\u00e1nchez","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/"},"author":{"name":"Silvia S\u00e1nchez","@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/54a1f5656d2b8acb0c1530cda7fabda4"},"headline":"Venezuela cierra la principal frontera con Colombia","datePublished":"2020-08-21T14:03:33+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/"},"wordCount":282,"commentCount":0,"image":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2020\/08\/inmigracion.jpg","articleSection":["Actualidad","Internacionales","Migraci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/","url":"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/","name":"Venezuela cierra la principal frontera con Colombia - Colombia | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2020\/08\/inmigracion.jpg","datePublished":"2020-08-21T14:03:33+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/54a1f5656d2b8acb0c1530cda7fabda4"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#primaryimage","url":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2020\/08\/inmigracion.jpg","contentUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2020\/08\/inmigracion.jpg","width":515,"height":330},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/colombia\/2020\/08\/21\/venezuela-cierra-la-principal-frontera-con-colombia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/colombia\/"},{"@type":"ListItem","position":2,"name":"Venezuela cierra la principal frontera con Colombia"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/colombia\/#website","url":"https:\/\/noti-america.com\/site\/colombia\/","name":"Colombia | Noti-America.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/54a1f5656d2b8acb0c1530cda7fabda4","name":"Silvia S\u00e1nchez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2287cfc8de78326c0baee5bffce79d09df06b397cb6bd0bce79b2faf6d45aa43?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2287cfc8de78326c0baee5bffce79d09df06b397cb6bd0bce79b2faf6d45aa43?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2287cfc8de78326c0baee5bffce79d09df06b397cb6bd0bce79b2faf6d45aa43?s=96&d=mm&r=g","caption":"Silvia S\u00e1nchez"},"url":"https:\/\/noti-america.com\/site\/colombia\/author\/ssanchez\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/5390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/users\/85"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/comments?post=5390"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/5390\/revisions"}],"predecessor-version":[{"id":5392,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/5390\/revisions\/5392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/media\/5391"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/media?parent=5390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/categories?post=5390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/tags?post=5390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}