{"id":18800,"date":"2025-04-09T22:36:39","date_gmt":"2025-04-09T22:36:39","guid":{"rendered":"https:\/\/noti-america.com\/site\/colombia\/?p=18800"},"modified":"2025-04-22T22:40:10","modified_gmt":"2025-04-22T22:40:10","slug":"pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/","title":{"rendered":"Pandora anuncia a Tyla como nueva embajadora de marca"},"content":{"rendered":"<p>NOTI-AMERICA | COLOMBIA<\/p>\n<p>Pandora, la marca de joyer\u00eda m\u00e1s grande del mundo, le da la bienvenida a su familia a <a href=\"https:\/\/www.instagram.com\/tyla\/\"><strong>Tyla<\/strong><\/a>, la sensaci\u00f3n musical global y ganadora del premio Grammy\u00ae, como su nueva embajadora de marca. Conocida por romper g\u00e9neros musicales, sus impactantes presentaciones y su estilo ic\u00f3nico, la cantante, compositora y performer originaria de Sud\u00e1frica ser\u00e1 imagen de la colecci\u00f3n completa de Pandora, incluyendo sus ya famosos charms, reconocidos en todo el mundo.<\/p>\n<p><strong>El anuncio llega d\u00edas antes del esperado debut de Tyla en el escenario de Coachella, el pr\u00f3ximo 11 de abril.<\/strong> Su talento para combinar arte, m\u00fasica y storytelling personal la convierte en la aliada perfecta para Pandora, una marca que celebra la autenticidad, la creatividad y el estilo individual.<\/p>\n<p>Como parte de esta colaboraci\u00f3n, Tyla protagoniza la campa\u00f1a <strong>\u201cPandora Styled by Tyla\u201d<\/strong>, donde presenta una selecci\u00f3n de joyer\u00eda Pandora que refleja su historia, sus pasiones e inspiraci\u00f3n. El coraz\u00f3n de esta colecci\u00f3n lo conforman <strong>los charms<\/strong>, cada uno con un significado especial en la vida de Tyla. Desde el <strong><em>Cherry Blossom Charm<\/em>,<\/strong> que remite al ic\u00f3nico video de su \u00e9xito \u201cWater\u201d, hasta s\u00edmbolos que honran sus ra\u00edces, su m\u00fasica y la conexi\u00f3n con sus fans \u2014como el <strong><em>Mini Shark Tooth Charm<\/em><\/strong>\u2014 cada pieza cuenta una historia.<\/p>\n<p><em>\u201cColaborar con Pandora es algo que me emociona much\u00edsimo,\u201d<\/em> comparti\u00f3 Tyla. <em>\u201cSiempre me ha gustado su joyer\u00eda porque te permite armar piezas \u00fanicas. Me recuerda mucho a casa: mi mam\u00e1 hac\u00eda joyas y los charms con piedras de nacimiento me hacen pensar en los abalorios que sol\u00eda ver por todos lados mientras crec\u00eda. Cuando quer\u00edamos llamar su atenci\u00f3n, nos daba un bote lleno de cuentas y mis hermanas y yo pas\u00e1bamos horas haciendo pulseras de amistad. Ahora, mis Tygers pueden tener pulseras iguales a las m\u00edas.\u201d<\/em><\/p>\n<p>Con esta alianza, <strong>Pandora y Tyla celebran el poder de la joyer\u00eda para capturar los momentos m\u00e1s especiales<\/strong>, inspirando a nuevas generaciones a contar su historia a trav\u00e9s de un estilo propio y aut\u00e9ntico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA | COLOMBIA Pandora, la marca de joyer\u00eda m\u00e1s grande del mundo, le da la bienvenida a su familia a Tyla, la sensaci\u00f3n musical global y ganadora del premio Grammy\u00ae, como su nueva embajadora&#46;&#46;&#46;<\/p>\n","protected":false},"author":135,"featured_media":18801,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[237],"tags":[],"class_list":["post-18800","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-tendencia-moda","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pandora anuncia a Tyla como nueva embajadora de marca - Colombia | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pandora anuncia a Tyla como nueva embajadora de marca\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA | COLOMBIA Pandora, la marca de joyer\u00eda m\u00e1s grande del mundo, le da la bienvenida a su familia a Tyla, la sensaci\u00f3n musical global y ganadora del premio Grammy\u00ae, como su nueva embajadora&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/\" \/>\n<meta property=\"og:site_name\" content=\"Colombia | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-09T22:36:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-22T22:40:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2025\/04\/Tyla.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"327\" \/>\n\t<meta property=\"og:image:height\" content=\"409\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mlenis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:site\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mlenis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/\"},\"author\":{\"name\":\"mlenis\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/d8ba689c53ca849eda73514018fa3428\"},\"headline\":\"Pandora anuncia a Tyla como nueva embajadora de marca\",\"datePublished\":\"2025-04-09T22:36:39+00:00\",\"dateModified\":\"2025-04-22T22:40:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/\"},\"wordCount\":372,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2025\/04\/Tyla.jpg\",\"articleSection\":[\"Tendencia-Moda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/\",\"name\":\"Pandora anuncia a Tyla como nueva embajadora de marca - Colombia | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2025\/04\/Tyla.jpg\",\"datePublished\":\"2025-04-09T22:36:39+00:00\",\"dateModified\":\"2025-04-22T22:40:10+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/d8ba689c53ca849eda73514018fa3428\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2025\/04\/Tyla.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2025\/04\/Tyla.jpg\",\"width\":327,\"height\":409},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pandora anuncia a Tyla como nueva embajadora de marca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/\",\"name\":\"Colombia | Noti-America.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/d8ba689c53ca849eda73514018fa3428\",\"name\":\"mlenis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"caption\":\"mlenis\"},\"url\":\"https:\/\/noti-america.com\/site\/colombia\/author\/mlenis\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pandora anuncia a Tyla como nueva embajadora de marca - Colombia | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/","og_locale":"es_ES","og_type":"article","og_title":"Pandora anuncia a Tyla como nueva embajadora de marca","og_description":"NOTI-AMERICA | COLOMBIA Pandora, la marca de joyer\u00eda m\u00e1s grande del mundo, le da la bienvenida a su familia a Tyla, la sensaci\u00f3n musical global y ganadora del premio Grammy\u00ae, como su nueva embajadora&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/","og_site_name":"Colombia | Noti-America.com","article_published_time":"2025-04-09T22:36:39+00:00","article_modified_time":"2025-04-22T22:40:10+00:00","og_image":[{"width":327,"height":409,"url":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2025\/04\/Tyla.jpg","type":"image\/jpeg"}],"author":"mlenis","twitter_card":"summary_large_image","twitter_creator":"@notiamerica","twitter_site":"@notiamerica","twitter_misc":{"Escrito por":"mlenis","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/"},"author":{"name":"mlenis","@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/d8ba689c53ca849eda73514018fa3428"},"headline":"Pandora anuncia a Tyla como nueva embajadora de marca","datePublished":"2025-04-09T22:36:39+00:00","dateModified":"2025-04-22T22:40:10+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/"},"wordCount":372,"commentCount":0,"image":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2025\/04\/Tyla.jpg","articleSection":["Tendencia-Moda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/","url":"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/","name":"Pandora anuncia a Tyla como nueva embajadora de marca - Colombia | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2025\/04\/Tyla.jpg","datePublished":"2025-04-09T22:36:39+00:00","dateModified":"2025-04-22T22:40:10+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/d8ba689c53ca849eda73514018fa3428"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#primaryimage","url":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2025\/04\/Tyla.jpg","contentUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2025\/04\/Tyla.jpg","width":327,"height":409},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/colombia\/2025\/04\/09\/pandora-anuncia-a-tyla-como-nueva-embajadora-de-marca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/colombia\/"},{"@type":"ListItem","position":2,"name":"Pandora anuncia a Tyla como nueva embajadora de marca"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/colombia\/#website","url":"https:\/\/noti-america.com\/site\/colombia\/","name":"Colombia | Noti-America.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/d8ba689c53ca849eda73514018fa3428","name":"mlenis","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","caption":"mlenis"},"url":"https:\/\/noti-america.com\/site\/colombia\/author\/mlenis\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/18800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/comments?post=18800"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/18800\/revisions"}],"predecessor-version":[{"id":18802,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/18800\/revisions\/18802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/media\/18801"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/media?parent=18800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/categories?post=18800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/tags?post=18800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}