{"id":17276,"date":"2024-10-10T22:49:41","date_gmt":"2024-10-10T22:49:41","guid":{"rendered":"https:\/\/noti-america.com\/site\/colombia\/?p=17276"},"modified":"2024-10-13T23:04:51","modified_gmt":"2024-10-13T23:04:51","slug":"expocervezas-2024-el-pub-mas-grande-de-colombia","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/","title":{"rendered":"Expocervezas 2024: El Pub mas grande de Colombia"},"content":{"rendered":"<p>NOTI-AMERICA | COLOMBIA<\/p>\n<p><strong>Expocervezas 2024<\/strong><\/p>\n<p>Bogot\u00e1, 10 al 13 de octubre, Gran Carpa Bogot\u00e1 (Carrera 60 calle 53).<\/p>\n<p>Medell\u00edn, 24 al 27 de octubre, City Hall Club El Rodeo (Calle 2 Sur # 65 &#8211; 135).<\/p>\n<p>Horario: jueves, viernes de 1:00 p.m. a 10:00 p.m., s\u00e1bado y domingo de<\/p>\n<p>12:00 m. a 10:00 p.m.<\/p>\n<p>Entrada exclusiva para mayores de 18 a\u00f1os.<\/p>\n<p>Expocervezas<strong>,<\/strong> el <em>pub<\/em> m\u00e1s grande de Colombia, vuelve en octubre a abrir sus puertas en Bogot\u00e1 y Medell\u00edn. Este espacio re\u00fane a los amantes de la cerveza que disfrutar\u00e1n de cuatro d\u00edas con shows de m\u00fasica, una variada oferta gastron\u00f3mica, diversi\u00f3n y nuevas experiencias bajo el concepto \u201cListos para el pr\u00f3ximo brindis\u201d. Brindis con una cerveza <em>ale<\/em>, brindis con una cerveza <em>lager<\/em>, brindis con una cerveza artesanal. Listos para el pr\u00f3ximo brindis con los amigos de la oficina, con los amigos de la universidad, con los amigos del barrio, listos para el pr\u00f3ximo brindis con los amigos de toda la vida.<\/p>\n<p><strong>\u201cCarulla tiene uno de los portafolios m\u00e1s grandes del pa\u00eds en cervezas importadas y nacionales. Con Expocervezas, la feria que re\u00fane el mayor n\u00famero de referencias de los diferentes or\u00edgenes de esta bebida, se busca crear una verdadera cultura cervecera que eduque y promueva un consumo responsable. Expocervezas en Bogot\u00e1 llega a su novena edici\u00f3n en una nueva locaci\u00f3n de 11,200 metros cuadrados de superficie en la Gran Carpa Bogot\u00e1, Carrera 60 calle 53. Este lugar est\u00e1 ubicado cerca al Centro Comercial Gran Estaci\u00f3n y el parque Sim\u00f3n Bol\u00edvar con v\u00edas de acceso por la Avenida 26 y la Avenida 68. En Medell\u00edn volvemos al City Hall Club El Rodeo en un espacio de 3, 200 metros cuadrados. Para esta nueva versi\u00f3n, estamos listos para el pr\u00f3ximo brindis con amigos para disfrutar de una buena cerveza en el pub m\u00e1s grande de Colombia\u201d,<\/strong> indic\u00f3 John Tello, director de Expocervezas.<\/p>\n<p><strong>Expocervezas; un conjunto de experiencias para todos<\/strong><\/p>\n<ul>\n<li>La m\u00fasica y el entretenimiento ser\u00e1n acompa\u00f1antes de los asistentes de Expocervezas en Bogot\u00e1 y Medell\u00edn. En 2024 en <strong>La Pista<\/strong> estar\u00e1n DJ\u2019S invitados, bandas de rock, solistas con shows de m\u00fasica como: Batalla Red Bull con 3 de los mejores exponentes sorpresa del genero free style, agrupaciones como Don Tetto, Aguanil\u00e9, Saturno, tributos y bandas locales estar\u00e1n enriqueciendo la parrilla musical.<\/li>\n<li><strong>Sal\u00f3n de Maestros Cerveceros<\/strong>: El espacio acad\u00e9mico de Expocervezas ofrece m\u00e1s de 50 charlas con expertos nacionales e internacionales sobre diversos temas relacionados con la bebida. Dos salones con catas y pantallas disponibles para mejorar la experiencia de aprendizaje de los fan\u00e1ticos cerveceros.<\/li>\n<li><strong>Concurso Catas a ciegas:<\/strong> Las mejores cervezas de la feria ser\u00e1n premiadas en 2 categor\u00edas (Importadas y nacionales). Las botellas ganadoras recibir\u00e1n medallas de oro, plata, bronce y menci\u00f3n de honor durante la feria y se convertir\u00e1n en referencia de compra para los amantes de la cerveza. Estas ser\u00e1n juzgadas en cata a ciegas por un grupo de 12 jurados expertos quienes elegir\u00e1n la mejor selecci\u00f3n.<\/li>\n<li>Clases de cocina a cargo de <em>chefs<\/em> de la <strong>Escuela de Cocina Carulla<\/strong> inspiradas en la cerveza y su maridaje ideal bajo la direcci\u00f3n de Federica Galeani. Un espacio para aprender sobre las mejores preparaciones con la cerveza como ingrediente principal.<\/li>\n<li><strong>Parrilla y sabor:<\/strong> una variada oferta gastron\u00f3mica con sabores de parrilla, <em>delicatessen<\/em>, <em>foodtrucks<\/em> y restaurantes de distintos tipos de comida.<\/li>\n<li>Una <strong>Estaci\u00f3n coctelera<\/strong> con <em>hard seltzers<\/em> y otros licores. Los <em>bartenders<\/em> ofrecer\u00e1n a los asistentes varias clases de cocteles.<\/li>\n<li>El <strong>BIP (<\/strong><em>Beer important people<\/em>), una zona exclusiva con la mejor selecci\u00f3n de cervezas premium, ofertas gastron\u00f3micas y shows musicales.<\/li>\n<li><strong>Tienda<\/strong> con un ambiente r\u00fastico y acogedor con tem\u00e1tica de \u201cbodega antigua\u201d donde estar\u00e1n a la venta m\u00e1s de 250 referencias provenientes de 15 pa\u00edses del mundo con promociones y descuentos.<\/li>\n<li><strong><em>Souvenir<\/em><\/strong> con <em>merchandising<\/em> para los apasionados de las cervezas como jarros, portavasos, camisetas, gorras, destapadores y muchos otros art\u00edculos de las diferentes marcas.<\/li>\n<\/ul>\n<p>Estas son algunas de las experiencias que vivir\u00e1n los asistentes a Expocervezas en Bogot\u00e1 y Medell\u00edn<strong>. \u201cLos esperamos en Expocervezas, el pub m\u00e1s grande de Colombia, en Bogot\u00e1 (10 al 13 de octubre) y Medell\u00edn (24 al 27 de octubre) para disfrutar de buenas cervezas, gastronom\u00eda, m\u00fasica, diversi\u00f3n y nuevas experiencias en torno a esta bebida milenaria\u201d,<\/strong> a\u00f1adi\u00f3 John Tello, director de Expocervezas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA | COLOMBIA Expocervezas 2024 Bogot\u00e1, 10 al 13 de octubre, Gran Carpa Bogot\u00e1 (Carrera 60 calle 53). Medell\u00edn, 24 al 27 de octubre, City Hall Club El Rodeo (Calle 2 Sur # 65&#46;&#46;&#46;<\/p>\n","protected":false},"author":135,"featured_media":17277,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[165],"tags":[],"class_list":["post-17276","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-eventos-y-mercadeo","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expocervezas 2024: El Pub mas grande de Colombia - Colombia | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expocervezas 2024: El Pub mas grande de Colombia\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA | COLOMBIA Expocervezas 2024 Bogot\u00e1, 10 al 13 de octubre, Gran Carpa Bogot\u00e1 (Carrera 60 calle 53). Medell\u00edn, 24 al 27 de octubre, City Hall Club El Rodeo (Calle 2 Sur # 65&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/\" \/>\n<meta property=\"og:site_name\" content=\"Colombia | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-10T22:49:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-13T23:04:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/10\/expocerverza.png\" \/>\n\t<meta property=\"og:image:width\" content=\"716\" \/>\n\t<meta property=\"og:image:height\" content=\"476\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mlenis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:site\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mlenis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/\"},\"author\":{\"name\":\"mlenis\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f\"},\"headline\":\"Expocervezas 2024: El Pub mas grande de Colombia\",\"datePublished\":\"2024-10-10T22:49:41+00:00\",\"dateModified\":\"2024-10-13T23:04:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/\"},\"wordCount\":750,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/10\/expocerverza.png\",\"articleSection\":[\"Eventos y Mercadeo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/\",\"name\":\"Expocervezas 2024: El Pub mas grande de Colombia - Colombia | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/10\/expocerverza.png\",\"datePublished\":\"2024-10-10T22:49:41+00:00\",\"dateModified\":\"2024-10-13T23:04:51+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/10\/expocerverza.png\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/10\/expocerverza.png\",\"width\":716,\"height\":476},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expocervezas 2024: El Pub mas grande de Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/\",\"name\":\"Colombia | Noti-America.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f\",\"name\":\"mlenis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"caption\":\"mlenis\"},\"url\":\"https:\/\/noti-america.com\/site\/colombia\/author\/mlenis\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expocervezas 2024: El Pub mas grande de Colombia - Colombia | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/","og_locale":"es_ES","og_type":"article","og_title":"Expocervezas 2024: El Pub mas grande de Colombia","og_description":"NOTI-AMERICA | COLOMBIA Expocervezas 2024 Bogot\u00e1, 10 al 13 de octubre, Gran Carpa Bogot\u00e1 (Carrera 60 calle 53). Medell\u00edn, 24 al 27 de octubre, City Hall Club El Rodeo (Calle 2 Sur # 65&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/","og_site_name":"Colombia | Noti-America.com","article_published_time":"2024-10-10T22:49:41+00:00","article_modified_time":"2024-10-13T23:04:51+00:00","og_image":[{"width":716,"height":476,"url":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/10\/expocerverza.png","type":"image\/png"}],"author":"mlenis","twitter_card":"summary_large_image","twitter_creator":"@notiamerica","twitter_site":"@notiamerica","twitter_misc":{"Escrito por":"mlenis","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/"},"author":{"name":"mlenis","@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f"},"headline":"Expocervezas 2024: El Pub mas grande de Colombia","datePublished":"2024-10-10T22:49:41+00:00","dateModified":"2024-10-13T23:04:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/"},"wordCount":750,"commentCount":0,"image":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/10\/expocerverza.png","articleSection":["Eventos y Mercadeo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/","url":"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/","name":"Expocervezas 2024: El Pub mas grande de Colombia - Colombia | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/10\/expocerverza.png","datePublished":"2024-10-10T22:49:41+00:00","dateModified":"2024-10-13T23:04:51+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#primaryimage","url":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/10\/expocerverza.png","contentUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/10\/expocerverza.png","width":716,"height":476},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/10\/10\/expocervezas-2024-el-pub-mas-grande-de-colombia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/colombia\/"},{"@type":"ListItem","position":2,"name":"Expocervezas 2024: El Pub mas grande de Colombia"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/colombia\/#website","url":"https:\/\/noti-america.com\/site\/colombia\/","name":"Colombia | Noti-America.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f","name":"mlenis","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","caption":"mlenis"},"url":"https:\/\/noti-america.com\/site\/colombia\/author\/mlenis\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/17276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/comments?post=17276"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/17276\/revisions"}],"predecessor-version":[{"id":17278,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/17276\/revisions\/17278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/media\/17277"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/media?parent=17276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/categories?post=17276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/tags?post=17276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}