{"id":16248,"date":"2024-07-08T21:17:45","date_gmt":"2024-07-08T21:17:45","guid":{"rendered":"https:\/\/noti-america.com\/site\/colombia\/?p=16248"},"modified":"2024-07-08T21:17:45","modified_gmt":"2024-07-08T21:17:45","slug":"meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/","title":{"rendered":"Meditech 2024: La plataforma internacional para la innovaci\u00f3n en salud llega a Bogot\u00e1"},"content":{"rendered":"<p>NOTI-AMERICA | COLOMBIA<\/p>\n<p>La VIII Feria Internacional de la Salud \u2013 Meditech, organizada por la Asociaci\u00f3n Colombiana de Hospitales y Cl\u00ednicas (ACHC), Corferias y Messe D\u00fcsseldorf Norteam\u00e9rica como socio internacional,\u00a0 se llevar\u00e1 a cabo del 9 al 12 de julio en Corferias. Este encuentro, que se ha consolidado como la feria m\u00e1s importante del sector en la regi\u00f3n, reunir\u00e1 a m\u00e1s de 17 pa\u00edses y a los principales actores del sector salud, en un escenario ideal para la actualizaci\u00f3n y el intercambio de conocimientos.<\/p>\n<p>\u201cHemos dise\u00f1ado una versi\u00f3n en la que participar\u00e1n m\u00e1s de 250 expositores, de ellos el 45% provienen de 16 pa\u00edses como los son: Alemania, Argentina, Brasil, Chile, China, Corea del Sur, Espa\u00f1a, Estados Unidos, India, Italia, Jap\u00f3n, Malasia, M\u00e9xico, Polonia, Taiw\u00e1n y Turqu\u00eda. Llegan a Meditech para mostrar lo \u00faltimo en tecnolog\u00eda de punta para el sector salud. Adem\u00e1s, tendremos una agenda de actividades acad\u00e9micas que llevar\u00e1n al p\u00fablico a actualizar y fortalecer los conocimientos\u201d afirm\u00f3 Ana Garibello, jefe de proyecto de Meditech.<\/p>\n<p><strong>Conozca los detalles de XV Congreso Colombiano de Hospitales y Cl\u00ednicas:<\/strong><\/p>\n<p>Un componente clave de Meditech 2024 ser\u00e1 el<strong> XV Congreso Colombiano de Hospitales y Cl\u00ednicas,<\/strong> organizado por la ACHC y que se realizar\u00e1 el 10 y 11 de julio. Este evento acad\u00e9mico brindar\u00e1 una actualizaci\u00f3n integral sobre las tendencias en gesti\u00f3n hospitalaria a nivel mundial y se presenta como una oportunidad \u00fanica para profesionales de la salud, directivos hospitalarios, funcionarios gubernamentales y dem\u00e1s actores del sector, para analizar y discutir los principales desaf\u00edos que enfrenta la salud en la actualidad.<\/p>\n<p>\u201cMeditech 2024, adem\u00e1s de ser un escenario\u00a0 clave para la actualizaci\u00f3n y la exploraci\u00f3n de soluciones innovadoras en el sector, abordar\u00e1, a trav\u00e9s del XV Congreso Internacional de Hospitales y Cl\u00ednicas, temas de gran relevancia para el futuro del sector salud, como:\u00a0 el futuro del sistema de salud en Colombia, el uso responsable de la inteligencia artificial en la atenci\u00f3n, la gesti\u00f3n de riesgos, los desaf\u00edos de la escasez\u00a0 de talento humano, la preparaci\u00f3n para futuras pandemias y el liderazgo en salud\u201d mencion\u00f3 Juan Carlos Giraldo Valencia, Director General de la Asociaci\u00f3n Colombiana de Hospitales y Cl\u00ednicas (ACHC)<\/p>\n<p><strong>Bogot\u00e1: un destino estrat\u00e9gico para el sector salud <\/strong><\/p>\n<p>La elecci\u00f3n de Bogot\u00e1 como sede de Meditech 2024 y el XV Congreso Internacional de Hospitales y Cl\u00ednicas no es casualidad. Colombia, y en particular Bogot\u00e1, ofrecen una serie de ventajas que lo convierten en un destino ideal para este tipo de eventos.<\/p>\n<p>El creciente mercado de salud representa una oportunidad para las empresas del sector. Adem\u00e1s, el pa\u00eds cuenta con un talento humano altamente calificado y una infraestructura hospitalaria moderna.<\/p>\n<p>Asimismo, la ubicaci\u00f3n estrat\u00e9gica de Colombia en la regi\u00f3n y la conectividad a\u00e9rea facilitan el acceso a profesionales de la salud de toda la regi\u00f3n.<\/p>\n<p>Por \u00faltimo, las pol\u00edticas gubernamentales que buscan atraer la inversi\u00f3n extranjera al sector salud y la estabilidad pol\u00edtica ponen a Colombia como un destino internacional en temas de salud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA | COLOMBIA La VIII Feria Internacional de la Salud \u2013 Meditech, organizada por la Asociaci\u00f3n Colombiana de Hospitales y Cl\u00ednicas (ACHC), Corferias y Messe D\u00fcsseldorf Norteam\u00e9rica como socio internacional,\u00a0 se llevar\u00e1 a cabo&#46;&#46;&#46;<\/p>\n","protected":false},"author":135,"featured_media":16249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-16248","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-salud","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Meditech 2024: La plataforma internacional para la innovaci\u00f3n en salud llega a Bogot\u00e1 - Colombia | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meditech 2024: La plataforma internacional para la innovaci\u00f3n en salud llega a Bogot\u00e1\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA | COLOMBIA La VIII Feria Internacional de la Salud \u2013 Meditech, organizada por la Asociaci\u00f3n Colombiana de Hospitales y Cl\u00ednicas (ACHC), Corferias y Messe D\u00fcsseldorf Norteam\u00e9rica como socio internacional,\u00a0 se llevar\u00e1 a cabo&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/\" \/>\n<meta property=\"og:site_name\" content=\"Colombia | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-08T21:17:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/07\/Meditech.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mlenis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:site\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mlenis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/\"},\"author\":{\"name\":\"mlenis\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007\"},\"headline\":\"Meditech 2024: La plataforma internacional para la innovaci\u00f3n en salud llega a Bogot\u00e1\",\"datePublished\":\"2024-07-08T21:17:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/\"},\"wordCount\":544,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/07\/Meditech.jpeg\",\"articleSection\":[\"Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/\",\"name\":\"Meditech 2024: La plataforma internacional para la innovaci\u00f3n en salud llega a Bogot\u00e1 - Colombia | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/07\/Meditech.jpeg\",\"datePublished\":\"2024-07-08T21:17:45+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/07\/Meditech.jpeg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/07\/Meditech.jpeg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meditech 2024: La plataforma internacional para la innovaci\u00f3n en salud llega a Bogot\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/\",\"name\":\"Colombia | Noti-America.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007\",\"name\":\"mlenis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"caption\":\"mlenis\"},\"url\":\"https:\/\/noti-america.com\/site\/colombia\/author\/mlenis\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Meditech 2024: La plataforma internacional para la innovaci\u00f3n en salud llega a Bogot\u00e1 - Colombia | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/","og_locale":"es_ES","og_type":"article","og_title":"Meditech 2024: La plataforma internacional para la innovaci\u00f3n en salud llega a Bogot\u00e1","og_description":"NOTI-AMERICA | COLOMBIA La VIII Feria Internacional de la Salud \u2013 Meditech, organizada por la Asociaci\u00f3n Colombiana de Hospitales y Cl\u00ednicas (ACHC), Corferias y Messe D\u00fcsseldorf Norteam\u00e9rica como socio internacional,\u00a0 se llevar\u00e1 a cabo&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/","og_site_name":"Colombia | Noti-America.com","article_published_time":"2024-07-08T21:17:45+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/07\/Meditech.jpeg","type":"image\/jpeg"}],"author":"mlenis","twitter_card":"summary_large_image","twitter_creator":"@notiamerica","twitter_site":"@notiamerica","twitter_misc":{"Escrito por":"mlenis","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/"},"author":{"name":"mlenis","@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007"},"headline":"Meditech 2024: La plataforma internacional para la innovaci\u00f3n en salud llega a Bogot\u00e1","datePublished":"2024-07-08T21:17:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/"},"wordCount":544,"commentCount":0,"image":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/07\/Meditech.jpeg","articleSection":["Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/","url":"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/","name":"Meditech 2024: La plataforma internacional para la innovaci\u00f3n en salud llega a Bogot\u00e1 - Colombia | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/07\/Meditech.jpeg","datePublished":"2024-07-08T21:17:45+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#primaryimage","url":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/07\/Meditech.jpeg","contentUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2024\/07\/Meditech.jpeg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/colombia\/2024\/07\/08\/meditech-2024-la-plataforma-internacional-para-la-innovacion-en-salud-llega-a-bogota\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/colombia\/"},{"@type":"ListItem","position":2,"name":"Meditech 2024: La plataforma internacional para la innovaci\u00f3n en salud llega a Bogot\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/colombia\/#website","url":"https:\/\/noti-america.com\/site\/colombia\/","name":"Colombia | Noti-America.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007","name":"mlenis","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","caption":"mlenis"},"url":"https:\/\/noti-america.com\/site\/colombia\/author\/mlenis\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/16248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/comments?post=16248"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/16248\/revisions"}],"predecessor-version":[{"id":16250,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/16248\/revisions\/16250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/media\/16249"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/media?parent=16248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/categories?post=16248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/tags?post=16248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}