{"id":12396,"date":"2023-11-11T02:37:09","date_gmt":"2023-11-11T02:37:09","guid":{"rendered":"https:\/\/noti-america.com\/site\/colombia\/?p=12396"},"modified":"2023-11-11T02:37:09","modified_gmt":"2023-11-11T02:37:09","slug":"chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/","title":{"rendered":"Chocoshow 2023, la feria para deleitarse con el mejor cacao y el chocolate de Colombia"},"content":{"rendered":"<p>NOTI-AMERICA | COLOMBIA<\/p>\n<p style=\"text-align: justify\">Del 24 al 26 de noviembre, Corferias y Fedecacao endulzar\u00e1n, llenar\u00e1n de sabores y de diversi\u00f3n los pabellones del recinto ferial por cuenta de la feria Chocoshow, evento en el que se congregar\u00e1 toda la cadena de producci\u00f3n del subsector cacaotero colombiano, en representaci\u00f3n de las m\u00e1s de 60.000 mil familias cacaoteras que dinamizan la producci\u00f3n en 29 de los 32 departamentos y que generan m\u00e1s de 67.000 empleos directos e indirectos.<\/p>\n<p style=\"text-align: justify\">El evento organizado por Corferias y la Federaci\u00f3n Nacional de Cacaoteros (FEDECACAO), que llega a su quinta edici\u00f3n, tendr\u00e1 una muestra comercial a cargo de m\u00e1s de 150 expositores, los cuales tendr\u00e1n las \u00faltimas novedades, productos, bienes y servicios en el marco de un espect\u00e1culo alrededor del cacao y el chocolate, con diferentes espacios para conocer las maravillas y potencialidades de este producto en todas sus manifestaciones.<\/p>\n<p style=\"text-align: justify\">As\u00ed lo sostiene <strong>Eduard Baquero L\u00f3pez, Presidente Ejecutivo de la Federaci\u00f3n Nacional de Cacaoteros<\/strong>: <em>\u201cChocoshow, en su quinto a\u00f1o, continuar\u00e1 siendo el escenario que impulsa el subsector cacaotero de nuestro pa\u00eds y genera experiencias alrededor de la cultura del chocolate. Adem\u00e1s, a partir de este evento esperamos promover el uso del cacao colombiano como materia prima, apoyando de esta manera el crecimiento del subsector, de manera que se puedan aperturar nuevos mercados para fortalecer la comercializaci\u00f3n del grano de cacao y de producto terminado\u201d.<\/em><\/p>\n<p style=\"text-align: justify\"><em>\u00a0<\/em>Chocoshow es una feria en la que los visitantes disfrutar\u00e1n en familia de todo lo que representa la cacaocultura colombiana, los asistentes a la feria podr\u00e1n conocer y experimentar m\u00e1s de esta industria, con productos como bombones y chocolates, productos de belleza, artesan\u00edas y dem\u00e1s realizados a base de chocolate-cacao.<\/p>\n<p style=\"text-align: justify\">Por su parte, los expositores tendr\u00e1n 4 pabellones y \u00e1reas libres a lo largo y ancho de\u00a0 12.000 m2, en los que podr\u00e1n mostrar sus productos al p\u00fablico masivo y a todos los representantes de esta industria y dem\u00e1s tomadores de decisi\u00f3n de toda la cadena que pertenece a este sector, donde tambi\u00e9n se promueve el consumo de sus productos y el posicionamiento de marcas.<\/p>\n<p style=\"text-align: justify\"><strong>Doris Chingat\u00e9 Jefe de Proyecto<\/strong> de la feria sostiene que: <em>\u201cChocoshow, adem\u00e1s de reconocer y visibilizar el trabajo de los cacaocultores y de quienes transforman el cacao, le entregar\u00e1 a los visitantes, a trav\u00e9s de actividades y experiencia, conocimiento en torno al cacao y el chocolate, para que estos puedan estar actualizados en las \u00faltimas tendencias\u201d.<\/em><\/p>\n<p style=\"text-align: justify\">El evento, a lo largo de sus tres d\u00edas pondr\u00e1 a disposici\u00f3n de los visitantes una serie de experiencias presenciales, las cuales enriquecer\u00e1n y llenar\u00e1n de valor la asistencia a Corferias, entre esas actividades se destacan:<\/p>\n<ul>\n<li style=\"text-align: justify\"><strong>Catas de Cacao: <\/strong>El evento se percibe como el escenario para acercarse y conocer de primera mano la \u00abCultura del Chocolate\u00bb, a lo largo de los 3 d\u00edas los visitantes de manera guiada aprenden c\u00f3mo degustar y disfrutar el chocolate con diferentes porcentajes de cacao por medio de sus sentidos.<\/li>\n<li style=\"text-align: justify\"><strong>Agenda acad\u00e9mica:<\/strong> Chocoshow tendr\u00e1 una agenda acad\u00e9mica complementaria en la cual se llevar\u00e1n a cabo diferentes charlas, en cabeza de actores clave para la feria, con temas de inter\u00e9s para cacaocultores y p\u00fablico visitante.<\/li>\n<li style=\"text-align: justify\"><strong>Tarima de talleres:<\/strong> Demostraci\u00f3n de preparaciones a base de cacao y chocolate y exhibici\u00f3n de los diferentes usos de este producto como materia prima.<\/li>\n<li style=\"text-align: justify\"><strong>Chocokids:<\/strong> En esta actividad experiencial los ni\u00f1os visitantes a la feria Chocoshow 2023, podr\u00e1n disfrutar de seis estaciones donde conocer\u00e1n, degustar\u00e1n y aprender\u00e1n del cacao y su origen de una forma muy divertida y l\u00fadica a trav\u00e9s de recorridos guiados por expertos, ser\u00e1 un encuentro lleno de muchos sabores.<\/li>\n<li style=\"text-align: justify\"><strong>La ruta del cacao: <\/strong>recorrido en el que el visitante conoce el origen del cacao y la magia que lo transforma en chocolate. Ense\u00f1a sobre el cultivo, la cosecha y la transformaci\u00f3n.<\/li>\n<li style=\"text-align: justify\"><strong>Galer\u00eda de arte:<\/strong> espacio comprendido por una exhibici\u00f3n fotogr\u00e1fica de los j\u00f3venes del programa de Fedecacao, \u00abSembrando Futuro\u00bb.<\/li>\n<li style=\"text-align: justify\"><strong>Santuario del cacao:<\/strong> Experiencia que muestra los elementos m\u00e1s representativos de las fincas cacaoteras de las regiones.<\/li>\n<li style=\"text-align: justify\"><strong>Escultura:<\/strong> Espacio para vivir la inigualable experiencia con la escultura m\u00e1s grande de Colombia.<\/li>\n<li style=\"text-align: justify\"><strong>Cine al aire libre:<\/strong> espacio de esparcimiento ubicado en plaza de banderas donde se tendr\u00e1 proyecciones de cortometrajes referentes a la historia del cacao o fabricaci\u00f3n del chocolate, mientras comparten un momento en familia.<\/li>\n<li style=\"text-align: justify\"><strong>Carnaval de chocolate:<\/strong> este ser\u00e1 un espacio para la diversi\u00f3n familiar con una muestra de circo o danza alusiva al cacao, acompa\u00f1ado de presentaciones itinerantes por los espacios abiertos de la feria, los grupos art\u00edsticos tendr\u00e1n vestuario relacionado con el cacao y chocolate, y realizar\u00e1n las presentaciones en transcurso de los tres d\u00edas de feria, en tarima y demostraciones itinerantes por los pabellones del evento.<\/li>\n<li style=\"text-align: justify\"><strong>Campeonato desengruyada de cacao:<\/strong> pr\u00e1ctica manual para extraer los granos del fruto de cacao, donde se separan de la placenta. Estas labores son propias de las familias cacaocultoras, en estos espacios comparten con amigos, vecinos y familia, vivencias, an\u00e9cdotas, chistes y temas de la actualidad. En este campeonato participar\u00e1n parejas cacaocultoras.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA | COLOMBIA Del 24 al 26 de noviembre, Corferias y Fedecacao endulzar\u00e1n, llenar\u00e1n de sabores y de diversi\u00f3n los pabellones del recinto ferial por cuenta de la feria Chocoshow, evento en el que&#46;&#46;&#46;<\/p>\n","protected":false},"author":135,"featured_media":12397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[228],"tags":[],"class_list":["post-12396","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-gastronomia","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Chocoshow 2023, la feria para deleitarse con el mejor cacao y el chocolate de Colombia - Colombia | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chocoshow 2023, la feria para deleitarse con el mejor cacao y el chocolate de Colombia\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA | COLOMBIA Del 24 al 26 de noviembre, Corferias y Fedecacao endulzar\u00e1n, llenar\u00e1n de sabores y de diversi\u00f3n los pabellones del recinto ferial por cuenta de la feria Chocoshow, evento en el que&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/\" \/>\n<meta property=\"og:site_name\" content=\"Colombia | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-11T02:37:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/11\/WhatsApp-Image-2023-10-26-at-9.05.19-AM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1068\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mlenis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:site\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mlenis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/\"},\"author\":{\"name\":\"mlenis\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f\"},\"headline\":\"Chocoshow 2023, la feria para deleitarse con el mejor cacao y el chocolate de Colombia\",\"datePublished\":\"2023-11-11T02:37:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/\"},\"wordCount\":893,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/11\/WhatsApp-Image-2023-10-26-at-9.05.19-AM.jpeg\",\"articleSection\":[\"Gastronom\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/\",\"name\":\"Chocoshow 2023, la feria para deleitarse con el mejor cacao y el chocolate de Colombia - Colombia | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/11\/WhatsApp-Image-2023-10-26-at-9.05.19-AM.jpeg\",\"datePublished\":\"2023-11-11T02:37:09+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/11\/WhatsApp-Image-2023-10-26-at-9.05.19-AM.jpeg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/11\/WhatsApp-Image-2023-10-26-at-9.05.19-AM.jpeg\",\"width\":1600,\"height\":1068},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chocoshow 2023, la feria para deleitarse con el mejor cacao y el chocolate de Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/\",\"name\":\"Colombia | Noti-America.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f\",\"name\":\"mlenis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"caption\":\"mlenis\"},\"url\":\"https:\/\/noti-america.com\/site\/colombia\/author\/mlenis\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Chocoshow 2023, la feria para deleitarse con el mejor cacao y el chocolate de Colombia - Colombia | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/","og_locale":"es_ES","og_type":"article","og_title":"Chocoshow 2023, la feria para deleitarse con el mejor cacao y el chocolate de Colombia","og_description":"NOTI-AMERICA | COLOMBIA Del 24 al 26 de noviembre, Corferias y Fedecacao endulzar\u00e1n, llenar\u00e1n de sabores y de diversi\u00f3n los pabellones del recinto ferial por cuenta de la feria Chocoshow, evento en el que&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/","og_site_name":"Colombia | Noti-America.com","article_published_time":"2023-11-11T02:37:09+00:00","og_image":[{"width":1600,"height":1068,"url":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/11\/WhatsApp-Image-2023-10-26-at-9.05.19-AM.jpeg","type":"image\/jpeg"}],"author":"mlenis","twitter_card":"summary_large_image","twitter_creator":"@notiamerica","twitter_site":"@notiamerica","twitter_misc":{"Escrito por":"mlenis","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/"},"author":{"name":"mlenis","@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f"},"headline":"Chocoshow 2023, la feria para deleitarse con el mejor cacao y el chocolate de Colombia","datePublished":"2023-11-11T02:37:09+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/"},"wordCount":893,"commentCount":0,"image":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/11\/WhatsApp-Image-2023-10-26-at-9.05.19-AM.jpeg","articleSection":["Gastronom\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/","url":"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/","name":"Chocoshow 2023, la feria para deleitarse con el mejor cacao y el chocolate de Colombia - Colombia | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/11\/WhatsApp-Image-2023-10-26-at-9.05.19-AM.jpeg","datePublished":"2023-11-11T02:37:09+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#primaryimage","url":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/11\/WhatsApp-Image-2023-10-26-at-9.05.19-AM.jpeg","contentUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/11\/WhatsApp-Image-2023-10-26-at-9.05.19-AM.jpeg","width":1600,"height":1068},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/11\/11\/chocoshow-2023-la-feria-para-deleitarse-con-el-mejor-cacao-y-el-chocolate-de-colombia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/colombia\/"},{"@type":"ListItem","position":2,"name":"Chocoshow 2023, la feria para deleitarse con el mejor cacao y el chocolate de Colombia"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/colombia\/#website","url":"https:\/\/noti-america.com\/site\/colombia\/","name":"Colombia | Noti-America.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/4b216aa1c65f5f3ee2a0f0ee69a3f85f","name":"mlenis","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","caption":"mlenis"},"url":"https:\/\/noti-america.com\/site\/colombia\/author\/mlenis\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/12396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/comments?post=12396"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/12396\/revisions"}],"predecessor-version":[{"id":12398,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/12396\/revisions\/12398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/media\/12397"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/media?parent=12396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/categories?post=12396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/tags?post=12396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}