{"id":10491,"date":"2023-06-14T18:10:09","date_gmt":"2023-06-14T18:10:09","guid":{"rendered":"https:\/\/noti-america.com\/site\/colombia\/?p=10491"},"modified":"2023-06-14T18:10:09","modified_gmt":"2023-06-14T18:10:09","slug":"etap-el-software-que-esta-transformando-las-industrias-renovables","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/","title":{"rendered":"ETAP: El software que est\u00e1 transformando las industrias renovables"},"content":{"rendered":"<p>NOTI-AMERICA | COLOMBIA<\/p>\n<p>La red el\u00e9ctrica es una de las m\u00e1quinas m\u00e1s complejas creada por la humanidad, ya que sin esta no existir\u00eda la civilizaci\u00f3n como la conocemos hoy. ETAP, un programa desarrollado en 1985 por el Dr. Farrokh Shokooh, fue creado para ayudar a los ingenieros a modelar y analizar los sistemas de potencia de la forma m\u00e1s eficiente y precisa. Su visi\u00f3n era crear un software basado en una sola plataforma con una \u00fanica base de datos, en donde tuvieran soluciones integradas y una interfaz intuitiva que permitiera a sus colegas reducir horas de ingenier\u00eda y ejecutar procesos de dise\u00f1o de manera m\u00e1s r\u00e1pida y confiable.<\/p>\n<p>La compa\u00f1\u00eda Schneider Electric, socio digital y l\u00edder en automatizaci\u00f3n y gesti\u00f3n eficiente de la energ\u00eda contin\u00faa avanzando en su plan de inversiones al interior de ETAP, buscando completar la cartera de software existente para sistemas de energ\u00eda el\u00e9ctrica. Esta tecnolog\u00eda se integrar\u00e1 con la exclusiva plataforma basada en la nube de Schneider para dise\u00f1ar y operar sistemas de energ\u00eda de empresas de misi\u00f3n cr\u00edtica, utilizando soluciones impulsadas por gemelos digitales independientes del proveedor.<\/p>\n<p><em>\u201cEs interesante observar c\u00f3mo empresas de ingenier\u00eda y consultor\u00eda el\u00e9ctrica a\u00fan utilizan herramientas de simulaci\u00f3n no integradas. Es por esta raz\u00f3n, que desde Schneider Electric impulsamos el despliegue de software CAD como ETAP, nativamente orientado al proceso de dise\u00f1o digital que permite la optimizaci\u00f3n de recursos de ingenier\u00eda\u201d<\/em> Alexander Valencia, desarrollador de software de negocios para Sudam\u00e9rica en Schneider Electric.<\/p>\n<p>El programa ofrece hardware de control y software de dise\u00f1o gestionado por medio de <a href=\"https:\/\/etap.com\/company\/news\/corporate-news\/2022\/05\/30\/integration-eOTS-PSMS-EcoStruxure\">gemelos digitales<\/a> el\u00e9ctricos, los cuales son integrados en soluciones para microrredes, centrales solares fotovoltaicas y e\u00f3licas; lo que permite a las organizaciones adoptar la integraci\u00f3n de <a href=\"https:\/\/etap.com\/industries\/renewable-energy\">energ\u00edas renovables<\/a> al tiempo que facilita energ\u00eda segura, confiable y eficiente.<\/p>\n<p>Tras conocerse la encuesta a afiliadas de la Asociaci\u00f3n de Energ\u00edas Renovables &#8211; SER Colombia la cual identific\u00f3 <strong>80 proyectos programados para entrar en operaci\u00f3n entre 2023 \u2013 2024<\/strong>, en 16 departamentos y por parte de 24 empresas y <strong>convierte a ETAP en un aliado t\u00e9cnico para su desarrollo y validaci\u00f3n durante las fases de dise\u00f1o, construcci\u00f3n y operaci\u00f3n<\/strong>.<\/p>\n<p><em>\u201cEn sus inicios, empez\u00f3 siendo utilizada exclusivamente por ingenieros de dise\u00f1o, pero con el <strong>crecimiento y mayor penetraci\u00f3n de los proyectos renovables, <\/strong>los operadores de red y administradores de proyectos, exigen tener un mayor control para determinar el impacto de las renovables en las redes de T&amp;D. Por lo que la <\/em><a href=\"https:\/\/etap.com\/packages\/monitoring-simulation\"><em>simulaci\u00f3n predictiva<\/em><\/a><em>, la <\/em><a href=\"https:\/\/etap.com\/product\/power-system-optimization-software\"><em>optimizaci\u00f3n<\/em><\/a><em> y el an\u00e1lisis en tiempo real durante <\/em><a href=\"https:\/\/etap.com\/solutions\/eots\"><em>la operaci\u00f3n<\/em><\/a><em>, son funciones vitales para mantener la confiabilidad de la red y maximizar la eficiencia de las plantas renovables\u201d<\/em> a\u00f1ade Alexander.<\/p>\n<p>Los modelos integrados en el software, permite el dise\u00f1o y simulaci\u00f3n de Recursos El\u00e9ctricos Distribuidos \u201cDERS\u201d, como <a href=\"https:\/\/etap.com\/product\/photovoltaic-array-solar-panel\">plantas de generaci\u00f3n solar<\/a> y <a href=\"https:\/\/etap.com\/product\/wind-turbine-generator-software\">e\u00f3licas<\/a>; <a href=\"https:\/\/etap.com\/solutions\/microgrid\">micro-redes<\/a>, sistemas de almacenamiento de energ\u00eda en bater\u00edas \u201c<a href=\"https:\/\/etap.com\/product\/battery-energy-storage-systems\">BESS<\/a>\u201d, y estaciones de carga para <a href=\"https:\/\/etap.com\/product\/quasi-dynamic-analysis\">Veh\u00edculos El\u00e9ctricos<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>Cabe resaltar que el 80% de los ingenieros que trabajan en ETAP son <a href=\"https:\/\/etap.com\/services\/research-development-services\">investigadores de desarrollo<\/a>, quienes buscan traer al mercado, nuevos productos de software que permitan acelerar la digitalizaci\u00f3n y transici\u00f3n energ\u00e9tica asistidos por modelos de ML e Inteligencia Artificial.<\/p>\n<p><strong>\u00bfCu\u00e1les son los desaf\u00edos que deben enfrentar los proyectos de energ\u00edas renovables?<\/strong><\/p>\n<p>Ante dicho contexto, uno de los principales retos que surgen con relaci\u00f3n al desarrollo de los proyectos de renovables en el pa\u00eds, es la <strong>intermitencia del recurso<\/strong> tanto solar como e\u00f3lica, que en grandes cantidades pueden introducir inestabilidades en sistema interconectado. ETAP permite hacer estudios para verificar cu\u00e1les son las condiciones operativas que las plantas renovables deben cumplir y poder garantizar dicha estabilidad.<\/p>\n<p><em>\u201cSi aumenta la penetraci\u00f3n de fuentes renovables y de los sistemas de almacenamiento, manteniendo la estabilidad de la red, es posible alcanzar las metas de descarbonizaci\u00f3n. El estudio el\u00e9ctrico de estabilidad estacionar\u00eda y din\u00e1mica validados en ETAP, permiten a los administradores del sistema de transmisi\u00f3n, encontrar los l\u00edmites en donde los renovables interfieren con el sistema, y por consiguiente planear cuidadosamente su expansi\u00f3n\u201d<\/em> concluye Alexander<\/p>\n<p><strong>\u00bfCu\u00e1l es la oferta de valor para las empresas de desarrollo e ingenier\u00eda<\/strong><\/p>\n<p>ETAP centra su oferta de valor en tres principios: <strong>Dise\u00f1o con conocimiento de operaci\u00f3n, Operar con conocimiento de dise\u00f1o, y Prevenir la interrupci\u00f3n del sistema garantizando la seguridad de personas y activos, <\/strong>adem\u00e1s permite alcanzar ahorros en costos derivados de reprocesos durante la fase de dise\u00f1o del sistema, tiempos muertos durante la validaci\u00f3n antes y durante la construcci\u00f3n.<\/p>\n<p>Finalmente, el equipo de dise\u00f1o de ETAP entiende la importancia de las operaciones de misi\u00f3n cr\u00edtica del cliente y la dedicaci\u00f3n para implementar soluciones de ingenier\u00eda inteligentes para construir, expandir, cambiar, mejorar y hacer que sus instalaciones de producci\u00f3n sean m\u00e1s seguras con las \u00faltimas herramientas y tecnolog\u00edas. Los clientes de todo el mundo utilizan ETAP para operar de manera m\u00e1s eficiente, confiable y econ\u00f3mica en una amplia gama de sectores e industrias: Universidades, Redes de Distribuci\u00f3n, Redes de Transmisi\u00f3n y Telecomunicaciones, Plantas de Energ\u00eda Renovable, Centros de Datos, Instalaciones de Manufactura, Salud, entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA | COLOMBIA La red el\u00e9ctrica es una de las m\u00e1quinas m\u00e1s complejas creada por la humanidad, ya que sin esta no existir\u00eda la civilizaci\u00f3n como la conocemos hoy. ETAP, un programa desarrollado en&#46;&#46;&#46;<\/p>\n","protected":false},"author":135,"featured_media":10492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[158],"tags":[],"class_list":["post-10491","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-ambiental","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ETAP: El software que est\u00e1 transformando las industrias renovables - Colombia | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ETAP: El software que est\u00e1 transformando las industrias renovables\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA | COLOMBIA La red el\u00e9ctrica es una de las m\u00e1quinas m\u00e1s complejas creada por la humanidad, ya que sin esta no existir\u00eda la civilizaci\u00f3n como la conocemos hoy. ETAP, un programa desarrollado en&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/\" \/>\n<meta property=\"og:site_name\" content=\"Colombia | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-14T18:10:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/06\/RENOVABLES.png\" \/>\n\t<meta property=\"og:image:width\" content=\"727\" \/>\n\t<meta property=\"og:image:height\" content=\"489\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mlenis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:site\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mlenis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/\"},\"author\":{\"name\":\"mlenis\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007\"},\"headline\":\"ETAP: El software que est\u00e1 transformando las industrias renovables\",\"datePublished\":\"2023-06-14T18:10:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/\"},\"wordCount\":931,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/06\/RENOVABLES.png\",\"articleSection\":[\"Ambiental\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/\",\"name\":\"ETAP: El software que est\u00e1 transformando las industrias renovables - Colombia | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/06\/RENOVABLES.png\",\"datePublished\":\"2023-06-14T18:10:09+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/06\/RENOVABLES.png\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/06\/RENOVABLES.png\",\"width\":727,\"height\":489},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ETAP: El software que est\u00e1 transformando las industrias renovables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/\",\"name\":\"Colombia | Noti-America.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007\",\"name\":\"mlenis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"caption\":\"mlenis\"},\"url\":\"https:\/\/noti-america.com\/site\/colombia\/author\/mlenis\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ETAP: El software que est\u00e1 transformando las industrias renovables - Colombia | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/","og_locale":"es_ES","og_type":"article","og_title":"ETAP: El software que est\u00e1 transformando las industrias renovables","og_description":"NOTI-AMERICA | COLOMBIA La red el\u00e9ctrica es una de las m\u00e1quinas m\u00e1s complejas creada por la humanidad, ya que sin esta no existir\u00eda la civilizaci\u00f3n como la conocemos hoy. ETAP, un programa desarrollado en&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/","og_site_name":"Colombia | Noti-America.com","article_published_time":"2023-06-14T18:10:09+00:00","og_image":[{"width":727,"height":489,"url":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/06\/RENOVABLES.png","type":"image\/png"}],"author":"mlenis","twitter_card":"summary_large_image","twitter_creator":"@notiamerica","twitter_site":"@notiamerica","twitter_misc":{"Escrito por":"mlenis","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/"},"author":{"name":"mlenis","@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007"},"headline":"ETAP: El software que est\u00e1 transformando las industrias renovables","datePublished":"2023-06-14T18:10:09+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/"},"wordCount":931,"commentCount":0,"image":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/06\/RENOVABLES.png","articleSection":["Ambiental"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/","url":"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/","name":"ETAP: El software que est\u00e1 transformando las industrias renovables - Colombia | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/06\/RENOVABLES.png","datePublished":"2023-06-14T18:10:09+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#primaryimage","url":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/06\/RENOVABLES.png","contentUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/06\/RENOVABLES.png","width":727,"height":489},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/06\/14\/etap-el-software-que-esta-transformando-las-industrias-renovables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/colombia\/"},{"@type":"ListItem","position":2,"name":"ETAP: El software que est\u00e1 transformando las industrias renovables"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/colombia\/#website","url":"https:\/\/noti-america.com\/site\/colombia\/","name":"Colombia | Noti-America.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007","name":"mlenis","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","caption":"mlenis"},"url":"https:\/\/noti-america.com\/site\/colombia\/author\/mlenis\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/10491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/comments?post=10491"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/10491\/revisions"}],"predecessor-version":[{"id":10493,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/10491\/revisions\/10493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/media\/10492"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/media?parent=10491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/categories?post=10491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/tags?post=10491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}