{"id":10149,"date":"2023-04-27T22:41:05","date_gmt":"2023-04-27T22:41:05","guid":{"rendered":"https:\/\/noti-america.com\/site\/colombia\/?p=10149"},"modified":"2023-04-27T22:44:37","modified_gmt":"2023-04-27T22:44:37","slug":"asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/","title":{"rendered":"ASUS y su enfoque ecol\u00f3gico: Protegiendo nuestro entorno con pr\u00e1cticas responsables en un mundo tecnol\u00f3gico"},"content":{"rendered":"<p>NOTI-AMERICA.COM | COLOMBIA<\/p>\n<p>Consciente de la necesidad de promover un cambio significativo en el medio ambiente, <a href=\"https:\/\/www.asus.com\/co\/\">ASUS<\/a> incorpora en sus dispositivos tecnolog\u00edas y materiales que colocan el pilar de la sostenibilidad en cada decisi\u00f3n comercial, con objetivos medibles y significativos para garantizar un futuro incre\u00edble.<\/p>\n<p>La multinacional de origen Taiwan\u00e9s ha integrado pr\u00e1cticas de responsabilidad social corporativa en cada fase del ciclo de vida del producto, desde su fabricaci\u00f3n hasta el final del uso, reafirmando su compromiso con el medioambiente y la sociedad.<\/p>\n<p><strong>Tecnolog\u00eda y medio ambiente: <\/strong><\/p>\n<p>Seg\u00fan el Programa para el Medio Ambiente de las Naciones Unidas, se generan cerca de 50 millones de toneladas de desechos electr\u00f3nicos al a\u00f1o. Y la mayor\u00eda no pasan por un sistema de reciclaje \u00f3ptimo para el medio ambiente, lo que puede llegar a afectar la salud de los humanos.<\/p>\n<p>Frente a este panorama, ASUS mantiene su compromiso con la protecci\u00f3n del medio ambiente y la promoci\u00f3n de pr\u00e1cticas comerciales sostenibles. Como empresa l\u00edder en tecnolog\u00eda, reconocemos la responsabilidad para minimizar el impacto en el medio ambiente y contribuir a la conservaci\u00f3n del planeta.<\/p>\n<p>Nuestros hitos en sostenibilidad:<\/p>\n<ul>\n<li>M\u00e1s de 1500 toneladas de pl\u00e1sticos reciclados posconsumo (PCR) utilizados en nuestros productos desde 2017.<\/li>\n<li>M\u00e1s de 20.000 toneladas de papel reciclado utilizadas en nuestros productos en 2022.<\/li>\n<li>Servicio de reciclaje que cubre el 75% del mundo con m\u00e1s de 40,000 toneladas de desechos electr\u00f3nicos reciclados desde 2019.<\/li>\n<li>M\u00e1s de 20 000 computadoras donadas a m\u00e1s de 1800 organizaciones sin fines de lucro desde 2008.<\/li>\n<\/ul>\n<p>Conoce c\u00f3mo puedes apoyar un mundo m\u00e1s sostenible a trav\u00e9s de la tecnolog\u00eda y soluciones de ASUS:<\/p>\n<ul>\n<li><strong>Port\u00e1tiles eco-amigables<\/strong><\/li>\n<\/ul>\n<p>Las mejores opciones para amar la Tierra, dispositivos construidos y empaquetados con materiales sostenibles y con las mejores certificaciones ecol\u00f3gicas, colocando un aporte a la protecci\u00f3n de la Tierra con las mejores tecnolog\u00edas.<\/p>\n<p>Recientemente, ASUS present\u00f3 en el mercado la nueva <a href=\"https:\/\/www.asus.com\/co\/laptops\/for-home\/zenbook\/asus-zenbook-s-13-oled-ux5304\/\">Zenbook S 13 OLED<\/a>, su nuevo port\u00e1til que pesa s\u00f3lo 1 KG y tiene un grosor de tan s\u00f3lo 1 cent\u00edmetro.<\/p>\n<p>Este es el dispositivo de la marca m\u00e1s ecol\u00f3gico jam\u00e1s fabricado, el cual incorpora aleaci\u00f3n de magnesio-aluminio reciclado post uso industrial (PIR) en la cubierta del teclado, chasis y tapa, reduciendo su huella de carbono en m\u00e1s del 50%. Las teclas y los altavoces incorporan pl\u00e1sticos reciclados posconsumo (PCR), y los altavoces tambi\u00e9n utilizan pl\u00e1sticos oce\u00e1nicos.<\/p>\n<p>Adem\u00e1s, ASUS ha utilizado primera vez un proceso de fabricaci\u00f3n especial para crear un material de aluminio cer\u00e1mico de plasma exclusivo para la tapa. Este proceso utiliza agua pura y electricidad, y no requiere compuestos org\u00e1nicos, \u00e1cidos fuertes o metales pesados. En cambio, este m\u00e9todo basado en un ba\u00f1o de bajo impacto ambiental produce una transformaci\u00f3n f\u00edsica y qu\u00edmica del aluminio. Esto da como resultado una mayor resistencia al desgaste, protecci\u00f3n contra la corrosi\u00f3n, gesti\u00f3n t\u00e9rmica, dureza y vida \u00fatil.<\/p>\n<p>Junto con las ventajas f\u00edsicas, la apariencia de este material es similar a la piedra natural que resuena con el esp\u00edritu de la serie Zenbook. Incre\u00edblemente, esto hace que cada tapa sea individualmente \u00fanica, no hay dos iguales. Una vida \u00fatil m\u00e1s larga de la computadora port\u00e1til tambi\u00e9n reduce el desperdicio a largo plazo, por lo que la <a href=\"https:\/\/www.asus.com\/co\/\">Zenbook 13 S OLED<\/a> se prueba rigurosamente utilizando el \u00faltimo est\u00e1ndar de durabilidad de grado militar MIL-STD-810H de EE. UU., con 12 m\u00e9todos de prueba y 26 pruebas individuales, es la laptop con la durabilidad m\u00e1s estrictamente probada del mundo.<\/p>\n<p><strong>Materiales y embalaje verde:<\/strong><\/p>\n<p>En ASUS utilizamos el pl\u00e1stico reciclado posconsumo y pl\u00e1stico procedente del oc\u00e9ano en la fabricaci\u00f3n de partes de sus equipos, as\u00ed como metal reciclado post-industrial en diversas partes de sus productos. Estas iniciativas demuestran la dedicaci\u00f3n de <a href=\"https:\/\/www.asus.com\/co\/\">ASUS<\/a> hacia la utilizaci\u00f3n de materiales reciclados y la promoci\u00f3n de pr\u00e1cticas eco amigables en su proceso de fabricaci\u00f3n, contribuyendo a la conservaci\u00f3n del medio ambiente y la promoci\u00f3n de la econom\u00eda circular.<\/p>\n<p>Como parte de nuestra acci\u00f3n sostenible, pensamos fuera de la caja en todos los aspectos de nuestro negocio, incluyendo el embalaje de nuestros productos. Utilizamos papel reciclado proveniente de fuentes de silvicultura responsable certificada FSC<sup>1<\/sup> en nuestros empaques, demostrando nuestro compromiso con la protecci\u00f3n del medio ambiente.<\/p>\n<p>Adem\u00e1s, buscamos constantemente formas innovadoras de transformar el embalaje en un stand, con el objetivo de reducir residuos y promover pr\u00e1cticas eco amigables. Creemos que el embalaje verde es una parte esencial de nuestro enfoque integral hacia la sostenibilidad y trabajamos continuamente en soluciones creativas y responsables para minimizar nuestro impacto ambiental en cada etapa de nuestros productos.<\/p>\n<ul>\n<li><strong>Eco-certificaciones:<\/strong><\/li>\n<\/ul>\n<p>Las ecoetiquetas son una herramienta eficaz para los consumidores conscientes que buscan productos responsables y con valores verdes comprobados. Estas etiquetas proporcionan informaci\u00f3n clara y transparente sobre el impacto ambiental de un producto, desde su producci\u00f3n hasta su disposici\u00f3n final. Al utilizar ecoetiquetas, los consumidores pueden tomar decisiones informadas, eligiendo productos que sean sostenibles, eco-amigables y que contribuyan a la protecci\u00f3n del medio ambiente. Las ecoetiquetas tambi\u00e9n fomentan la adopci\u00f3n de pr\u00e1cticas empresariales responsables, promoviendo la adopci\u00f3n de est\u00e1ndares ecol\u00f3gicos en la producci\u00f3n de bienes y servicios.<\/p>\n<ul>\n<li><strong>EPEAT\u00ae<\/strong> es una etiqueta ecol\u00f3gica l\u00edder mundial que cubre productos y servicios tecnol\u00f3gicos. Los productos registrados en EPEAT \u00ae tienen un impacto ambiental y social positivo a lo largo de todo el ciclo de vida del producto, desde la extracci\u00f3n de recursos y la fabricaci\u00f3n hasta el ensamblaje, el uso y el final de la vida \u00fatil.<\/li>\n<li><strong>ENERGY STAR\u00ae<\/strong> es un certificado mundialmente reconocido de eficiencia energ\u00e9tica. Los productos que obtienen ENERGY STAR \u00ae evitan las emisiones de gases de efecto invernadero al cumplir con los estrictos requisitos de eficiencia energ\u00e9tica establecidos por la Agencia de Protecci\u00f3n Ambiental de EE. UU.<\/li>\n<li><strong>RoHS<\/strong> es una regulaci\u00f3n global que protege el medio ambiente y la salud p\u00fablica, restringiendo las sustancias peligrosas en los productos.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA.COM | COLOMBIA Consciente de la necesidad de promover un cambio significativo en el medio ambiente, ASUS incorpora en sus dispositivos tecnolog\u00edas y materiales que colocan el pilar de la sostenibilidad en cada decisi\u00f3n&#46;&#46;&#46;<\/p>\n","protected":false},"author":135,"featured_media":10150,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[158],"tags":[],"class_list":["post-10149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiental"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ASUS y su enfoque ecol\u00f3gico: Protegiendo nuestro entorno con pr\u00e1cticas responsables en un mundo tecnol\u00f3gico - Colombia | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASUS y su enfoque ecol\u00f3gico: Protegiendo nuestro entorno con pr\u00e1cticas responsables en un mundo tecnol\u00f3gico\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA.COM | COLOMBIA Consciente de la necesidad de promover un cambio significativo en el medio ambiente, ASUS incorpora en sus dispositivos tecnolog\u00edas y materiales que colocan el pilar de la sostenibilidad en cada decisi\u00f3n&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/\" \/>\n<meta property=\"og:site_name\" content=\"Colombia | Noti-America.com\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-27T22:41:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-27T22:44:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/04\/asus-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"736\" \/>\n\t<meta property=\"og:image:height\" content=\"498\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mlenis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:site\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mlenis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/\"},\"author\":{\"name\":\"mlenis\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007\"},\"headline\":\"ASUS y su enfoque ecol\u00f3gico: Protegiendo nuestro entorno con pr\u00e1cticas responsables en un mundo tecnol\u00f3gico\",\"datePublished\":\"2023-04-27T22:41:05+00:00\",\"dateModified\":\"2023-04-27T22:44:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/\"},\"wordCount\":1057,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/04\/asus-2.jpg\",\"articleSection\":[\"Ambiental\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/\",\"name\":\"ASUS y su enfoque ecol\u00f3gico: Protegiendo nuestro entorno con pr\u00e1cticas responsables en un mundo tecnol\u00f3gico - Colombia | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/04\/asus-2.jpg\",\"datePublished\":\"2023-04-27T22:41:05+00:00\",\"dateModified\":\"2023-04-27T22:44:37+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/04\/asus-2.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/04\/asus-2.jpg\",\"width\":736,\"height\":498},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASUS y su enfoque ecol\u00f3gico: Protegiendo nuestro entorno con pr\u00e1cticas responsables en un mundo tecnol\u00f3gico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/colombia\/\",\"name\":\"Colombia | Noti-America.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007\",\"name\":\"mlenis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g\",\"caption\":\"mlenis\"},\"url\":\"https:\/\/noti-america.com\/site\/colombia\/author\/mlenis\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ASUS y su enfoque ecol\u00f3gico: Protegiendo nuestro entorno con pr\u00e1cticas responsables en un mundo tecnol\u00f3gico - Colombia | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/","og_locale":"es_ES","og_type":"article","og_title":"ASUS y su enfoque ecol\u00f3gico: Protegiendo nuestro entorno con pr\u00e1cticas responsables en un mundo tecnol\u00f3gico","og_description":"NOTI-AMERICA.COM | COLOMBIA Consciente de la necesidad de promover un cambio significativo en el medio ambiente, ASUS incorpora en sus dispositivos tecnolog\u00edas y materiales que colocan el pilar de la sostenibilidad en cada decisi\u00f3n&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/","og_site_name":"Colombia | Noti-America.com","article_published_time":"2023-04-27T22:41:05+00:00","article_modified_time":"2023-04-27T22:44:37+00:00","og_image":[{"width":736,"height":498,"url":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/04\/asus-2.jpg","type":"image\/jpeg"}],"author":"mlenis","twitter_card":"summary_large_image","twitter_creator":"@notiamerica","twitter_site":"@notiamerica","twitter_misc":{"Escrito por":"mlenis","Tiempo estimado de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/"},"author":{"name":"mlenis","@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007"},"headline":"ASUS y su enfoque ecol\u00f3gico: Protegiendo nuestro entorno con pr\u00e1cticas responsables en un mundo tecnol\u00f3gico","datePublished":"2023-04-27T22:41:05+00:00","dateModified":"2023-04-27T22:44:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/"},"wordCount":1057,"commentCount":0,"image":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/04\/asus-2.jpg","articleSection":["Ambiental"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/","url":"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/","name":"ASUS y su enfoque ecol\u00f3gico: Protegiendo nuestro entorno con pr\u00e1cticas responsables en un mundo tecnol\u00f3gico - Colombia | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/04\/asus-2.jpg","datePublished":"2023-04-27T22:41:05+00:00","dateModified":"2023-04-27T22:44:37+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#primaryimage","url":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/04\/asus-2.jpg","contentUrl":"https:\/\/noti-america.com\/site\/colombia\/wp-content\/uploads\/sites\/20\/2023\/04\/asus-2.jpg","width":736,"height":498},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/colombia\/2023\/04\/27\/asus-y-su-enfoque-ecologico-protegiendo-nuestro-entorno-con-practicas-responsables-en-un-mundo-tecnologico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/colombia\/"},{"@type":"ListItem","position":2,"name":"ASUS y su enfoque ecol\u00f3gico: Protegiendo nuestro entorno con pr\u00e1cticas responsables en un mundo tecnol\u00f3gico"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/colombia\/#website","url":"https:\/\/noti-america.com\/site\/colombia\/","name":"Colombia | Noti-America.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/colombia\/#\/schema\/person\/617d081e872b6429a5894295ffd0b007","name":"mlenis","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71bbe7129a082888d49bedca63e7a6e75ca485c648bb239a7515a2a55acd510f?s=96&d=mm&r=g","caption":"mlenis"},"url":"https:\/\/noti-america.com\/site\/colombia\/author\/mlenis\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/10149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/comments?post=10149"}],"version-history":[{"count":1,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/10149\/revisions"}],"predecessor-version":[{"id":10151,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/posts\/10149\/revisions\/10151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/media\/10150"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/media?parent=10149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/categories?post=10149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/colombia\/wp-json\/wp\/v2\/tags?post=10149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}