{"id":7368,"date":"2024-06-06T11:57:09","date_gmt":"2024-06-06T14:57:09","guid":{"rendered":"https:\/\/noti-america.com\/site\/argentina\/?p=7368"},"modified":"2024-06-06T11:57:56","modified_gmt":"2024-06-06T14:57:56","slug":"realizan-marcha-contra-la-violencia-de-genero-en-argentinag","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/","title":{"rendered":"Realizan marcha contra la violencia de g\u00e9nero en Argentina"},"content":{"rendered":"<p><strong>NOTI-AMERICA.COM | ARGENTINA<\/strong><\/p>\n<p style=\"text-align: justify\">Bajo la consigna \u00abNi una menos\u00bb, miles de argentinas marcharon este lunes frente al Congreso Nacional para denunciar las pol\u00edticas gubernamentales del presidente Javier Milei que atentan contra los derechos de las mujeres en el pa\u00eds suramericano, as\u00ed como en rechazo a las pol\u00edticas de femicidio.<\/p>\n<p style=\"text-align: justify\">La manifestaci\u00f3n tambi\u00e9n rechaza la violencia econ\u00f3mica, se opone a la Ley de Bases, los despidos del Estado y a los cr\u00edmenes de odio, como el perpetrado contra cuatro mujeres lesbianas en Barracas, en la capital federal, el pasado 5 de mayo.<\/p>\n<p style=\"text-align: justify\">El hecho ocurri\u00f3 cuando un hombre nombrado Justo Fernando Barrientos arroj\u00f3 un c\u00f3ctel molotov contra la habitaci\u00f3n de un hotel donde se encontraban. El agresor bloque\u00f3 la puerta de la habitaci\u00f3n para que no pudieran salir. Tres de las mujeres murieron como consecuencia de las quemaduras.<\/p>\n<p style=\"text-align: justify\">\u201cRepudiamos al Gobierno que hace de la crueldad una pol\u00edtica de Estado y promueve abiertamente los discursos de odio\u201d,\u00a0indicaron las participantes en la convocatoria.<\/p>\n<p style=\"text-align: justify\">Consignas como \u00abAbajo el decreto de necesidad y urgencia\u00bb y \u00abNo a la Ley de Bases\u00bb pudieron escucharse a lo largo de la marcha, que fue convocada de forma masiva y en unidad por el movimiento Ni Una Menos.<\/p>\n<p style=\"text-align: justify\">El evento no s\u00f3lo ocurri\u00f3 en Buenos Aires (capital), sino en la mayor\u00eda de las ciudades argentinas en conmemoraci\u00f3n de la movilizaci\u00f3n que tuvo lugar en 2015 en 80 ciudades de la Argentina, que marc\u00f3 un antes y despu\u00e9s en la lucha feminista contra la violencia de g\u00e9nero.<\/p>\n<p style=\"text-align: justify\">Recientemente, el Informe\u00a0Nacional de Femicidios indic\u00f3 que desde el 3 de junio de 2015 al 30 de mayo de 2024, se han registrado en Argentina 2.348, lo que equivale a un femicidio de mujeres, lesbianas, travestis y personas transg\u00e9nero cada 33 horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTI-AMERICA.COM | ARGENTINA Bajo la consigna \u00abNi una menos\u00bb, miles de argentinas marcharon este lunes frente al Congreso Nacional para denunciar las pol\u00edticas gubernamentales del presidente Javier Milei que atentan contra los derechos de&#46;&#46;&#46;<\/p>\n","protected":false},"author":133,"featured_media":7369,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_242054905_242054905":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[287],"tags":[],"class_list":["post-7368","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-actualidad","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Realizan marcha contra la violencia de g\u00e9nero en Argentina - Argentina | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Realizan marcha contra la violencia de g\u00e9nero en Argentina\" \/>\n<meta property=\"og:description\" content=\"NOTI-AMERICA.COM | ARGENTINA Bajo la consigna \u00abNi una menos\u00bb, miles de argentinas marcharon este lunes frente al Congreso Nacional para denunciar las pol\u00edticas gubernamentales del presidente Javier Milei que atentan contra los derechos de&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/\" \/>\n<meta property=\"og:site_name\" content=\"Argentina | Noti-America.com\" \/>\n<meta property=\"article:author\" content=\"Mar\u00eda Valentina Noguera\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-06T14:57:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-06T14:57:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/argentina\/wp-content\/uploads\/sites\/24\/2024\/06\/8-millones-mujeres-huelga_23-2151400523.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"740\" \/>\n\t<meta property=\"og:image:height\" content=\"493\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maria Valentina Noguera Medina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@inotiamerica\" \/>\n<meta name=\"twitter:site\" content=\"@inotiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Valentina Noguera Medina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/\"},\"author\":{\"name\":\"Maria Valentina Noguera Medina\",\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/#\/schema\/person\/22806efcc2cfc4b45efb0e17be210ea8\"},\"headline\":\"Realizan marcha contra la violencia de g\u00e9nero en Argentina\",\"datePublished\":\"2024-06-06T14:57:09+00:00\",\"dateModified\":\"2024-06-06T14:57:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/\"},\"wordCount\":311,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/#organization\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/argentina\/wp-content\/uploads\/sites\/24\/2024\/06\/8-millones-mujeres-huelga_23-2151400523.jpg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/\",\"url\":\"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/\",\"name\":\"Realizan marcha contra la violencia de g\u00e9nero en Argentina - Argentina | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/argentina\/wp-content\/uploads\/sites\/24\/2024\/06\/8-millones-mujeres-huelga_23-2151400523.jpg\",\"datePublished\":\"2024-06-06T14:57:09+00:00\",\"dateModified\":\"2024-06-06T14:57:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/argentina\/wp-content\/uploads\/sites\/24\/2024\/06\/8-millones-mujeres-huelga_23-2151400523.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/argentina\/wp-content\/uploads\/sites\/24\/2024\/06\/8-millones-mujeres-huelga_23-2151400523.jpg\",\"width\":740,\"height\":493},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/argentina\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Realizan marcha contra la violencia de g\u00e9nero en Argentina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/argentina\/\",\"name\":\"Argentina | Noti-America.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/argentina\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/#organization\",\"name\":\"Noti-America LLC | Argentina\",\"url\":\"https:\/\/noti-america.com\/site\/argentina\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noti-america.com\/site\/argentina\/wp-content\/uploads\/sites\/24\/2020\/07\/LogoNA-4x3-1.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/argentina\/wp-content\/uploads\/sites\/24\/2020\/07\/LogoNA-4x3-1.jpg\",\"width\":1236,\"height\":1080,\"caption\":\"Noti-America LLC | Argentina\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/inotiamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/argentina\/#\/schema\/person\/22806efcc2cfc4b45efb0e17be210ea8\",\"name\":\"Maria Valentina Noguera Medina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g\",\"caption\":\"Maria Valentina Noguera Medina\"},\"description\":\"Periodista - noti-america - Promar Community Manager - Talento Plus Dise\u00f1adora\/ creadora de contenido...\",\"sameAs\":[\"Mar\u00eda Valentina Noguera\",\"https:\/\/www.facebook.com\/mariavalentina.noguera\",\"https:\/\/www.linkedin.com\/in\/mara-valentina-noguera-medina-373075165\/\",\"https:\/\/www.pinterest.es\/valentinanoguera95\/\",\"https:\/\/www.youtube.com\/channel\/UCdek6mbUZ-Tqqw0I63i4nmQ\"],\"url\":\"https:\/\/noti-america.com\/site\/argentina\/author\/mnoguera\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Realizan marcha contra la violencia de g\u00e9nero en Argentina - Argentina | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/","og_locale":"es_ES","og_type":"article","og_title":"Realizan marcha contra la violencia de g\u00e9nero en Argentina","og_description":"NOTI-AMERICA.COM | ARGENTINA Bajo la consigna \u00abNi una menos\u00bb, miles de argentinas marcharon este lunes frente al Congreso Nacional para denunciar las pol\u00edticas gubernamentales del presidente Javier Milei que atentan contra los derechos de&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/","og_site_name":"Argentina | Noti-America.com","article_author":"Mar\u00eda Valentina Noguera","article_published_time":"2024-06-06T14:57:09+00:00","article_modified_time":"2024-06-06T14:57:56+00:00","og_image":[{"width":740,"height":493,"url":"https:\/\/noti-america.com\/site\/argentina\/wp-content\/uploads\/sites\/24\/2024\/06\/8-millones-mujeres-huelga_23-2151400523.jpg","type":"image\/jpeg"}],"author":"Maria Valentina Noguera Medina","twitter_card":"summary_large_image","twitter_creator":"@inotiamerica","twitter_site":"@inotiamerica","twitter_misc":{"Escrito por":"Maria Valentina Noguera Medina","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/"},"author":{"name":"Maria Valentina Noguera Medina","@id":"https:\/\/noti-america.com\/site\/argentina\/#\/schema\/person\/22806efcc2cfc4b45efb0e17be210ea8"},"headline":"Realizan marcha contra la violencia de g\u00e9nero en Argentina","datePublished":"2024-06-06T14:57:09+00:00","dateModified":"2024-06-06T14:57:56+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/"},"wordCount":311,"commentCount":0,"publisher":{"@id":"https:\/\/noti-america.com\/site\/argentina\/#organization"},"image":{"@id":"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/argentina\/wp-content\/uploads\/sites\/24\/2024\/06\/8-millones-mujeres-huelga_23-2151400523.jpg","articleSection":["Actualidad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/","url":"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/","name":"Realizan marcha contra la violencia de g\u00e9nero en Argentina - Argentina | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/argentina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/argentina\/wp-content\/uploads\/sites\/24\/2024\/06\/8-millones-mujeres-huelga_23-2151400523.jpg","datePublished":"2024-06-06T14:57:09+00:00","dateModified":"2024-06-06T14:57:56+00:00","breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#primaryimage","url":"https:\/\/noti-america.com\/site\/argentina\/wp-content\/uploads\/sites\/24\/2024\/06\/8-millones-mujeres-huelga_23-2151400523.jpg","contentUrl":"https:\/\/noti-america.com\/site\/argentina\/wp-content\/uploads\/sites\/24\/2024\/06\/8-millones-mujeres-huelga_23-2151400523.jpg","width":740,"height":493},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/argentina\/2024\/06\/06\/realizan-marcha-contra-la-violencia-de-genero-en-argentinag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/argentina\/"},{"@type":"ListItem","position":2,"name":"Realizan marcha contra la violencia de g\u00e9nero en Argentina"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/argentina\/#website","url":"https:\/\/noti-america.com\/site\/argentina\/","name":"Argentina | Noti-America.com","description":"","publisher":{"@id":"https:\/\/noti-america.com\/site\/argentina\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/argentina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noti-america.com\/site\/argentina\/#organization","name":"Noti-America LLC | Argentina","url":"https:\/\/noti-america.com\/site\/argentina\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/argentina\/#\/schema\/logo\/image\/","url":"https:\/\/noti-america.com\/site\/argentina\/wp-content\/uploads\/sites\/24\/2020\/07\/LogoNA-4x3-1.jpg","contentUrl":"https:\/\/noti-america.com\/site\/argentina\/wp-content\/uploads\/sites\/24\/2020\/07\/LogoNA-4x3-1.jpg","width":1236,"height":1080,"caption":"Noti-America LLC | Argentina"},"image":{"@id":"https:\/\/noti-america.com\/site\/argentina\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/inotiamerica"]},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/argentina\/#\/schema\/person\/22806efcc2cfc4b45efb0e17be210ea8","name":"Maria Valentina Noguera Medina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ec5eb9d099f2608a49c9df6f7341f66f04f819cdffa09d56a7a0e91d2819d56?s=96&d=mm&r=g","caption":"Maria Valentina Noguera Medina"},"description":"Periodista - noti-america - Promar Community Manager - Talento Plus Dise\u00f1adora\/ creadora de contenido...","sameAs":["Mar\u00eda Valentina Noguera","https:\/\/www.facebook.com\/mariavalentina.noguera","https:\/\/www.linkedin.com\/in\/mara-valentina-noguera-medina-373075165\/","https:\/\/www.pinterest.es\/valentinanoguera95\/","https:\/\/www.youtube.com\/channel\/UCdek6mbUZ-Tqqw0I63i4nmQ"],"url":"https:\/\/noti-america.com\/site\/argentina\/author\/mnoguera\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/argentina\/wp-json\/wp\/v2\/posts\/7368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/argentina\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/argentina\/wp-json\/wp\/v2\/comments?post=7368"}],"version-history":[{"count":2,"href":"https:\/\/noti-america.com\/site\/argentina\/wp-json\/wp\/v2\/posts\/7368\/revisions"}],"predecessor-version":[{"id":7371,"href":"https:\/\/noti-america.com\/site\/argentina\/wp-json\/wp\/v2\/posts\/7368\/revisions\/7371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/argentina\/wp-json\/wp\/v2\/media\/7369"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/argentina\/wp-json\/wp\/v2\/media?parent=7368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/argentina\/wp-json\/wp\/v2\/categories?post=7368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/argentina\/wp-json\/wp\/v2\/tags?post=7368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}