{"id":2281,"date":"2022-05-03T13:59:06","date_gmt":"2022-05-03T13:59:06","guid":{"rendered":"https:\/\/noti-america.com\/site\/uk\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/"},"modified":"2022-05-03T13:59:06","modified_gmt":"2022-05-03T13:59:06","slug":"cristiano-ronaldo-se-despidio-del-publico-de-old-trafford","status":"publish","type":"post","link":"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/","title":{"rendered":"Cristiano Ronaldo se despidi\u00f3 del p\u00fablico de Old Trafford"},"content":{"rendered":"<p style=\"text-align: justify\">El Manchester United venci\u00f3 3-0 al Brentford en lo que fue el \u00faltimo partido de la temporada para los Diablos Rojos en Old Trafford.<\/p>\n<p style=\"text-align: justify\">Bruno Fernandez, Cristiano Ronaldo y Varane marcaron los goles para los locales, que pese a la victoria se ubican 6tos en la tabla con 58 puntos.<\/p>\n<p style=\"text-align: justify\">Con 2 partidos por jugarse de Premier League parece casi imposible que se clasifiquen a Champions, teniendo al Arsenal a 5 puntos por encima y estos con 2 partidos menos todav\u00eda.<\/p>\n<p style=\"text-align: justify\">Al portugu\u00e9s luego del pitado final se le not\u00f3 muy cari\u00f1oso con la grada,\u00a0 mientras caminada por el terreno de juego, las c\u00e1maras captaron a un Cristiano emotivo con signos de despedida.<\/p>\n<p style=\"text-align: justify\">Se habla de la llegada de CR7 al PSG o al Bayern M\u00fanich. Lo que si es seguro es que tendremos un mercado de fichajes muy movido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Manchester United venci\u00f3 3-0 al Brentford en lo que fue el \u00faltimo partido de la temporada para los Diablos Rojos en Old Trafford. Bruno Fernandez, Cristiano Ronaldo y Varane marcaron los goles para&#46;&#46;&#46;<\/p>\n","protected":false},"author":4,"featured_media":2282,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[16,177],"tags":[],"class_list":["post-2281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-deportes-futbol-internacional"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cristiano Ronaldo se despidi\u00f3 del p\u00fablico de Old Trafford - Alemania | Noti-America.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cristiano Ronaldo se despidi\u00f3 del p\u00fablico de Old Trafford\" \/>\n<meta property=\"og:description\" content=\"El Manchester United venci\u00f3 3-0 al Brentford en lo que fue el \u00faltimo partido de la temporada para los Diablos Rojos en Old Trafford. Bruno Fernandez, Cristiano Ronaldo y Varane marcaron los goles para&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/\" \/>\n<meta property=\"og:site_name\" content=\"Alemania | Noti-America.com\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/AndresSalazarTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-03T13:59:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noti-america.com\/site\/alemania\/wp-content\/uploads\/sites\/29\/2022\/05\/182118_1253773.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"439\" \/>\n\t<meta property=\"og:image:height\" content=\"246\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andr\u00e9s Salazar TV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:site\" content=\"@notiamerica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andr\u00e9s Salazar TV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/\"},\"author\":{\"name\":\"Andr\u00e9s Salazar TV\",\"@id\":\"https:\/\/noti-america.com\/site\/alemania\/#\/schema\/person\/5536bbfd0e2b9220dabb68be6a79e6a2\"},\"headline\":\"Cristiano Ronaldo se despidi\u00f3 del p\u00fablico de Old Trafford\",\"datePublished\":\"2022-05-03T13:59:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/\"},\"wordCount\":151,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/alemania\/wp-content\/uploads\/sites\/29\/2022\/05\/182118_1253773.jpg\",\"articleSection\":[\"Deportes\",\"F\u00fatbol Internacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/\",\"url\":\"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/\",\"name\":\"Cristiano Ronaldo se despidi\u00f3 del p\u00fablico de Old Trafford - Alemania | Noti-America.com\",\"isPartOf\":{\"@id\":\"https:\/\/noti-america.com\/site\/alemania\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noti-america.com\/site\/alemania\/wp-content\/uploads\/sites\/29\/2022\/05\/182118_1253773.jpg\",\"datePublished\":\"2022-05-03T13:59:06+00:00\",\"author\":{\"@id\":\"https:\/\/noti-america.com\/site\/alemania\/#\/schema\/person\/5536bbfd0e2b9220dabb68be6a79e6a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#primaryimage\",\"url\":\"https:\/\/noti-america.com\/site\/alemania\/wp-content\/uploads\/sites\/29\/2022\/05\/182118_1253773.jpg\",\"contentUrl\":\"https:\/\/noti-america.com\/site\/alemania\/wp-content\/uploads\/sites\/29\/2022\/05\/182118_1253773.jpg\",\"width\":439,\"height\":246},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/noti-america.com\/site\/alemania\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cristiano Ronaldo se despidi\u00f3 del p\u00fablico de Old Trafford\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noti-america.com\/site\/alemania\/#website\",\"url\":\"https:\/\/noti-america.com\/site\/alemania\/\",\"name\":\"Alemania | Noti-America.com\",\"description\":\"Alemania | Noti-America.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noti-america.com\/site\/alemania\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/noti-america.com\/site\/alemania\/#\/schema\/person\/5536bbfd0e2b9220dabb68be6a79e6a2\",\"name\":\"Andr\u00e9s Salazar TV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/afe6826ba750395b641021d9bf08e5496b9d29671cfabb16346350901fb94310?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/afe6826ba750395b641021d9bf08e5496b9d29671cfabb16346350901fb94310?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/afe6826ba750395b641021d9bf08e5496b9d29671cfabb16346350901fb94310?s=96&d=mm&r=g\",\"caption\":\"Andr\u00e9s Salazar TV\"},\"description\":\"Andr\u00e9s Salazar. Corresponsal de Noti-Am\u00e9rica en Venezuela. Periodista con m\u00e1s de 14 a\u00f1os de trayectoria en la cobertura de hechos informativos. Amplia experiencia en la narrativa de eventos deportivos, musicales y sucesos de \u00faltima hora.\",\"sameAs\":[\"https:\/\/www.facebook.com\/AndresSalazarTV\/\",\"https:\/\/youtube.com\/@andressalazartv?si=fYrt2l__ee2OK_Fh\"],\"url\":\"https:\/\/noti-america.com\/site\/alemania\/author\/asalazar\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cristiano Ronaldo se despidi\u00f3 del p\u00fablico de Old Trafford - Alemania | Noti-America.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/","og_locale":"es_ES","og_type":"article","og_title":"Cristiano Ronaldo se despidi\u00f3 del p\u00fablico de Old Trafford","og_description":"El Manchester United venci\u00f3 3-0 al Brentford en lo que fue el \u00faltimo partido de la temporada para los Diablos Rojos en Old Trafford. Bruno Fernandez, Cristiano Ronaldo y Varane marcaron los goles para&#46;&#46;&#46;","og_url":"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/","og_site_name":"Alemania | Noti-America.com","article_author":"https:\/\/www.facebook.com\/AndresSalazarTV\/","article_published_time":"2022-05-03T13:59:06+00:00","og_image":[{"width":439,"height":246,"url":"https:\/\/noti-america.com\/site\/alemania\/wp-content\/uploads\/sites\/29\/2022\/05\/182118_1253773.jpg","type":"image\/jpeg"}],"author":"Andr\u00e9s Salazar TV","twitter_card":"summary_large_image","twitter_creator":"@notiamerica","twitter_site":"@notiamerica","twitter_misc":{"Escrito por":"Andr\u00e9s Salazar TV","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#article","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/"},"author":{"name":"Andr\u00e9s Salazar TV","@id":"https:\/\/noti-america.com\/site\/alemania\/#\/schema\/person\/5536bbfd0e2b9220dabb68be6a79e6a2"},"headline":"Cristiano Ronaldo se despidi\u00f3 del p\u00fablico de Old Trafford","datePublished":"2022-05-03T13:59:06+00:00","mainEntityOfPage":{"@id":"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/"},"wordCount":151,"commentCount":0,"image":{"@id":"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/alemania\/wp-content\/uploads\/sites\/29\/2022\/05\/182118_1253773.jpg","articleSection":["Deportes","F\u00fatbol Internacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/","url":"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/","name":"Cristiano Ronaldo se despidi\u00f3 del p\u00fablico de Old Trafford - Alemania | Noti-America.com","isPartOf":{"@id":"https:\/\/noti-america.com\/site\/alemania\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#primaryimage"},"image":{"@id":"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#primaryimage"},"thumbnailUrl":"https:\/\/noti-america.com\/site\/alemania\/wp-content\/uploads\/sites\/29\/2022\/05\/182118_1253773.jpg","datePublished":"2022-05-03T13:59:06+00:00","author":{"@id":"https:\/\/noti-america.com\/site\/alemania\/#\/schema\/person\/5536bbfd0e2b9220dabb68be6a79e6a2"},"breadcrumb":{"@id":"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#primaryimage","url":"https:\/\/noti-america.com\/site\/alemania\/wp-content\/uploads\/sites\/29\/2022\/05\/182118_1253773.jpg","contentUrl":"https:\/\/noti-america.com\/site\/alemania\/wp-content\/uploads\/sites\/29\/2022\/05\/182118_1253773.jpg","width":439,"height":246},{"@type":"BreadcrumbList","@id":"https:\/\/noti-america.com\/site\/alemania\/2022\/05\/03\/cristiano-ronaldo-se-despidio-del-publico-de-old-trafford\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noti-america.com\/site\/alemania\/"},{"@type":"ListItem","position":2,"name":"Cristiano Ronaldo se despidi\u00f3 del p\u00fablico de Old Trafford"}]},{"@type":"WebSite","@id":"https:\/\/noti-america.com\/site\/alemania\/#website","url":"https:\/\/noti-america.com\/site\/alemania\/","name":"Alemania | Noti-America.com","description":"Alemania | Noti-America.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noti-america.com\/site\/alemania\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noti-america.com\/site\/alemania\/#\/schema\/person\/5536bbfd0e2b9220dabb68be6a79e6a2","name":"Andr\u00e9s Salazar TV","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/afe6826ba750395b641021d9bf08e5496b9d29671cfabb16346350901fb94310?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/afe6826ba750395b641021d9bf08e5496b9d29671cfabb16346350901fb94310?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/afe6826ba750395b641021d9bf08e5496b9d29671cfabb16346350901fb94310?s=96&d=mm&r=g","caption":"Andr\u00e9s Salazar TV"},"description":"Andr\u00e9s Salazar. Corresponsal de Noti-Am\u00e9rica en Venezuela. Periodista con m\u00e1s de 14 a\u00f1os de trayectoria en la cobertura de hechos informativos. Amplia experiencia en la narrativa de eventos deportivos, musicales y sucesos de \u00faltima hora.","sameAs":["https:\/\/www.facebook.com\/AndresSalazarTV\/","https:\/\/youtube.com\/@andressalazartv?si=fYrt2l__ee2OK_Fh"],"url":"https:\/\/noti-america.com\/site\/alemania\/author\/asalazar\/"}]}},"_links":{"self":[{"href":"https:\/\/noti-america.com\/site\/alemania\/wp-json\/wp\/v2\/posts\/2281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noti-america.com\/site\/alemania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noti-america.com\/site\/alemania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/alemania\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/alemania\/wp-json\/wp\/v2\/comments?post=2281"}],"version-history":[{"count":0,"href":"https:\/\/noti-america.com\/site\/alemania\/wp-json\/wp\/v2\/posts\/2281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noti-america.com\/site\/alemania\/wp-json\/wp\/v2\/media\/2282"}],"wp:attachment":[{"href":"https:\/\/noti-america.com\/site\/alemania\/wp-json\/wp\/v2\/media?parent=2281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noti-america.com\/site\/alemania\/wp-json\/wp\/v2\/categories?post=2281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noti-america.com\/site\/alemania\/wp-json\/wp\/v2\/tags?post=2281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}